{"id":80,"date":"2007-08-01T20:14:47","date_gmt":"2007-08-01T18:14:47","guid":{"rendered":"http:\/\/lesbridg.cluster015.ovh.net\/wordpress\/index.php\/films-romantiques-sur-le-couple-et-le-celibat\/idees-de-films-a-voir-ou-revoir-en-fonction-du-moment.html"},"modified":"2019-03-18T17:54:46","modified_gmt":"2019-03-18T16:54:46","slug":"idees-de-films-a-voir-ou-revoir-en-fonction-du-moment","status":"publish","type":"post","link":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/idees-de-films-a-voir-ou-revoir-en-fonction-du-moment.html","title":{"rendered":"Id\u00e9es de films \u00e0 voir ou revoir en fonction du moment"},"content":{"rendered":"<p>Beaucoup sont des films avec des histoires d&rsquo;amour, romantiques qu&rsquo;on ne se lasse pas de revoir. Des histoires qui ne cessent de nous faire r\u00eaver ou pleurer. C&rsquo;est notre petite vid\u00e9oth\u00e8que \u00e0 nous.<br \/>\nAttention pour certains films vous allez devoir pr\u00e9parer vos mouchoirs. Voici quelques id\u00e9es de films :<\/p>\n<p><!-- START ADVERTISER: Votre Voyance GRATUITE sur Internet FR from awin.com --><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.awin1.com\/cread.php?s=2327668&amp;v=13126&amp;q=355922&amp;r=290297\"><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.awin1.com\/cshow.php?s=2327668&amp;v=13126&amp;q=355922&amp;r=290297\" border=\"0\" \/><br \/>\n<\/a><\/p>\n<h2>&#8211; Le journal de Bridget Jones<\/h2>\n<p>Film adapt\u00e9 du livre, r\u00e9cit du journal intime d&rsquo;une trentenaire c\u00e9libataire avec les probl\u00e8mes courant d&rsquo;une femme de son \u00e2ge aujourd&rsquo;hui.<\/p>\n<p>A la recherche du prince charmant, tout faire pour que \u00e7a marche, avec ses probl\u00e8mes de r\u00e9gime, et donc essayer en vain de maigrir, choisir la tenue id\u00e9al pour le s\u00e9duire, avec beaucoup de d\u00e9ception, de chagrin.<\/p>\n<h2>\u00a0&#8211; L&rsquo;\u00e2ge de raison (Bridget Jones 2)<\/h2>\n<p>La suite de la petite vie de notre Bridget pr\u00e9f\u00e9r\u00e9e, toujours pleine de rebondissements.<br \/>\nVa t-elle enfin trouver l&rsquo;homme de sa vie ?<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2128 size-full aligncenter\" src=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2016\/09\/bridget-jones-fin.gif\" alt=\"\" width=\"500\" height=\"224\" \/><\/p>\n<h2>&#8211; <a href=\"https:\/\/www.lesbridgets.com\/index.php\/films-romantiques-sur-le-couple-et-le-celibat\/film-j-me-sens-pas-belle-avec-marina-fois-et-julien-boisselier.html\" target=\"_blank\" rel=\"noopener noreferrer\">J&rsquo;me sens pas belle<\/a> avec Marina Fo\u00efs et Benoit Dussolier<\/h2>\n<p>Pour nous c&rsquo;est un petit chez d&rsquo;oeuvre pour toutes les nanas, qui ont connu le c\u00e9libat, qui ne croit plus en l&rsquo;amour.<br \/>\nNous aimons tellement ce film que nous lui avons fait une page sp\u00e9ciale .<\/p>\n<h2>&#8211; <b><a href=\"https:\/\/www.lesbridgets.com\/index.php\/films-romantiques-sur-le-couple-et-le-celibat\/eternal-sunshine-of-the-spotless-mind-un-film-d-amour-sur-la-rupture-amoureuse.html\" target=\"_blank\" rel=\"noopener noreferrer\">Eternal sunshine of the spotless mind<\/a> <\/b>avec Jim Carrey et Kate Winsley<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-245607 size-full aligncenter\" src=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/02\/glace-eternal-sunshine-film.jpg\" alt=\"\" width=\"750\" height=\"460\" srcset=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/02\/glace-eternal-sunshine-film.jpg 750w, https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/02\/glace-eternal-sunshine-film-300x184.jpg 300w, https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/02\/glace-eternal-sunshine-film-600x368.jpg 600w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<h2>&#8211; <a href=\"https:\/\/www.lesbridgets.com\/index.php\/films-romantiques-sur-le-couple-et-le-celibat\/cashback-un-film-qui-sublime-les-femmes-et-qui-respire-lamour.html\">Cashback<\/a> avec Sean Biggerstaff et Emilia Fox<\/h2>\n<h2>&#8211; Vous avez un message avec Meg Ryan<\/h2>\n<p>Kathleen et Fox, se parlent tous les jours, s&rsquo;appr\u00e9cient \u00e9norm\u00e9ment, ils \u00e9changent une correspondance tr\u00e8s soutenue, quand Kathleen d\u00e9couvre que Fox va devenir son principal concurrent et provoquer la fermeture de sa boutique.<br \/>\nIntrigu\u00e9 par ce film, \u00e0 cause de la correspondance des deux personnes et les liens qui vont se cr\u00e9er, mais j&rsquo;ai \u00e9t\u00e9 assez de\u00e7u par le sc\u00e9nario, et le peu d &lsquo;importance qui a \u00e9t\u00e9 donn\u00e9 \u00e0 cette relation virtuelle.A voir mais une seule fois.<\/p>\n<h2>\u00a0&#8211; Comment se faire larguer en 10 le\u00e7ons.<\/h2>\n<p>Une jeune femme journaliste pour un magazine f\u00e9minin, doit trouver pour un de ses prochains articles les bonnes raisons pour qu&rsquo;un mec larguent une fille! Elle d\u00e9cide de prendre pour cobaye un jeune agent publicitaire, tr\u00e8s convoit\u00e9 et tombeur de ses dames&#8230;elle va devenir la fianc\u00e9e la plus exc\u00e9crable et insuportable! Mais ce qu&rsquo;elle ne sait pas c&rsquo;est que lui a fait le pari de la conqu\u00e9rir&#8230;<br \/>\nS\u00fbrement pas un film culte, mais \u00e0 voir une fois entre copines&#8230;<\/p>\n<p>[amazon_link asins=&rsquo;B01M7V27TI,B00UY1YTGG,B07HMXJG6N,B07HMVLYWM,B01LQE4ZS6,B00Z9PVOJM,B01MR4L962&prime; template=&rsquo;ProductCarousel&rsquo; store=&rsquo;lesbricomcomp-21&prime; marketplace=&rsquo;FR&rsquo; link_id=&rsquo;e922ed55-4c3b-41a4-8da6-78f0ca9f8a04&prime;]<\/p>\n<h2>\u00a0&#8211; Fan Fan avec Sophie Marceau et Vincent Perez<\/h2>\n<p>Un homme pr\u00eat \u00e0 se marier, rencontre une fille exceptionnelle dont il va tomber fou amoureux, mais il repousse le moment o\u00f9 il devra consommer leur amour afin que les sentiments restent toujours comme aux premiers jours.<\/p>\n<h2>&#8211; Pretty Woman<\/h2>\n<p>Pretty woman &#8211; un conte de f\u00e9e du XX\u00e8me si\u00e8cle, qui fait toujours autant r\u00eaver&#8230;<br \/>\nCe film est une des raisons pour laquelle tout le monde aime Julia Roberts et Richard Gere, il a contribu\u00e9 \u00e0 lancer la carri\u00e8re des deux acteurs dans le monde entier.<br \/>\nMais il est aussi la raison pour laquelle on adore manger des fraises avec du champagne!!!<\/p>\n<h2>&#8211; Flash Dance<\/h2>\n<p>Un vrai film de nana!<br \/>\nAvec de la dance et une histoire d&rsquo;amour. Elle est belle, elle danse vraiment bien mais elle ne peut pas vivre de sa passion donc travail dans une fonderie (si!si!).Les gens sont presque tous gentils, il n&rsquo;y a pratiquement pas de m\u00e9chant.<br \/>\nEnfin \u00e7a fait du bien pour r\u00eaver, et voir m\u00eame pour les plus sensibles d&rsquo;entre nous, pleurer&#8230;<br \/>\nA voir aussi pour la BO qui a donn\u00e9 le succ\u00e8s du film, avec le c\u00e9l\u00e8bre morceau \u00ab\u00a0What a feeling\u00a0\u00bb interpr\u00e8t\u00e9e par Ir\u00e8ne Cara.<\/p>\n<h2>&#8211; Modigliani avec Andy Garcia<\/h2>\n<p>Superbe film sur la vie de cet artiste romantique avec son amour passionnel et d\u00e9chirant&#8230; les filles pr\u00e9par\u00e9es vos mouchoirs&#8230;<br \/>\nCasting parfait, Elsa Zylberstein incarne parfaitement la muse et l&rsquo;amour de Modi.<br \/>\nUn film surprenant.<br \/>\nPr\u00e9voir un peu de temps devant vous car le film dure plus de 2 heures.<\/p>\n<p>Sortie le 29 septembre 2004.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-242995 size-full aligncenter\" src=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2018\/03\/film-modigliani-andy-garcia.png\" alt=\"\" width=\"750\" height=\"483\" srcset=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2018\/03\/film-modigliani-andy-garcia.png 750w, https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2018\/03\/film-modigliani-andy-garcia-300x193.png 300w, https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2018\/03\/film-modigliani-andy-garcia-600x386.png 600w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<h2>&#8211; Le Coeur des hommes<\/h2>\n<p>Une fois n&rsquo;est pas coutume un film sur des hommes et leur vie amoureuse, leurs questions, leurs sentiments, beaucoup des cas typiques d&rsquo;hommes d\u00e9passant la quarantaine sont repr\u00e9sent\u00e9s.<br \/>\nL&rsquo;homme mari\u00e9 depuis des ann\u00e9es qui trompent sa femme.<br \/>\nL&rsquo;homme divorc\u00e9 qui a peur de l&rsquo;engagement.<br \/>\nL&rsquo;homme mari\u00e9 que sa femme a tromp\u00e9.<br \/>\nEt enfin un homme veuf qui red\u00e9couvre l&rsquo;amour.<\/p>\n<p><b>&#8211; <a href=\"index.php\/Films-romantiques-sur-le-couple-et-le-celibat\/Un-film-qui-bouscule-notre-vision-des-relations-amoureuses.html\">Vicky Cristina Barcelona<\/a><\/b> de Woody Allen avec P\u00e9n\u00e9lope Cruz et Scarlett Johansson<\/p>\n<h2>&#8211; Love et ses petits d\u00e9sastres<\/h2>\n<p>Com\u00e9die am\u00e9ricaine qui survole bri\u00e8vement les relations amoureuses de notre \u00e9poque dans l&rsquo;univers de la mode.<br \/>\nJack vit avec son colocataire gay, et ils sont tous deux \u00e0 la recherche du grand amour.<\/p>\n<p>Existe il vraiment?<br \/>\nNe le cherchons nous pas au bon endroit?<\/p>\n<p>Quelques questions auxquelles le film tente de r\u00e9pondre. Une petite com\u00e9die romantique bien sympatique \u00e0 regarder pour se d\u00e9tendre.<\/p>\n<p>En attendant de le trouver Jack couche toujours avec son ex avec qui elle a rompu il y a quelques semaines.<\/p>\n<h3>&#8211; Quand Harry rencontre Sally<\/h3>\n<h3>&#8211; Dirty Dancing<\/h3>\n<h3>&#8211; Romeo et juliette de William Shakespeare<\/h3>\n<h3>&#8211; Ma vie en l&rsquo;air<\/h3>\n<h3>&#8211; Je reste avec Sophie Marceau et Vincent Perez<\/h3>\n<p>N&rsquo;h\u00e9sitez pas en ajouter d&rsquo;autres dans les commentaires.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Beaucoup sont des films avec des histoires d&rsquo;amour, romantiques qu&rsquo;on ne se lasse pas de revoir. Des histoires qui ne cessent de nous faire r\u00eaver ou pleurer. C&rsquo;est notre petite vid\u00e9oth\u00e8que \u00e0 nous.<br \/> Attention pour certains films vous allez devoir pr\u00e9parer vos mouchoirs.<\/p>\n","protected":false},"author":2,"featured_media":246253,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"om_disable_all_campaigns":false,"_lmt_disableupdate":"","_lmt_disable":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[28],"tags":[815,816],"class_list":["post-80","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-films","tag-films","tag-films-amour"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Id\u00e9es de films \u00e0 voir ou revoir en fonction du moment - Les Bridgets<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/idees-de-films-a-voir-ou-revoir-en-fonction-du-moment.html\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Id\u00e9es de films \u00e0 voir ou revoir en fonction du moment - Les Bridgets\" \/>\n<meta property=\"og:description\" content=\"Beaucoup sont des films avec des histoires d&#039;amour, romantiques qu&#039;on ne se lasse pas de revoir. Des histoires qui ne cessent de nous faire r\u00eaver ou pleurer. C&#039;est notre petite vid\u00e9oth\u00e8que \u00e0 nous. Attention pour certains films vous allez devoir pr\u00e9parer vos mouchoirs.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/idees-de-films-a-voir-ou-revoir-en-fonction-du-moment.html\" \/>\n<meta property=\"og:site_name\" content=\"Les Bridgets\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Les.Bridgets\" \/>\n<meta property=\"article:published_time\" content=\"2007-08-01T18:14:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-03-18T16:54:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2007\/08\/listes-films-a-voir.png\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"466\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Bridget\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@les_bridgets\" \/>\n<meta name=\"twitter:site\" content=\"@les_bridgets\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bridget\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/idees-de-films-a-voir-ou-revoir-en-fonction-du-moment.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/idees-de-films-a-voir-ou-revoir-en-fonction-du-moment.html\"},\"author\":{\"name\":\"Bridget\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/person\\\/82a31c27ae0ddd23ee59e1e2ac5713ba\"},\"headline\":\"Id\u00e9es de films \u00e0 voir ou revoir en fonction du moment\",\"datePublished\":\"2007-08-01T18:14:47+00:00\",\"dateModified\":\"2019-03-18T16:54:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/idees-de-films-a-voir-ou-revoir-en-fonction-du-moment.html\"},\"wordCount\":994,\"commentCount\":13,\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/idees-de-films-a-voir-ou-revoir-en-fonction-du-moment.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2007\\\/08\\\/listes-films-a-voir.png\",\"keywords\":[\"films\",\"films amour\"],\"articleSection\":[\"Film\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/idees-de-films-a-voir-ou-revoir-en-fonction-du-moment.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/idees-de-films-a-voir-ou-revoir-en-fonction-du-moment.html\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/idees-de-films-a-voir-ou-revoir-en-fonction-du-moment.html\",\"name\":\"Id\u00e9es de films \u00e0 voir ou revoir en fonction du moment - Les Bridgets\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/idees-de-films-a-voir-ou-revoir-en-fonction-du-moment.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/idees-de-films-a-voir-ou-revoir-en-fonction-du-moment.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2007\\\/08\\\/listes-films-a-voir.png\",\"datePublished\":\"2007-08-01T18:14:47+00:00\",\"dateModified\":\"2019-03-18T16:54:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/idees-de-films-a-voir-ou-revoir-en-fonction-du-moment.html#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/idees-de-films-a-voir-ou-revoir-en-fonction-du-moment.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/idees-de-films-a-voir-ou-revoir-en-fonction-du-moment.html#primaryimage\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2007\\\/08\\\/listes-films-a-voir.png\",\"contentUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2007\\\/08\\\/listes-films-a-voir.png\",\"width\":750,\"height\":466},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/idees-de-films-a-voir-ou-revoir-en-fonction-du-moment.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Les Bridgets\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00e9f\u00e9rences sur le couple et le c\u00e9libat\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/category\\\/references\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Film\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/category\\\/references\\\/films\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Id\u00e9es de films \u00e0 voir ou revoir en fonction du moment\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#website\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/\",\"name\":\"Les Bridgets\",\"description\":\"R\u00e9f\u00e9rences et r\u00e9flexions sur nos relations\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lesbridgets.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\",\"name\":\"Les Bridgets\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo-3-lesbridgets.png\",\"contentUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo-3-lesbridgets.png\",\"width\":251,\"height\":59,\"caption\":\"Les Bridgets\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Les.Bridgets\",\"https:\\\/\\\/x.com\\\/les_bridgets\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/person\\\/82a31c27ae0ddd23ee59e1e2ac5713ba\",\"name\":\"Bridget\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"caption\":\"Bridget\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Id\u00e9es de films \u00e0 voir ou revoir en fonction du moment - Les Bridgets","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/idees-de-films-a-voir-ou-revoir-en-fonction-du-moment.html","og_locale":"fr_FR","og_type":"article","og_title":"Id\u00e9es de films \u00e0 voir ou revoir en fonction du moment - Les Bridgets","og_description":"Beaucoup sont des films avec des histoires d'amour, romantiques qu'on ne se lasse pas de revoir. Des histoires qui ne cessent de nous faire r\u00eaver ou pleurer. C'est notre petite vid\u00e9oth\u00e8que \u00e0 nous. Attention pour certains films vous allez devoir pr\u00e9parer vos mouchoirs.","og_url":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/idees-de-films-a-voir-ou-revoir-en-fonction-du-moment.html","og_site_name":"Les Bridgets","article_publisher":"https:\/\/www.facebook.com\/Les.Bridgets","article_published_time":"2007-08-01T18:14:47+00:00","article_modified_time":"2019-03-18T16:54:46+00:00","og_image":[{"width":750,"height":466,"url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2007\/08\/listes-films-a-voir.png","type":"image\/png"}],"author":"Bridget","twitter_card":"summary_large_image","twitter_creator":"@les_bridgets","twitter_site":"@les_bridgets","twitter_misc":{"\u00c9crit par":"Bridget","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/idees-de-films-a-voir-ou-revoir-en-fonction-du-moment.html#article","isPartOf":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/idees-de-films-a-voir-ou-revoir-en-fonction-du-moment.html"},"author":{"name":"Bridget","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/person\/82a31c27ae0ddd23ee59e1e2ac5713ba"},"headline":"Id\u00e9es de films \u00e0 voir ou revoir en fonction du moment","datePublished":"2007-08-01T18:14:47+00:00","dateModified":"2019-03-18T16:54:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/idees-de-films-a-voir-ou-revoir-en-fonction-du-moment.html"},"wordCount":994,"commentCount":13,"publisher":{"@id":"https:\/\/www.lesbridgets.com\/#organization"},"image":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/idees-de-films-a-voir-ou-revoir-en-fonction-du-moment.html#primaryimage"},"thumbnailUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2007\/08\/listes-films-a-voir.png","keywords":["films","films amour"],"articleSection":["Film"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.lesbridgets.com\/index.php\/references\/films\/idees-de-films-a-voir-ou-revoir-en-fonction-du-moment.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/idees-de-films-a-voir-ou-revoir-en-fonction-du-moment.html","url":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/idees-de-films-a-voir-ou-revoir-en-fonction-du-moment.html","name":"Id\u00e9es de films \u00e0 voir ou revoir en fonction du moment - Les Bridgets","isPartOf":{"@id":"https:\/\/www.lesbridgets.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/idees-de-films-a-voir-ou-revoir-en-fonction-du-moment.html#primaryimage"},"image":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/idees-de-films-a-voir-ou-revoir-en-fonction-du-moment.html#primaryimage"},"thumbnailUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2007\/08\/listes-films-a-voir.png","datePublished":"2007-08-01T18:14:47+00:00","dateModified":"2019-03-18T16:54:46+00:00","breadcrumb":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/idees-de-films-a-voir-ou-revoir-en-fonction-du-moment.html#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lesbridgets.com\/index.php\/references\/films\/idees-de-films-a-voir-ou-revoir-en-fonction-du-moment.html"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/idees-de-films-a-voir-ou-revoir-en-fonction-du-moment.html#primaryimage","url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2007\/08\/listes-films-a-voir.png","contentUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2007\/08\/listes-films-a-voir.png","width":750,"height":466},{"@type":"BreadcrumbList","@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/idees-de-films-a-voir-ou-revoir-en-fonction-du-moment.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Les Bridgets","item":"https:\/\/www.lesbridgets.com\/"},{"@type":"ListItem","position":2,"name":"R\u00e9f\u00e9rences sur le couple et le c\u00e9libat","item":"https:\/\/www.lesbridgets.com\/index.php\/category\/references"},{"@type":"ListItem","position":3,"name":"Film","item":"https:\/\/www.lesbridgets.com\/index.php\/category\/references\/films"},{"@type":"ListItem","position":4,"name":"Id\u00e9es de films \u00e0 voir ou revoir en fonction du moment"}]},{"@type":"WebSite","@id":"https:\/\/www.lesbridgets.com\/#website","url":"https:\/\/www.lesbridgets.com\/","name":"Les Bridgets","description":"R\u00e9f\u00e9rences et r\u00e9flexions sur nos relations","publisher":{"@id":"https:\/\/www.lesbridgets.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lesbridgets.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lesbridgets.com\/#organization","name":"Les Bridgets","url":"https:\/\/www.lesbridgets.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2022\/07\/cropped-logo-3-lesbridgets.png","contentUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2022\/07\/cropped-logo-3-lesbridgets.png","width":251,"height":59,"caption":"Les Bridgets"},"image":{"@id":"https:\/\/www.lesbridgets.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Les.Bridgets","https:\/\/x.com\/les_bridgets"]},{"@type":"Person","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/person\/82a31c27ae0ddd23ee59e1e2ac5713ba","name":"Bridget","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","caption":"Bridget"}}]}},"modified_by":"Bridget","_links":{"self":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/80","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/comments?post=80"}],"version-history":[{"count":13,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/80\/revisions"}],"predecessor-version":[{"id":246260,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/80\/revisions\/246260"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/media\/246253"}],"wp:attachment":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/media?parent=80"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/categories?post=80"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/tags?post=80"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}