{"id":782,"date":"2010-08-31T15:58:58","date_gmt":"2010-08-31T13:58:58","guid":{"rendered":"http:\/\/lesbridg.cluster015.ovh.net\/wordpress\/index.php\/etude-statistiques-sur-les-celibataires\/une-rupture-amoureuse-peut-etre-aussi-difficile-a-surmonter-quun-sevrage-de-la-cocaine.html"},"modified":"2020-05-17T11:03:59","modified_gmt":"2020-05-17T09:03:59","slug":"une-rupture-amoureuse-peut-etre-aussi-difficile-a-surmonter-qu-un-sevrage-de-la-cocaine","status":"publish","type":"post","link":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rupture-amoureuse\/une-rupture-amoureuse-peut-etre-aussi-difficile-a-surmonter-qu-un-sevrage-de-la-cocaine.html","title":{"rendered":"Sevrage de la coca\u00efne : Une rupture amoureuse peut \u00eatre aussi difficile \u00e0 surmonter"},"content":{"rendered":"<p>Fin juillet une \u00e9tude canadienne d&rsquo;une \u00e9quipe de l&rsquo;Universit\u00e9 de Stony Brook publi\u00e9e dans le Journal of Neurophysiology nous l&rsquo;affirme: L&rsquo;amour provoque dans notre cerveau une d\u00e9pendance similaire \u00e0 une drogue.<br \/>\nLe Pr Arthur Aron et ses \u00e9tudiants arrivent \u00e0 cette conclusion apr\u00e8s avoir \u00e9tudi\u00e9 les r\u00e9actions du cerveau de personnes en peine d&rsquo;amour auxquelles une photo du partenaire perdu \u00e9tait pr\u00e9sent\u00e9e.<\/p>\n<p>En effet, les chercheurs ont constat\u00e9 que la zone c\u00e9r\u00e9brale sollicit\u00e9e \u00e9tait la m\u00eame que celle associ\u00e9e \u00e0 une tr\u00e8s forte d\u00e9pendance \u00e0 la drogue.<\/p>\n<p>Celle qui produit de la <a href=\"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rencontre-seduction\/tomber-amoureux-une-question-d-odeur.html\" target=\"_blank\" rel=\"noopener noreferrer\">ph\u00e9nyl\u00e9thylamine, une hormone s\u00e9cr\u00e9t\u00e9e lorsque l&rsquo;on mange un simple carr\u00e9 de chocolat<\/a>.<\/p>\n<p>Cette r\u00e9gion est aussi impliqu\u00e9e dans la motivation, la r\u00e9compense et d&rsquo;autres d\u00e9pendances.<\/p>\n<blockquote>\n<h3>Ces r\u00e9sultats appuient la th\u00e8se selon laquelle l&rsquo;amour romantique est une forme sp\u00e9cifique de d\u00e9pendance.\u2014 Arthur Aron<\/h3>\n<\/blockquote>\n<p>Ces donn\u00e9es aident aussi \u00e0 expliquer pourquoi les \u00e9motions et les comportements li\u00e9s aux rejets amoureux, comme le harc\u00e8lement, le meurtre, le suicide et la d\u00e9pression, sont les m\u00eames dans les diff\u00e9rentes cultures.<\/p>\n<p>Signe encourageant, notent les auteurs : plus le temps passe, moins la zone du cerveau li\u00e9e au sentiment d&rsquo;attachement est stimul\u00e9e en regardant la photographie. (Mais les alcooliques oublient-ils vraiment leur premier verre ou encore les fumeurs leur premi\u00e8re cigarette?)<\/p>\n<p>En effet, pour comprendre cette \u00e9tude il suffit de lire les effets d&rsquo;un sevrage \u00e0 une drogue tel que l&rsquo;alcool ou encore la coca\u00efne pour y d\u00e9couvrir les m\u00eame sympt\u00f4mes que l&rsquo;on peut ressentir \u00e0 l&rsquo;annonce d&rsquo;une rupture amoureuse :<\/p>\n<p>Nous avons simplement repris ci-dessous, les effets d&rsquo;un sevrage \u00e0 la cocaine et l&rsquo;alcool. Pour ceux qui ont d\u00e9j\u00e0 connu une rupture amoureuse douloureuse vous allez bizarrement vous reconnaitre.<\/p>\n<p style=\"text-align: center;\">Votre voyance gratuite, <a href=\"https:\/\/action.metaffiliation.com\/trk.php?mclic=P41F164267911109\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">en cliquant ici<\/a><\/p>\n<h2>Les sympt\u00f4mes du sevrage de la coca\u00efne et donc \u00e0 une rupture amoureuse sont principalement :<\/h2>\n<ul>\n<li>D\u00e9pression<\/li>\n<li>Crise de panique<\/li>\n<li>Anxi\u00e9t\u00e9 (Sueurs et des tremblements. Selon l&rsquo;origine et les causes de la rupture, vous pouvez ressentir des \u00e9c\u0153urements au point d&rsquo;avoir des envies de vomir.)<\/li>\n<li>Changements de l&rsquo;app\u00e9tit (M\u00eame si vous n&rsquo;avez pas d&rsquo;app\u00e9tit, mangez une alimentation \u00e9quilibr\u00e9e aux heures des repas. Votre app\u00e9tit reviendra)<\/li>\n<li>Probl\u00e8mes de sommeil (Vous verrez que m\u00eame avec des somnif\u00e8res, ou lorsque leur dose est r\u00e9duite par votre m\u00e9decin (ce qui est n\u00e9cessaire au bout de quelques semaines), le manque de sommeil (souvent sur\u00e9valu\u00e9). Ne vous inqui\u00e9tez pas, votre sommeil reviendra progressivement \u00e0 la normale en quelques semaines. Essayez de vous coucher plus tard.<\/li>\n<li>Fatigue<\/li>\n<\/ul>\n<p><strong>La p\u00e9riode de sevrage dure environ de deux \u00e0 trois semaines.<br \/>\n<\/strong><br \/>\nPendant tout cette p\u00e9riode et bien apr\u00e8s, <a href=\"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rupture-amoureuse-separation-conseils\/comment-se-retenir-de-lui-envoyer-un-message.html\">\u00e9vitez tout contact avec votre ex<\/a>. Mais aussi toutes les choses qui peuvent vous rappeler ou vous faire penser \u00e0 lui (Amis, <a href=\"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/vivre-a-deux-en-couple-le-quotidien\/nouvelle-relation-conserver-les-souvenirs-et-cadeaux-de-son-ex.html\" target=\"_blank\" rel=\"noopener noreferrer\">cadeaux de son ex<\/a>, habitudes&#8230;)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fin juillet une \u00e9tude canadienne d&rsquo;une \u00e9quipe de l&rsquo;Universit\u00e9 de Stony Brook publi\u00e9e dans le Journal of Neurophysiology nous l&rsquo;affirme: L&rsquo;amour provoque dans notre cerveau une d\u00e9pendance similaire \u00e0 une drogue.<br \/> Le Pr Arthur Aron et ses \u00e9tudiants arrivent \u00e0 cette conclusion apr\u00e8s avoir \u00e9tudi\u00e9 les r\u00e9actions du cerveau de personnes en peine d&rsquo;amour auxquelles une photo du partenaire perdu \u00e9tait pr\u00e9sent\u00e9e.<\/p>\n","protected":false},"author":2,"featured_media":244952,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"om_disable_all_campaigns":false,"_lmt_disableupdate":"no","_lmt_disable":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[4,10],"tags":[310,60],"class_list":["post-782","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rupture-amoureuse","category-etude-statistiques-celibataires","tag-etude-rupture","tag-rupture-amoureuse"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sevrage de la coca\u00efne : Une rupture amoureuse peut \u00eatre aussi difficile \u00e0 surmonter - Les Bridgets<\/title>\n<meta name=\"description\" content=\"Une \u00e9tude de 2010 prouve que suite \u00e0 une rupture, le manque de l&#039;autre peut s&#039;av\u00e9rer aussi difficile qu&#039;un sevrage de la cocaine.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rupture-amoureuse\/une-rupture-amoureuse-peut-etre-aussi-difficile-a-surmonter-qu-un-sevrage-de-la-cocaine.html\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sevrage de la coca\u00efne : Une rupture amoureuse peut \u00eatre aussi difficile \u00e0 surmonter - Les Bridgets\" \/>\n<meta property=\"og:description\" content=\"Une \u00e9tude de 2010 prouve que suite \u00e0 une rupture, le manque de l&#039;autre peut s&#039;av\u00e9rer aussi difficile qu&#039;un sevrage de la cocaine.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rupture-amoureuse\/une-rupture-amoureuse-peut-etre-aussi-difficile-a-surmonter-qu-un-sevrage-de-la-cocaine.html\" \/>\n<meta property=\"og:site_name\" content=\"Les Bridgets\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Les.Bridgets\" \/>\n<meta property=\"article:published_time\" content=\"2010-08-31T13:58:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-17T09:03:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2010\/08\/rupture-sevrage-cocaine.png\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"563\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Bridget\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@les_bridgets\" \/>\n<meta name=\"twitter:site\" content=\"@les_bridgets\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bridget\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/rupture-amoureuse\\\/une-rupture-amoureuse-peut-etre-aussi-difficile-a-surmonter-qu-un-sevrage-de-la-cocaine.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/rupture-amoureuse\\\/une-rupture-amoureuse-peut-etre-aussi-difficile-a-surmonter-qu-un-sevrage-de-la-cocaine.html\"},\"author\":{\"name\":\"Bridget\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/person\\\/82a31c27ae0ddd23ee59e1e2ac5713ba\"},\"headline\":\"Sevrage de la coca\u00efne : Une rupture amoureuse peut \u00eatre aussi difficile \u00e0 surmonter\",\"datePublished\":\"2010-08-31T13:58:58+00:00\",\"dateModified\":\"2020-05-17T09:03:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/rupture-amoureuse\\\/une-rupture-amoureuse-peut-etre-aussi-difficile-a-surmonter-qu-un-sevrage-de-la-cocaine.html\"},\"wordCount\":527,\"commentCount\":37,\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/rupture-amoureuse\\\/une-rupture-amoureuse-peut-etre-aussi-difficile-a-surmonter-qu-un-sevrage-de-la-cocaine.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2010\\\/08\\\/rupture-sevrage-cocaine.png\",\"keywords\":[\"etude rupture\",\"rupture amoureuse\"],\"articleSection\":[\"Rupture amoureuse - S\u00e9paration\",\"Statistiques sur les c\u00e9libataires\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/rupture-amoureuse\\\/une-rupture-amoureuse-peut-etre-aussi-difficile-a-surmonter-qu-un-sevrage-de-la-cocaine.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/rupture-amoureuse\\\/une-rupture-amoureuse-peut-etre-aussi-difficile-a-surmonter-qu-un-sevrage-de-la-cocaine.html\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/rupture-amoureuse\\\/une-rupture-amoureuse-peut-etre-aussi-difficile-a-surmonter-qu-un-sevrage-de-la-cocaine.html\",\"name\":\"Sevrage de la coca\u00efne : Une rupture amoureuse peut \u00eatre aussi difficile \u00e0 surmonter - Les Bridgets\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/rupture-amoureuse\\\/une-rupture-amoureuse-peut-etre-aussi-difficile-a-surmonter-qu-un-sevrage-de-la-cocaine.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/rupture-amoureuse\\\/une-rupture-amoureuse-peut-etre-aussi-difficile-a-surmonter-qu-un-sevrage-de-la-cocaine.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2010\\\/08\\\/rupture-sevrage-cocaine.png\",\"datePublished\":\"2010-08-31T13:58:58+00:00\",\"dateModified\":\"2020-05-17T09:03:59+00:00\",\"description\":\"Une \u00e9tude de 2010 prouve que suite \u00e0 une rupture, le manque de l'autre peut s'av\u00e9rer aussi difficile qu'un sevrage de la cocaine.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/rupture-amoureuse\\\/une-rupture-amoureuse-peut-etre-aussi-difficile-a-surmonter-qu-un-sevrage-de-la-cocaine.html#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/rupture-amoureuse\\\/une-rupture-amoureuse-peut-etre-aussi-difficile-a-surmonter-qu-un-sevrage-de-la-cocaine.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/rupture-amoureuse\\\/une-rupture-amoureuse-peut-etre-aussi-difficile-a-surmonter-qu-un-sevrage-de-la-cocaine.html#primaryimage\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2010\\\/08\\\/rupture-sevrage-cocaine.png\",\"contentUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2010\\\/08\\\/rupture-sevrage-cocaine.png\",\"width\":750,\"height\":563},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/rupture-amoureuse\\\/une-rupture-amoureuse-peut-etre-aussi-difficile-a-surmonter-qu-un-sevrage-de-la-cocaine.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Les Bridgets\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conseils sur l'amour, le couple &amp; les c\u00e9libataires\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/category\\\/conseils-relations\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Rupture amoureuse - S\u00e9paration\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/category\\\/conseils-relations\\\/rupture-amoureuse\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Sevrage de la coca\u00efne : Une rupture amoureuse peut \u00eatre aussi difficile \u00e0 surmonter\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#website\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/\",\"name\":\"Les Bridgets\",\"description\":\"R\u00e9f\u00e9rences et r\u00e9flexions sur nos relations\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lesbridgets.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\",\"name\":\"Les Bridgets\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo-3-lesbridgets.png\",\"contentUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo-3-lesbridgets.png\",\"width\":251,\"height\":59,\"caption\":\"Les Bridgets\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Les.Bridgets\",\"https:\\\/\\\/x.com\\\/les_bridgets\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/person\\\/82a31c27ae0ddd23ee59e1e2ac5713ba\",\"name\":\"Bridget\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"caption\":\"Bridget\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sevrage de la coca\u00efne : Une rupture amoureuse peut \u00eatre aussi difficile \u00e0 surmonter - Les Bridgets","description":"Une \u00e9tude de 2010 prouve que suite \u00e0 une rupture, le manque de l'autre peut s'av\u00e9rer aussi difficile qu'un sevrage de la cocaine.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rupture-amoureuse\/une-rupture-amoureuse-peut-etre-aussi-difficile-a-surmonter-qu-un-sevrage-de-la-cocaine.html","og_locale":"fr_FR","og_type":"article","og_title":"Sevrage de la coca\u00efne : Une rupture amoureuse peut \u00eatre aussi difficile \u00e0 surmonter - Les Bridgets","og_description":"Une \u00e9tude de 2010 prouve que suite \u00e0 une rupture, le manque de l'autre peut s'av\u00e9rer aussi difficile qu'un sevrage de la cocaine.","og_url":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rupture-amoureuse\/une-rupture-amoureuse-peut-etre-aussi-difficile-a-surmonter-qu-un-sevrage-de-la-cocaine.html","og_site_name":"Les Bridgets","article_publisher":"https:\/\/www.facebook.com\/Les.Bridgets","article_published_time":"2010-08-31T13:58:58+00:00","article_modified_time":"2020-05-17T09:03:59+00:00","og_image":[{"width":750,"height":563,"url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2010\/08\/rupture-sevrage-cocaine.png","type":"image\/png"}],"author":"Bridget","twitter_card":"summary_large_image","twitter_creator":"@les_bridgets","twitter_site":"@les_bridgets","twitter_misc":{"\u00c9crit par":"Bridget","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rupture-amoureuse\/une-rupture-amoureuse-peut-etre-aussi-difficile-a-surmonter-qu-un-sevrage-de-la-cocaine.html#article","isPartOf":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rupture-amoureuse\/une-rupture-amoureuse-peut-etre-aussi-difficile-a-surmonter-qu-un-sevrage-de-la-cocaine.html"},"author":{"name":"Bridget","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/person\/82a31c27ae0ddd23ee59e1e2ac5713ba"},"headline":"Sevrage de la coca\u00efne : Une rupture amoureuse peut \u00eatre aussi difficile \u00e0 surmonter","datePublished":"2010-08-31T13:58:58+00:00","dateModified":"2020-05-17T09:03:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rupture-amoureuse\/une-rupture-amoureuse-peut-etre-aussi-difficile-a-surmonter-qu-un-sevrage-de-la-cocaine.html"},"wordCount":527,"commentCount":37,"publisher":{"@id":"https:\/\/www.lesbridgets.com\/#organization"},"image":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rupture-amoureuse\/une-rupture-amoureuse-peut-etre-aussi-difficile-a-surmonter-qu-un-sevrage-de-la-cocaine.html#primaryimage"},"thumbnailUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2010\/08\/rupture-sevrage-cocaine.png","keywords":["etude rupture","rupture amoureuse"],"articleSection":["Rupture amoureuse - S\u00e9paration","Statistiques sur les c\u00e9libataires"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rupture-amoureuse\/une-rupture-amoureuse-peut-etre-aussi-difficile-a-surmonter-qu-un-sevrage-de-la-cocaine.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rupture-amoureuse\/une-rupture-amoureuse-peut-etre-aussi-difficile-a-surmonter-qu-un-sevrage-de-la-cocaine.html","url":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rupture-amoureuse\/une-rupture-amoureuse-peut-etre-aussi-difficile-a-surmonter-qu-un-sevrage-de-la-cocaine.html","name":"Sevrage de la coca\u00efne : Une rupture amoureuse peut \u00eatre aussi difficile \u00e0 surmonter - Les Bridgets","isPartOf":{"@id":"https:\/\/www.lesbridgets.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rupture-amoureuse\/une-rupture-amoureuse-peut-etre-aussi-difficile-a-surmonter-qu-un-sevrage-de-la-cocaine.html#primaryimage"},"image":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rupture-amoureuse\/une-rupture-amoureuse-peut-etre-aussi-difficile-a-surmonter-qu-un-sevrage-de-la-cocaine.html#primaryimage"},"thumbnailUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2010\/08\/rupture-sevrage-cocaine.png","datePublished":"2010-08-31T13:58:58+00:00","dateModified":"2020-05-17T09:03:59+00:00","description":"Une \u00e9tude de 2010 prouve que suite \u00e0 une rupture, le manque de l'autre peut s'av\u00e9rer aussi difficile qu'un sevrage de la cocaine.","breadcrumb":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rupture-amoureuse\/une-rupture-amoureuse-peut-etre-aussi-difficile-a-surmonter-qu-un-sevrage-de-la-cocaine.html#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rupture-amoureuse\/une-rupture-amoureuse-peut-etre-aussi-difficile-a-surmonter-qu-un-sevrage-de-la-cocaine.html"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rupture-amoureuse\/une-rupture-amoureuse-peut-etre-aussi-difficile-a-surmonter-qu-un-sevrage-de-la-cocaine.html#primaryimage","url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2010\/08\/rupture-sevrage-cocaine.png","contentUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2010\/08\/rupture-sevrage-cocaine.png","width":750,"height":563},{"@type":"BreadcrumbList","@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rupture-amoureuse\/une-rupture-amoureuse-peut-etre-aussi-difficile-a-surmonter-qu-un-sevrage-de-la-cocaine.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Les Bridgets","item":"https:\/\/www.lesbridgets.com\/"},{"@type":"ListItem","position":2,"name":"Conseils sur l'amour, le couple &amp; les c\u00e9libataires","item":"https:\/\/www.lesbridgets.com\/index.php\/category\/conseils-relations"},{"@type":"ListItem","position":3,"name":"Rupture amoureuse - S\u00e9paration","item":"https:\/\/www.lesbridgets.com\/index.php\/category\/conseils-relations\/rupture-amoureuse"},{"@type":"ListItem","position":4,"name":"Sevrage de la coca\u00efne : Une rupture amoureuse peut \u00eatre aussi difficile \u00e0 surmonter"}]},{"@type":"WebSite","@id":"https:\/\/www.lesbridgets.com\/#website","url":"https:\/\/www.lesbridgets.com\/","name":"Les Bridgets","description":"R\u00e9f\u00e9rences et r\u00e9flexions sur nos relations","publisher":{"@id":"https:\/\/www.lesbridgets.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lesbridgets.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lesbridgets.com\/#organization","name":"Les Bridgets","url":"https:\/\/www.lesbridgets.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2022\/07\/cropped-logo-3-lesbridgets.png","contentUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2022\/07\/cropped-logo-3-lesbridgets.png","width":251,"height":59,"caption":"Les Bridgets"},"image":{"@id":"https:\/\/www.lesbridgets.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Les.Bridgets","https:\/\/x.com\/les_bridgets"]},{"@type":"Person","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/person\/82a31c27ae0ddd23ee59e1e2ac5713ba","name":"Bridget","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","caption":"Bridget"}}]}},"modified_by":"Bridget","_links":{"self":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/comments?post=782"}],"version-history":[{"count":9,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/782\/revisions"}],"predecessor-version":[{"id":252443,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/782\/revisions\/252443"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/media\/244952"}],"wp:attachment":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/media?parent=782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/categories?post=782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/tags?post=782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}