{"id":571,"date":"2010-01-07T15:07:31","date_gmt":"2010-01-07T14:07:31","guid":{"rendered":"http:\/\/lesbridg.cluster015.ovh.net\/wordpress\/index.php\/films-romantiques-sur-le-couple-et-le-celibat\/qla-princesse-et-la-grenouilleq-quand-walt-disney-se-remet-a-la-2d.html"},"modified":"2017-08-11T18:30:40","modified_gmt":"2017-08-11T16:30:40","slug":"la-princesse-et-la-grenouille-quand-walt-disney-se-remet-a-la-2d","status":"publish","type":"post","link":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/la-princesse-et-la-grenouille-quand-walt-disney-se-remet-a-la-2d.html","title":{"rendered":"\u00ab\u00a0La princesse et la grenouille\u00a0\u00bb quand Walt Disney se remet \u00e0 la 2D"},"content":{"rendered":"<p><em>La Princesse et la Grenouille <\/em>de Walt Disney<em>, <\/em>c&rsquo;est reprendre\u00a0une petite bouff\u00e9e de conte de f\u00e9es, de prince qui nous aime malgr\u00e9 nos rondeurs, de belles robes de princesses qui scintillent, et de cet entourage qui s&rsquo;entraide alors qu&rsquo;ils se connaissent \u00e0 peine. Il faut l&rsquo;avouer aujourd&rsquo;hui \u00e7a peut faire r\u00eaver.<\/p>\n<p>Mais surtout l&rsquo;\u00e9v\u00e8nement de ce r\u00e9cent dessin anim\u00e9 de Walt Disney est qu&rsquo;\u00e0 l&rsquo;heure de la 3D ils se remettent \u00e0 la 2D.<\/p>\n<p>Effectivement, ce nouveau Walt Disney est enti\u00e8rement dessin\u00e9 \u00e0 la main, on reconnait le bon coup de crayon des anciens de Walt Disney, Clements et Musker.<\/p>\n<h2>Pour preuve l&rsquo;aper\u00e7u dans la bande-annonce ci-dessous<\/h2>\n<p><iframe loading=\"lazy\" style=\"display: block; margin-left: auto; margin-right: auto;\" src=\"http:\/\/www.youtube.com\/embed\/PHvMH4opSmg\" width=\"560\" height=\"315\" frameborder=\"0\"><\/iframe><\/p>\n<p>On avait ador\u00e9 <em>Le roi Lion<\/em> (notre pr\u00e9f\u00e9r\u00e9), <em>Pocahontas<\/em>, ou bien encore <em>La Petite Sir\u00e8ne<\/em> et je confirme dans <em>La Princesse et la Grenouille<\/em> on retrouve totalement l&rsquo;esprit des anciens Walt Disney mais malheureusement \u00e0 tel point qu&rsquo;il n&rsquo;y a rien d&rsquo;innovant.<\/p>\n<p>Aucune surprise, aucun humour, aucune larme, certes nous n&rsquo;avons plus 5 ans mais on prend \u00e0 chaque fois un plaisir \u00e0 voir de nouveaux Pixar.<\/p>\n<p>Je ne parle pas de la technique car les dessins et animations sont toujours aussi superbes mais des dialogues et du sc\u00e9nario.<br \/>\n<span style=\"line-height: 1.3em;\">Certes l&rsquo;histoire se passe dans les ann\u00e9es 20 \u00e0 la Nouvelle Orl\u00e9ans, on ne peut pas avoir des dialogues des <\/span><em style=\"line-height: 1.3em;\">Lascars<\/em><span style=\"line-height: 1.3em;\"> et du rap en fond musical, mais il \u00e9tait s\u00fbrement possible de glisser un peu d&rsquo;humour ?<\/span><\/p>\n<p>La grande nouveaut\u00e9 c&rsquo;est que le r\u00f4le principal de la princesse est afro-am\u00e9ricaine.<br \/>\nLors de la projection et \u00e0 la lecture de certain blogs il semblerait que le dessin-anim\u00e9 est plu \u00e0 pas mal de personnes, personnellement Bridget s&rsquo;est endormie (clairement je me suis ennuy\u00e9e).<\/p>\n<h2>Alors est-ce que j&#8217;emm\u00e8nerai mes ni\u00e8ces le voir ?<\/h2>\n<p>Oui parce que \u00e7a reste un beau conte, un beau dessin anim\u00e9, mais si j&rsquo;ai le choix ce sera avec un autre Pixar ou m\u00eame un <em>Kirikou<\/em>, j&rsquo;opterai pour eux.<br \/>\nSi vous avez du sommeil \u00e0 rattraper ou que vous \u00eates vraiment fan des classiques de Walt Disney alors vous ne serez pas d\u00e9\u00e7u par <em>La Princesse et la Grenouille<\/em>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><em>La Princesse et la Grenouille <\/em>de Walt Disney<em>, <\/em>c&rsquo;est reprendre\u00a0une petite bouff\u00e9e de conte de f\u00e9es, de prince qui nous aime malgr\u00e9 nos rondeurs, de belles robes de princesses qui scintillent, et de cet entourage qui s&rsquo;entraide alors qu&rsquo;ils se connaissent \u00e0 peine. Il faut l&rsquo;avouer aujourd&rsquo;hui \u00e7a peut faire r\u00eaver.<\/p>\n<p>Mais surtout l&rsquo;\u00e9v\u00e8nement de ce r\u00e9cent dessin anim\u00e9 de Walt Disney est qu&rsquo;\u00e0 l&rsquo;heure de la 3D ils se remettent \u00e0 la 2D.<\/p>\n","protected":false},"author":2,"featured_media":570,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"om_disable_all_campaigns":false,"_lmt_disableupdate":"","_lmt_disable":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[28],"tags":[283],"class_list":["post-571","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-films","tag-dessin-anime"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;La princesse et la grenouille&quot; quand Walt Disney se remet \u00e0 la 2D - Les Bridgets<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/la-princesse-et-la-grenouille-quand-walt-disney-se-remet-a-la-2d.html\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;La princesse et la grenouille&quot; quand Walt Disney se remet \u00e0 la 2D - Les Bridgets\" \/>\n<meta property=\"og:description\" content=\"La Princesse et la Grenouille de Walt Disney, c&#039;est reprendre\u00a0une petite bouff\u00e9e de conte de f\u00e9es, de prince qui nous aime malgr\u00e9 nos rondeurs, de belles robes de princesses qui scintillent, et de cet entourage qui s&#039;entraide alors qu&#039;ils se connaissent \u00e0 peine. Il faut l&#039;avouer aujourd&#039;hui \u00e7a peut faire r\u00eaver. Mais surtout l&#039;\u00e9v\u00e8nement de ce r\u00e9cent dessin anim\u00e9 de Walt Disney est qu&#039;\u00e0 l&#039;heure de la 3D ils se remettent \u00e0 la 2D.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/la-princesse-et-la-grenouille-quand-walt-disney-se-remet-a-la-2d.html\" \/>\n<meta property=\"og:site_name\" content=\"Les Bridgets\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Les.Bridgets\" \/>\n<meta property=\"article:published_time\" content=\"2010-01-07T14:07:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-08-11T16:30:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2010\/01\/la-princesse-et-la-grenouille.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"230\" \/>\n\t<meta property=\"og:image:height\" content=\"159\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bridget\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@les_bridgets\" \/>\n<meta name=\"twitter:site\" content=\"@les_bridgets\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bridget\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/la-princesse-et-la-grenouille-quand-walt-disney-se-remet-a-la-2d.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/la-princesse-et-la-grenouille-quand-walt-disney-se-remet-a-la-2d.html\"},\"author\":{\"name\":\"Bridget\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/person\\\/82a31c27ae0ddd23ee59e1e2ac5713ba\"},\"headline\":\"\u00ab\u00a0La princesse et la grenouille\u00a0\u00bb quand Walt Disney se remet \u00e0 la 2D\",\"datePublished\":\"2010-01-07T14:07:31+00:00\",\"dateModified\":\"2017-08-11T16:30:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/la-princesse-et-la-grenouille-quand-walt-disney-se-remet-a-la-2d.html\"},\"wordCount\":388,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/la-princesse-et-la-grenouille-quand-walt-disney-se-remet-a-la-2d.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2010\\\/01\\\/la-princesse-et-la-grenouille.jpg\",\"keywords\":[\"Dessin anim\u00e9\"],\"articleSection\":[\"Film\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/la-princesse-et-la-grenouille-quand-walt-disney-se-remet-a-la-2d.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/la-princesse-et-la-grenouille-quand-walt-disney-se-remet-a-la-2d.html\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/la-princesse-et-la-grenouille-quand-walt-disney-se-remet-a-la-2d.html\",\"name\":\"\\\"La princesse et la grenouille\\\" quand Walt Disney se remet \u00e0 la 2D - Les Bridgets\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/la-princesse-et-la-grenouille-quand-walt-disney-se-remet-a-la-2d.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/la-princesse-et-la-grenouille-quand-walt-disney-se-remet-a-la-2d.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2010\\\/01\\\/la-princesse-et-la-grenouille.jpg\",\"datePublished\":\"2010-01-07T14:07:31+00:00\",\"dateModified\":\"2017-08-11T16:30:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/la-princesse-et-la-grenouille-quand-walt-disney-se-remet-a-la-2d.html#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/la-princesse-et-la-grenouille-quand-walt-disney-se-remet-a-la-2d.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/la-princesse-et-la-grenouille-quand-walt-disney-se-remet-a-la-2d.html#primaryimage\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2010\\\/01\\\/la-princesse-et-la-grenouille.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2010\\\/01\\\/la-princesse-et-la-grenouille.jpg\",\"width\":230,\"height\":159,\"caption\":\"La princesse et la grenouille sur le balcon\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/la-princesse-et-la-grenouille-quand-walt-disney-se-remet-a-la-2d.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Les Bridgets\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00e9f\u00e9rences sur le couple et le c\u00e9libat\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/category\\\/references\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Film\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/category\\\/references\\\/films\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"\u00ab\u00a0La princesse et la grenouille\u00a0\u00bb quand Walt Disney se remet \u00e0 la 2D\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#website\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/\",\"name\":\"Les Bridgets\",\"description\":\"R\u00e9f\u00e9rences et r\u00e9flexions sur nos relations\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lesbridgets.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\",\"name\":\"Les Bridgets\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo-3-lesbridgets.png\",\"contentUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo-3-lesbridgets.png\",\"width\":251,\"height\":59,\"caption\":\"Les Bridgets\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Les.Bridgets\",\"https:\\\/\\\/x.com\\\/les_bridgets\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/person\\\/82a31c27ae0ddd23ee59e1e2ac5713ba\",\"name\":\"Bridget\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"caption\":\"Bridget\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"La princesse et la grenouille\" quand Walt Disney se remet \u00e0 la 2D - Les Bridgets","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/la-princesse-et-la-grenouille-quand-walt-disney-se-remet-a-la-2d.html","og_locale":"fr_FR","og_type":"article","og_title":"\"La princesse et la grenouille\" quand Walt Disney se remet \u00e0 la 2D - Les Bridgets","og_description":"La Princesse et la Grenouille de Walt Disney, c'est reprendre\u00a0une petite bouff\u00e9e de conte de f\u00e9es, de prince qui nous aime malgr\u00e9 nos rondeurs, de belles robes de princesses qui scintillent, et de cet entourage qui s'entraide alors qu'ils se connaissent \u00e0 peine. Il faut l'avouer aujourd'hui \u00e7a peut faire r\u00eaver. Mais surtout l'\u00e9v\u00e8nement de ce r\u00e9cent dessin anim\u00e9 de Walt Disney est qu'\u00e0 l'heure de la 3D ils se remettent \u00e0 la 2D.","og_url":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/la-princesse-et-la-grenouille-quand-walt-disney-se-remet-a-la-2d.html","og_site_name":"Les Bridgets","article_publisher":"https:\/\/www.facebook.com\/Les.Bridgets","article_published_time":"2010-01-07T14:07:31+00:00","article_modified_time":"2017-08-11T16:30:40+00:00","og_image":[{"width":230,"height":159,"url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2010\/01\/la-princesse-et-la-grenouille.jpg","type":"image\/jpeg"}],"author":"Bridget","twitter_card":"summary_large_image","twitter_creator":"@les_bridgets","twitter_site":"@les_bridgets","twitter_misc":{"\u00c9crit par":"Bridget","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/la-princesse-et-la-grenouille-quand-walt-disney-se-remet-a-la-2d.html#article","isPartOf":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/la-princesse-et-la-grenouille-quand-walt-disney-se-remet-a-la-2d.html"},"author":{"name":"Bridget","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/person\/82a31c27ae0ddd23ee59e1e2ac5713ba"},"headline":"\u00ab\u00a0La princesse et la grenouille\u00a0\u00bb quand Walt Disney se remet \u00e0 la 2D","datePublished":"2010-01-07T14:07:31+00:00","dateModified":"2017-08-11T16:30:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/la-princesse-et-la-grenouille-quand-walt-disney-se-remet-a-la-2d.html"},"wordCount":388,"commentCount":1,"publisher":{"@id":"https:\/\/www.lesbridgets.com\/#organization"},"image":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/la-princesse-et-la-grenouille-quand-walt-disney-se-remet-a-la-2d.html#primaryimage"},"thumbnailUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2010\/01\/la-princesse-et-la-grenouille.jpg","keywords":["Dessin anim\u00e9"],"articleSection":["Film"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.lesbridgets.com\/index.php\/references\/films\/la-princesse-et-la-grenouille-quand-walt-disney-se-remet-a-la-2d.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/la-princesse-et-la-grenouille-quand-walt-disney-se-remet-a-la-2d.html","url":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/la-princesse-et-la-grenouille-quand-walt-disney-se-remet-a-la-2d.html","name":"\"La princesse et la grenouille\" quand Walt Disney se remet \u00e0 la 2D - Les Bridgets","isPartOf":{"@id":"https:\/\/www.lesbridgets.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/la-princesse-et-la-grenouille-quand-walt-disney-se-remet-a-la-2d.html#primaryimage"},"image":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/la-princesse-et-la-grenouille-quand-walt-disney-se-remet-a-la-2d.html#primaryimage"},"thumbnailUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2010\/01\/la-princesse-et-la-grenouille.jpg","datePublished":"2010-01-07T14:07:31+00:00","dateModified":"2017-08-11T16:30:40+00:00","breadcrumb":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/la-princesse-et-la-grenouille-quand-walt-disney-se-remet-a-la-2d.html#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lesbridgets.com\/index.php\/references\/films\/la-princesse-et-la-grenouille-quand-walt-disney-se-remet-a-la-2d.html"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/la-princesse-et-la-grenouille-quand-walt-disney-se-remet-a-la-2d.html#primaryimage","url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2010\/01\/la-princesse-et-la-grenouille.jpg","contentUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2010\/01\/la-princesse-et-la-grenouille.jpg","width":230,"height":159,"caption":"La princesse et la grenouille sur le balcon"},{"@type":"BreadcrumbList","@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/la-princesse-et-la-grenouille-quand-walt-disney-se-remet-a-la-2d.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Les Bridgets","item":"https:\/\/www.lesbridgets.com\/"},{"@type":"ListItem","position":2,"name":"R\u00e9f\u00e9rences sur le couple et le c\u00e9libat","item":"https:\/\/www.lesbridgets.com\/index.php\/category\/references"},{"@type":"ListItem","position":3,"name":"Film","item":"https:\/\/www.lesbridgets.com\/index.php\/category\/references\/films"},{"@type":"ListItem","position":4,"name":"\u00ab\u00a0La princesse et la grenouille\u00a0\u00bb quand Walt Disney se remet \u00e0 la 2D"}]},{"@type":"WebSite","@id":"https:\/\/www.lesbridgets.com\/#website","url":"https:\/\/www.lesbridgets.com\/","name":"Les Bridgets","description":"R\u00e9f\u00e9rences et r\u00e9flexions sur nos relations","publisher":{"@id":"https:\/\/www.lesbridgets.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lesbridgets.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lesbridgets.com\/#organization","name":"Les Bridgets","url":"https:\/\/www.lesbridgets.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2022\/07\/cropped-logo-3-lesbridgets.png","contentUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2022\/07\/cropped-logo-3-lesbridgets.png","width":251,"height":59,"caption":"Les Bridgets"},"image":{"@id":"https:\/\/www.lesbridgets.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Les.Bridgets","https:\/\/x.com\/les_bridgets"]},{"@type":"Person","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/person\/82a31c27ae0ddd23ee59e1e2ac5713ba","name":"Bridget","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","caption":"Bridget"}}]}},"modified_by":"admin_bridg","_links":{"self":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/comments?post=571"}],"version-history":[{"count":1,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/571\/revisions"}],"predecessor-version":[{"id":235491,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/571\/revisions\/235491"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/media\/570"}],"wp:attachment":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/media?parent=571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/categories?post=571"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/tags?post=571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}