{"id":558,"date":"2009-12-07T23:04:31","date_gmt":"2009-12-07T22:04:31","guid":{"rendered":"http:\/\/lesbridg.cluster015.ovh.net\/wordpress\/index.php\/films-romantiques-sur-le-couple-et-le-celibat\/film-la-merditude-des-chosesen-belgique-il-ny-a-pas-que-la-biere-qui-est-bonne.html"},"modified":"2020-01-14T22:50:20","modified_gmt":"2020-01-14T21:50:20","slug":"film-la-merditude-des-chosesen-belgique-il-n-y-a-pas-que-la-biere-qui-est-bonne","status":"publish","type":"post","link":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/film-la-merditude-des-chosesen-belgique-il-n-y-a-pas-que-la-biere-qui-est-bonne.html","title":{"rendered":"La merditude des choses : en belgique, il n&rsquo;y a pas que la bi\u00e8re qui est bonne"},"content":{"rendered":"<p>&#8230;souvent leur cin\u00e9ma aussi. Apr\u00e8s \u00ab\u00a0<a href=\"index.php\/Films-romantiques-sur-le-couple-et-le-celibat\/Le-vilain-on-n-est-pas-forcement-l-enfant-qu-avait-imagine-sa-maman.html\">Le vilain<\/a>\u00a0\u00bb il y a quelques semaines nous avons eu la chance de d\u00e9couvrir le 3 d\u00e9cembre en avant-premiere le film belge \u00ab\u00a0La merditude des choses\u00a0\u00bb, en version Originale flamande, qui nous parle \u00e0 nouveau des relations familliales.<br \/>\nDans un registre totalement diff\u00e9rent du film de Dupontel, \u00ab\u00a0<b>La Merditude des choses<\/b>\u00a0\u00bb nous raconte la vie marginale d&rsquo;un gar\u00e7on de 13 ans \u00e9lev\u00e9 dans une famille flamande berc\u00e9e par l&rsquo;alcool&#8230;<\/p>\n<h2>Ce film contrairement a beaucoup de blockbusters am\u00e9ricains poss\u00e8de une bande-annonce peu vendeuse<\/h2>\n<p>Elle ne repr\u00e9sente pas le film et elle ne donne pas envie de le voir, elle est beaucoup trop ennuyeuse et sans int\u00e9r\u00eat contrairement au film.<\/p>\n<p align=\"center\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/NSzUfBIz4Eo\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<h2>Heureusement, nous ne nous sommes pas arr\u00eat\u00e9es \u00e0 la bande annonce<\/h2>\n<p>\u00ab\u00a0La merditude des choses\u00a0\u00bb (et non pas \u00ab\u00a0la mertitude des choses\u00a0\u00bb comme \u00e9crit sur le panneau digital du cin\u00e9ma lors de la projection), c&rsquo;est l&rsquo;histoire de Gunther qui nous raconte \u00e0 travers son livre, qu&rsquo;il a \u00e9crit 15 ans plus tard, son enfance, sa m\u00e8re qu&rsquo;il l&rsquo;a abandonn\u00e9 \u00e0 la naissance, et r\u00e9cup\u00e9r\u00e9 par son p\u00e8re alcoolique.<\/p>\n<p>Son p\u00e8re, facteur du village de \u00ab\u00a0Truc muche les oies\u00a0\u00bb faute de moyen, restera habiter chez sa m\u00e8re avec ses 3 autres fr\u00e8res les Strobbes.<br \/>\nLe petit grandit alors dans les beuveries et malgr\u00e9 le manque d&rsquo;argent, la bi\u00e8re coule \u00e0 flot.<br \/>\nSa chambre qu&rsquo;il partage avec l&rsquo;un de ses oncles, le cadet des 4, est le spectacle de multiples \u00e9bats sexuels.<\/p>\n<p>Le petit gar\u00e7on qui se sent diff\u00e9rent de ses oncles et qui a envie de s&rsquo;en sortir, va malgr\u00e9 des tentations, les r\u00e9flexions de ses proches, et des tentatives de dissuasion de son p\u00e8re, essayer d&rsquo;\u00e9chapper comme il le pourra \u00e0 ce milieu familial n\u00e9faste.<\/p>\n<p>Ce film nous montre \u00e0 nouveau mais dans le sens inverse du vilain comment on peut devenir quelqu&rsquo;un de bien, s&rsquo;en sortir et ne pas reproduire (totalement) le milieu dans lequel on a grandi.<\/p>\n<h2>Ce film n&rsquo;est pas \u00e0 recommander \u00e0 toutes les \u00e2mes surtout les plus sensibles, certaines sc\u00e8nes peuvent choquer, m\u00eame si beaucoup pr\u00eatent \u00e0 rire.<\/h2>\n<p>La merditude des choses, une belle surprise, un bon moment qui donne \u00e0 nouveau \u00e0 r\u00e9fl\u00e9chir sur l&rsquo;impact de notre \u00e9ducation dans notre vie d&rsquo;adulte.<\/p>\n<p>Un film \u00e0 aller voir id\u00e9alement juste avant l&rsquo;ap\u00e9ro, histoire d&rsquo;en discuter apr\u00e8s autour d&rsquo;une bonne bi\u00e8re.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8230;souvent leur cin\u00e9ma aussi. Apr\u00e8s \u00ab\u00a0<a href=\"index.php\/Films-romantiques-sur-le-couple-et-le-celibat\/Le-vilain-on-n-est-pas-forcement-l-enfant-qu-avait-imagine-sa-maman.html\">Le vilain<\/a>\u00a0\u00bb il y a quelques semaines nous avons eu la chance de d\u00e9couvrir le 3 d\u00e9cembre en avant-premiere le film belge \u00ab\u00a0La merditude des choses\u00a0\u00bb, en version Originale flamande, qui nous parle \u00e0 nouveau des relations familliales.<br \/> Dans un registre totalement diff\u00e9rent du film de Dupontel, \u00ab\u00a0<b>La Merditude des choses<\/b>\u00a0\u00bb nous raconte la vie marginale d&rsquo;un gar\u00e7on de 13 ans \u00e9lev\u00e9 dans une famille flamande berc\u00e9e par l&rsquo;alcool&#8230;<\/p>\n","protected":false},"author":2,"featured_media":251083,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"om_disable_all_campaigns":false,"_lmt_disableupdate":"no","_lmt_disable":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[28],"tags":[277,280,586,642],"class_list":["post-558","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-films","tag-belgique","tag-famille","tag-film-dramatique","tag-film-famille"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La merditude des choses : en belgique, il n&#039;y a pas que la bi\u00e8re qui est bonne - Les Bridgets<\/title>\n<meta name=\"description\" content=\"Critique du film belge La Merditude des Choses du talentueux r\u00e9alisateur Felix Van Groeningen sortie en d\u00e9cembre 2009\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/film-la-merditude-des-chosesen-belgique-il-n-y-a-pas-que-la-biere-qui-est-bonne.html\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La merditude des choses : en belgique, il n&#039;y a pas que la bi\u00e8re qui est bonne - Les Bridgets\" \/>\n<meta property=\"og:description\" content=\"Critique du film belge La Merditude des Choses du talentueux r\u00e9alisateur Felix Van Groeningen sortie en d\u00e9cembre 2009\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/film-la-merditude-des-chosesen-belgique-il-n-y-a-pas-que-la-biere-qui-est-bonne.html\" \/>\n<meta property=\"og:site_name\" content=\"Les Bridgets\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Les.Bridgets\" \/>\n<meta property=\"article:published_time\" content=\"2009-12-07T22:04:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-14T21:50:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2009\/12\/critique-film-merditude-des-choses.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Bridget\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@les_bridgets\" \/>\n<meta name=\"twitter:site\" content=\"@les_bridgets\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bridget\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/film-la-merditude-des-chosesen-belgique-il-n-y-a-pas-que-la-biere-qui-est-bonne.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/film-la-merditude-des-chosesen-belgique-il-n-y-a-pas-que-la-biere-qui-est-bonne.html\"},\"author\":{\"name\":\"Bridget\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/person\\\/82a31c27ae0ddd23ee59e1e2ac5713ba\"},\"headline\":\"La merditude des choses : en belgique, il n&rsquo;y a pas que la bi\u00e8re qui est bonne\",\"datePublished\":\"2009-12-07T22:04:31+00:00\",\"dateModified\":\"2020-01-14T21:50:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/film-la-merditude-des-chosesen-belgique-il-n-y-a-pas-que-la-biere-qui-est-bonne.html\"},\"wordCount\":445,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/film-la-merditude-des-chosesen-belgique-il-n-y-a-pas-que-la-biere-qui-est-bonne.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2009\\\/12\\\/critique-film-merditude-des-choses.png\",\"keywords\":[\"belgique\",\"famille\",\"film dramatique\",\"film famille\"],\"articleSection\":[\"Film\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/film-la-merditude-des-chosesen-belgique-il-n-y-a-pas-que-la-biere-qui-est-bonne.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/film-la-merditude-des-chosesen-belgique-il-n-y-a-pas-que-la-biere-qui-est-bonne.html\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/film-la-merditude-des-chosesen-belgique-il-n-y-a-pas-que-la-biere-qui-est-bonne.html\",\"name\":\"La merditude des choses : en belgique, il n'y a pas que la bi\u00e8re qui est bonne - Les Bridgets\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/film-la-merditude-des-chosesen-belgique-il-n-y-a-pas-que-la-biere-qui-est-bonne.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/film-la-merditude-des-chosesen-belgique-il-n-y-a-pas-que-la-biere-qui-est-bonne.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2009\\\/12\\\/critique-film-merditude-des-choses.png\",\"datePublished\":\"2009-12-07T22:04:31+00:00\",\"dateModified\":\"2020-01-14T21:50:20+00:00\",\"description\":\"Critique du film belge La Merditude des Choses du talentueux r\u00e9alisateur Felix Van Groeningen sortie en d\u00e9cembre 2009\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/film-la-merditude-des-chosesen-belgique-il-n-y-a-pas-que-la-biere-qui-est-bonne.html#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/film-la-merditude-des-chosesen-belgique-il-n-y-a-pas-que-la-biere-qui-est-bonne.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/film-la-merditude-des-chosesen-belgique-il-n-y-a-pas-que-la-biere-qui-est-bonne.html#primaryimage\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2009\\\/12\\\/critique-film-merditude-des-choses.png\",\"contentUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2009\\\/12\\\/critique-film-merditude-des-choses.png\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/film-la-merditude-des-chosesen-belgique-il-n-y-a-pas-que-la-biere-qui-est-bonne.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Les Bridgets\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00e9f\u00e9rences sur le couple et le c\u00e9libat\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/category\\\/references\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Film\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/category\\\/references\\\/films\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"La merditude des choses : en belgique, il n&rsquo;y a pas que la bi\u00e8re qui est bonne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#website\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/\",\"name\":\"Les Bridgets\",\"description\":\"R\u00e9f\u00e9rences et r\u00e9flexions sur nos relations\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lesbridgets.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\",\"name\":\"Les Bridgets\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo-3-lesbridgets.png\",\"contentUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo-3-lesbridgets.png\",\"width\":251,\"height\":59,\"caption\":\"Les Bridgets\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Les.Bridgets\",\"https:\\\/\\\/x.com\\\/les_bridgets\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/person\\\/82a31c27ae0ddd23ee59e1e2ac5713ba\",\"name\":\"Bridget\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"caption\":\"Bridget\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La merditude des choses : en belgique, il n'y a pas que la bi\u00e8re qui est bonne - Les Bridgets","description":"Critique du film belge La Merditude des Choses du talentueux r\u00e9alisateur Felix Van Groeningen sortie en d\u00e9cembre 2009","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/film-la-merditude-des-chosesen-belgique-il-n-y-a-pas-que-la-biere-qui-est-bonne.html","og_locale":"fr_FR","og_type":"article","og_title":"La merditude des choses : en belgique, il n'y a pas que la bi\u00e8re qui est bonne - Les Bridgets","og_description":"Critique du film belge La Merditude des Choses du talentueux r\u00e9alisateur Felix Van Groeningen sortie en d\u00e9cembre 2009","og_url":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/film-la-merditude-des-chosesen-belgique-il-n-y-a-pas-que-la-biere-qui-est-bonne.html","og_site_name":"Les Bridgets","article_publisher":"https:\/\/www.facebook.com\/Les.Bridgets","article_published_time":"2009-12-07T22:04:31+00:00","article_modified_time":"2020-01-14T21:50:20+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2009\/12\/critique-film-merditude-des-choses.png","type":"image\/png"}],"author":"Bridget","twitter_card":"summary_large_image","twitter_creator":"@les_bridgets","twitter_site":"@les_bridgets","twitter_misc":{"\u00c9crit par":"Bridget","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/film-la-merditude-des-chosesen-belgique-il-n-y-a-pas-que-la-biere-qui-est-bonne.html#article","isPartOf":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/film-la-merditude-des-chosesen-belgique-il-n-y-a-pas-que-la-biere-qui-est-bonne.html"},"author":{"name":"Bridget","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/person\/82a31c27ae0ddd23ee59e1e2ac5713ba"},"headline":"La merditude des choses : en belgique, il n&rsquo;y a pas que la bi\u00e8re qui est bonne","datePublished":"2009-12-07T22:04:31+00:00","dateModified":"2020-01-14T21:50:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/film-la-merditude-des-chosesen-belgique-il-n-y-a-pas-que-la-biere-qui-est-bonne.html"},"wordCount":445,"commentCount":0,"publisher":{"@id":"https:\/\/www.lesbridgets.com\/#organization"},"image":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/film-la-merditude-des-chosesen-belgique-il-n-y-a-pas-que-la-biere-qui-est-bonne.html#primaryimage"},"thumbnailUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2009\/12\/critique-film-merditude-des-choses.png","keywords":["belgique","famille","film dramatique","film famille"],"articleSection":["Film"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.lesbridgets.com\/index.php\/references\/films\/film-la-merditude-des-chosesen-belgique-il-n-y-a-pas-que-la-biere-qui-est-bonne.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/film-la-merditude-des-chosesen-belgique-il-n-y-a-pas-que-la-biere-qui-est-bonne.html","url":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/film-la-merditude-des-chosesen-belgique-il-n-y-a-pas-que-la-biere-qui-est-bonne.html","name":"La merditude des choses : en belgique, il n'y a pas que la bi\u00e8re qui est bonne - Les Bridgets","isPartOf":{"@id":"https:\/\/www.lesbridgets.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/film-la-merditude-des-chosesen-belgique-il-n-y-a-pas-que-la-biere-qui-est-bonne.html#primaryimage"},"image":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/film-la-merditude-des-chosesen-belgique-il-n-y-a-pas-que-la-biere-qui-est-bonne.html#primaryimage"},"thumbnailUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2009\/12\/critique-film-merditude-des-choses.png","datePublished":"2009-12-07T22:04:31+00:00","dateModified":"2020-01-14T21:50:20+00:00","description":"Critique du film belge La Merditude des Choses du talentueux r\u00e9alisateur Felix Van Groeningen sortie en d\u00e9cembre 2009","breadcrumb":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/film-la-merditude-des-chosesen-belgique-il-n-y-a-pas-que-la-biere-qui-est-bonne.html#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lesbridgets.com\/index.php\/references\/films\/film-la-merditude-des-chosesen-belgique-il-n-y-a-pas-que-la-biere-qui-est-bonne.html"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/film-la-merditude-des-chosesen-belgique-il-n-y-a-pas-que-la-biere-qui-est-bonne.html#primaryimage","url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2009\/12\/critique-film-merditude-des-choses.png","contentUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2009\/12\/critique-film-merditude-des-choses.png","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/film-la-merditude-des-chosesen-belgique-il-n-y-a-pas-que-la-biere-qui-est-bonne.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Les Bridgets","item":"https:\/\/www.lesbridgets.com\/"},{"@type":"ListItem","position":2,"name":"R\u00e9f\u00e9rences sur le couple et le c\u00e9libat","item":"https:\/\/www.lesbridgets.com\/index.php\/category\/references"},{"@type":"ListItem","position":3,"name":"Film","item":"https:\/\/www.lesbridgets.com\/index.php\/category\/references\/films"},{"@type":"ListItem","position":4,"name":"La merditude des choses : en belgique, il n&rsquo;y a pas que la bi\u00e8re qui est bonne"}]},{"@type":"WebSite","@id":"https:\/\/www.lesbridgets.com\/#website","url":"https:\/\/www.lesbridgets.com\/","name":"Les Bridgets","description":"R\u00e9f\u00e9rences et r\u00e9flexions sur nos relations","publisher":{"@id":"https:\/\/www.lesbridgets.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lesbridgets.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lesbridgets.com\/#organization","name":"Les Bridgets","url":"https:\/\/www.lesbridgets.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2022\/07\/cropped-logo-3-lesbridgets.png","contentUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2022\/07\/cropped-logo-3-lesbridgets.png","width":251,"height":59,"caption":"Les Bridgets"},"image":{"@id":"https:\/\/www.lesbridgets.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Les.Bridgets","https:\/\/x.com\/les_bridgets"]},{"@type":"Person","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/person\/82a31c27ae0ddd23ee59e1e2ac5713ba","name":"Bridget","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","caption":"Bridget"}}]}},"modified_by":"Bridget","_links":{"self":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/comments?post=558"}],"version-history":[{"count":4,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/558\/revisions"}],"predecessor-version":[{"id":251086,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/558\/revisions\/251086"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/media\/251083"}],"wp:attachment":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/media?parent=558"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/categories?post=558"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/tags?post=558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}