{"id":541,"date":"2009-11-17T16:11:18","date_gmt":"2009-11-17T15:11:18","guid":{"rendered":"http:\/\/lesbridg.cluster015.ovh.net\/wordpress\/index.php\/etude-statistiques-sur-le-couple\/les-femmes-face-a-un-cancer-sont-6-fois-plus-quittes-que-les-hommes.html"},"modified":"2020-05-12T17:13:33","modified_gmt":"2020-05-12T15:13:33","slug":"les-femmes-face-a-un-cancer-sont-6-fois-plus-quittes-que-les-hommes","status":"publish","type":"post","link":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/les-femmes-face-a-un-cancer-sont-6-fois-plus-quittes-que-les-hommes.html","title":{"rendered":"Les femmes, face \u00e0 un cancer, sont 6 fois plus quitt\u00e9es que les hommes."},"content":{"rendered":"<p>Apr\u00e8s notre article sur notre d\u00e9couverte <a href=\"index.php\/Histoire\/Se-marier-au-dela-de-la-mort-porter-le-nom-de-son-amour-pour-toujours.html\">qu&rsquo;il existe la possibilit\u00e9 de se marier avec un mort<\/a>, il semblerait selon une \u00e9tude am\u00e9ricaine que les femmes souffrant d&rsquo;un cancer ou d&rsquo;une scl\u00e9rose en plaques sont six fois plus susceptibles d&rsquo;\u00eatre quitt\u00e9es par leur compagnon qu&rsquo;un homme dans le cas inverse.<\/p>\n<p><span class=\"content\">C&rsquo;est \u00e0 dire, une femme est six fois plus susceptible de vivre une s\u00e9paration apr\u00e8s avoir re\u00e7u un diagnostic de cancer ou de scl\u00e9rose en plaques qu&rsquo;un homme qui a re\u00e7u un tel diagnostic.<br \/>\nLe taux de s\u00e9paration ou de divorce \u00e9tait de 20,8% pour les femmes malades, comparativement \u00e0 2,9% pour les hommes malades. Ce qui se compare \u00e0 un taux de 11% dans la population g\u00e9n\u00e9rale. <\/span><\/p>\n<p>Nous croyons que ces r\u00e9sultats s&rsquo;appliquent g\u00e9n\u00e9ralement aux personnes atteintes de maladies qui changent la vie\u00a0\u00bb, \u00e9crivent les auteurs, Marc Chamberlain de l&rsquo;Universit\u00e9 de Washington et Michael Glanz de l&rsquo;Universit\u00e9 de l&rsquo;Utah.<\/p>\n<h2><span class=\"content\">Pourquoi les hommes quittent leur conjointe malade?<\/span><\/h2>\n<p><span class=\"content\"> Les auteurs de l&rsquo;\u00e9tude l&rsquo;expliquent partiellement :<br \/>\n<\/span><\/p>\n<ul>\n<li><span class=\"content\"> par leur manque de capacit\u00e9, comparativement aux femmes, de s&rsquo;engager rapidement \u00e0 prendre soin d&rsquo;une partenaire malade<\/span><\/li>\n<\/ul>\n<ul>\n<li><span class=\"content\"> par la meilleure capacit\u00e9 des femmes \u00e0 assumer la charge d&rsquo;un foyer et d&rsquo;une famille, croient les auteurs.<\/span><\/li>\n<\/ul>\n<p><span class=\"content\"><br \/>\nIl faut quand m\u00eame pr\u00e9ciser qu&rsquo;ils ont men\u00e9 cette \u00e9tude avec 515 personnes malades suivies de 2001-2002 \u00e0 2006. Elles \u00e9taient atteintes d&rsquo;une tumeur c\u00e9r\u00e9brale primaire, de tumeurs n&rsquo;impliquant pas le syst\u00e8me nerveux central ou de scl\u00e9rose en plaques.<br \/>\n<\/span><\/p>\n<p><span class=\"content\"> Les femmes plus \u00e2g\u00e9es \u00e9taient plus susceptibles de vivre une s\u00e9paration. <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quelle nouvelle \u00e9tude glauque! Apr\u00e8s notre article sur notre d\u00e9couverte <a href=\"index.php\/Histoire\/Se-marier-au-dela-de-la-mort-porter-le-nom-de-son-amour-pour-toujours.html\" mce_href=\"index.php\/Histoire\/Se-marier-au-dela-de-la-mort-porter-le-nom-de-son-amour-pour-toujours.html\">qu&rsquo;il existe la possibilit\u00e9 de se marier avec un mort<\/a>, il semblerait selon une \u00e9tude am\u00e9ricaine que les femmes souffrant d&rsquo;un cancer ou d&rsquo;une scl\u00e9rose en plaques sont six fois plus susceptibles d&rsquo;\u00eatre quitt\u00e9es par leur compagnon qu&rsquo;un homme dans le cas inverse.  <\/p>\n","protected":false},"author":2,"featured_media":245870,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"om_disable_all_campaigns":false,"_lmt_disableupdate":"no","_lmt_disable":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-541","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-etude-statistiques-couple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les femmes, face \u00e0 un cancer, sont 6 fois plus quitt\u00e9es que les hommes. - Les Bridgets<\/title>\n<meta name=\"description\" content=\"Selon une \u00e9tude, les femmes souffrant d&#039;un cancer ou d&#039;une scl\u00e9rose en plaques sont 6 fois plus susceptibles d&#039;\u00eatre quitt\u00e9es par leur compagnon qu&#039;un homme.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/les-femmes-face-a-un-cancer-sont-6-fois-plus-quittes-que-les-hommes.html\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les femmes, face \u00e0 un cancer, sont 6 fois plus quitt\u00e9es que les hommes. - Les Bridgets\" \/>\n<meta property=\"og:description\" content=\"Selon une \u00e9tude, les femmes souffrant d&#039;un cancer ou d&#039;une scl\u00e9rose en plaques sont 6 fois plus susceptibles d&#039;\u00eatre quitt\u00e9es par leur compagnon qu&#039;un homme.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/les-femmes-face-a-un-cancer-sont-6-fois-plus-quittes-que-les-hommes.html\" \/>\n<meta property=\"og:site_name\" content=\"Les Bridgets\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Les.Bridgets\" \/>\n<meta property=\"article:published_time\" content=\"2009-11-17T15:11:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-12T15:13:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2009\/11\/femme-cancer-quitter-mari.png\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"425\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Bridget\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@les_bridgets\" \/>\n<meta name=\"twitter:site\" content=\"@les_bridgets\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bridget\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/statistiques\\\/etude-statistiques-couple\\\/les-femmes-face-a-un-cancer-sont-6-fois-plus-quittes-que-les-hommes.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/statistiques\\\/etude-statistiques-couple\\\/les-femmes-face-a-un-cancer-sont-6-fois-plus-quittes-que-les-hommes.html\"},\"author\":{\"name\":\"Bridget\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/person\\\/82a31c27ae0ddd23ee59e1e2ac5713ba\"},\"headline\":\"Les femmes, face \u00e0 un cancer, sont 6 fois plus quitt\u00e9es que les hommes.\",\"datePublished\":\"2009-11-17T15:11:18+00:00\",\"dateModified\":\"2020-05-12T15:13:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/statistiques\\\/etude-statistiques-couple\\\/les-femmes-face-a-un-cancer-sont-6-fois-plus-quittes-que-les-hommes.html\"},\"wordCount\":293,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/statistiques\\\/etude-statistiques-couple\\\/les-femmes-face-a-un-cancer-sont-6-fois-plus-quittes-que-les-hommes.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2009\\\/11\\\/femme-cancer-quitter-mari.png\",\"articleSection\":[\"Statistiques sur le couple\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/statistiques\\\/etude-statistiques-couple\\\/les-femmes-face-a-un-cancer-sont-6-fois-plus-quittes-que-les-hommes.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/statistiques\\\/etude-statistiques-couple\\\/les-femmes-face-a-un-cancer-sont-6-fois-plus-quittes-que-les-hommes.html\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/statistiques\\\/etude-statistiques-couple\\\/les-femmes-face-a-un-cancer-sont-6-fois-plus-quittes-que-les-hommes.html\",\"name\":\"Les femmes, face \u00e0 un cancer, sont 6 fois plus quitt\u00e9es que les hommes. - Les Bridgets\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/statistiques\\\/etude-statistiques-couple\\\/les-femmes-face-a-un-cancer-sont-6-fois-plus-quittes-que-les-hommes.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/statistiques\\\/etude-statistiques-couple\\\/les-femmes-face-a-un-cancer-sont-6-fois-plus-quittes-que-les-hommes.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2009\\\/11\\\/femme-cancer-quitter-mari.png\",\"datePublished\":\"2009-11-17T15:11:18+00:00\",\"dateModified\":\"2020-05-12T15:13:33+00:00\",\"description\":\"Selon une \u00e9tude, les femmes souffrant d'un cancer ou d'une scl\u00e9rose en plaques sont 6 fois plus susceptibles d'\u00eatre quitt\u00e9es par leur compagnon qu'un homme.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/statistiques\\\/etude-statistiques-couple\\\/les-femmes-face-a-un-cancer-sont-6-fois-plus-quittes-que-les-hommes.html#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/statistiques\\\/etude-statistiques-couple\\\/les-femmes-face-a-un-cancer-sont-6-fois-plus-quittes-que-les-hommes.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/statistiques\\\/etude-statistiques-couple\\\/les-femmes-face-a-un-cancer-sont-6-fois-plus-quittes-que-les-hommes.html#primaryimage\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2009\\\/11\\\/femme-cancer-quitter-mari.png\",\"contentUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2009\\\/11\\\/femme-cancer-quitter-mari.png\",\"width\":750,\"height\":425},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/statistiques\\\/etude-statistiques-couple\\\/les-femmes-face-a-un-cancer-sont-6-fois-plus-quittes-que-les-hommes.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Les Bridgets\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Statistiques sur le couple &amp; celibat\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/category\\\/statistiques\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Statistiques sur le couple\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/category\\\/statistiques\\\/etude-statistiques-couple\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Les femmes, face \u00e0 un cancer, sont 6 fois plus quitt\u00e9es que les hommes.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#website\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/\",\"name\":\"Les Bridgets\",\"description\":\"R\u00e9f\u00e9rences et r\u00e9flexions sur nos relations\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lesbridgets.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\",\"name\":\"Les Bridgets\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo-3-lesbridgets.png\",\"contentUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo-3-lesbridgets.png\",\"width\":251,\"height\":59,\"caption\":\"Les Bridgets\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Les.Bridgets\",\"https:\\\/\\\/x.com\\\/les_bridgets\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/person\\\/82a31c27ae0ddd23ee59e1e2ac5713ba\",\"name\":\"Bridget\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"caption\":\"Bridget\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les femmes, face \u00e0 un cancer, sont 6 fois plus quitt\u00e9es que les hommes. - Les Bridgets","description":"Selon une \u00e9tude, les femmes souffrant d'un cancer ou d'une scl\u00e9rose en plaques sont 6 fois plus susceptibles d'\u00eatre quitt\u00e9es par leur compagnon qu'un homme.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/les-femmes-face-a-un-cancer-sont-6-fois-plus-quittes-que-les-hommes.html","og_locale":"fr_FR","og_type":"article","og_title":"Les femmes, face \u00e0 un cancer, sont 6 fois plus quitt\u00e9es que les hommes. - Les Bridgets","og_description":"Selon une \u00e9tude, les femmes souffrant d'un cancer ou d'une scl\u00e9rose en plaques sont 6 fois plus susceptibles d'\u00eatre quitt\u00e9es par leur compagnon qu'un homme.","og_url":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/les-femmes-face-a-un-cancer-sont-6-fois-plus-quittes-que-les-hommes.html","og_site_name":"Les Bridgets","article_publisher":"https:\/\/www.facebook.com\/Les.Bridgets","article_published_time":"2009-11-17T15:11:18+00:00","article_modified_time":"2020-05-12T15:13:33+00:00","og_image":[{"width":750,"height":425,"url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2009\/11\/femme-cancer-quitter-mari.png","type":"image\/png"}],"author":"Bridget","twitter_card":"summary_large_image","twitter_creator":"@les_bridgets","twitter_site":"@les_bridgets","twitter_misc":{"\u00c9crit par":"Bridget","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/les-femmes-face-a-un-cancer-sont-6-fois-plus-quittes-que-les-hommes.html#article","isPartOf":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/les-femmes-face-a-un-cancer-sont-6-fois-plus-quittes-que-les-hommes.html"},"author":{"name":"Bridget","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/person\/82a31c27ae0ddd23ee59e1e2ac5713ba"},"headline":"Les femmes, face \u00e0 un cancer, sont 6 fois plus quitt\u00e9es que les hommes.","datePublished":"2009-11-17T15:11:18+00:00","dateModified":"2020-05-12T15:13:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/les-femmes-face-a-un-cancer-sont-6-fois-plus-quittes-que-les-hommes.html"},"wordCount":293,"commentCount":1,"publisher":{"@id":"https:\/\/www.lesbridgets.com\/#organization"},"image":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/les-femmes-face-a-un-cancer-sont-6-fois-plus-quittes-que-les-hommes.html#primaryimage"},"thumbnailUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2009\/11\/femme-cancer-quitter-mari.png","articleSection":["Statistiques sur le couple"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/les-femmes-face-a-un-cancer-sont-6-fois-plus-quittes-que-les-hommes.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/les-femmes-face-a-un-cancer-sont-6-fois-plus-quittes-que-les-hommes.html","url":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/les-femmes-face-a-un-cancer-sont-6-fois-plus-quittes-que-les-hommes.html","name":"Les femmes, face \u00e0 un cancer, sont 6 fois plus quitt\u00e9es que les hommes. - Les Bridgets","isPartOf":{"@id":"https:\/\/www.lesbridgets.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/les-femmes-face-a-un-cancer-sont-6-fois-plus-quittes-que-les-hommes.html#primaryimage"},"image":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/les-femmes-face-a-un-cancer-sont-6-fois-plus-quittes-que-les-hommes.html#primaryimage"},"thumbnailUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2009\/11\/femme-cancer-quitter-mari.png","datePublished":"2009-11-17T15:11:18+00:00","dateModified":"2020-05-12T15:13:33+00:00","description":"Selon une \u00e9tude, les femmes souffrant d'un cancer ou d'une scl\u00e9rose en plaques sont 6 fois plus susceptibles d'\u00eatre quitt\u00e9es par leur compagnon qu'un homme.","breadcrumb":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/les-femmes-face-a-un-cancer-sont-6-fois-plus-quittes-que-les-hommes.html#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/les-femmes-face-a-un-cancer-sont-6-fois-plus-quittes-que-les-hommes.html"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/les-femmes-face-a-un-cancer-sont-6-fois-plus-quittes-que-les-hommes.html#primaryimage","url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2009\/11\/femme-cancer-quitter-mari.png","contentUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2009\/11\/femme-cancer-quitter-mari.png","width":750,"height":425},{"@type":"BreadcrumbList","@id":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/les-femmes-face-a-un-cancer-sont-6-fois-plus-quittes-que-les-hommes.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Les Bridgets","item":"https:\/\/www.lesbridgets.com\/"},{"@type":"ListItem","position":2,"name":"Statistiques sur le couple &amp; celibat","item":"https:\/\/www.lesbridgets.com\/index.php\/category\/statistiques"},{"@type":"ListItem","position":3,"name":"Statistiques sur le couple","item":"https:\/\/www.lesbridgets.com\/index.php\/category\/statistiques\/etude-statistiques-couple"},{"@type":"ListItem","position":4,"name":"Les femmes, face \u00e0 un cancer, sont 6 fois plus quitt\u00e9es que les hommes."}]},{"@type":"WebSite","@id":"https:\/\/www.lesbridgets.com\/#website","url":"https:\/\/www.lesbridgets.com\/","name":"Les Bridgets","description":"R\u00e9f\u00e9rences et r\u00e9flexions sur nos relations","publisher":{"@id":"https:\/\/www.lesbridgets.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lesbridgets.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lesbridgets.com\/#organization","name":"Les Bridgets","url":"https:\/\/www.lesbridgets.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2022\/07\/cropped-logo-3-lesbridgets.png","contentUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2022\/07\/cropped-logo-3-lesbridgets.png","width":251,"height":59,"caption":"Les Bridgets"},"image":{"@id":"https:\/\/www.lesbridgets.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Les.Bridgets","https:\/\/x.com\/les_bridgets"]},{"@type":"Person","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/person\/82a31c27ae0ddd23ee59e1e2ac5713ba","name":"Bridget","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","caption":"Bridget"}}]}},"modified_by":"Bridget","_links":{"self":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/comments?post=541"}],"version-history":[{"count":5,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/541\/revisions"}],"predecessor-version":[{"id":252404,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/541\/revisions\/252404"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/media\/245870"}],"wp:attachment":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/media?parent=541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/categories?post=541"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/tags?post=541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}