{"id":495,"date":"2009-08-06T12:03:53","date_gmt":"2009-08-06T10:03:53","guid":{"rendered":"http:\/\/lesbridg.cluster015.ovh.net\/wordpress\/index.php\/discographie-musique-relations-homme-femme\/boire-ou-bien-se-conduire-il-faut-choisir-selon-charlotte-marin.html"},"modified":"2017-09-17T21:24:06","modified_gmt":"2017-09-17T19:24:06","slug":"boire-ou-bien-se-conduire-il-faut-choisir-selon-charlotte-marin","status":"publish","type":"post","link":"https:\/\/www.lesbridgets.com\/index.php\/references\/discographie-musique-relations-homme-femme\/boire-ou-bien-se-conduire-il-faut-choisir-selon-charlotte-marin.html","title":{"rendered":"Boire ou bien se conduire il faut choisir selon Charlotte Marin !?"},"content":{"rendered":"<p>Apr\u00e8s les livres, les films on a notre v\u00e9ritable Bridget Jones (d&rsquo;aujourd&rsquo;hui) en paroles et musique, gr\u00e2ce \u00e0 Charlotte Marin.<br \/>On vous laisse visionner son clip qui va parler \u00e0 beaucoup d&rsquo;entre vous.<br \/>D&rsquo;apr\u00e8s certains Bridget aurait pu \u00e9crire ses paroles?! en tout cas elle a le m\u00e9rite de nous faire sourire. <\/p>\n<div align=\"left\">&nbsp;<\/div>\n<div align=\"left\">&nbsp;<\/div>\n<div align=\"left\">&nbsp;<\/div>\n<div align=\"left\">&nbsp;<\/div>\n<div align=\"left\">&nbsp;<\/div>\n<div align=\"left\">&nbsp;<\/div>\n<div align=\"left\">&nbsp;<\/div>\n<div align=\"left\">Sp\u00e9ciale d\u00e9dicace \u00e0 toutes celles qui ont la manie d&rsquo;appeler leurs exs, potentiels quand elles sont bourr\u00e9es, ou bien encore qu&rsquo;on surnomme Sue Ellen, qui font boulette sur boulette en soir\u00e9e et surtout qui ram\u00e8nent des boulets&#8230;&nbsp; <\/div>\n<div align=\"center\">&nbsp;<\/div>\n<div align=\"center\">&nbsp;<\/div>\n<div align=\"center\">{swfremote}http:\/\/www.youtube.com\/v\/WEDYWKDWXeo&amp;hl=fr&amp;fs=1&amp;color1=0xcc2550&amp;color2=0xe87a9f&amp;border=1{\/swfremote}<\/div>\n<div align=\"center\">&nbsp;<\/div>\n<div align=\"center\">&nbsp;<\/div>\n<div align=\"left\">Nous allons suivre de pr\u00e8s cette demoiselle, qui a d\u00e9j\u00e0 fait les avant-premi\u00e8res de B\u00e9nabar et qui sort son deuxi\u00e8me album,<i> <b>Trentenaire \u00e0 vif<\/b> , <\/i>le 1er octobre 2009..<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s les livres, les films on a notre v\u00e9ritable Bridget Jones (d&rsquo;aujourd&rsquo;hui) en paroles et musique, gr\u00e2ce \u00e0 Charlotte Marin.<br \/>On vous laisse visionner son clip qui va parler \u00e0 beaucoup d&rsquo;entre vous.<br \/>D&rsquo;apr\u00e8s certains Bridget aurait pu \u00e9crire ses paroles?! en tout cas elle a le m\u00e9rite de nous faire sourire.<\/p>\n","protected":false},"author":2,"featured_media":494,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"om_disable_all_campaigns":false,"_lmt_disableupdate":"","_lmt_disable":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-495","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-discographie-musique-relations-homme-femme"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Boire ou bien se conduire il faut choisir selon Charlotte Marin !? - Les Bridgets<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lesbridgets.com\/index.php\/references\/discographie-musique-relations-homme-femme\/boire-ou-bien-se-conduire-il-faut-choisir-selon-charlotte-marin.html\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Boire ou bien se conduire il faut choisir selon Charlotte Marin !? - Les Bridgets\" \/>\n<meta property=\"og:description\" content=\"Apr\u00e8s les livres, les films on a notre v\u00e9ritable Bridget Jones (d&#039;aujourd&#039;hui) en paroles et musique, gr\u00e2ce \u00e0 Charlotte Marin.On vous laisse visionner son clip qui va parler \u00e0 beaucoup d&#039;entre vous.D&#039;apr\u00e8s certains Bridget aurait pu \u00e9crire ses paroles?! en tout cas elle a le m\u00e9rite de nous faire sourire.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lesbridgets.com\/index.php\/references\/discographie-musique-relations-homme-femme\/boire-ou-bien-se-conduire-il-faut-choisir-selon-charlotte-marin.html\" \/>\n<meta property=\"og:site_name\" content=\"Les Bridgets\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Les.Bridgets\" \/>\n<meta property=\"article:published_time\" content=\"2009-08-06T10:03:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-09-17T19:24:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2009\/08\/boire-ou-bien-se-conduire.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"230\" \/>\n\t<meta property=\"og:image:height\" content=\"153\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bridget\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@les_bridgets\" \/>\n<meta name=\"twitter:site\" content=\"@les_bridgets\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bridget\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/discographie-musique-relations-homme-femme\\\/boire-ou-bien-se-conduire-il-faut-choisir-selon-charlotte-marin.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/discographie-musique-relations-homme-femme\\\/boire-ou-bien-se-conduire-il-faut-choisir-selon-charlotte-marin.html\"},\"author\":{\"name\":\"Bridget\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/person\\\/82a31c27ae0ddd23ee59e1e2ac5713ba\"},\"headline\":\"Boire ou bien se conduire il faut choisir selon Charlotte Marin !?\",\"datePublished\":\"2009-08-06T10:03:53+00:00\",\"dateModified\":\"2017-09-17T19:24:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/discographie-musique-relations-homme-femme\\\/boire-ou-bien-se-conduire-il-faut-choisir-selon-charlotte-marin.html\"},\"wordCount\":179,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/discographie-musique-relations-homme-femme\\\/boire-ou-bien-se-conduire-il-faut-choisir-selon-charlotte-marin.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2009\\\/08\\\/boire-ou-bien-se-conduire.jpg\",\"articleSection\":[\"Musique\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/discographie-musique-relations-homme-femme\\\/boire-ou-bien-se-conduire-il-faut-choisir-selon-charlotte-marin.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/discographie-musique-relations-homme-femme\\\/boire-ou-bien-se-conduire-il-faut-choisir-selon-charlotte-marin.html\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/discographie-musique-relations-homme-femme\\\/boire-ou-bien-se-conduire-il-faut-choisir-selon-charlotte-marin.html\",\"name\":\"Boire ou bien se conduire il faut choisir selon Charlotte Marin !? - Les Bridgets\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/discographie-musique-relations-homme-femme\\\/boire-ou-bien-se-conduire-il-faut-choisir-selon-charlotte-marin.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/discographie-musique-relations-homme-femme\\\/boire-ou-bien-se-conduire-il-faut-choisir-selon-charlotte-marin.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2009\\\/08\\\/boire-ou-bien-se-conduire.jpg\",\"datePublished\":\"2009-08-06T10:03:53+00:00\",\"dateModified\":\"2017-09-17T19:24:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/discographie-musique-relations-homme-femme\\\/boire-ou-bien-se-conduire-il-faut-choisir-selon-charlotte-marin.html#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/discographie-musique-relations-homme-femme\\\/boire-ou-bien-se-conduire-il-faut-choisir-selon-charlotte-marin.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/discographie-musique-relations-homme-femme\\\/boire-ou-bien-se-conduire-il-faut-choisir-selon-charlotte-marin.html#primaryimage\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2009\\\/08\\\/boire-ou-bien-se-conduire.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2009\\\/08\\\/boire-ou-bien-se-conduire.jpg\",\"width\":230,\"height\":153,\"caption\":\"boire ou bien se conduire\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/discographie-musique-relations-homme-femme\\\/boire-ou-bien-se-conduire-il-faut-choisir-selon-charlotte-marin.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Les Bridgets\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00e9f\u00e9rences sur le couple et le c\u00e9libat\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/category\\\/references\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Musique\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/category\\\/references\\\/discographie-musique-relations-homme-femme\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Boire ou bien se conduire il faut choisir selon Charlotte Marin !?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#website\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/\",\"name\":\"Les Bridgets\",\"description\":\"R\u00e9f\u00e9rences et r\u00e9flexions sur nos relations\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lesbridgets.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\",\"name\":\"Les Bridgets\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo-3-lesbridgets.png\",\"contentUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo-3-lesbridgets.png\",\"width\":251,\"height\":59,\"caption\":\"Les Bridgets\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Les.Bridgets\",\"https:\\\/\\\/x.com\\\/les_bridgets\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/person\\\/82a31c27ae0ddd23ee59e1e2ac5713ba\",\"name\":\"Bridget\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"caption\":\"Bridget\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Boire ou bien se conduire il faut choisir selon Charlotte Marin !? - Les Bridgets","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lesbridgets.com\/index.php\/references\/discographie-musique-relations-homme-femme\/boire-ou-bien-se-conduire-il-faut-choisir-selon-charlotte-marin.html","og_locale":"fr_FR","og_type":"article","og_title":"Boire ou bien se conduire il faut choisir selon Charlotte Marin !? - Les Bridgets","og_description":"Apr\u00e8s les livres, les films on a notre v\u00e9ritable Bridget Jones (d'aujourd'hui) en paroles et musique, gr\u00e2ce \u00e0 Charlotte Marin.On vous laisse visionner son clip qui va parler \u00e0 beaucoup d'entre vous.D'apr\u00e8s certains Bridget aurait pu \u00e9crire ses paroles?! en tout cas elle a le m\u00e9rite de nous faire sourire.","og_url":"https:\/\/www.lesbridgets.com\/index.php\/references\/discographie-musique-relations-homme-femme\/boire-ou-bien-se-conduire-il-faut-choisir-selon-charlotte-marin.html","og_site_name":"Les Bridgets","article_publisher":"https:\/\/www.facebook.com\/Les.Bridgets","article_published_time":"2009-08-06T10:03:53+00:00","article_modified_time":"2017-09-17T19:24:06+00:00","og_image":[{"width":230,"height":153,"url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2009\/08\/boire-ou-bien-se-conduire.jpg","type":"image\/jpeg"}],"author":"Bridget","twitter_card":"summary_large_image","twitter_creator":"@les_bridgets","twitter_site":"@les_bridgets","twitter_misc":{"\u00c9crit par":"Bridget","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/discographie-musique-relations-homme-femme\/boire-ou-bien-se-conduire-il-faut-choisir-selon-charlotte-marin.html#article","isPartOf":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/discographie-musique-relations-homme-femme\/boire-ou-bien-se-conduire-il-faut-choisir-selon-charlotte-marin.html"},"author":{"name":"Bridget","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/person\/82a31c27ae0ddd23ee59e1e2ac5713ba"},"headline":"Boire ou bien se conduire il faut choisir selon Charlotte Marin !?","datePublished":"2009-08-06T10:03:53+00:00","dateModified":"2017-09-17T19:24:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/discographie-musique-relations-homme-femme\/boire-ou-bien-se-conduire-il-faut-choisir-selon-charlotte-marin.html"},"wordCount":179,"commentCount":2,"publisher":{"@id":"https:\/\/www.lesbridgets.com\/#organization"},"image":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/discographie-musique-relations-homme-femme\/boire-ou-bien-se-conduire-il-faut-choisir-selon-charlotte-marin.html#primaryimage"},"thumbnailUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2009\/08\/boire-ou-bien-se-conduire.jpg","articleSection":["Musique"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.lesbridgets.com\/index.php\/references\/discographie-musique-relations-homme-femme\/boire-ou-bien-se-conduire-il-faut-choisir-selon-charlotte-marin.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/discographie-musique-relations-homme-femme\/boire-ou-bien-se-conduire-il-faut-choisir-selon-charlotte-marin.html","url":"https:\/\/www.lesbridgets.com\/index.php\/references\/discographie-musique-relations-homme-femme\/boire-ou-bien-se-conduire-il-faut-choisir-selon-charlotte-marin.html","name":"Boire ou bien se conduire il faut choisir selon Charlotte Marin !? - Les Bridgets","isPartOf":{"@id":"https:\/\/www.lesbridgets.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/discographie-musique-relations-homme-femme\/boire-ou-bien-se-conduire-il-faut-choisir-selon-charlotte-marin.html#primaryimage"},"image":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/discographie-musique-relations-homme-femme\/boire-ou-bien-se-conduire-il-faut-choisir-selon-charlotte-marin.html#primaryimage"},"thumbnailUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2009\/08\/boire-ou-bien-se-conduire.jpg","datePublished":"2009-08-06T10:03:53+00:00","dateModified":"2017-09-17T19:24:06+00:00","breadcrumb":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/discographie-musique-relations-homme-femme\/boire-ou-bien-se-conduire-il-faut-choisir-selon-charlotte-marin.html#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lesbridgets.com\/index.php\/references\/discographie-musique-relations-homme-femme\/boire-ou-bien-se-conduire-il-faut-choisir-selon-charlotte-marin.html"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/discographie-musique-relations-homme-femme\/boire-ou-bien-se-conduire-il-faut-choisir-selon-charlotte-marin.html#primaryimage","url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2009\/08\/boire-ou-bien-se-conduire.jpg","contentUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2009\/08\/boire-ou-bien-se-conduire.jpg","width":230,"height":153,"caption":"boire ou bien se conduire"},{"@type":"BreadcrumbList","@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/discographie-musique-relations-homme-femme\/boire-ou-bien-se-conduire-il-faut-choisir-selon-charlotte-marin.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Les Bridgets","item":"https:\/\/www.lesbridgets.com\/"},{"@type":"ListItem","position":2,"name":"R\u00e9f\u00e9rences sur le couple et le c\u00e9libat","item":"https:\/\/www.lesbridgets.com\/index.php\/category\/references"},{"@type":"ListItem","position":3,"name":"Musique","item":"https:\/\/www.lesbridgets.com\/index.php\/category\/references\/discographie-musique-relations-homme-femme"},{"@type":"ListItem","position":4,"name":"Boire ou bien se conduire il faut choisir selon Charlotte Marin !?"}]},{"@type":"WebSite","@id":"https:\/\/www.lesbridgets.com\/#website","url":"https:\/\/www.lesbridgets.com\/","name":"Les Bridgets","description":"R\u00e9f\u00e9rences et r\u00e9flexions sur nos relations","publisher":{"@id":"https:\/\/www.lesbridgets.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lesbridgets.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lesbridgets.com\/#organization","name":"Les Bridgets","url":"https:\/\/www.lesbridgets.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2022\/07\/cropped-logo-3-lesbridgets.png","contentUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2022\/07\/cropped-logo-3-lesbridgets.png","width":251,"height":59,"caption":"Les Bridgets"},"image":{"@id":"https:\/\/www.lesbridgets.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Les.Bridgets","https:\/\/x.com\/les_bridgets"]},{"@type":"Person","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/person\/82a31c27ae0ddd23ee59e1e2ac5713ba","name":"Bridget","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","caption":"Bridget"}}]}},"modified_by":null,"_links":{"self":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/comments?post=495"}],"version-history":[{"count":1,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/495\/revisions"}],"predecessor-version":[{"id":241595,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/495\/revisions\/241595"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/media\/494"}],"wp:attachment":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/media?parent=495"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/categories?post=495"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/tags?post=495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}