{"id":256498,"date":"2023-04-08T14:48:59","date_gmt":"2023-04-08T12:48:59","guid":{"rendered":"https:\/\/www.lesbridgets.com\/?p=256498"},"modified":"2023-04-28T10:43:05","modified_gmt":"2023-04-28T08:43:05","slug":"temoignage-grossesse-test-du-diabete-gestationnel","status":"publish","type":"post","link":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/grossesse\/temoignage-grossesse-test-du-diabete-gestationnel.html","title":{"rendered":"T\u00e9moignage grossesse : test du diab\u00e8te gestationnel"},"content":{"rendered":"<p>Une grossesse \u00e0 42 ans, un peu de surpoids (aux yeux de la m\u00e9decine) et hop vous \u00eates s\u00fbres comme moi de faire le test du diab\u00e8te gestationnel. J&rsquo;avais lu et entendu beaucoup de choses (fausses) sur le test du diab\u00e8te gestationnel.<br \/>\nVoici donc quelques r\u00e9ponses suite \u00e0 mon exp\u00e9rience en avril 2023 \u00e0 des questions que je me suis pos\u00e9e et des infos que j&rsquo;avais lu et qui \u00e9taient fausses.<\/p>\n<h2>Quand se fait le test du diab\u00e8te gestationnel ?<\/h2>\n<p>Beaucoup de m\u00e9decins le prescrivent syst\u00e9matiquement. D&rsquo;autres seulement si vous avez plus de 40 ans, du surpoids et\/ou du diab\u00e8te dans votre famille.<\/p>\n<h2>Quel parfum choisir pour le glucose \u00e0 boire ?<\/h2>\n<p>J&rsquo;avais lu que j&rsquo;aurais le choix entre plusieurs parfums : citron ou orange. Dans mon laboratoire, il n&rsquo;y avait que citron et visiblement parce que c&rsquo;est celui que tout le monde choisit. Ce serait le moins \u00e9coeurant. Apparemment on trouve aussi le parfum coca dans certains labo.<\/p>\n<h2>Peut-on boire de l&rsquo;eau avant et pendant le test du diab\u00e8te gestationnel ?<\/h2>\n<p>Avant non, il faut \u00eatre vraiment \u00e0 jeun. Pendant, l&rsquo;infirmi\u00e8re m&rsquo;avait dit que je pouvais boire un demi vers d&rsquo;eau si vraiment j&rsquo;en ressentais le besoin. Cela a \u00e9t\u00e9 supportable, je n&rsquo;ai rien bu jusqu&rsquo;\u00e0 la derni\u00e8re prise de sang. En sortant du labo, j&rsquo;\u00e9tais contente d&rsquo;avoir pris ma gourde d&rsquo;eau.<\/p>\n<h2>On peut \u00eatre malade la premi\u00e8re heure ?<\/h2>\n<p>Vous \u00eates \u00e0 jeun depuis 10 \u00e0 12h. Il est t\u00f4t (mon labo demande de venir avant 9H30). Vous buvez 200ml de glucose. Ca peut vous assommer un peu. Perso, j&rsquo;\u00e9tais un peu K.O mais pas de possibilit\u00e9 de dormir et discuter avec mon compagnon a bien aid\u00e9.<\/p>\n<h2>Faut il \u00eatre accompagn\u00e9e pour le test ?<\/h2>\n<p>Si vous \u00eates un peu hypcondriaque et que par exemple vous avez un peu de route pour rentrer: oui, cela peut \u00eatre utile. Personnellement, le papa a insist\u00e9 pour venir et j&rsquo;avoue que \u00e7a m&rsquo;a bien aid\u00e9. Notamment \u00e0 me changer les id\u00e9es et donc \u00e0 voir moins le temps pass\u00e9.<\/p>\n<h2>Sommes-nous isol\u00e9s dans une salle pendant l&rsquo;attente entre chaque prise de sang ?<\/h2>\n<p>Certaines ont eu la chance d&rsquo;avoir eu droit \u00e0 une salle isol\u00e9e avec de quoi s&rsquo;allonger. Je pensais avoir cela mais on m&rsquo;a clairement dit que non, seulement si je me sentais vraiment mal.<br \/>\nNous \u00e9tions 3 femmes enceintes \u00e0 passer le test. J&rsquo;ai compris qu&rsquo;il \u00e9tait compliqu\u00e9 de trouver 3 salles dispo.<\/p>\n<h2>Comment bien pr\u00e9parer son test du diab\u00e8te gestationnel ?<\/h2>\n<p>J&rsquo;avais lu que certaines recommandait de manger des p\u00e2tes la veille. Apr\u00e8s avoir relu pas mal de choses sur le diab\u00e8te, le sucre lent des p\u00e2tes n&rsquo;\u00e9tait pas id\u00e9al. Personnellement, je conseille de manger le plus sainement possible et copieusement pour bien tenir jusqu&rsquo;\u00e0 la fin du test.<\/p>\n<p>Le super conseil que j&rsquo;avais lu partout, \u00e9tait de venir bien avec de quoi bien s&rsquo;occuper. Voici ce que j&rsquo;ai emmen\u00e9 pour voir moins le temps pass\u00e9 :<\/p>\n<ul>\n<li>Le chargeur de mon tel au cas o\u00f9 il se vide trop vite ainsi qu&rsquo;<a href=\"https:\/\/www.amazon.fr\/gp\/product\/B08CC9JNDW\/ref=ppx_yo_dt_b_asin_title_o06_s01?ie=UTF8&amp;th=1\" target=\"_blank\" rel=\"nofollow noopener\">une batterie externe<\/a> pour le charger m\u00eame si il n&rsquo;y a pas de prise accessible (<a href=\"https:\/\/www.amazon.fr\/gp\/product\/B08CC9JNDW\/ref=ppx_yo_dt_b_asin_title_o06_s01?ie=UTF8&amp;th=1\" target=\"_blank\" rel=\"nofollow noopener\">ce mod\u00e8le<\/a> est parfait pour charger plusieurs appareils donc celui du papa et elle sera tr\u00e8s utile \u00e0 la maternit\u00e9 par exemple)<\/li>\n<li><a href=\"https:\/\/www.amazon.fr\/Xiaomi-REDMI-True-Buds-Air\/dp\/B09J4T4JF5?keywords=ecouteurs+bluetooth+sans+fil+xiaomi&amp;qid=1682671063&amp;s=books&amp;sprefix=ecouteurs+sans+%2Cstripbooks%2C109&amp;sr=1-4&amp;linkCode=ll1&amp;tag=lesbricomcomp-21&amp;linkId=9d5882dcc36124cccc579af5d1a0c22d&amp;ref_=as_li_ss_tl\" target=\"_blank\" rel=\"nofollow noopener\">Des \u00e9couteurs<\/a> pour \u00e9couter podcast et musique sans emb\u00eater les autres.<\/li>\n<li>Des livres sur l&rsquo;\u00e9ducation, la parentalit\u00e9 : pour moi c&rsquo;\u00e9tait <a href=\"https:\/\/www.amazon.fr\/Chasseur-cueilleur-parent-cultures-ancestrales\/dp\/2266324314?pd_rd_w=U8gIE&amp;content-id=amzn1.sym.1bec6179-e78a-4900-91c1-a0cbdfe0e062&amp;pf_rd_p=1bec6179-e78a-4900-91c1-a0cbdfe0e062&amp;pf_rd_r=EYBEZ153J4MY6REH7QP4&amp;pd_rd_wg=b1wWk&amp;pd_rd_r=0735dea7-b633-46d8-8ec2-25b1e2496453&amp;pd_rd_i=2266324314&amp;psc=1&amp;linkCode=ll1&amp;tag=lesbricomcomp-21&amp;linkId=3765e3ec72aab3164272fbbfa931deaa&amp;ref_=as_li_ss_tl\" target=\"_blank\" rel=\"nofollow noopener\">Chasseur cueilleur<\/a> et <a href=\"https:\/\/www.amazon.fr\/Tu-seras-homme-f%C3%A9ministe-fils\/dp\/2501134052?&amp;linkCode=ll1&amp;tag=lesbricomcomp-21&amp;linkId=38ffb4ce08cd7d1c3b01e80485d718c2&amp;ref_=as_li_ss_tl\" target=\"_blank\" rel=\"nofollow noopener\">Tu seras un homme f\u00e9ministe mon fils<\/a>.<\/li>\n<li>Mon ordinateur portable qui m&rsquo;a bien occup\u00e9 au moins 1H !<\/li>\n<\/ul>\n<p style=\"text-align: center;\"><iframe style=\"width: 120px; height: 240px;\" src=\"\/\/ws-eu.amazon-adsystem.com\/widgets\/q?ServiceVersion=20070822&amp;OneJS=1&amp;Operation=GetAdHtml&amp;MarketPlace=FR&amp;source=ss&amp;ref=as_ss_li_til&amp;ad_type=product_link&amp;tracking_id=lesbricomcomp-21&amp;marketplace=amazon&amp;region=FR&amp;placement=B08CC9JNDW&amp;asins=B08CC9JNDW&amp;linkId=db11c8fe2622304b05f7b10db86a714c&amp;show_border=true&amp;link_opens_in_new_window=true\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" sandbox=\"allow-popups allow-scripts allow-modals allow-forms allow-same-origin\"><\/iframe><\/p>\n<h2>Est-ce que les veines supportent les 3 prises de sang m\u00eame si on en a peu ou elles sont fragiles ?<\/h2>\n<p>J&rsquo;ai des veines tr\u00e8s fragiles et quasi invisible. L&rsquo;infirmi\u00e8re a r\u00e9ussi \u00e0 piquer deux fois une m\u00eame veine. Je stressais plus pour \u00e7a car on ne m&rsquo;avait jamais 3 prises de sang en 2 h. Maintenant je sais que c&rsquo;est possible !<\/p>\n<h2>Comme se sent-on les heures, jours qui suivent le test ?<\/h2>\n<p>J&rsquo;ai \u00e9t\u00e9 rapidement fatigu\u00e9e. Et 2h apr\u00e8s je faisais une sieste d&rsquo;une demi-heure.<br \/>\nEffectivement, vous \u00eates \u00e0 jeun, on vous fait 3 prises de sangs. Vous restez assise 2 heures d&rsquo;affil\u00e9es. Et accessoirement vous avez un petit \u00eatre humain qui vous prend de l&rsquo;\u00e9nergie dans votre corps.<br \/>\nIl est tout \u00e0 fait normal de se sentir plus fatigu\u00e9e qu&rsquo;\u00e0 la normale.<\/p>\n<p>De plus j&rsquo;avais pu lire que certaines n&rsquo;avaient pas \u00e9t\u00e9 bien les deux jours suivant. Comme j&rsquo;\u00e9tais de mariage le we suivant, j&rsquo;ai essay\u00e9 de pas le faire la veille au cas o\u00f9. Personnellement, les jours qui ont suivi, je n&rsquo;ai pas ressenti une plus grande fatigue que les semaines pr\u00e9c\u00e9dentes<\/p>\n<h2>Bilan<\/h2>\n<p>Ne stressez pas pour rien. Le plus chiant de ce test c&rsquo;est la dur\u00e9e car il faut au total attendre deux heures. Le glucose de 200Ml est facile \u00e0 boire et rapide. J&rsquo;ai trouv\u00e9 \u00e7a moins \u00e9coeurant que du sirop Teisseire pur (par exemple).<br \/>\nEnfin rares sont les femmes qui ont des effets secondaires (vomissements, malaises).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une grossesse \u00e0 42 ans, un peu de surpoids (aux yeux de la m\u00e9decine) et hop vous \u00eates s\u00fbres comme moi de faire le test&hellip; <\/p>\n","protected":false},"author":2,"featured_media":256501,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"om_disable_all_campaigns":false,"_lmt_disableupdate":"no","_lmt_disable":"no","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[1393],"tags":[],"class_list":["post-256498","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-grossesse"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>T\u00e9moignage grossesse : test du diab\u00e8te gestationnel - Les Bridgets<\/title>\n<meta name=\"description\" content=\"T\u00e9moignage sur mes deux heures de test de diab\u00e8te gestationnel \u00e0 42 ans. Les choses bonnes \u00e0 savoir : comment passer le temps...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/grossesse\/temoignage-grossesse-test-du-diabete-gestationnel.html\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"T\u00e9moignage grossesse : test du diab\u00e8te gestationnel - Les Bridgets\" \/>\n<meta property=\"og:description\" content=\"T\u00e9moignage sur mes deux heures de test de diab\u00e8te gestationnel \u00e0 42 ans. Les choses bonnes \u00e0 savoir : comment passer le temps...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/grossesse\/temoignage-grossesse-test-du-diabete-gestationnel.html\" \/>\n<meta property=\"og:site_name\" content=\"Les Bridgets\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Les.Bridgets\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-08T12:48:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-28T08:43:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2023\/04\/temoignage-test-diabete-gestationnel.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bridget\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@les_bridgets\" \/>\n<meta name=\"twitter:site\" content=\"@les_bridgets\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bridget\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/grossesse\\\/temoignage-grossesse-test-du-diabete-gestationnel.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/grossesse\\\/temoignage-grossesse-test-du-diabete-gestationnel.html\"},\"author\":{\"name\":\"Bridget\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/person\\\/82a31c27ae0ddd23ee59e1e2ac5713ba\"},\"headline\":\"T\u00e9moignage grossesse : test du diab\u00e8te gestationnel\",\"datePublished\":\"2023-04-08T12:48:59+00:00\",\"dateModified\":\"2023-04-28T08:43:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/grossesse\\\/temoignage-grossesse-test-du-diabete-gestationnel.html\"},\"wordCount\":888,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/grossesse\\\/temoignage-grossesse-test-du-diabete-gestationnel.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/temoignage-test-diabete-gestationnel.jpg\",\"articleSection\":[\"Grossesse\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/grossesse\\\/temoignage-grossesse-test-du-diabete-gestationnel.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/grossesse\\\/temoignage-grossesse-test-du-diabete-gestationnel.html\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/grossesse\\\/temoignage-grossesse-test-du-diabete-gestationnel.html\",\"name\":\"T\u00e9moignage grossesse : test du diab\u00e8te gestationnel - Les Bridgets\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/grossesse\\\/temoignage-grossesse-test-du-diabete-gestationnel.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/grossesse\\\/temoignage-grossesse-test-du-diabete-gestationnel.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/temoignage-test-diabete-gestationnel.jpg\",\"datePublished\":\"2023-04-08T12:48:59+00:00\",\"dateModified\":\"2023-04-28T08:43:05+00:00\",\"description\":\"T\u00e9moignage sur mes deux heures de test de diab\u00e8te gestationnel \u00e0 42 ans. Les choses bonnes \u00e0 savoir : comment passer le temps...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/grossesse\\\/temoignage-grossesse-test-du-diabete-gestationnel.html#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/grossesse\\\/temoignage-grossesse-test-du-diabete-gestationnel.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/grossesse\\\/temoignage-grossesse-test-du-diabete-gestationnel.html#primaryimage\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/temoignage-test-diabete-gestationnel.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/temoignage-test-diabete-gestationnel.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/grossesse\\\/temoignage-grossesse-test-du-diabete-gestationnel.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Les Bridgets\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conseils sur l'amour, le couple &amp; les c\u00e9libataires\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/category\\\/conseils-relations\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Grossesse\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/category\\\/conseils-relations\\\/grossesse\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"T\u00e9moignage grossesse : test du diab\u00e8te gestationnel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#website\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/\",\"name\":\"Les Bridgets\",\"description\":\"R\u00e9f\u00e9rences et r\u00e9flexions sur nos relations\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lesbridgets.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\",\"name\":\"Les Bridgets\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo-3-lesbridgets.png\",\"contentUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo-3-lesbridgets.png\",\"width\":251,\"height\":59,\"caption\":\"Les Bridgets\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Les.Bridgets\",\"https:\\\/\\\/x.com\\\/les_bridgets\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/person\\\/82a31c27ae0ddd23ee59e1e2ac5713ba\",\"name\":\"Bridget\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"caption\":\"Bridget\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"T\u00e9moignage grossesse : test du diab\u00e8te gestationnel - Les Bridgets","description":"T\u00e9moignage sur mes deux heures de test de diab\u00e8te gestationnel \u00e0 42 ans. Les choses bonnes \u00e0 savoir : comment passer le temps...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/grossesse\/temoignage-grossesse-test-du-diabete-gestationnel.html","og_locale":"fr_FR","og_type":"article","og_title":"T\u00e9moignage grossesse : test du diab\u00e8te gestationnel - Les Bridgets","og_description":"T\u00e9moignage sur mes deux heures de test de diab\u00e8te gestationnel \u00e0 42 ans. Les choses bonnes \u00e0 savoir : comment passer le temps...","og_url":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/grossesse\/temoignage-grossesse-test-du-diabete-gestationnel.html","og_site_name":"Les Bridgets","article_publisher":"https:\/\/www.facebook.com\/Les.Bridgets","article_published_time":"2023-04-08T12:48:59+00:00","article_modified_time":"2023-04-28T08:43:05+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2023\/04\/temoignage-test-diabete-gestationnel.jpg","type":"image\/jpeg"}],"author":"Bridget","twitter_card":"summary_large_image","twitter_creator":"@les_bridgets","twitter_site":"@les_bridgets","twitter_misc":{"\u00c9crit par":"Bridget","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/grossesse\/temoignage-grossesse-test-du-diabete-gestationnel.html#article","isPartOf":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/grossesse\/temoignage-grossesse-test-du-diabete-gestationnel.html"},"author":{"name":"Bridget","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/person\/82a31c27ae0ddd23ee59e1e2ac5713ba"},"headline":"T\u00e9moignage grossesse : test du diab\u00e8te gestationnel","datePublished":"2023-04-08T12:48:59+00:00","dateModified":"2023-04-28T08:43:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/grossesse\/temoignage-grossesse-test-du-diabete-gestationnel.html"},"wordCount":888,"commentCount":0,"publisher":{"@id":"https:\/\/www.lesbridgets.com\/#organization"},"image":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/grossesse\/temoignage-grossesse-test-du-diabete-gestationnel.html#primaryimage"},"thumbnailUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2023\/04\/temoignage-test-diabete-gestationnel.jpg","articleSection":["Grossesse"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/grossesse\/temoignage-grossesse-test-du-diabete-gestationnel.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/grossesse\/temoignage-grossesse-test-du-diabete-gestationnel.html","url":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/grossesse\/temoignage-grossesse-test-du-diabete-gestationnel.html","name":"T\u00e9moignage grossesse : test du diab\u00e8te gestationnel - Les Bridgets","isPartOf":{"@id":"https:\/\/www.lesbridgets.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/grossesse\/temoignage-grossesse-test-du-diabete-gestationnel.html#primaryimage"},"image":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/grossesse\/temoignage-grossesse-test-du-diabete-gestationnel.html#primaryimage"},"thumbnailUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2023\/04\/temoignage-test-diabete-gestationnel.jpg","datePublished":"2023-04-08T12:48:59+00:00","dateModified":"2023-04-28T08:43:05+00:00","description":"T\u00e9moignage sur mes deux heures de test de diab\u00e8te gestationnel \u00e0 42 ans. Les choses bonnes \u00e0 savoir : comment passer le temps...","breadcrumb":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/grossesse\/temoignage-grossesse-test-du-diabete-gestationnel.html#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/grossesse\/temoignage-grossesse-test-du-diabete-gestationnel.html"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/grossesse\/temoignage-grossesse-test-du-diabete-gestationnel.html#primaryimage","url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2023\/04\/temoignage-test-diabete-gestationnel.jpg","contentUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2023\/04\/temoignage-test-diabete-gestationnel.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/grossesse\/temoignage-grossesse-test-du-diabete-gestationnel.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Les Bridgets","item":"https:\/\/www.lesbridgets.com\/"},{"@type":"ListItem","position":2,"name":"Conseils sur l'amour, le couple &amp; les c\u00e9libataires","item":"https:\/\/www.lesbridgets.com\/index.php\/category\/conseils-relations"},{"@type":"ListItem","position":3,"name":"Grossesse","item":"https:\/\/www.lesbridgets.com\/index.php\/category\/conseils-relations\/grossesse"},{"@type":"ListItem","position":4,"name":"T\u00e9moignage grossesse : test du diab\u00e8te gestationnel"}]},{"@type":"WebSite","@id":"https:\/\/www.lesbridgets.com\/#website","url":"https:\/\/www.lesbridgets.com\/","name":"Les Bridgets","description":"R\u00e9f\u00e9rences et r\u00e9flexions sur nos relations","publisher":{"@id":"https:\/\/www.lesbridgets.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lesbridgets.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lesbridgets.com\/#organization","name":"Les Bridgets","url":"https:\/\/www.lesbridgets.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2022\/07\/cropped-logo-3-lesbridgets.png","contentUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2022\/07\/cropped-logo-3-lesbridgets.png","width":251,"height":59,"caption":"Les Bridgets"},"image":{"@id":"https:\/\/www.lesbridgets.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Les.Bridgets","https:\/\/x.com\/les_bridgets"]},{"@type":"Person","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/person\/82a31c27ae0ddd23ee59e1e2ac5713ba","name":"Bridget","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","caption":"Bridget"}}]}},"modified_by":"Bridget","_links":{"self":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/256498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/comments?post=256498"}],"version-history":[{"count":11,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/256498\/revisions"}],"predecessor-version":[{"id":256513,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/256498\/revisions\/256513"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/media\/256501"}],"wp:attachment":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/media?parent=256498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/categories?post=256498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/tags?post=256498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}