{"id":253225,"date":"2020-07-30T16:03:10","date_gmt":"2020-07-30T14:03:10","guid":{"rendered":"https:\/\/www.lesbridgets.com\/?p=253225"},"modified":"2020-07-30T16:47:17","modified_gmt":"2020-07-30T14:47:17","slug":"la-pma-accessible-et-remboursee-pour-les-femmes-seules-et-les-couples-de-femmes","status":"publish","type":"post","link":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/la-pma-accessible-et-remboursee-pour-les-femmes-seules-et-les-couples-de-femmes.html","title":{"rendered":"PMA accessible et rembours\u00e9e pour les femmes seules et les couples de femmes en France"},"content":{"rendered":"<p>Il y a 4 ans, on partageait <a href=\"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/faire-un-bebe-toute-seule-le-temoignage-de-deborah-33-ans.html\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">l&rsquo;histoire de D\u00e9borah qui avait fait des jumeaux toute seule<\/a> gr\u00e2ce \u00e0 une PMA (procr\u00e9ation m\u00e9dicalement assist\u00e9e) en Espagne. Depuis vous avez \u00e9t\u00e9 des milliers \u00e0 \u00e9couter son t\u00e9moignage audio et des dizaines \u00e0 avoir demand\u00e9 en message priv\u00e9 le contact de sa clinique pour aller vous aussi faire un enfant seul \u00e0 l&rsquo;\u00e9tranger.<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/4kD50HLOqJQ\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Ce mercredi 29 juillet 2020 comme l&rsquo;avait promis Emmanuel Macron lors de sa campagne, un projet de loi en faveur de l&rsquo;article premier du projet de loi de bio\u00e9thique a \u00e9t\u00e9 vot\u00e9. C&rsquo;est \u00e0 dire qu&rsquo;une femme seule, c\u00e9libataire ainsi que les couples de femmes homosexuelles pourront avoir recours \u00e0 la PMA rembours\u00e9e par la s\u00e9curit\u00e9 sociale.<\/p>\n<p>Cette loi devrait aboutir prochainement, nous attendons donc avec impatience sa date de mise en application.<\/p>\n<h2>Quel est l&rsquo;\u00e2ge limite d&rsquo;une femme pour une PMA en france ?<\/h2>\n<p>ll n&rsquo;y a pas d&rsquo;\u00e2ge limite\u00a0strictement fix\u00e9 pour b\u00e9n\u00e9ficier d&rsquo;une\u00a0PMA. Toutefois l&rsquo;assurance maladie prend en charge la PMA (\u00e0 100%) \u00e0 condition que la femme n&rsquo;ait pas d\u00e9pass\u00e9 les 43 ans.<\/p>\n<p>A suivre sur le <a href=\"https:\/\/www.legifrance.gouv.fr\/affichLoiPreparation.do?idDocument=JORFDOLE000038811571&amp;type=general&amp;typeLoi=proj&amp;legislature=15\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">site du gouvernement<\/a> (on mettra \u00e0 jour cet article des qu&rsquo;on en saura plus)<\/p>\n<h2>Comment faire une PMA en France ?<\/h2>\n<p>Comme le font depuis toujours les couples h\u00e9t\u00e9rosexuels, il suffira de se rapprocher de son gyn\u00e9cologue qui pourra lui nous prescrire les diff\u00e9rents examens et notamment le traitement pour la stimulation hormonale.<\/p>\n<p>Pour rappel : depuis des ann\u00e9es des femmes font des aller\/retours en Espagne et en Belgique (majoritairement) pour avoir le droit d&rsquo;\u00eatre m\u00e8re.<br \/>\nEt seulement celles qui avaient la possibilit\u00e9 de d\u00e9penser des milliers d&rsquo;euros quand tout se passait bien. Car si \u00e7a ne marchait pas la premi\u00e8re fois c&rsquo;\u00e9tait ces quelques milliers d&rsquo;euros qu&rsquo;il fallait d\u00e9penser \u00e0 nouveau.<\/p>\n<h2>Pour ceux qui se demandent si les femmes vont se passer d&rsquo;homme pour faire des enfants ?<\/h2>\n<p>Peu de femmes r\u00eavent de faire un enfant seul mais \u00e0 d\u00e9faut d&rsquo;avoir trouv\u00e9 un homme qui veuille en faire un, elle pourront tenter de vivre leur d\u00e9sir de maternit\u00e9.<\/p>\n<p>D\u00e9j\u00e0 33 ans avant cette loi, Jean Jacques Goldman d\u00e9diait une chanson \u00e0 une femme qui a fait un b\u00e9b\u00e9 toute seule :<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/zuNmzTLwjcc\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il y a 4 ans, on partageait l&rsquo;histoire de D\u00e9borah qui avait fait des jumeaux toute seule gr\u00e2ce \u00e0 une PMA (procr\u00e9ation m\u00e9dicalement assist\u00e9e) en&hellip; <\/p>\n","protected":false},"author":2,"featured_media":253227,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"om_disable_all_campaigns":false,"_lmt_disableupdate":"no","_lmt_disable":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[7],"tags":[443,415,1092,1366],"class_list":["post-253225","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-celibataire","tag-femme-seule","tag-grossesse","tag-maternite","tag-pma"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PMA accessible et rembours\u00e9e pour les femmes seules et les couples de femmes en France - Les Bridgets<\/title>\n<meta name=\"description\" content=\"Loi PMA pour toutes en France : Quel est l&#039;\u00e2ge limite d&#039;une femme pour une PMA en france ? Comment faire une procr\u00e9ation m\u00e9dicalement assist\u00e9e en France ?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/la-pma-accessible-et-remboursee-pour-les-femmes-seules-et-les-couples-de-femmes.html\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PMA accessible et rembours\u00e9e pour les femmes seules et les couples de femmes en France - Les Bridgets\" \/>\n<meta property=\"og:description\" content=\"Loi PMA pour toutes en France : Quel est l&#039;\u00e2ge limite d&#039;une femme pour une PMA en france ? Comment faire une procr\u00e9ation m\u00e9dicalement assist\u00e9e en France ?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/la-pma-accessible-et-remboursee-pour-les-femmes-seules-et-les-couples-de-femmes.html\" \/>\n<meta property=\"og:site_name\" content=\"Les Bridgets\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Les.Bridgets\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-30T14:03:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-30T14:47:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2020\/07\/pma-france-femme-seule.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"733\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bridget\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@les_bridgets\" \/>\n<meta name=\"twitter:site\" content=\"@les_bridgets\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bridget\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/celibataire\\\/la-pma-accessible-et-remboursee-pour-les-femmes-seules-et-les-couples-de-femmes.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/celibataire\\\/la-pma-accessible-et-remboursee-pour-les-femmes-seules-et-les-couples-de-femmes.html\"},\"author\":{\"name\":\"Bridget\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/person\\\/82a31c27ae0ddd23ee59e1e2ac5713ba\"},\"headline\":\"PMA accessible et rembours\u00e9e pour les femmes seules et les couples de femmes en France\",\"datePublished\":\"2020-07-30T14:03:10+00:00\",\"dateModified\":\"2020-07-30T14:47:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/celibataire\\\/la-pma-accessible-et-remboursee-pour-les-femmes-seules-et-les-couples-de-femmes.html\"},\"wordCount\":408,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/celibataire\\\/la-pma-accessible-et-remboursee-pour-les-femmes-seules-et-les-couples-de-femmes.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/pma-france-femme-seule.jpg\",\"keywords\":[\"femme seule\",\"grossesse\",\"maternit\u00e9\",\"pma\"],\"articleSection\":[\"Etre c\u00e9libataire - vivre seule\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/celibataire\\\/la-pma-accessible-et-remboursee-pour-les-femmes-seules-et-les-couples-de-femmes.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/celibataire\\\/la-pma-accessible-et-remboursee-pour-les-femmes-seules-et-les-couples-de-femmes.html\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/celibataire\\\/la-pma-accessible-et-remboursee-pour-les-femmes-seules-et-les-couples-de-femmes.html\",\"name\":\"PMA accessible et rembours\u00e9e pour les femmes seules et les couples de femmes en France - Les Bridgets\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/celibataire\\\/la-pma-accessible-et-remboursee-pour-les-femmes-seules-et-les-couples-de-femmes.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/celibataire\\\/la-pma-accessible-et-remboursee-pour-les-femmes-seules-et-les-couples-de-femmes.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/pma-france-femme-seule.jpg\",\"datePublished\":\"2020-07-30T14:03:10+00:00\",\"dateModified\":\"2020-07-30T14:47:17+00:00\",\"description\":\"Loi PMA pour toutes en France : Quel est l'\u00e2ge limite d'une femme pour une PMA en france ? Comment faire une procr\u00e9ation m\u00e9dicalement assist\u00e9e en France ?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/celibataire\\\/la-pma-accessible-et-remboursee-pour-les-femmes-seules-et-les-couples-de-femmes.html#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/celibataire\\\/la-pma-accessible-et-remboursee-pour-les-femmes-seules-et-les-couples-de-femmes.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/celibataire\\\/la-pma-accessible-et-remboursee-pour-les-femmes-seules-et-les-couples-de-femmes.html#primaryimage\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/pma-france-femme-seule.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/pma-france-femme-seule.jpg\",\"width\":1200,\"height\":733,\"caption\":\"ventre d'une femme enceinte qui se touche le ventre\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/celibataire\\\/la-pma-accessible-et-remboursee-pour-les-femmes-seules-et-les-couples-de-femmes.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Les Bridgets\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conseils sur l'amour, le couple &amp; les c\u00e9libataires\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/category\\\/conseils-relations\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Etre c\u00e9libataire - vivre seule\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/category\\\/conseils-relations\\\/celibataire\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"PMA accessible et rembours\u00e9e pour les femmes seules et les couples de femmes en France\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#website\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/\",\"name\":\"Les Bridgets\",\"description\":\"R\u00e9f\u00e9rences et r\u00e9flexions sur nos relations\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lesbridgets.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\",\"name\":\"Les Bridgets\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo-3-lesbridgets.png\",\"contentUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo-3-lesbridgets.png\",\"width\":251,\"height\":59,\"caption\":\"Les Bridgets\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Les.Bridgets\",\"https:\\\/\\\/x.com\\\/les_bridgets\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/person\\\/82a31c27ae0ddd23ee59e1e2ac5713ba\",\"name\":\"Bridget\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"caption\":\"Bridget\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PMA accessible et rembours\u00e9e pour les femmes seules et les couples de femmes en France - Les Bridgets","description":"Loi PMA pour toutes en France : Quel est l'\u00e2ge limite d'une femme pour une PMA en france ? Comment faire une procr\u00e9ation m\u00e9dicalement assist\u00e9e en France ?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/la-pma-accessible-et-remboursee-pour-les-femmes-seules-et-les-couples-de-femmes.html","og_locale":"fr_FR","og_type":"article","og_title":"PMA accessible et rembours\u00e9e pour les femmes seules et les couples de femmes en France - Les Bridgets","og_description":"Loi PMA pour toutes en France : Quel est l'\u00e2ge limite d'une femme pour une PMA en france ? Comment faire une procr\u00e9ation m\u00e9dicalement assist\u00e9e en France ?","og_url":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/la-pma-accessible-et-remboursee-pour-les-femmes-seules-et-les-couples-de-femmes.html","og_site_name":"Les Bridgets","article_publisher":"https:\/\/www.facebook.com\/Les.Bridgets","article_published_time":"2020-07-30T14:03:10+00:00","article_modified_time":"2020-07-30T14:47:17+00:00","og_image":[{"width":1200,"height":733,"url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2020\/07\/pma-france-femme-seule.jpg","type":"image\/jpeg"}],"author":"Bridget","twitter_card":"summary_large_image","twitter_creator":"@les_bridgets","twitter_site":"@les_bridgets","twitter_misc":{"\u00c9crit par":"Bridget","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/la-pma-accessible-et-remboursee-pour-les-femmes-seules-et-les-couples-de-femmes.html#article","isPartOf":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/la-pma-accessible-et-remboursee-pour-les-femmes-seules-et-les-couples-de-femmes.html"},"author":{"name":"Bridget","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/person\/82a31c27ae0ddd23ee59e1e2ac5713ba"},"headline":"PMA accessible et rembours\u00e9e pour les femmes seules et les couples de femmes en France","datePublished":"2020-07-30T14:03:10+00:00","dateModified":"2020-07-30T14:47:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/la-pma-accessible-et-remboursee-pour-les-femmes-seules-et-les-couples-de-femmes.html"},"wordCount":408,"commentCount":0,"publisher":{"@id":"https:\/\/www.lesbridgets.com\/#organization"},"image":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/la-pma-accessible-et-remboursee-pour-les-femmes-seules-et-les-couples-de-femmes.html#primaryimage"},"thumbnailUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2020\/07\/pma-france-femme-seule.jpg","keywords":["femme seule","grossesse","maternit\u00e9","pma"],"articleSection":["Etre c\u00e9libataire - vivre seule"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/la-pma-accessible-et-remboursee-pour-les-femmes-seules-et-les-couples-de-femmes.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/la-pma-accessible-et-remboursee-pour-les-femmes-seules-et-les-couples-de-femmes.html","url":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/la-pma-accessible-et-remboursee-pour-les-femmes-seules-et-les-couples-de-femmes.html","name":"PMA accessible et rembours\u00e9e pour les femmes seules et les couples de femmes en France - Les Bridgets","isPartOf":{"@id":"https:\/\/www.lesbridgets.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/la-pma-accessible-et-remboursee-pour-les-femmes-seules-et-les-couples-de-femmes.html#primaryimage"},"image":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/la-pma-accessible-et-remboursee-pour-les-femmes-seules-et-les-couples-de-femmes.html#primaryimage"},"thumbnailUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2020\/07\/pma-france-femme-seule.jpg","datePublished":"2020-07-30T14:03:10+00:00","dateModified":"2020-07-30T14:47:17+00:00","description":"Loi PMA pour toutes en France : Quel est l'\u00e2ge limite d'une femme pour une PMA en france ? Comment faire une procr\u00e9ation m\u00e9dicalement assist\u00e9e en France ?","breadcrumb":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/la-pma-accessible-et-remboursee-pour-les-femmes-seules-et-les-couples-de-femmes.html#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/la-pma-accessible-et-remboursee-pour-les-femmes-seules-et-les-couples-de-femmes.html"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/la-pma-accessible-et-remboursee-pour-les-femmes-seules-et-les-couples-de-femmes.html#primaryimage","url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2020\/07\/pma-france-femme-seule.jpg","contentUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2020\/07\/pma-france-femme-seule.jpg","width":1200,"height":733,"caption":"ventre d'une femme enceinte qui se touche le ventre"},{"@type":"BreadcrumbList","@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/la-pma-accessible-et-remboursee-pour-les-femmes-seules-et-les-couples-de-femmes.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Les Bridgets","item":"https:\/\/www.lesbridgets.com\/"},{"@type":"ListItem","position":2,"name":"Conseils sur l'amour, le couple &amp; les c\u00e9libataires","item":"https:\/\/www.lesbridgets.com\/index.php\/category\/conseils-relations"},{"@type":"ListItem","position":3,"name":"Etre c\u00e9libataire - vivre seule","item":"https:\/\/www.lesbridgets.com\/index.php\/category\/conseils-relations\/celibataire"},{"@type":"ListItem","position":4,"name":"PMA accessible et rembours\u00e9e pour les femmes seules et les couples de femmes en France"}]},{"@type":"WebSite","@id":"https:\/\/www.lesbridgets.com\/#website","url":"https:\/\/www.lesbridgets.com\/","name":"Les Bridgets","description":"R\u00e9f\u00e9rences et r\u00e9flexions sur nos relations","publisher":{"@id":"https:\/\/www.lesbridgets.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lesbridgets.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lesbridgets.com\/#organization","name":"Les Bridgets","url":"https:\/\/www.lesbridgets.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2022\/07\/cropped-logo-3-lesbridgets.png","contentUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2022\/07\/cropped-logo-3-lesbridgets.png","width":251,"height":59,"caption":"Les Bridgets"},"image":{"@id":"https:\/\/www.lesbridgets.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Les.Bridgets","https:\/\/x.com\/les_bridgets"]},{"@type":"Person","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/person\/82a31c27ae0ddd23ee59e1e2ac5713ba","name":"Bridget","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","caption":"Bridget"}}]}},"modified_by":"Bridget","_links":{"self":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/253225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/comments?post=253225"}],"version-history":[{"count":14,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/253225\/revisions"}],"predecessor-version":[{"id":253240,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/253225\/revisions\/253240"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/media\/253227"}],"wp:attachment":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/media?parent=253225"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/categories?post=253225"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/tags?post=253225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}