{"id":249679,"date":"2019-11-30T23:23:04","date_gmt":"2019-11-30T22:23:04","guid":{"rendered":"https:\/\/www.lesbridgets.com\/?p=249679"},"modified":"2020-08-24T22:06:42","modified_gmt":"2020-08-24T20:06:42","slug":"que-faire-a-noel-quand-on-est-tout-seul","status":"publish","type":"post","link":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/que-faire-a-noel-quand-on-est-tout-seul.html","title":{"rendered":"Que faire \u00e0 No\u00ebl quand on est tout seul ?"},"content":{"rendered":"<p>Expatriation, m\u00e9sentente dans les familles, famille absente, c\u00e9libataire, il y a de nombreuses raisons pour lesquelles de plus en plus de personnes se retrouvent plus ou moins par choix, seul \u00e0 No\u00ebl.<\/p>\n<p>Voici une petite liste de choses \u00e0 faire pour ceux qui sont \u00e0 court d&rsquo;id\u00e9es le soir et\/ou le jour de No\u00ebl :<\/p>\n<ul>\n<li>\n<h2>Aider les autres avec d&rsquo;autres<\/h2>\n<\/li>\n<\/ul>\n<p>Proposer votre temps \u00e0 des associations le jour de No\u00ebl. L&rsquo;id\u00e9al est de s&rsquo;y prendre assez t\u00f4t.<br \/>\nVoici quelques sites pour trouver des missions le jour de no\u00ebl :&nbsp; <a href=\"http:\/\/www.tousbenevoles.org\/\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">tousbenevoles.org<\/a>,&nbsp;<a href=\"http:\/\/www.francebenevolat.org\/\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">francebenevolat.org<\/a> et <a href=\"http:\/\/www.francebenevolat.org\/\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">je m&rsquo;engage<\/a> recensent et classent les missions disponibles ces soirs-l\u00e0.<br \/>\nCertaines organisent des repas de no\u00ebl et ont besoin de b\u00e9n\u00e9voles pour pr\u00e9parer le repas au plus d\u00e9munis comme l&rsquo;association <a href=\"http:\/\/www.autremonde.org\/\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">Autremonde.org<\/a>. Vous pouvez aussi distribuer des repas avec l&rsquo;association Les petits fr\u00e8res des pauvres.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-249643 size-large aligncenter\" src=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/12\/avis-film-last-christmas-1024x679.png\" alt=\"Un partie de l'affiche de last chritmas avec Emilia Clarke en lutin verre et henry golding\" width=\"640\" height=\"424\" srcset=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/12\/avis-film-last-christmas-1024x679.png 1024w, https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/12\/avis-film-last-christmas-300x200.png 300w, https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/12\/avis-film-last-christmas-768x509.png 768w, https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/12\/avis-film-last-christmas.png 1200w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<ul>\n<li>\n<h2>Aller au cin\u00e9ma ou voir un spectacle<\/h2>\n<\/li>\n<\/ul>\n<p>En profiter pour se faire un spectacle que vous avez choisi. De nombreux artistes jouent le 24 au soir et les cin\u00e9mas restent ouverts.<br \/>\nSelon le film que vous choisissez, attendez vous \u00e0 croiser pas mal de famille pour qui c&rsquo;est un rituel de No\u00ebl<\/p>\n<p><!-- START ADVERTISER: Fnac Spectacles FR from awin.com --><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.awin1.com\/cread.php?s=2500850&amp;v=12494&amp;q=360250&amp;r=290297\"><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.awin1.com\/cshow.php?s=2500850&amp;v=12494&amp;q=360250&amp;r=290297\" border=\"0\"><\/a><!-- END ADVERTISER: Fnac Spectacles FR from awin.com --><\/p>\n<p style=\"text-align: center;\"><a class=\"fasc-button fasc-size-medium fasc-type-flat fasc-rounded-medium\" style=\"background-color: #f00e16; color: #ffffff;\" target=\"_blank\" rel=\"nofollow noopener noreferrer\" href=\"https:\/\/www.awin1.com\/cread.php?s=2500850&amp;v=12494&amp;q=360250&amp;r=290297\">Voir les spectacles dispo<\/a><\/p>\n<ul>\n<li>\n<h2>Assister \u00e0 un concert religieux (gospel&#8230;)<\/h2>\n<\/li>\n<\/ul>\n<p>Beaucoup d&rsquo;\u00e9glises et autres organismes religieux notamment dans les grandes villes proposent des messes, c\u00e9r\u00e9monies de No\u00ebl. Renseignez vous sur les sites de la mairie ou aupr\u00e8s des \u00e9glises pr\u00e8s de chez vous.<br \/>\nL&rsquo;occasion d&rsquo;assister une fois dans sa vie \u00e0 la fameuse messe de minuit.<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/Pr7wcHTzcTg\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<ul>\n<li>\n<h2>Prendre soin de soi<\/h2>\n<\/li>\n<\/ul>\n<p>Test\u00e9 et approuv\u00e9, profiter de cette soir\u00e9e o\u00f9 vous \u00eates seul \u00e0 No\u00ebl pour vous faire plaisir. Personne pour vous imposer les hu\u00eetres ou le film de No\u00ebl. Vous faites ce que vous voulez !<br \/>\nNetflix ou <a href=\"https:\/\/www.amazon.fr\/amazonprime\/ref=as_li_ss_tl?ie=UTF8&amp;linkCode=ll2&amp;tag=lesbricomcomp-21&amp;linkId=c960d9fa14daff10d7eaaf2fb88146bf&amp;language=fr_FR\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">Amazon Prime<\/a>, chocolat chaud, p\u00e2tisserie de ouf, pizza bien fat&#8230; tout est possible. On est jamais mieux servi que par soi-m\u00eame.<br \/>\nC\u00e9l\u00e9brez le fait d&rsquo;\u00e9chapper aux conflits familiaux et de ne plus c\u00f4toyer des heures cette belle-soeur que vous ne pouviez pas blairer.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-248040 size-full aligncenter\" src=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2008\/12\/celibataire-noel-statistiques.jpg\" alt=\"\" width=\"800\" height=\"533\" srcset=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2008\/12\/celibataire-noel-statistiques.jpg 800w, https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2008\/12\/celibataire-noel-statistiques-300x200.jpg 300w, https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2008\/12\/celibataire-noel-statistiques-768x512.jpg 768w, https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2008\/12\/celibataire-noel-statistiques-600x400.jpg 600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<ul>\n<li>\n<h2>Utiliser onvasortir pour sortir \u00e0 plusieurs<\/h2>\n<\/li>\n<\/ul>\n<p>Le site <a href=\"https:\/\/www.onvasortir.com\/\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">onvasortir.com<\/a> est valable dans toute la France o\u00f9 vous trouverez les \u00e9v\u00e8nements qui sont organis\u00e9s pr\u00e8s de chez vous et auxquels vous pouvez participer avec d&rsquo;autres personnes.<br \/>\nEt si le coeur vous en dit, vous pouvez m\u00eame en organiser un.<\/p>\n<p>Les sites de rencontres comme <a href=\"https:\/\/tracking.publicidees.com\/clic.php?promoid=55044&amp;progid=2167&amp;partid=41407\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">Meetic<\/a> seront tout comme vous, remplis de c\u00e9libataires connect\u00e9s ce jour l\u00e0. Profitez en.<\/p>\n<ul>\n<li>\n<h2>Partir en voyage seul \u00e0 No\u00ebl<\/h2>\n<\/li>\n<\/ul>\n<p>Lucie nous en parlait dans une interview audio, elle a fait plusieurs fois No\u00ebl seule \u00e0 l&rsquo;\u00e9tranger loin de sa famille. Si vous n&rsquo;arrivez pas \u00e0 vous d\u00e9cider sur l&rsquo;endroit, retrouver toutes <a href=\"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/soirees-voyages-rencontres\/celibataire-voici-des-idees-de-destinations-ou-voyager-seul-a-noel.html\">nos id\u00e9es de destinations o\u00f9 voyager seul \u00e0 no\u00ebl<\/a>.<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/hp67gmuxYh0\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Avec le <a href=\"https:\/\/clk.tradedoubler.com\/click?p=224458&amp;a=2003317&amp;g=24012386\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">site de r\u00e9servation d&rsquo;avion Skyscanner<\/a>, vous pouvez trouver un vol qui part selon la p\u00e9riode choisie (par exemple entre le 22 d\u00e9cembre et le 24 d\u00e9cembre) et \u00e0 la derni\u00e8re minute (la veille de votre vol) au tarif le moins cher.<br \/>\nSuper pratique quand on sait pas trop o\u00f9 aller.<\/p>\n<p>Si votre budget n&rsquo;est pas \u00e9norme, les <a href=\"https:\/\/clk.tradedoubler.com\/click?p=282940&amp;a=2003317&amp;g=24347774\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">trains SNCF \u00e0 petits prix en derni\u00e8res minutes<\/a> font tr\u00e8s bien l&rsquo;affaire aussi et votre bilan carbone ne s&rsquo;en portera que mieux.<\/p>\n<p>Et joyeux no\u00ebl !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Expatriation, m\u00e9sentente dans les familles, famille absente, c\u00e9libataire, il y a de nombreuses raisons pour lesquelles de plus en plus de personnes se retrouvent plus&hellip; <\/p>\n","protected":false},"author":2,"featured_media":249680,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"om_disable_all_campaigns":false,"_lmt_disableupdate":"no","_lmt_disable":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-249679","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-celibataire"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Que faire \u00e0 No\u00ebl quand on est tout seul ? - Les Bridgets<\/title>\n<meta name=\"description\" content=\"\u00a0Les gens sont de plus en seul \u00e0 no\u00ebl. Voici une petite liste de choses \u00e0 faire pour ceux qui sont \u00e0 court d&#039;id\u00e9es le soir de No\u00ebl.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/que-faire-a-noel-quand-on-est-tout-seul.html\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Que faire \u00e0 No\u00ebl quand on est tout seul ? - Les Bridgets\" \/>\n<meta property=\"og:description\" content=\"\u00a0Les gens sont de plus en seul \u00e0 no\u00ebl. Voici une petite liste de choses \u00e0 faire pour ceux qui sont \u00e0 court d&#039;id\u00e9es le soir de No\u00ebl.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/que-faire-a-noel-quand-on-est-tout-seul.html\" \/>\n<meta property=\"og:site_name\" content=\"Les Bridgets\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Les.Bridgets\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-30T22:23:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-24T20:06:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/12\/que-faire-tout-seul-noel.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Bridget\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@les_bridgets\" \/>\n<meta name=\"twitter:site\" content=\"@les_bridgets\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bridget\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/celibataire\\\/que-faire-a-noel-quand-on-est-tout-seul.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/celibataire\\\/que-faire-a-noel-quand-on-est-tout-seul.html\"},\"author\":{\"name\":\"Bridget\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/person\\\/82a31c27ae0ddd23ee59e1e2ac5713ba\"},\"headline\":\"Que faire \u00e0 No\u00ebl quand on est tout seul ?\",\"datePublished\":\"2019-11-30T22:23:04+00:00\",\"dateModified\":\"2020-08-24T20:06:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/celibataire\\\/que-faire-a-noel-quand-on-est-tout-seul.html\"},\"wordCount\":592,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/celibataire\\\/que-faire-a-noel-quand-on-est-tout-seul.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/que-faire-tout-seul-noel.png\",\"articleSection\":[\"Etre c\u00e9libataire - vivre seule\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/celibataire\\\/que-faire-a-noel-quand-on-est-tout-seul.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/celibataire\\\/que-faire-a-noel-quand-on-est-tout-seul.html\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/celibataire\\\/que-faire-a-noel-quand-on-est-tout-seul.html\",\"name\":\"Que faire \u00e0 No\u00ebl quand on est tout seul ? - Les Bridgets\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/celibataire\\\/que-faire-a-noel-quand-on-est-tout-seul.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/celibataire\\\/que-faire-a-noel-quand-on-est-tout-seul.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/que-faire-tout-seul-noel.png\",\"datePublished\":\"2019-11-30T22:23:04+00:00\",\"dateModified\":\"2020-08-24T20:06:42+00:00\",\"description\":\"\u00a0Les gens sont de plus en seul \u00e0 no\u00ebl. Voici une petite liste de choses \u00e0 faire pour ceux qui sont \u00e0 court d'id\u00e9es le soir de No\u00ebl.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/celibataire\\\/que-faire-a-noel-quand-on-est-tout-seul.html#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/celibataire\\\/que-faire-a-noel-quand-on-est-tout-seul.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/celibataire\\\/que-faire-a-noel-quand-on-est-tout-seul.html#primaryimage\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/que-faire-tout-seul-noel.png\",\"contentUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/que-faire-tout-seul-noel.png\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/celibataire\\\/que-faire-a-noel-quand-on-est-tout-seul.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Les Bridgets\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conseils sur l'amour, le couple &amp; les c\u00e9libataires\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/category\\\/conseils-relations\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Etre c\u00e9libataire - vivre seule\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/category\\\/conseils-relations\\\/celibataire\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Que faire \u00e0 No\u00ebl quand on est tout seul ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#website\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/\",\"name\":\"Les Bridgets\",\"description\":\"R\u00e9f\u00e9rences et r\u00e9flexions sur nos relations\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lesbridgets.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\",\"name\":\"Les Bridgets\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo-3-lesbridgets.png\",\"contentUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo-3-lesbridgets.png\",\"width\":251,\"height\":59,\"caption\":\"Les Bridgets\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Les.Bridgets\",\"https:\\\/\\\/x.com\\\/les_bridgets\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/person\\\/82a31c27ae0ddd23ee59e1e2ac5713ba\",\"name\":\"Bridget\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"caption\":\"Bridget\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Que faire \u00e0 No\u00ebl quand on est tout seul ? - Les Bridgets","description":"\u00a0Les gens sont de plus en seul \u00e0 no\u00ebl. Voici une petite liste de choses \u00e0 faire pour ceux qui sont \u00e0 court d'id\u00e9es le soir de No\u00ebl.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/que-faire-a-noel-quand-on-est-tout-seul.html","og_locale":"fr_FR","og_type":"article","og_title":"Que faire \u00e0 No\u00ebl quand on est tout seul ? - Les Bridgets","og_description":"\u00a0Les gens sont de plus en seul \u00e0 no\u00ebl. Voici une petite liste de choses \u00e0 faire pour ceux qui sont \u00e0 court d'id\u00e9es le soir de No\u00ebl.","og_url":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/que-faire-a-noel-quand-on-est-tout-seul.html","og_site_name":"Les Bridgets","article_publisher":"https:\/\/www.facebook.com\/Les.Bridgets","article_published_time":"2019-11-30T22:23:04+00:00","article_modified_time":"2020-08-24T20:06:42+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/12\/que-faire-tout-seul-noel.png","type":"image\/png"}],"author":"Bridget","twitter_card":"summary_large_image","twitter_creator":"@les_bridgets","twitter_site":"@les_bridgets","twitter_misc":{"\u00c9crit par":"Bridget","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/que-faire-a-noel-quand-on-est-tout-seul.html#article","isPartOf":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/que-faire-a-noel-quand-on-est-tout-seul.html"},"author":{"name":"Bridget","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/person\/82a31c27ae0ddd23ee59e1e2ac5713ba"},"headline":"Que faire \u00e0 No\u00ebl quand on est tout seul ?","datePublished":"2019-11-30T22:23:04+00:00","dateModified":"2020-08-24T20:06:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/que-faire-a-noel-quand-on-est-tout-seul.html"},"wordCount":592,"commentCount":0,"publisher":{"@id":"https:\/\/www.lesbridgets.com\/#organization"},"image":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/que-faire-a-noel-quand-on-est-tout-seul.html#primaryimage"},"thumbnailUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/12\/que-faire-tout-seul-noel.png","articleSection":["Etre c\u00e9libataire - vivre seule"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/que-faire-a-noel-quand-on-est-tout-seul.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/que-faire-a-noel-quand-on-est-tout-seul.html","url":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/que-faire-a-noel-quand-on-est-tout-seul.html","name":"Que faire \u00e0 No\u00ebl quand on est tout seul ? - Les Bridgets","isPartOf":{"@id":"https:\/\/www.lesbridgets.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/que-faire-a-noel-quand-on-est-tout-seul.html#primaryimage"},"image":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/que-faire-a-noel-quand-on-est-tout-seul.html#primaryimage"},"thumbnailUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/12\/que-faire-tout-seul-noel.png","datePublished":"2019-11-30T22:23:04+00:00","dateModified":"2020-08-24T20:06:42+00:00","description":"\u00a0Les gens sont de plus en seul \u00e0 no\u00ebl. Voici une petite liste de choses \u00e0 faire pour ceux qui sont \u00e0 court d'id\u00e9es le soir de No\u00ebl.","breadcrumb":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/que-faire-a-noel-quand-on-est-tout-seul.html#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/que-faire-a-noel-quand-on-est-tout-seul.html"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/que-faire-a-noel-quand-on-est-tout-seul.html#primaryimage","url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/12\/que-faire-tout-seul-noel.png","contentUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/12\/que-faire-tout-seul-noel.png","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/que-faire-a-noel-quand-on-est-tout-seul.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Les Bridgets","item":"https:\/\/www.lesbridgets.com\/"},{"@type":"ListItem","position":2,"name":"Conseils sur l'amour, le couple &amp; les c\u00e9libataires","item":"https:\/\/www.lesbridgets.com\/index.php\/category\/conseils-relations"},{"@type":"ListItem","position":3,"name":"Etre c\u00e9libataire - vivre seule","item":"https:\/\/www.lesbridgets.com\/index.php\/category\/conseils-relations\/celibataire"},{"@type":"ListItem","position":4,"name":"Que faire \u00e0 No\u00ebl quand on est tout seul ?"}]},{"@type":"WebSite","@id":"https:\/\/www.lesbridgets.com\/#website","url":"https:\/\/www.lesbridgets.com\/","name":"Les Bridgets","description":"R\u00e9f\u00e9rences et r\u00e9flexions sur nos relations","publisher":{"@id":"https:\/\/www.lesbridgets.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lesbridgets.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lesbridgets.com\/#organization","name":"Les Bridgets","url":"https:\/\/www.lesbridgets.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2022\/07\/cropped-logo-3-lesbridgets.png","contentUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2022\/07\/cropped-logo-3-lesbridgets.png","width":251,"height":59,"caption":"Les Bridgets"},"image":{"@id":"https:\/\/www.lesbridgets.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Les.Bridgets","https:\/\/x.com\/les_bridgets"]},{"@type":"Person","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/person\/82a31c27ae0ddd23ee59e1e2ac5713ba","name":"Bridget","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","caption":"Bridget"}}]}},"modified_by":"Bridget","_links":{"self":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/249679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/comments?post=249679"}],"version-history":[{"count":22,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/249679\/revisions"}],"predecessor-version":[{"id":253760,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/249679\/revisions\/253760"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/media\/249680"}],"wp:attachment":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/media?parent=249679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/categories?post=249679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/tags?post=249679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}