{"id":247842,"date":"2019-06-03T14:55:36","date_gmt":"2019-06-03T12:55:36","guid":{"rendered":"https:\/\/www.lesbridgets.com\/?p=247842"},"modified":"2020-04-20T18:13:23","modified_gmt":"2020-04-20T16:13:23","slug":"rocketman-le-tres-bon-film-qui-fantasme-la-vie-d-elton-john","status":"publish","type":"post","link":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/rocketman-le-tres-bon-film-qui-fantasme-la-vie-d-elton-john.html","title":{"rendered":"Rocketman le tr\u00e8s bon film qui fantasme la vie d&rsquo;Elton John"},"content":{"rendered":"<p>Rocketman fait partie de ces films qui marquent et qu&rsquo;on a envie de recommander \u00e0 toutes les personnes que l&rsquo;on conna\u00eet ou presque. Il y a des dizaines de raisons d&rsquo;aller voir ce film et encore plus au cin\u00e9ma, on va essayer de les r\u00e9sumer ici :<\/p>\n<p>Si il n&rsquo;y avait qu&rsquo;un seul argument pour aller le Rocketman au cin\u00e9ma plut\u00f4t que sur votre ordinateur c&rsquo;est la musique.<\/p>\n<h2>Nous ne sommes pas fans d&rsquo;Elton John \u00e0 la base mais on en prend plein les oreilles et on verse pas mal de larmes.<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-247843 size-full aligncenter\" src=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/06\/elton-john-rocketman.png\" alt=\"\" width=\"800\" height=\"385\" srcset=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/06\/elton-john-rocketman.png 800w, https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/06\/elton-john-rocketman-300x144.png 300w, https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/06\/elton-john-rocketman-768x370.png 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Le talentueux acteur Taron Egerton chante sur plusieurs des musiques et porte des proth\u00e8ses dentaires pour avoir les dents \u00e9cart\u00e9es comme le chanteur.<\/p>\n<h2>La bande annonce de Rocketman<\/h2>\n<p>La plupart des musiques n&rsquo;ont pas \u00e9t\u00e9 cr\u00e9\u00e9es dans l&rsquo;ordre chronologique du film mais elles ont permis d&rsquo;illustrer des moments de la vie d&rsquo;Elton John.<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/OV0qslSFbfU\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<h2>Les d\u00e9cors et les costumes sont fous.<\/h2>\n<p>Taron Egerton en porte 10 dans le film. Certains ont \u00e9t\u00e9 invent\u00e9s sp\u00e9cialement pour le film comme celui le orange vif du diable.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-247857 size-full aligncenter\" src=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/06\/rocketman-costume-orange.png\" alt=\"Costume diable \u00e0 plume Rocketman\" width=\"800\" height=\"437\" srcset=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/06\/rocketman-costume-orange.png 800w, https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/06\/rocketman-costume-orange-300x164.png 300w, https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/06\/rocketman-costume-orange-768x420.png 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Si comme nous vous n&rsquo;avez pas \u00e0 remettre le visage de la maman d&rsquo;Elton John jou\u00e9e par Bryce Dallas Howard, c&rsquo;est elle dans le super \u00e9pisode de Black Mirror de la saison 3 o\u00f9 elle essaie d&rsquo;augmenter sa note pour se rendre au mariage d&rsquo;une copine d&rsquo;\u00e9cole.<\/p>\n<h2>Relation conflictuelle avec les parents ?<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-247844 size-full aligncenter\" src=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/06\/Taron-David-Egerton-elton-john.png\" alt=\"\" width=\"800\" height=\"407\" srcset=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/06\/Taron-David-Egerton-elton-john.png 800w, https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/06\/Taron-David-Egerton-elton-john-300x153.png 300w, https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/06\/Taron-David-Egerton-elton-john-768x391.png 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Rocketman est inspir\u00e9 de la vie d&rsquo;Elton John mais beaucoup des faits du film ont \u00e9t\u00e9 exag\u00e9r\u00e9s.<\/p>\n<blockquote><p>\u00ab\u00a0Elton John \u00e9tait en effet int\u00e9ress\u00e9 par une relecture fantasmatique de sa vie qui ne chercherait pas forc\u00e9ment \u00e0 raconter avec exactitude les \u00e9v\u00e9nements pass\u00e9s.\u00a0\u00bb<\/p><\/blockquote>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-247845 size-full aligncenter\" src=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/06\/BRYCE-DALLAS-HOWARD-rocketman.png\" alt=\"\" width=\"800\" height=\"383\" srcset=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/06\/BRYCE-DALLAS-HOWARD-rocketman.png 800w, https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/06\/BRYCE-DALLAS-HOWARD-rocketman-300x144.png 300w, https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/06\/BRYCE-DALLAS-HOWARD-rocketman-768x368.png 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>On ressort du film avec des questions en ayant verser plusieurs larmes. Qui sommes nous vraiment ? et Quel impact nos parents ont eu r\u00e9ellement sur nos choix de vie ?<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-247855 size-full aligncenter\" src=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/06\/elton-john-rocketman-film.png\" alt=\"\" width=\"800\" height=\"502\" srcset=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/06\/elton-john-rocketman-film.png 800w, https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/06\/elton-john-rocketman-film-300x188.png 300w, https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/06\/elton-john-rocketman-film-768x482.png 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Le film nous montre que lorsqu&rsquo;on ne sait pas ce que c&rsquo;est d&rsquo;\u00eatre aim\u00e9, difficile de faire le bon choix de partenaire.<\/p>\n<p>Au cin\u00e9ma en France depuis le 29 mai et on vous recommande fortement d&rsquo;y aller. Sachant qu&rsquo;il y a un peu de sc\u00e8nes de sexe \u00e0 vous de voir si vous souhaitez emmener les enfants mais on dirait pas avant 10\/11 ans.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rocketman fait partie de ces films qui marquent et qu&rsquo;on a envie de recommander \u00e0 toutes les personnes que l&rsquo;on conna\u00eet ou presque. Il y&hellip; <\/p>\n","protected":false},"author":2,"featured_media":247844,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"om_disable_all_campaigns":false,"_lmt_disableupdate":"no","_lmt_disable":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[28],"tags":[533,452],"class_list":["post-247842","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-films","tag-biopic","tag-film-depoque"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rocketman le tr\u00e8s bon film qui fantasme la vie d&#039;Elton John - Les Bridgets<\/title>\n<meta name=\"description\" content=\"Critique du film Rocketman sur la vie incroyable du c\u00e9l\u00e8bre chanteur anglais Elton John interpr\u00e9t\u00e9 par le talentueux acteur Taron Egerton.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/rocketman-le-tres-bon-film-qui-fantasme-la-vie-d-elton-john.html\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rocketman le tr\u00e8s bon film qui fantasme la vie d&#039;Elton John - Les Bridgets\" \/>\n<meta property=\"og:description\" content=\"Critique du film Rocketman sur la vie incroyable du c\u00e9l\u00e8bre chanteur anglais Elton John interpr\u00e9t\u00e9 par le talentueux acteur Taron Egerton.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/rocketman-le-tres-bon-film-qui-fantasme-la-vie-d-elton-john.html\" \/>\n<meta property=\"og:site_name\" content=\"Les Bridgets\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Les.Bridgets\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-03T12:55:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-20T16:13:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/06\/Taron-David-Egerton-elton-john.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"407\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Bridget\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@les_bridgets\" \/>\n<meta name=\"twitter:site\" content=\"@les_bridgets\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bridget\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/rocketman-le-tres-bon-film-qui-fantasme-la-vie-d-elton-john.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/rocketman-le-tres-bon-film-qui-fantasme-la-vie-d-elton-john.html\"},\"author\":{\"name\":\"Bridget\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/person\\\/82a31c27ae0ddd23ee59e1e2ac5713ba\"},\"headline\":\"Rocketman le tr\u00e8s bon film qui fantasme la vie d&rsquo;Elton John\",\"datePublished\":\"2019-06-03T12:55:36+00:00\",\"dateModified\":\"2020-04-20T16:13:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/rocketman-le-tres-bon-film-qui-fantasme-la-vie-d-elton-john.html\"},\"wordCount\":409,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/rocketman-le-tres-bon-film-qui-fantasme-la-vie-d-elton-john.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/Taron-David-Egerton-elton-john.png\",\"keywords\":[\"biopic\",\"film d'\u00e9poque\"],\"articleSection\":[\"Film\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/rocketman-le-tres-bon-film-qui-fantasme-la-vie-d-elton-john.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/rocketman-le-tres-bon-film-qui-fantasme-la-vie-d-elton-john.html\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/rocketman-le-tres-bon-film-qui-fantasme-la-vie-d-elton-john.html\",\"name\":\"Rocketman le tr\u00e8s bon film qui fantasme la vie d'Elton John - Les Bridgets\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/rocketman-le-tres-bon-film-qui-fantasme-la-vie-d-elton-john.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/rocketman-le-tres-bon-film-qui-fantasme-la-vie-d-elton-john.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/Taron-David-Egerton-elton-john.png\",\"datePublished\":\"2019-06-03T12:55:36+00:00\",\"dateModified\":\"2020-04-20T16:13:23+00:00\",\"description\":\"Critique du film Rocketman sur la vie incroyable du c\u00e9l\u00e8bre chanteur anglais Elton John interpr\u00e9t\u00e9 par le talentueux acteur Taron Egerton.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/rocketman-le-tres-bon-film-qui-fantasme-la-vie-d-elton-john.html#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/rocketman-le-tres-bon-film-qui-fantasme-la-vie-d-elton-john.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/rocketman-le-tres-bon-film-qui-fantasme-la-vie-d-elton-john.html#primaryimage\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/Taron-David-Egerton-elton-john.png\",\"contentUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/Taron-David-Egerton-elton-john.png\",\"width\":800,\"height\":407},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/rocketman-le-tres-bon-film-qui-fantasme-la-vie-d-elton-john.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Les Bridgets\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00e9f\u00e9rences sur le couple et le c\u00e9libat\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/category\\\/references\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Film\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/category\\\/references\\\/films\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Rocketman le tr\u00e8s bon film qui fantasme la vie d&rsquo;Elton John\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#website\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/\",\"name\":\"Les Bridgets\",\"description\":\"R\u00e9f\u00e9rences et r\u00e9flexions sur nos relations\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lesbridgets.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\",\"name\":\"Les Bridgets\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo-3-lesbridgets.png\",\"contentUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo-3-lesbridgets.png\",\"width\":251,\"height\":59,\"caption\":\"Les Bridgets\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Les.Bridgets\",\"https:\\\/\\\/x.com\\\/les_bridgets\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/person\\\/82a31c27ae0ddd23ee59e1e2ac5713ba\",\"name\":\"Bridget\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"caption\":\"Bridget\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rocketman le tr\u00e8s bon film qui fantasme la vie d'Elton John - Les Bridgets","description":"Critique du film Rocketman sur la vie incroyable du c\u00e9l\u00e8bre chanteur anglais Elton John interpr\u00e9t\u00e9 par le talentueux acteur Taron Egerton.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/rocketman-le-tres-bon-film-qui-fantasme-la-vie-d-elton-john.html","og_locale":"fr_FR","og_type":"article","og_title":"Rocketman le tr\u00e8s bon film qui fantasme la vie d'Elton John - Les Bridgets","og_description":"Critique du film Rocketman sur la vie incroyable du c\u00e9l\u00e8bre chanteur anglais Elton John interpr\u00e9t\u00e9 par le talentueux acteur Taron Egerton.","og_url":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/rocketman-le-tres-bon-film-qui-fantasme-la-vie-d-elton-john.html","og_site_name":"Les Bridgets","article_publisher":"https:\/\/www.facebook.com\/Les.Bridgets","article_published_time":"2019-06-03T12:55:36+00:00","article_modified_time":"2020-04-20T16:13:23+00:00","og_image":[{"width":800,"height":407,"url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/06\/Taron-David-Egerton-elton-john.png","type":"image\/png"}],"author":"Bridget","twitter_card":"summary_large_image","twitter_creator":"@les_bridgets","twitter_site":"@les_bridgets","twitter_misc":{"\u00c9crit par":"Bridget","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/rocketman-le-tres-bon-film-qui-fantasme-la-vie-d-elton-john.html#article","isPartOf":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/rocketman-le-tres-bon-film-qui-fantasme-la-vie-d-elton-john.html"},"author":{"name":"Bridget","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/person\/82a31c27ae0ddd23ee59e1e2ac5713ba"},"headline":"Rocketman le tr\u00e8s bon film qui fantasme la vie d&rsquo;Elton John","datePublished":"2019-06-03T12:55:36+00:00","dateModified":"2020-04-20T16:13:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/rocketman-le-tres-bon-film-qui-fantasme-la-vie-d-elton-john.html"},"wordCount":409,"commentCount":0,"publisher":{"@id":"https:\/\/www.lesbridgets.com\/#organization"},"image":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/rocketman-le-tres-bon-film-qui-fantasme-la-vie-d-elton-john.html#primaryimage"},"thumbnailUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/06\/Taron-David-Egerton-elton-john.png","keywords":["biopic","film d'\u00e9poque"],"articleSection":["Film"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.lesbridgets.com\/index.php\/references\/films\/rocketman-le-tres-bon-film-qui-fantasme-la-vie-d-elton-john.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/rocketman-le-tres-bon-film-qui-fantasme-la-vie-d-elton-john.html","url":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/rocketman-le-tres-bon-film-qui-fantasme-la-vie-d-elton-john.html","name":"Rocketman le tr\u00e8s bon film qui fantasme la vie d'Elton John - Les Bridgets","isPartOf":{"@id":"https:\/\/www.lesbridgets.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/rocketman-le-tres-bon-film-qui-fantasme-la-vie-d-elton-john.html#primaryimage"},"image":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/rocketman-le-tres-bon-film-qui-fantasme-la-vie-d-elton-john.html#primaryimage"},"thumbnailUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/06\/Taron-David-Egerton-elton-john.png","datePublished":"2019-06-03T12:55:36+00:00","dateModified":"2020-04-20T16:13:23+00:00","description":"Critique du film Rocketman sur la vie incroyable du c\u00e9l\u00e8bre chanteur anglais Elton John interpr\u00e9t\u00e9 par le talentueux acteur Taron Egerton.","breadcrumb":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/rocketman-le-tres-bon-film-qui-fantasme-la-vie-d-elton-john.html#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lesbridgets.com\/index.php\/references\/films\/rocketman-le-tres-bon-film-qui-fantasme-la-vie-d-elton-john.html"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/rocketman-le-tres-bon-film-qui-fantasme-la-vie-d-elton-john.html#primaryimage","url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/06\/Taron-David-Egerton-elton-john.png","contentUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/06\/Taron-David-Egerton-elton-john.png","width":800,"height":407},{"@type":"BreadcrumbList","@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/rocketman-le-tres-bon-film-qui-fantasme-la-vie-d-elton-john.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Les Bridgets","item":"https:\/\/www.lesbridgets.com\/"},{"@type":"ListItem","position":2,"name":"R\u00e9f\u00e9rences sur le couple et le c\u00e9libat","item":"https:\/\/www.lesbridgets.com\/index.php\/category\/references"},{"@type":"ListItem","position":3,"name":"Film","item":"https:\/\/www.lesbridgets.com\/index.php\/category\/references\/films"},{"@type":"ListItem","position":4,"name":"Rocketman le tr\u00e8s bon film qui fantasme la vie d&rsquo;Elton John"}]},{"@type":"WebSite","@id":"https:\/\/www.lesbridgets.com\/#website","url":"https:\/\/www.lesbridgets.com\/","name":"Les Bridgets","description":"R\u00e9f\u00e9rences et r\u00e9flexions sur nos relations","publisher":{"@id":"https:\/\/www.lesbridgets.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lesbridgets.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lesbridgets.com\/#organization","name":"Les Bridgets","url":"https:\/\/www.lesbridgets.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2022\/07\/cropped-logo-3-lesbridgets.png","contentUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2022\/07\/cropped-logo-3-lesbridgets.png","width":251,"height":59,"caption":"Les Bridgets"},"image":{"@id":"https:\/\/www.lesbridgets.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Les.Bridgets","https:\/\/x.com\/les_bridgets"]},{"@type":"Person","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/person\/82a31c27ae0ddd23ee59e1e2ac5713ba","name":"Bridget","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","caption":"Bridget"}}]}},"modified_by":"Bridget","_links":{"self":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/247842","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/comments?post=247842"}],"version-history":[{"count":14,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/247842\/revisions"}],"predecessor-version":[{"id":251835,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/247842\/revisions\/251835"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/media\/247844"}],"wp:attachment":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/media?parent=247842"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/categories?post=247842"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/tags?post=247842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}