{"id":247236,"date":"2019-05-04T11:22:43","date_gmt":"2019-05-04T09:22:43","guid":{"rendered":"https:\/\/www.lesbridgets.com\/?p=247236"},"modified":"2025-04-24T20:52:11","modified_gmt":"2025-04-24T18:52:11","slug":"la-serie-mme-maisel-femme-fabuleuse-le-feminisme-dans-les-annees-50","status":"publish","type":"post","link":"https:\/\/www.lesbridgets.com\/index.php\/references\/serie-couple-celibataire\/la-serie-mme-maisel-femme-fabuleuse-le-feminisme-dans-les-annees-50.html","title":{"rendered":"Avis : s\u00e9rie Mme Maisel, femme fabuleuse : le f\u00e9minisme dans les ann\u00e9es 50"},"content":{"rendered":"<p>Apr\u00e8s <a href=\"https:\/\/www.lesbridgets.com\/index.php\/references-sur-le-couple-et-le-celibat\/serie-couple-celibataire\/pourquoi-on-aime-la-serie-fleabag-decouverte-sur-amazon-prime.html\" target=\"_blank\" rel=\"noopener noreferrer\">Fleabag<\/a>, deuxi\u00e8me d\u00e9couverte pour la s\u00e9rie <strong>Mme Maisel, femme fabuleuse<\/strong> sur Amazon Prime, le titre en Anglais (The Marvelous <em>Mrs<\/em>.\u00a0<em>Maisel<\/em>).<br \/>\nUne s\u00e9rie que se passe dans les ann\u00e9es 50 aux Etats Unis mais aussi un peu en France de mani\u00e8re tr\u00e8s clich\u00e9 dans la 2\u00e8me saison. Pour r\u00e9sumer la s\u00e9rie, c&rsquo;est l&rsquo;histoire d&rsquo;une femme newyorkaise bourgeoise qui se lance dans le stand up dans les ann\u00e9es 50.<\/p>\n<h2>Pourquoi la s\u00e9rie Mme Maisel est f\u00e9ministe<\/h2>\n<p>Une s\u00e9rie tr\u00e8s f\u00e9ministe surtout si on la situe dans les mentalit\u00e9s de l&rsquo;\u00e9poque. S&rsquo;\u00e9manciper de son mari, s&rsquo;\u00e9couter sur ce qui nous passionne et le r\u00e9aliser.<br \/>\nS&rsquo;habiller comme on le souhaite loin des codes comme l&rsquo;agent de Mme Maisel. Se lancer dans un milieu compl\u00e8tement masculin malgr\u00e9 tous les barrages.<\/p>\n<figure id=\"attachment_247241\" aria-describedby=\"caption-attachment-247241\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-247241 size-full\" src=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/05\/mrs-maisel-amazon-prime.jpg\" alt=\"\" width=\"800\" height=\"534\" srcset=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/05\/mrs-maisel-amazon-prime.jpg 800w, https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/05\/mrs-maisel-amazon-prime-300x200.jpg 300w, https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/05\/mrs-maisel-amazon-prime-768x513.jpg 768w, https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/05\/mrs-maisel-amazon-prime-600x400.jpg 600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-247241\" class=\"wp-caption-text\">Rachel Brosnahan et Alex Borstein dans Mrs Maisel<\/figcaption><\/figure>\n<h2 style=\"text-align: left;\">La bande annonce de Mme Maisel en anglais mais dispo en fran\u00e7ais sur Amazon Prime<\/h2>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/fOmwkTrW4OQ\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<h2>On adore le style ann\u00e9es 50 : les superbes tenues de Mme Maisel<\/h2>\n<p>En passionn\u00e9e des ann\u00e9es 50, on ne peut que craquer \u00e0 chaque \u00e9pisode devant les superbes tenues sur la taille fine de Rachel Brosnahan l&rsquo;actrice qui joue Mrs Maisel. De la robe rouge au pantalon rose taille haute, elle donne terriblement envie de s&rsquo;habiller ainsi sans parler des coiffures, des chaussures ou encore de la d\u00e9coration.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-247242 size-full aligncenter\" src=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/05\/Rachel-Brosnahan-mrs-maisel.jpg\" alt=\"\" width=\"800\" height=\"447\" srcset=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/05\/Rachel-Brosnahan-mrs-maisel.jpg 800w, https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/05\/Rachel-Brosnahan-mrs-maisel-300x168.jpg 300w, https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/05\/Rachel-Brosnahan-mrs-maisel-768x429.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>On notera ce quotidien qui semble si fou \u00e0 notre \u00e9poque comme de se d\u00e9maquiller uniquement quand le mari dort d\u00e9j\u00e0 et de se lever avant lui pour se remaquiller afin qu&rsquo;il nous voit toujours superbe.<\/p>\n<p>Une s\u00e9rie qui parfois un peu comme <a href=\"https:\/\/www.lesbridgets.com\/index.php\/references-sur-le-couple-et-le-celibat\/serie-couple-celibataire\/avis-this-is-us-la-serie-a-voir-absolument.html\" target=\"_blank\" rel=\"noopener noreferrer\">This is Us<\/a> nous fait nous poser des questions sur ce que nous sommes et ce que nous d\u00e9calquons de notre \u00e9ducation.<\/p>\n<h2>Une histoire vrai Mrs Maisel ?<\/h2>\n<p>Dan Palladino, le co-auteur de la s\u00e9rie, a indiqu\u00e9 dans une interview que le personnage de Midge (Mme Maisel) est librement inspir\u00e9 de quelques artistes f\u00e9minines de l&rsquo;\u00e9poque comme Jean Caroll,\u00a0Phyllis Diller,\u00a0Joan Rivers,\u00a0Jackie Moms Mabley, ou encore\u00a0Elaine May<sup id=\"cite_ref-9\" class=\"reference\"><\/sup>.<\/p>\n<p>2 saisons sont disponibles sur <a href=\"https:\/\/www.amazon.fr\/amazonprime\/ref=as_li_ss_tl?ie=UTF8&amp;linkCode=ll2&amp;tag=lesbricomcomp-21&amp;linkId=840cf09e19e46a576a7d6fe4e33dd860&amp;language=fr_FR\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">Amazon Prime<\/a> vous pouvez profiter des 30 jours gratuits pour regarder la s\u00e9rie.<br \/>\nLa 3\u00e8me saison est en cours de tournage \u00e0 l&rsquo;heure o\u00f9 nous \u00e9crivons ses lignes en avril 2019.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s Fleabag, deuxi\u00e8me d\u00e9couverte pour la s\u00e9rie Mme Maisel, femme fabuleuse sur Amazon Prime, le titre en Anglais (The Marvelous Mrs.\u00a0Maisel). Une s\u00e9rie que se&hellip; <\/p>\n","protected":false},"author":2,"featured_media":247244,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"om_disable_all_campaigns":false,"_lmt_disableupdate":"no","_lmt_disable":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[43],"tags":[1260,916,99],"class_list":["post-247236","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-serie-couple-celibataire","tag-annees-50","tag-feminisme","tag-serie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Avis : s\u00e9rie Mme Maisel, femme fabuleuse : le f\u00e9minisme dans les ann\u00e9es 50 - Les Bridgets<\/title>\n<meta name=\"description\" content=\"La s\u00e9rie Mme Maisel femme fabuleuse: l&#039;histoire d&#039;une femme newyorkaise bourgeoise qui se lance dans le stand up dans les ann\u00e9es 50 \u00e0 voir sur Amazon Prime.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lesbridgets.com\/index.php\/references\/serie-couple-celibataire\/la-serie-mme-maisel-femme-fabuleuse-le-feminisme-dans-les-annees-50.html\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avis : s\u00e9rie Mme Maisel, femme fabuleuse : le f\u00e9minisme dans les ann\u00e9es 50 - Les Bridgets\" \/>\n<meta property=\"og:description\" content=\"La s\u00e9rie Mme Maisel femme fabuleuse: l&#039;histoire d&#039;une femme newyorkaise bourgeoise qui se lance dans le stand up dans les ann\u00e9es 50 \u00e0 voir sur Amazon Prime.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lesbridgets.com\/index.php\/references\/serie-couple-celibataire\/la-serie-mme-maisel-femme-fabuleuse-le-feminisme-dans-les-annees-50.html\" \/>\n<meta property=\"og:site_name\" content=\"Les Bridgets\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Les.Bridgets\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-04T09:22:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-24T18:52:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/05\/Mme-Maisel-robe-rouge.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"449\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bridget\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@les_bridgets\" \/>\n<meta name=\"twitter:site\" content=\"@les_bridgets\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bridget\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/serie-couple-celibataire\\\/la-serie-mme-maisel-femme-fabuleuse-le-feminisme-dans-les-annees-50.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/serie-couple-celibataire\\\/la-serie-mme-maisel-femme-fabuleuse-le-feminisme-dans-les-annees-50.html\"},\"author\":{\"name\":\"Bridget\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/person\\\/82a31c27ae0ddd23ee59e1e2ac5713ba\"},\"headline\":\"Avis : s\u00e9rie Mme Maisel, femme fabuleuse : le f\u00e9minisme dans les ann\u00e9es 50\",\"datePublished\":\"2019-05-04T09:22:43+00:00\",\"dateModified\":\"2025-04-24T18:52:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/serie-couple-celibataire\\\/la-serie-mme-maisel-femme-fabuleuse-le-feminisme-dans-les-annees-50.html\"},\"wordCount\":421,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/serie-couple-celibataire\\\/la-serie-mme-maisel-femme-fabuleuse-le-feminisme-dans-les-annees-50.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Mme-Maisel-robe-rouge.jpg\",\"keywords\":[\"ann\u00e9es 50\",\"f\u00e9minisme\",\"serie\"],\"articleSection\":[\"S\u00e9rie\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/serie-couple-celibataire\\\/la-serie-mme-maisel-femme-fabuleuse-le-feminisme-dans-les-annees-50.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/serie-couple-celibataire\\\/la-serie-mme-maisel-femme-fabuleuse-le-feminisme-dans-les-annees-50.html\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/serie-couple-celibataire\\\/la-serie-mme-maisel-femme-fabuleuse-le-feminisme-dans-les-annees-50.html\",\"name\":\"Avis : s\u00e9rie Mme Maisel, femme fabuleuse : le f\u00e9minisme dans les ann\u00e9es 50 - Les Bridgets\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/serie-couple-celibataire\\\/la-serie-mme-maisel-femme-fabuleuse-le-feminisme-dans-les-annees-50.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/serie-couple-celibataire\\\/la-serie-mme-maisel-femme-fabuleuse-le-feminisme-dans-les-annees-50.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Mme-Maisel-robe-rouge.jpg\",\"datePublished\":\"2019-05-04T09:22:43+00:00\",\"dateModified\":\"2025-04-24T18:52:11+00:00\",\"description\":\"La s\u00e9rie Mme Maisel femme fabuleuse: l'histoire d'une femme newyorkaise bourgeoise qui se lance dans le stand up dans les ann\u00e9es 50 \u00e0 voir sur Amazon Prime.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/serie-couple-celibataire\\\/la-serie-mme-maisel-femme-fabuleuse-le-feminisme-dans-les-annees-50.html#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/serie-couple-celibataire\\\/la-serie-mme-maisel-femme-fabuleuse-le-feminisme-dans-les-annees-50.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/serie-couple-celibataire\\\/la-serie-mme-maisel-femme-fabuleuse-le-feminisme-dans-les-annees-50.html#primaryimage\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Mme-Maisel-robe-rouge.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Mme-Maisel-robe-rouge.jpg\",\"width\":800,\"height\":449},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/serie-couple-celibataire\\\/la-serie-mme-maisel-femme-fabuleuse-le-feminisme-dans-les-annees-50.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Les Bridgets\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00e9f\u00e9rences sur le couple et le c\u00e9libat\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/category\\\/references\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"S\u00e9rie\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/category\\\/references\\\/serie-couple-celibataire\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Avis : s\u00e9rie Mme Maisel, femme fabuleuse : le f\u00e9minisme dans les ann\u00e9es 50\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#website\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/\",\"name\":\"Les Bridgets\",\"description\":\"R\u00e9f\u00e9rences et r\u00e9flexions sur nos relations\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lesbridgets.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\",\"name\":\"Les Bridgets\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo-3-lesbridgets.png\",\"contentUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo-3-lesbridgets.png\",\"width\":251,\"height\":59,\"caption\":\"Les Bridgets\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Les.Bridgets\",\"https:\\\/\\\/x.com\\\/les_bridgets\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/person\\\/82a31c27ae0ddd23ee59e1e2ac5713ba\",\"name\":\"Bridget\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"caption\":\"Bridget\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avis : s\u00e9rie Mme Maisel, femme fabuleuse : le f\u00e9minisme dans les ann\u00e9es 50 - Les Bridgets","description":"La s\u00e9rie Mme Maisel femme fabuleuse: l'histoire d'une femme newyorkaise bourgeoise qui se lance dans le stand up dans les ann\u00e9es 50 \u00e0 voir sur Amazon Prime.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lesbridgets.com\/index.php\/references\/serie-couple-celibataire\/la-serie-mme-maisel-femme-fabuleuse-le-feminisme-dans-les-annees-50.html","og_locale":"fr_FR","og_type":"article","og_title":"Avis : s\u00e9rie Mme Maisel, femme fabuleuse : le f\u00e9minisme dans les ann\u00e9es 50 - Les Bridgets","og_description":"La s\u00e9rie Mme Maisel femme fabuleuse: l'histoire d'une femme newyorkaise bourgeoise qui se lance dans le stand up dans les ann\u00e9es 50 \u00e0 voir sur Amazon Prime.","og_url":"https:\/\/www.lesbridgets.com\/index.php\/references\/serie-couple-celibataire\/la-serie-mme-maisel-femme-fabuleuse-le-feminisme-dans-les-annees-50.html","og_site_name":"Les Bridgets","article_publisher":"https:\/\/www.facebook.com\/Les.Bridgets","article_published_time":"2019-05-04T09:22:43+00:00","article_modified_time":"2025-04-24T18:52:11+00:00","og_image":[{"width":800,"height":449,"url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/05\/Mme-Maisel-robe-rouge.jpg","type":"image\/jpeg"}],"author":"Bridget","twitter_card":"summary_large_image","twitter_creator":"@les_bridgets","twitter_site":"@les_bridgets","twitter_misc":{"\u00c9crit par":"Bridget","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/serie-couple-celibataire\/la-serie-mme-maisel-femme-fabuleuse-le-feminisme-dans-les-annees-50.html#article","isPartOf":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/serie-couple-celibataire\/la-serie-mme-maisel-femme-fabuleuse-le-feminisme-dans-les-annees-50.html"},"author":{"name":"Bridget","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/person\/82a31c27ae0ddd23ee59e1e2ac5713ba"},"headline":"Avis : s\u00e9rie Mme Maisel, femme fabuleuse : le f\u00e9minisme dans les ann\u00e9es 50","datePublished":"2019-05-04T09:22:43+00:00","dateModified":"2025-04-24T18:52:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/serie-couple-celibataire\/la-serie-mme-maisel-femme-fabuleuse-le-feminisme-dans-les-annees-50.html"},"wordCount":421,"commentCount":0,"publisher":{"@id":"https:\/\/www.lesbridgets.com\/#organization"},"image":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/serie-couple-celibataire\/la-serie-mme-maisel-femme-fabuleuse-le-feminisme-dans-les-annees-50.html#primaryimage"},"thumbnailUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/05\/Mme-Maisel-robe-rouge.jpg","keywords":["ann\u00e9es 50","f\u00e9minisme","serie"],"articleSection":["S\u00e9rie"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.lesbridgets.com\/index.php\/references\/serie-couple-celibataire\/la-serie-mme-maisel-femme-fabuleuse-le-feminisme-dans-les-annees-50.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/serie-couple-celibataire\/la-serie-mme-maisel-femme-fabuleuse-le-feminisme-dans-les-annees-50.html","url":"https:\/\/www.lesbridgets.com\/index.php\/references\/serie-couple-celibataire\/la-serie-mme-maisel-femme-fabuleuse-le-feminisme-dans-les-annees-50.html","name":"Avis : s\u00e9rie Mme Maisel, femme fabuleuse : le f\u00e9minisme dans les ann\u00e9es 50 - Les Bridgets","isPartOf":{"@id":"https:\/\/www.lesbridgets.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/serie-couple-celibataire\/la-serie-mme-maisel-femme-fabuleuse-le-feminisme-dans-les-annees-50.html#primaryimage"},"image":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/serie-couple-celibataire\/la-serie-mme-maisel-femme-fabuleuse-le-feminisme-dans-les-annees-50.html#primaryimage"},"thumbnailUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/05\/Mme-Maisel-robe-rouge.jpg","datePublished":"2019-05-04T09:22:43+00:00","dateModified":"2025-04-24T18:52:11+00:00","description":"La s\u00e9rie Mme Maisel femme fabuleuse: l'histoire d'une femme newyorkaise bourgeoise qui se lance dans le stand up dans les ann\u00e9es 50 \u00e0 voir sur Amazon Prime.","breadcrumb":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/serie-couple-celibataire\/la-serie-mme-maisel-femme-fabuleuse-le-feminisme-dans-les-annees-50.html#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lesbridgets.com\/index.php\/references\/serie-couple-celibataire\/la-serie-mme-maisel-femme-fabuleuse-le-feminisme-dans-les-annees-50.html"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/serie-couple-celibataire\/la-serie-mme-maisel-femme-fabuleuse-le-feminisme-dans-les-annees-50.html#primaryimage","url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/05\/Mme-Maisel-robe-rouge.jpg","contentUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2019\/05\/Mme-Maisel-robe-rouge.jpg","width":800,"height":449},{"@type":"BreadcrumbList","@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/serie-couple-celibataire\/la-serie-mme-maisel-femme-fabuleuse-le-feminisme-dans-les-annees-50.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Les Bridgets","item":"https:\/\/www.lesbridgets.com\/"},{"@type":"ListItem","position":2,"name":"R\u00e9f\u00e9rences sur le couple et le c\u00e9libat","item":"https:\/\/www.lesbridgets.com\/index.php\/category\/references"},{"@type":"ListItem","position":3,"name":"S\u00e9rie","item":"https:\/\/www.lesbridgets.com\/index.php\/category\/references\/serie-couple-celibataire"},{"@type":"ListItem","position":4,"name":"Avis : s\u00e9rie Mme Maisel, femme fabuleuse : le f\u00e9minisme dans les ann\u00e9es 50"}]},{"@type":"WebSite","@id":"https:\/\/www.lesbridgets.com\/#website","url":"https:\/\/www.lesbridgets.com\/","name":"Les Bridgets","description":"R\u00e9f\u00e9rences et r\u00e9flexions sur nos relations","publisher":{"@id":"https:\/\/www.lesbridgets.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lesbridgets.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lesbridgets.com\/#organization","name":"Les Bridgets","url":"https:\/\/www.lesbridgets.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2022\/07\/cropped-logo-3-lesbridgets.png","contentUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2022\/07\/cropped-logo-3-lesbridgets.png","width":251,"height":59,"caption":"Les Bridgets"},"image":{"@id":"https:\/\/www.lesbridgets.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Les.Bridgets","https:\/\/x.com\/les_bridgets"]},{"@type":"Person","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/person\/82a31c27ae0ddd23ee59e1e2ac5713ba","name":"Bridget","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","caption":"Bridget"}}]}},"modified_by":"Bridget","_links":{"self":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/247236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/comments?post=247236"}],"version-history":[{"count":16,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/247236\/revisions"}],"predecessor-version":[{"id":253777,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/247236\/revisions\/253777"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/media\/247244"}],"wp:attachment":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/media?parent=247236"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/categories?post=247236"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/tags?post=247236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}