{"id":241678,"date":"2017-09-27T20:44:44","date_gmt":"2017-09-27T18:44:44","guid":{"rendered":"https:\/\/www.lesbridgets.com\/?p=241678"},"modified":"2017-09-27T21:12:18","modified_gmt":"2017-09-27T19:12:18","slug":"jeremy-james-aurait-voulu-a-la-comedie-des-boulevards","status":"publish","type":"post","link":"https:\/\/www.lesbridgets.com\/index.php\/references\/theatre\/jeremy-james-aurait-voulu-a-la-comedie-des-boulevards.html","title":{"rendered":"Jeremy James aurait voulu \u00e0 la Com\u00e9die des Boulevards"},"content":{"rendered":"<p>Pour ceux qui nous suivent depuis au moins un an <a href=\"https:\/\/www.facebook.com\/Les.Bridgets\/\" target=\"_blank\" rel=\"noopener\">sur la page facebook<\/a> (vous \u00eates plus de 10 000 donc \u00e7a fait un paquet) on vous a d\u00e9j\u00e0 parl\u00e9 de Jeremy James mais surtout d\u00e9j\u00e0 fait gagner des places pour le voir sur sc\u00e8ne dans sa premi\u00e8re salle \u00e0 La Com\u00e9die des 3 bornes. L\u00e0 o\u00f9 nous l&rsquo;avons d\u00e9couvert.<br \/>\nOn a ador\u00e9 et visiblement pas que nous, puisqu&rsquo;il joue maintenant \u00e0 la Com\u00e9die des Boulevards ! Une salle plus grande, avec plus de confort.<\/p>\n<p>Jeremy James aurait voulu, c&rsquo;est un spectacle autobiographique avec de la danse mais surtout un parcours peu ordinaire. Bref on vous conseille vraiment d&rsquo;y aller !<\/p>\n<h2>Les images valent mieux que des mots<\/h2>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/EAHnsqnXsF8\" width=\"760\" height=\"420\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<h1>3 fois 2 places \u00e0 gagner pour mardi 3 octobre \u00e0 20H<\/h1>\n<p style=\"text-align: left;\">La bonne nouvelle c&rsquo;est qu&rsquo;on vous propose de gagner 3 fois 2 places parce que comme un bon dessert un bon spectacle c&rsquo;est mieux \u00e0 partager.<br \/>\nPour gagner votre place, il vous suffit juste de nous dire en commentaire avec qui vous souhaitez y aller et si vous \u00eates fan de la page facebook c&rsquo;est encore mieux.<\/p>\n<p>Tirage au sort dimanche 1er octobre \u00e0 21h, pour \u00eatre sures que vous r\u00e9serviez bien votre soir\u00e9e avec Jeremy.<br \/>\nEt puis si vous \u00eates pas dispo le 3 octobre, <a href=\"http:\/\/www.billetreduc.com\/192415\/evt.htm\" target=\"_blank\" rel=\"noopener\">il joue tous les autres mardi jusqu&rsquo;en janvier<\/a> !<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour ceux qui nous suivent depuis au moins un an sur la page facebook (vous \u00eates plus de 10 000 donc \u00e7a fait un paquet)&hellip; <\/p>\n","protected":false},"author":2,"featured_media":241679,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"om_disable_all_campaigns":false,"_lmt_disableupdate":"","_lmt_disable":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[26],"tags":[895,346,922],"class_list":["post-241678","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-theatre","tag-danse","tag-humour","tag-spectacle"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jeremy James aurait voulu \u00e0 la Com\u00e9die des Boulevards - Les Bridgets<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lesbridgets.com\/index.php\/references\/theatre\/jeremy-james-aurait-voulu-a-la-comedie-des-boulevards.html\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jeremy James aurait voulu \u00e0 la Com\u00e9die des Boulevards - Les Bridgets\" \/>\n<meta property=\"og:description\" content=\"Pour ceux qui nous suivent depuis au moins un an sur la page facebook (vous \u00eates plus de 10 000 donc \u00e7a fait un paquet)&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lesbridgets.com\/index.php\/references\/theatre\/jeremy-james-aurait-voulu-a-la-comedie-des-boulevards.html\" \/>\n<meta property=\"og:site_name\" content=\"Les Bridgets\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Les.Bridgets\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-27T18:44:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-09-27T19:12:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2017\/09\/jeremy-james-comedie-danse.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"421\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bridget\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@les_bridgets\" \/>\n<meta name=\"twitter:site\" content=\"@les_bridgets\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bridget\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/theatre\\\/jeremy-james-aurait-voulu-a-la-comedie-des-boulevards.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/theatre\\\/jeremy-james-aurait-voulu-a-la-comedie-des-boulevards.html\"},\"author\":{\"name\":\"Bridget\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/person\\\/82a31c27ae0ddd23ee59e1e2ac5713ba\"},\"headline\":\"Jeremy James aurait voulu \u00e0 la Com\u00e9die des Boulevards\",\"datePublished\":\"2017-09-27T18:44:44+00:00\",\"dateModified\":\"2017-09-27T19:12:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/theatre\\\/jeremy-james-aurait-voulu-a-la-comedie-des-boulevards.html\"},\"wordCount\":235,\"commentCount\":13,\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/theatre\\\/jeremy-james-aurait-voulu-a-la-comedie-des-boulevards.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/jeremy-james-comedie-danse.jpg\",\"keywords\":[\"danse\",\"humour\",\"spectacle\"],\"articleSection\":[\"Th\u00e9\u00e2tre\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/theatre\\\/jeremy-james-aurait-voulu-a-la-comedie-des-boulevards.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/theatre\\\/jeremy-james-aurait-voulu-a-la-comedie-des-boulevards.html\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/theatre\\\/jeremy-james-aurait-voulu-a-la-comedie-des-boulevards.html\",\"name\":\"Jeremy James aurait voulu \u00e0 la Com\u00e9die des Boulevards - Les Bridgets\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/theatre\\\/jeremy-james-aurait-voulu-a-la-comedie-des-boulevards.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/theatre\\\/jeremy-james-aurait-voulu-a-la-comedie-des-boulevards.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/jeremy-james-comedie-danse.jpg\",\"datePublished\":\"2017-09-27T18:44:44+00:00\",\"dateModified\":\"2017-09-27T19:12:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/theatre\\\/jeremy-james-aurait-voulu-a-la-comedie-des-boulevards.html#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/theatre\\\/jeremy-james-aurait-voulu-a-la-comedie-des-boulevards.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/theatre\\\/jeremy-james-aurait-voulu-a-la-comedie-des-boulevards.html#primaryimage\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/jeremy-james-comedie-danse.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/jeremy-james-comedie-danse.jpg\",\"width\":750,\"height\":421},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/theatre\\\/jeremy-james-aurait-voulu-a-la-comedie-des-boulevards.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Les Bridgets\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00e9f\u00e9rences sur le couple et le c\u00e9libat\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/category\\\/references\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Th\u00e9\u00e2tre\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/category\\\/references\\\/theatre\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Jeremy James aurait voulu \u00e0 la Com\u00e9die des Boulevards\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#website\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/\",\"name\":\"Les Bridgets\",\"description\":\"R\u00e9f\u00e9rences et r\u00e9flexions sur nos relations\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lesbridgets.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\",\"name\":\"Les Bridgets\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo-3-lesbridgets.png\",\"contentUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo-3-lesbridgets.png\",\"width\":251,\"height\":59,\"caption\":\"Les Bridgets\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Les.Bridgets\",\"https:\\\/\\\/x.com\\\/les_bridgets\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/person\\\/82a31c27ae0ddd23ee59e1e2ac5713ba\",\"name\":\"Bridget\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"caption\":\"Bridget\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jeremy James aurait voulu \u00e0 la Com\u00e9die des Boulevards - Les Bridgets","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lesbridgets.com\/index.php\/references\/theatre\/jeremy-james-aurait-voulu-a-la-comedie-des-boulevards.html","og_locale":"fr_FR","og_type":"article","og_title":"Jeremy James aurait voulu \u00e0 la Com\u00e9die des Boulevards - Les Bridgets","og_description":"Pour ceux qui nous suivent depuis au moins un an sur la page facebook (vous \u00eates plus de 10 000 donc \u00e7a fait un paquet)&hellip;","og_url":"https:\/\/www.lesbridgets.com\/index.php\/references\/theatre\/jeremy-james-aurait-voulu-a-la-comedie-des-boulevards.html","og_site_name":"Les Bridgets","article_publisher":"https:\/\/www.facebook.com\/Les.Bridgets","article_published_time":"2017-09-27T18:44:44+00:00","article_modified_time":"2017-09-27T19:12:18+00:00","og_image":[{"width":750,"height":421,"url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2017\/09\/jeremy-james-comedie-danse.jpg","type":"image\/jpeg"}],"author":"Bridget","twitter_card":"summary_large_image","twitter_creator":"@les_bridgets","twitter_site":"@les_bridgets","twitter_misc":{"\u00c9crit par":"Bridget","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/theatre\/jeremy-james-aurait-voulu-a-la-comedie-des-boulevards.html#article","isPartOf":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/theatre\/jeremy-james-aurait-voulu-a-la-comedie-des-boulevards.html"},"author":{"name":"Bridget","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/person\/82a31c27ae0ddd23ee59e1e2ac5713ba"},"headline":"Jeremy James aurait voulu \u00e0 la Com\u00e9die des Boulevards","datePublished":"2017-09-27T18:44:44+00:00","dateModified":"2017-09-27T19:12:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/theatre\/jeremy-james-aurait-voulu-a-la-comedie-des-boulevards.html"},"wordCount":235,"commentCount":13,"publisher":{"@id":"https:\/\/www.lesbridgets.com\/#organization"},"image":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/theatre\/jeremy-james-aurait-voulu-a-la-comedie-des-boulevards.html#primaryimage"},"thumbnailUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2017\/09\/jeremy-james-comedie-danse.jpg","keywords":["danse","humour","spectacle"],"articleSection":["Th\u00e9\u00e2tre"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.lesbridgets.com\/index.php\/references\/theatre\/jeremy-james-aurait-voulu-a-la-comedie-des-boulevards.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/theatre\/jeremy-james-aurait-voulu-a-la-comedie-des-boulevards.html","url":"https:\/\/www.lesbridgets.com\/index.php\/references\/theatre\/jeremy-james-aurait-voulu-a-la-comedie-des-boulevards.html","name":"Jeremy James aurait voulu \u00e0 la Com\u00e9die des Boulevards - Les Bridgets","isPartOf":{"@id":"https:\/\/www.lesbridgets.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/theatre\/jeremy-james-aurait-voulu-a-la-comedie-des-boulevards.html#primaryimage"},"image":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/theatre\/jeremy-james-aurait-voulu-a-la-comedie-des-boulevards.html#primaryimage"},"thumbnailUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2017\/09\/jeremy-james-comedie-danse.jpg","datePublished":"2017-09-27T18:44:44+00:00","dateModified":"2017-09-27T19:12:18+00:00","breadcrumb":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/theatre\/jeremy-james-aurait-voulu-a-la-comedie-des-boulevards.html#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lesbridgets.com\/index.php\/references\/theatre\/jeremy-james-aurait-voulu-a-la-comedie-des-boulevards.html"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/theatre\/jeremy-james-aurait-voulu-a-la-comedie-des-boulevards.html#primaryimage","url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2017\/09\/jeremy-james-comedie-danse.jpg","contentUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2017\/09\/jeremy-james-comedie-danse.jpg","width":750,"height":421},{"@type":"BreadcrumbList","@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/theatre\/jeremy-james-aurait-voulu-a-la-comedie-des-boulevards.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Les Bridgets","item":"https:\/\/www.lesbridgets.com\/"},{"@type":"ListItem","position":2,"name":"R\u00e9f\u00e9rences sur le couple et le c\u00e9libat","item":"https:\/\/www.lesbridgets.com\/index.php\/category\/references"},{"@type":"ListItem","position":3,"name":"Th\u00e9\u00e2tre","item":"https:\/\/www.lesbridgets.com\/index.php\/category\/references\/theatre"},{"@type":"ListItem","position":4,"name":"Jeremy James aurait voulu \u00e0 la Com\u00e9die des Boulevards"}]},{"@type":"WebSite","@id":"https:\/\/www.lesbridgets.com\/#website","url":"https:\/\/www.lesbridgets.com\/","name":"Les Bridgets","description":"R\u00e9f\u00e9rences et r\u00e9flexions sur nos relations","publisher":{"@id":"https:\/\/www.lesbridgets.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lesbridgets.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lesbridgets.com\/#organization","name":"Les Bridgets","url":"https:\/\/www.lesbridgets.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2022\/07\/cropped-logo-3-lesbridgets.png","contentUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2022\/07\/cropped-logo-3-lesbridgets.png","width":251,"height":59,"caption":"Les Bridgets"},"image":{"@id":"https:\/\/www.lesbridgets.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Les.Bridgets","https:\/\/x.com\/les_bridgets"]},{"@type":"Person","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/person\/82a31c27ae0ddd23ee59e1e2ac5713ba","name":"Bridget","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","caption":"Bridget"}}]}},"modified_by":"Bridget","_links":{"self":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/241678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/comments?post=241678"}],"version-history":[{"count":7,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/241678\/revisions"}],"predecessor-version":[{"id":241686,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/241678\/revisions\/241686"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/media\/241679"}],"wp:attachment":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/media?parent=241678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/categories?post=241678"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/tags?post=241678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}