{"id":2191,"date":"2017-02-07T08:49:53","date_gmt":"2017-02-07T07:49:53","guid":{"rendered":"http:\/\/lesbridg.cluster015.ovh.net\/wordpress\/index.php\/soirees-voyages-rencontres\/un-an-apres-mon-voyage-de-3-semaines-en-inde-ce-que-je-retiens.html"},"modified":"2020-06-21T10:51:57","modified_gmt":"2020-06-21T08:51:57","slug":"un-an-apres-mon-voyage-de-3-semaines-en-inde-ce-que-je-retiens","status":"publish","type":"post","link":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/soirees-voyages-rencontres\/un-an-apres-mon-voyage-de-3-semaines-en-inde-ce-que-je-retiens.html","title":{"rendered":"Un an apr\u00e8s mon voyage de 3 semaines en Inde ce que je retiens"},"content":{"rendered":"<div>Bient\u00f4t un an que je suis partie direction l&rsquo;Inde. Bient\u00f4t un an que je partais pour la premi\u00e8re fois \u00e0 la d\u00e9couverte d&rsquo;une soci\u00e9t\u00e9 v\u00e9ritablement diff\u00e9rente de la notre pendant 3 semaines.<br \/>\nBient\u00f4t un an que je n&rsquo;arrivais pas \u00e0 \u00e9crire sur ce voyage si particulier et inoubliable.<\/div>\n<div>J&rsquo;ai pris mes billets d&rsquo;avion peu apr\u00e8s le 13 novembre 2015 car encore plus qu&rsquo;avant je voulais rayer des \u00e9l\u00e9ments de ma liste de choses que je veux faire absolument dans ma vie.<\/div>\n<div>\n<p>Parmi ceux qui concr\u00e8tement ne m&rsquo;\u00e9taient pas impossible et dans les plus urgents \u00e0 r\u00e9aliser :<\/p>\n<\/div>\n<div><strong>&#8211; Aller voir mon oncle qui vit en Inde depuis plus de 10 ans et d\u00e9couvrir par moi-m\u00eame ce pays envers lequel on entend beaucoup de choses dont souvent tout et n&rsquo;importe quoi.<\/strong><\/div>\n<div><\/div>\n<div>J&rsquo;ai donc pass\u00e9 15 jours avec mon oncle qui connait tr\u00e8s bien l&rsquo;Inde.<\/div>\n<h2>Une semaine \u00e0 la d\u00e9couverte des alentours de Chennai, une semaine \u00e0 Kavali l\u00e0 o\u00f9 il vit \u00e0 un peu plus de 5h en train et une semaine seule \u00e0 Pondicherry.<\/h2>\n<p><center><ins class=\"bookingaff\" data-aid=\"1715140\" data-target_aid=\"1715140\" data-prod=\"map\" data-width=\"100%\" data-height=\"590\" data-lang=\"ualng\" data-dest_id=\"0\" data-dest_type=\"landmark\" data-latitude=\"11.9415915\" data-longitude=\"79.8083133\" data-mwhsb=\"0\"><\/ins><br \/>\n<script type=\"text\/javascript\">\n    (function(d, sc, u) {\n      var s = d.createElement(sc), p = d.getElementsByTagName(sc)[0];\n      s.type = 'text\/javascript';\n      s.async = true;\n      s.src = u + '?v=' + (+new Date());\n      p.parentNode.insertBefore(s,p);\n      })(document, 'script', '\/\/aff.bstatic.com\/static\/affiliate_base\/js\/flexiproduct.js');\n<\/script><\/center><\/p>\n<div>Le contexte fut particulier. Je ne connaissais pas vraiment mon oncle, pour des raisons familiales je ne l&rsquo;ai pas beaucoup vu.<br \/>\nL\u00e0-bas dans l&rsquo;Andhra Pradesh, il g\u00e8re avec sa femme Catherine (et des indiens fantastiques) un beau projet qui est d&rsquo;aider les malades du SIDA notamment avec deux dispensaires.<br \/>\nOui le Sida en Inde est m\u00e9connu et pourtant il fait des ravages sans vraiment d&rsquo;aide de l&rsquo;\u00e9tat.<\/div>\n<div><\/div>\n<h2 style=\"text-align: left;\">Un vaste sujet que j&rsquo;ai abord\u00e9 sur place mais dont vous trouverez toutes les explications dans cette vid\u00e9o<\/h2>\n<h1 style=\"text-align: center;\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/q1r4hvXg-wY\" width=\"750\" height=\"422\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/h1>\n<h2>Ce fut donc un voyage riche en d\u00e9couvertes et en \u00e9motions.<\/h2>\n<div>L&rsquo;Inde vous procure d\u00e9j\u00e0 ces sensations naturellement et obligatoirement, pour moi elles furent d\u00e9cupl\u00e9es.<\/div>\n<div><\/div>\n<div>Je me consid\u00e8re comme chanceuse :<\/div>\n<ul>\n<li>Mon oncle m&rsquo;a permis d&rsquo;appr\u00e9hender l&rsquo;Inde comme je n&rsquo;aurais pas pu la comprendre dans les livres ou autres billets de blogs surtout que je suis de nature tr\u00e8s curieuse \u00e0 poser \u00e9norm\u00e9ment de questions parfois des plus basiques alors l\u00e0-bas j&rsquo;en avais des centaines.<\/li>\n<\/ul>\n<div><\/div>\n<div>Si vous souhaitez rencontrer l&rsquo;Inde sans connaitre personne l\u00e0 bas, <a href=\"https:\/\/clk.tradedoubler.com\/click?p=276456&amp;a=2003317&amp;g=23991724\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">Evan\u00e9os<\/a> vous propose des guides et activit\u00e9s avec des personnes de confiance qui vivent sur place et connaissent votre langue<\/div>\n<div><center><script type=\"text\/javascript\">\nvar uri = 'https:\/\/impfr.tradedoubler.com\/imp?type(img)g(23967760)a(2003317)' + new String (Math.random()).substring (2, 11);\ndocument.write('<a href=\"https:\/\/clk.tradedoubler.com\/click?p=276456&#038;a=2003317&#038;g=23967760\" target=\"_BLANK\" rel=\"noopener noreferrer\"><\/a>');\n<\/script><\/center><\/div>\n<div><\/div>\n<ul>\n<li>Il m&rsquo;a permis \u00e9galement de d\u00e9couvrir les indiens comme aucune autre agence de voyages ne me les auraient fait d\u00e9couvrir.<\/li>\n<\/ul>\n<div>Des indiens dans une ville de 400 000 habitants pas touristique o\u00f9 il n&rsquo;y a aucun h\u00f4tel. Des indiens qui ne voient pas souvent des blancs dans leur ville.<\/div>\n<h2>C&rsquo;est comme \u00e7a que pour la premi\u00e8re fois, je me suis sentie de \u00ab\u00a0couleur\u00a0\u00bb<\/h2>\n<p>Les voyages comme l&rsquo;Inde ou s\u00fbrement l&rsquo;Afrique permettent de comprendre beaucoup de choses sur nous-m\u00eame et beaucoup de choses sur les autres.<br \/>\nJ&rsquo;ai essay\u00e9 de m&rsquo;int\u00e9grer un maximum comme \u00e0 chaque fois que je voyage. J&rsquo;ai achet\u00e9 des habits sur place : des penjabis et d&rsquo;autres que l&rsquo;on m&rsquo;a pr\u00eat\u00e9. Malgr\u00e9 tout je restais la blanche, l&rsquo;occidentale et d&rsquo;autant plus une femme blanche seule qui se ballade librement sans mari.<br \/>\nUne extra-terrestre un peu pour l&rsquo;Inde.<br \/>\nJ&rsquo;ai ressenti ce que c&rsquo;\u00e9tait de ne pas pouvoir passer inaper\u00e7ue pendant plus d&rsquo;une semaine, d&rsquo;\u00eatre d\u00e9visag\u00e9e parfois juste parce que j&rsquo;ai une couleur de peau diff\u00e9rente. Moi qui suis habitu\u00e9e \u00e0 me fondre dans la masse parisienne ou \u00e0 ne croiser pas grand monde quand je rentre dans ma douce campagne, la sensation \u00e9tait tr\u00e8s particuli\u00e8re.<\/p>\n<h2>Mais non, je n&rsquo;ai pas eu le syndrome de l&rsquo;Inde<\/h2>\n<p>Il parait que l&rsquo;Inde nous bouleverse soit positivement, soit n\u00e9gativement mais \u00e0 l&rsquo;extreme. Peut-\u00eatre que le contexte de mon voyage a contribu\u00e9 \u00e0 ne pas subir ce syndrome. Certes c&rsquo;est un voyage \u00e9prouvant, d\u00e9routant, bouleversant, passionnant, excitant, inoubliable mais je n&rsquo;ai pas p\u00e9t\u00e9 un plomb comme beaucoup de t\u00e9moignages que je peux lire encore fr\u00e9quemment.<\/p>\n<h2>Ce que je retiendrais de l&rsquo;Inde<\/h2>\n<ul>\n<li>Ma rencontre avec les jeunes filles du foyer que g\u00e8re l&rsquo;association de mon oncle. Leurs regards si bienveillants, si beaux. leur gentillesse. J&rsquo;ai tellement aim\u00e9 partager une s\u00e9ance de cin\u00e9 avec elle, une baignade habill\u00e9e dans la mer (oui les indiens n&rsquo;utilisent pas de maillot de bain, se baigner n&rsquo;est pas vraiment dans leur culture) et \u00e9changer quelques mots en anglais.<\/li>\n<li>Ma rencontre avec Sambu, le bras droit de mon oncle. Un homme incroyable qui est d&rsquo;une gentillesse et d&rsquo;une disponibilit\u00e9 incroyable. Des \u00eatres comme on en croise si peu.<\/li>\n<li>Cette jeune fille atteinte du SIDA et de la tuberculose a m\u00eame pas 25 ans parce qu&rsquo;elle a couch\u00e9 avec un coll\u00e8gue dans les champs de th\u00e9. Et qui se laisse mourir parce qu&rsquo;en Inde personne ne voudra marier une femme qui n&rsquo;est plus vierge et malade\u00a0? Oui une femme c\u00e9libataire l\u00e0 bas elle n&rsquo;est pas grand chose surtout si elle n&rsquo;a pas beaucoup d&rsquo;argent.<\/li>\n<\/ul>\n<div>Aller en Inde sans rencontrer v\u00e9ritablement personne l\u00e0 bas, ce n&rsquo;est pas voyager et d\u00e9couvrir l&rsquo;Inde. <a href=\"https:\/\/clk.tradedoubler.com\/click?p=276456&amp;a=2003317&amp;g=23991724\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">Evan\u00e9os<\/a> vous propose des guides et activit\u00e9s avec des personnes de confiance qui vivent sur place et connaissent votre langue ou au moins l&rsquo;anglais.<\/div>\n<div><center><script type=\"text\/javascript\">\nvar uri = 'https:\/\/impfr.tradedoubler.com\/imp?type(img)g(23967760)a(2003317)' + new String (Math.random()).substring (2, 11);\ndocument.write('<a href=\"https:\/\/clk.tradedoubler.com\/click?p=276456&#038;a=2003317&#038;g=23967760\" target=\"_BLANK\" rel=\"noopener noreferrer\"><\/a>');\n<\/script><\/center><\/div>\n<h1>Ce voyage m&rsquo;a fait r\u00e9alis\u00e9 plus que jamais, la chance que j&rsquo;ai d&rsquo;\u00eatre une femme libre de mes choix, libre d&rsquo;aimer, libre d&rsquo;\u00eatre seule, libre de travailler, libre d&rsquo;\u00e9tudier, libre de m&rsquo;\u00e9couter, libre de voyager, libre de mon corps.<\/h1>\n<p>Combien de fois, si ce n&rsquo;est \u00e0 chaque fois que j&rsquo;ai crois\u00e9 des femmes, elles m&rsquo;ont demand\u00e9 \u00ab\u00a0Si j&rsquo;avais un mari ?\u00a0\u00bb et me dire qu&rsquo;elles allaient prier pour moi afin que j&rsquo;en trouve un.<\/p>\n<p>Au d\u00e9but, j&rsquo;essayais de leur dire que j&rsquo;\u00e9tais heureuse seule et que je n&rsquo;avais pas besoin de mari. J&rsquo;\u00e9tais un peu la Bridget Jones dans la sc\u00e8ne avec les tha\u00eflandaises en prison o\u00f9 elles leur parlent des soutiens-gorges.<\/p>\n<h2>Et puis j&rsquo;ai abandonn\u00e9 car je ne venais pas ici pour parler de moi mais d\u00e9couvrir et apprendre d&rsquo;eux.<\/h2>\n<p>Depuis ce voyage inoubliable, je relativise \u00e9norm\u00e9ment ma vie. Ce qui est certain c&rsquo;est qu&rsquo;on ne peut pas revenir en \u00e9tant exactement la m\u00eame personne apr\u00e8s un voyage en Inde.<br \/>\nEt je ne sais pas si ce sont leurs pri\u00e8res ou la lucidit\u00e9 que ces femmes indiennes m&rsquo;ont apport\u00e9 au sujet de ma condition personnelle mais depuis j&rsquo;ai rencontr\u00e9 l&rsquo;amour.<\/p>\n<p>NB: Si vous souhaitez donner \u00e0 une association et \u00eatre sur(e) que votre argent soit bien d\u00e9pens\u00e9, n&rsquo;h\u00e9sitez pas \u00e0 faire des dons pour aider tous ces indiens qui en ont bien besoin.<\/p>\n<p>Pour voir des photos du voyage, j&rsquo;ai r\u00e9uni <a href=\"http:\/\/www.lemomentm.com\/2016\/08\/toutes-les-photos-instagram-de-mon-voyage-en-inde\/\" target=\"_blank\" rel=\"alternate noopener noreferrer\">les 58 photos instagram de l&rsquo;Inde dans un billet<\/a>\u00a0et il y aussi <a href=\"http:\/\/www.lemomentm.com\/2016\/04\/video-3-semaines-en-inde-dans-le-sud-est-de-linde\/\" target=\"_blank\" rel=\"alternate noopener noreferrer\">une petite vid\u00e9o<\/a>.<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/h6qLyedokqU\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<div>Bient\u00f4t un an que je suis partie direction l&rsquo;Inde. Bient\u00f4t un an que je partais pour la premi\u00e8re fois \u00e0 la d\u00e9couverte d&rsquo;une soci\u00e9t\u00e9 v\u00e9ritablement diff\u00e9rente de la notre pendant 3 semaines. <br \/>Bient\u00f4t un an que je n&rsquo;arrivais pas \u00e0 \u00e9crire sur ce voyage si particulier et inoubliable.<\/div>\n<div>J&rsquo;ai pris mes billets d&rsquo;avion peu apr\u00e8s le 13 novembre 2015 car encore plus qu&rsquo;avant je voulais rayer des \u00e9l\u00e9ments de ma liste de choses que je veux faire absolument dans ma vie.<\/p>\n","protected":false},"author":2,"featured_media":2190,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"om_disable_all_campaigns":false,"_lmt_disableupdate":"no","_lmt_disable":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[27],"tags":[861,807,1193],"class_list":["post-2191","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-soirees-voyages-rencontres","tag-droit","tag-inde","tag-voyager-seule"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un an apr\u00e8s mon voyage de 3 semaines en Inde ce que je retiens - Les Bridgets<\/title>\n<meta name=\"description\" content=\"Bilan un an apr\u00e8s de mon mois pass\u00e9 dans le Sud Ouest de l&#039;Inde : Chenai, Kavali et Pondichery. Ce que ce voyage m&#039;a appris sur moi en tant que femme.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/soirees-voyages-rencontres\/un-an-apres-mon-voyage-de-3-semaines-en-inde-ce-que-je-retiens.html\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un an apr\u00e8s mon voyage de 3 semaines en Inde ce que je retiens - Les Bridgets\" \/>\n<meta property=\"og:description\" content=\"Bilan un an apr\u00e8s de mon mois pass\u00e9 dans le Sud Ouest de l&#039;Inde : Chenai, Kavali et Pondichery. Ce que ce voyage m&#039;a appris sur moi en tant que femme.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/soirees-voyages-rencontres\/un-an-apres-mon-voyage-de-3-semaines-en-inde-ce-que-je-retiens.html\" \/>\n<meta property=\"og:site_name\" content=\"Les Bridgets\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Les.Bridgets\" \/>\n<meta property=\"article:published_time\" content=\"2017-02-07T07:49:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-21T08:51:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2017\/02\/voyage-Inde-femme-seule.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"511\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bridget\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@les_bridgets\" \/>\n<meta name=\"twitter:site\" content=\"@les_bridgets\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bridget\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/soirees-voyages-rencontres\\\/un-an-apres-mon-voyage-de-3-semaines-en-inde-ce-que-je-retiens.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/soirees-voyages-rencontres\\\/un-an-apres-mon-voyage-de-3-semaines-en-inde-ce-que-je-retiens.html\"},\"author\":{\"name\":\"Bridget\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/person\\\/82a31c27ae0ddd23ee59e1e2ac5713ba\"},\"headline\":\"Un an apr\u00e8s mon voyage de 3 semaines en Inde ce que je retiens\",\"datePublished\":\"2017-02-07T07:49:53+00:00\",\"dateModified\":\"2020-06-21T08:51:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/soirees-voyages-rencontres\\\/un-an-apres-mon-voyage-de-3-semaines-en-inde-ce-que-je-retiens.html\"},\"wordCount\":1226,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/soirees-voyages-rencontres\\\/un-an-apres-mon-voyage-de-3-semaines-en-inde-ce-que-je-retiens.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/voyage-Inde-femme-seule.jpg\",\"keywords\":[\"droit\",\"inde\",\"voyager seule\"],\"articleSection\":[\"Soir\u00e9es, voyages, rencontres\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/soirees-voyages-rencontres\\\/un-an-apres-mon-voyage-de-3-semaines-en-inde-ce-que-je-retiens.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/soirees-voyages-rencontres\\\/un-an-apres-mon-voyage-de-3-semaines-en-inde-ce-que-je-retiens.html\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/soirees-voyages-rencontres\\\/un-an-apres-mon-voyage-de-3-semaines-en-inde-ce-que-je-retiens.html\",\"name\":\"Un an apr\u00e8s mon voyage de 3 semaines en Inde ce que je retiens - Les Bridgets\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/soirees-voyages-rencontres\\\/un-an-apres-mon-voyage-de-3-semaines-en-inde-ce-que-je-retiens.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/soirees-voyages-rencontres\\\/un-an-apres-mon-voyage-de-3-semaines-en-inde-ce-que-je-retiens.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/voyage-Inde-femme-seule.jpg\",\"datePublished\":\"2017-02-07T07:49:53+00:00\",\"dateModified\":\"2020-06-21T08:51:57+00:00\",\"description\":\"Bilan un an apr\u00e8s de mon mois pass\u00e9 dans le Sud Ouest de l'Inde : Chenai, Kavali et Pondichery. Ce que ce voyage m'a appris sur moi en tant que femme.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/soirees-voyages-rencontres\\\/un-an-apres-mon-voyage-de-3-semaines-en-inde-ce-que-je-retiens.html#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/soirees-voyages-rencontres\\\/un-an-apres-mon-voyage-de-3-semaines-en-inde-ce-que-je-retiens.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/soirees-voyages-rencontres\\\/un-an-apres-mon-voyage-de-3-semaines-en-inde-ce-que-je-retiens.html#primaryimage\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/voyage-Inde-femme-seule.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/voyage-Inde-femme-seule.jpg\",\"width\":750,\"height\":511},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/soirees-voyages-rencontres\\\/un-an-apres-mon-voyage-de-3-semaines-en-inde-ce-que-je-retiens.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Les Bridgets\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conseils sur l'amour, le couple &amp; les c\u00e9libataires\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/category\\\/conseils-relations\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Soir\u00e9es, voyages, rencontres\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/category\\\/conseils-relations\\\/soirees-voyages-rencontres\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Un an apr\u00e8s mon voyage de 3 semaines en Inde ce que je retiens\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#website\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/\",\"name\":\"Les Bridgets\",\"description\":\"R\u00e9f\u00e9rences et r\u00e9flexions sur nos relations\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lesbridgets.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\",\"name\":\"Les Bridgets\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo-3-lesbridgets.png\",\"contentUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo-3-lesbridgets.png\",\"width\":251,\"height\":59,\"caption\":\"Les Bridgets\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Les.Bridgets\",\"https:\\\/\\\/x.com\\\/les_bridgets\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/person\\\/82a31c27ae0ddd23ee59e1e2ac5713ba\",\"name\":\"Bridget\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"caption\":\"Bridget\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un an apr\u00e8s mon voyage de 3 semaines en Inde ce que je retiens - Les Bridgets","description":"Bilan un an apr\u00e8s de mon mois pass\u00e9 dans le Sud Ouest de l'Inde : Chenai, Kavali et Pondichery. Ce que ce voyage m'a appris sur moi en tant que femme.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/soirees-voyages-rencontres\/un-an-apres-mon-voyage-de-3-semaines-en-inde-ce-que-je-retiens.html","og_locale":"fr_FR","og_type":"article","og_title":"Un an apr\u00e8s mon voyage de 3 semaines en Inde ce que je retiens - Les Bridgets","og_description":"Bilan un an apr\u00e8s de mon mois pass\u00e9 dans le Sud Ouest de l'Inde : Chenai, Kavali et Pondichery. Ce que ce voyage m'a appris sur moi en tant que femme.","og_url":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/soirees-voyages-rencontres\/un-an-apres-mon-voyage-de-3-semaines-en-inde-ce-que-je-retiens.html","og_site_name":"Les Bridgets","article_publisher":"https:\/\/www.facebook.com\/Les.Bridgets","article_published_time":"2017-02-07T07:49:53+00:00","article_modified_time":"2020-06-21T08:51:57+00:00","og_image":[{"width":750,"height":511,"url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2017\/02\/voyage-Inde-femme-seule.jpg","type":"image\/jpeg"}],"author":"Bridget","twitter_card":"summary_large_image","twitter_creator":"@les_bridgets","twitter_site":"@les_bridgets","twitter_misc":{"\u00c9crit par":"Bridget","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/soirees-voyages-rencontres\/un-an-apres-mon-voyage-de-3-semaines-en-inde-ce-que-je-retiens.html#article","isPartOf":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/soirees-voyages-rencontres\/un-an-apres-mon-voyage-de-3-semaines-en-inde-ce-que-je-retiens.html"},"author":{"name":"Bridget","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/person\/82a31c27ae0ddd23ee59e1e2ac5713ba"},"headline":"Un an apr\u00e8s mon voyage de 3 semaines en Inde ce que je retiens","datePublished":"2017-02-07T07:49:53+00:00","dateModified":"2020-06-21T08:51:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/soirees-voyages-rencontres\/un-an-apres-mon-voyage-de-3-semaines-en-inde-ce-que-je-retiens.html"},"wordCount":1226,"commentCount":2,"publisher":{"@id":"https:\/\/www.lesbridgets.com\/#organization"},"image":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/soirees-voyages-rencontres\/un-an-apres-mon-voyage-de-3-semaines-en-inde-ce-que-je-retiens.html#primaryimage"},"thumbnailUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2017\/02\/voyage-Inde-femme-seule.jpg","keywords":["droit","inde","voyager seule"],"articleSection":["Soir\u00e9es, voyages, rencontres"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/soirees-voyages-rencontres\/un-an-apres-mon-voyage-de-3-semaines-en-inde-ce-que-je-retiens.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/soirees-voyages-rencontres\/un-an-apres-mon-voyage-de-3-semaines-en-inde-ce-que-je-retiens.html","url":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/soirees-voyages-rencontres\/un-an-apres-mon-voyage-de-3-semaines-en-inde-ce-que-je-retiens.html","name":"Un an apr\u00e8s mon voyage de 3 semaines en Inde ce que je retiens - Les Bridgets","isPartOf":{"@id":"https:\/\/www.lesbridgets.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/soirees-voyages-rencontres\/un-an-apres-mon-voyage-de-3-semaines-en-inde-ce-que-je-retiens.html#primaryimage"},"image":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/soirees-voyages-rencontres\/un-an-apres-mon-voyage-de-3-semaines-en-inde-ce-que-je-retiens.html#primaryimage"},"thumbnailUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2017\/02\/voyage-Inde-femme-seule.jpg","datePublished":"2017-02-07T07:49:53+00:00","dateModified":"2020-06-21T08:51:57+00:00","description":"Bilan un an apr\u00e8s de mon mois pass\u00e9 dans le Sud Ouest de l'Inde : Chenai, Kavali et Pondichery. Ce que ce voyage m'a appris sur moi en tant que femme.","breadcrumb":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/soirees-voyages-rencontres\/un-an-apres-mon-voyage-de-3-semaines-en-inde-ce-que-je-retiens.html#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/soirees-voyages-rencontres\/un-an-apres-mon-voyage-de-3-semaines-en-inde-ce-que-je-retiens.html"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/soirees-voyages-rencontres\/un-an-apres-mon-voyage-de-3-semaines-en-inde-ce-que-je-retiens.html#primaryimage","url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2017\/02\/voyage-Inde-femme-seule.jpg","contentUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2017\/02\/voyage-Inde-femme-seule.jpg","width":750,"height":511},{"@type":"BreadcrumbList","@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/soirees-voyages-rencontres\/un-an-apres-mon-voyage-de-3-semaines-en-inde-ce-que-je-retiens.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Les Bridgets","item":"https:\/\/www.lesbridgets.com\/"},{"@type":"ListItem","position":2,"name":"Conseils sur l'amour, le couple &amp; les c\u00e9libataires","item":"https:\/\/www.lesbridgets.com\/index.php\/category\/conseils-relations"},{"@type":"ListItem","position":3,"name":"Soir\u00e9es, voyages, rencontres","item":"https:\/\/www.lesbridgets.com\/index.php\/category\/conseils-relations\/soirees-voyages-rencontres"},{"@type":"ListItem","position":4,"name":"Un an apr\u00e8s mon voyage de 3 semaines en Inde ce que je retiens"}]},{"@type":"WebSite","@id":"https:\/\/www.lesbridgets.com\/#website","url":"https:\/\/www.lesbridgets.com\/","name":"Les Bridgets","description":"R\u00e9f\u00e9rences et r\u00e9flexions sur nos relations","publisher":{"@id":"https:\/\/www.lesbridgets.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lesbridgets.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lesbridgets.com\/#organization","name":"Les Bridgets","url":"https:\/\/www.lesbridgets.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2022\/07\/cropped-logo-3-lesbridgets.png","contentUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2022\/07\/cropped-logo-3-lesbridgets.png","width":251,"height":59,"caption":"Les Bridgets"},"image":{"@id":"https:\/\/www.lesbridgets.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Les.Bridgets","https:\/\/x.com\/les_bridgets"]},{"@type":"Person","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/person\/82a31c27ae0ddd23ee59e1e2ac5713ba","name":"Bridget","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","caption":"Bridget"}}]}},"modified_by":"Bridget","_links":{"self":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/2191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/comments?post=2191"}],"version-history":[{"count":13,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/2191\/revisions"}],"predecessor-version":[{"id":252876,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/2191\/revisions\/252876"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/media\/2190"}],"wp:attachment":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/media?parent=2191"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/categories?post=2191"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/tags?post=2191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}