{"id":2016,"date":"2016-03-30T07:14:17","date_gmt":"2016-03-30T05:14:17","guid":{"rendered":"http:\/\/lesbridg.cluster015.ovh.net\/wordpress\/index.php\/etude-statistiques-sur-le-couple\/le-nombre-de-divorces-et-de-mariages-en-france-en-baisse-depuis-2013.html"},"modified":"2019-04-02T14:58:20","modified_gmt":"2019-04-02T12:58:20","slug":"le-nombre-de-divorces-et-de-mariages-en-france-en-baisse-depuis-2013","status":"publish","type":"post","link":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/le-nombre-de-divorces-et-de-mariages-en-france-en-baisse-depuis-2013.html","title":{"rendered":"Le nombre de divorces et de mariages en France en baisse depuis 2013"},"content":{"rendered":"<p>Voil\u00e0 un article du site que vous aimez bien \u00ab\u00a0<a href=\"index.php\/Etude-\/-Statistiques-sur-le-couple\/Mariage-puis-divorce-les-chiffres.html\" target=\"_blank\" rel=\"alternate noopener noreferrer\">Mariage puis divorce : les chiffres en France<\/a>\u00a0\u00bb un article qui date de 2007 (que vous avez \u00e9t\u00e9 plus de 150 000 \u00e0 lire) dont il est temps de partager les nouveaux chiffres presque 10 ans apr\u00e8s !<br \/>\nAussi surprenant que cela puisse para\u00eetre si on regarde <a href=\"http:\/\/www.insee.fr\/fr\/themes\/tableau.asp?reg_id=0&amp;ref_id=bilandemo8\" target=\"_blank\" rel=\"alternate noopener noreferrer\">les chiffres de l&rsquo;Insee<\/a>, le nombre de <a href=\"http:\/\/www.alexia.fr\/divorce\/\" target=\"_blank\" rel=\"alternate noopener noreferrer\">divorce<\/a>\u00a0est en baisse depuis 2010 o\u00f9 ils \u00e9taient presque 134 000 \u00e0 divorcer contre 123 500 aujourd&rsquo;hui.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/tracking.publicidees.com\/clic.php?partid=41407&amp;progid=3055&amp;promoid=78895\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" src=\"https:\/\/tracking.publicidees.com\/banner.php?partid=41407&amp;progid=3055&amp;promoid=78895\" border=\"0\" \/><\/a><\/p>\n<p>La raison est peut-\u00eatre qu&rsquo;il y a de moins en moins de gens mari\u00e9s ?<\/p>\n<p>Regardons les chiffres de ce c\u00f4t\u00e9 :<\/p>\n<h1>En effet, depuis 2005 c&rsquo;est la d\u00e9gringolade niveau nombre de mariages en France, on est pass\u00e9 d&rsquo;\u00e0 peine 283 000 mariages \u00e0 231 000 en 2015 )<\/h1>\n<p>Notons tout de m\u00eame que les pacs sont en progression. En 2009, ce sont deux pacs pour trois mariages.<\/p>\n<p>L\u2019\u00e2ge moyen des partenaires de Pacs de sexe diff\u00e9rent est proche de celui du mariage (34 ans pour les hommes, 32 ans pour les femmes), celui des couples de m\u00eame sexe est plus \u00e9lev\u00e9 (respectivement 38 et 37 ans).<\/p>\n<h1>Il faut noter aussi que l&rsquo;on se marie aussi de plus en plus tardivement.<\/h1>\n<p>Depuis 2004, les femmes se mariaient en moyenne \u00e0 32 ans pour aujourd&rsquo;hui se marier \u00e0 presque 35 ans. Quand aux hommes, ils\u00a0se mariaient \u00e0 presque 35 ans en 2005 contre aujourd&rsquo;hui plus de 37 ans.<\/p>\n<p style=\"text-align: left;\">En France la dur\u00e9e moyenne d&rsquo;un mariage est de 13 ans pour un taux de divorce de 55%. Si on compare avec les autres pays c&rsquo;est en Italie que les mariages durent le plus longtemps avec une moyenne de 18 ans contre le Quatar o\u00f9 la dur\u00e9e moyenne du mariage est de 5,5 ans !<\/p>\n<p style=\"text-align: center;\">\n<script type=\"text\/javascript\" src=\"https:\/\/img.metaffiliation.com\/na\/na\/res\/trk\/script.js\"><\/script><br \/>\n<!-- BEGIN CODE IMAGE 336x280 --><br \/>\n<script type=\"text\/javascript\">\n\ttry {\n\t\tnew __trknanapub(\"S41F164267911113\");\n\t} catch(e) {}\n<\/script><br \/>\n<noscript><br \/>\n<iframe loading=\"lazy\" src=\"https:\/\/action.metaffiliation.com\/trk.php?maff=N41F164267911113\" width=\"336\" height=\"280\" frameborder=\"0\" scrolling=\"no\"><\/iframe><br \/>\n<\/noscript><br \/>\n<!-- END CODE --><\/p>\n<h1>En France, les unions se fragilisent.<\/h1>\n<p>La proportion d\u2019unions rompues dans les 5 premi\u00e8res ann\u00e9es a beaucoup augment\u00e9, aussi bien pour les couples mari\u00e9s directement que pour ceux qui ont commenc\u00e9 leur vie commune hors mariage <a href=\"http:\/\/www.ined.fr\/fichier\/s_rubrique\/19090\/pop_et_soc_francais_422.fr.pdf\" target=\"_blank\" rel=\"alternate noopener noreferrer\">(tableau).<\/a>\u00a0Mais la probabilit\u00e9 de rupture de ces derniers est beaucoup plus forte. Les enqu\u00eates europ\u00e9ennes confirment partout cette plus grande fragilit\u00e9 des unions hors mariage : c\u2019est surtout dans les premi\u00e8res ann\u00e9es de l\u2019union que le risque de rupture est tr\u00e8s \u00e9lev\u00e9, en comparaison des mariages directs.<\/p>\n<p>Mais le mariage ne constitue pas non plus une garantie absolue contre la rupture, et dans la plupart des pays o\u00f9 la cohabitation est aujourd\u2019hui fr\u00e9quente, les couples dont le mariage a \u00e9t\u00e9 pr\u00e9c\u00e9d\u00e9 d\u2019une p\u00e9riode de cohabitation sont plus enclins \u00e0 se s\u00e9parer que ceux qui se sont mari\u00e9s directement.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voil\u00e0 un article du site que vous aimez bien \u00ab\u00a0<a href=\"index.php\/Etude-\/-Statistiques-sur-le-couple\/Mariage-puis-divorce-les-chiffres.html\" target=\"_blank\" rel=\"alternate noopener noreferrer\">Mariage puis divorce : les chiffres en France<\/a>\u00a0\u00bb un article qui date de 2007 (que vous avez \u00e9t\u00e9 plus de 150 000 \u00e0 lire) dont il est temps de partager les nouveaux chiffres presque 10 ans apr\u00e8s ! <br \/>Aussi surprenant que cela puisse para\u00eetre si on regarde <a href=\"http:\/\/www.insee.fr\/fr\/themes\/tableau.asp?reg_id=0&amp;ref_id=bilandemo8\" target=\"_blank\" rel=\"alternate noopener noreferrer\">les chiffres de l&rsquo;Insee<\/a>, le nombre de <a href=\"http:\/\/www.alexia.fr\/divorce\/\" target=\"_blank\" rel=\"alternate noopener noreferrer\">divorce<\/a>\u00a0est en baisse depuis 2010 o\u00f9 ils \u00e9taient presque 134 000 \u00e0 divorcer contre 123 500 aujourd&rsquo;hui.<\/p>\n<p>La raison est peut-\u00eatre qu&rsquo;il y a de moins en moins de gens mari\u00e9s ?<\/p>\n","protected":false},"author":2,"featured_media":2015,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"om_disable_all_campaigns":false,"_lmt_disableupdate":"","_lmt_disable":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[9],"tags":[100,125],"class_list":["post-2016","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-etude-statistiques-couple","tag-divorce","tag-mariage"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le nombre de divorces et de mariages en France en baisse depuis 2013 - Les Bridgets<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/le-nombre-de-divorces-et-de-mariages-en-france-en-baisse-depuis-2013.html\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le nombre de divorces et de mariages en France en baisse depuis 2013 - Les Bridgets\" \/>\n<meta property=\"og:description\" content=\"Voil\u00e0 un article du site que vous aimez bien &quot;Mariage puis divorce : les chiffres en France&quot; un article qui date de 2007 (que vous avez \u00e9t\u00e9 plus de 150 000 \u00e0 lire) dont il est temps de partager les nouveaux chiffres presque 10 ans apr\u00e8s ! Aussi surprenant que cela puisse para\u00eetre si on regarde les chiffres de l&#039;Insee, le nombre de divorce\u00a0est en baisse depuis 2010 o\u00f9 ils \u00e9taient presque 134 000 \u00e0 divorcer contre 123 500 aujourd&#039;hui. La raison est peut-\u00eatre qu&#039;il y a de moins en moins de gens mari\u00e9s ?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/le-nombre-de-divorces-et-de-mariages-en-france-en-baisse-depuis-2013.html\" \/>\n<meta property=\"og:site_name\" content=\"Les Bridgets\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Les.Bridgets\" \/>\n<meta property=\"article:published_time\" content=\"2016-03-30T05:14:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-02T12:58:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2016\/03\/divorce-mariage-france.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"462\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bridget\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@les_bridgets\" \/>\n<meta name=\"twitter:site\" content=\"@les_bridgets\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bridget\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/statistiques\\\/etude-statistiques-couple\\\/le-nombre-de-divorces-et-de-mariages-en-france-en-baisse-depuis-2013.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/statistiques\\\/etude-statistiques-couple\\\/le-nombre-de-divorces-et-de-mariages-en-france-en-baisse-depuis-2013.html\"},\"author\":{\"name\":\"Bridget\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/person\\\/82a31c27ae0ddd23ee59e1e2ac5713ba\"},\"headline\":\"Le nombre de divorces et de mariages en France en baisse depuis 2013\",\"datePublished\":\"2016-03-30T05:14:17+00:00\",\"dateModified\":\"2019-04-02T12:58:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/statistiques\\\/etude-statistiques-couple\\\/le-nombre-de-divorces-et-de-mariages-en-france-en-baisse-depuis-2013.html\"},\"wordCount\":436,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/statistiques\\\/etude-statistiques-couple\\\/le-nombre-de-divorces-et-de-mariages-en-france-en-baisse-depuis-2013.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2016\\\/03\\\/divorce-mariage-france.jpg\",\"keywords\":[\"divorce\",\"mariage\"],\"articleSection\":[\"Statistiques sur le couple\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/statistiques\\\/etude-statistiques-couple\\\/le-nombre-de-divorces-et-de-mariages-en-france-en-baisse-depuis-2013.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/statistiques\\\/etude-statistiques-couple\\\/le-nombre-de-divorces-et-de-mariages-en-france-en-baisse-depuis-2013.html\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/statistiques\\\/etude-statistiques-couple\\\/le-nombre-de-divorces-et-de-mariages-en-france-en-baisse-depuis-2013.html\",\"name\":\"Le nombre de divorces et de mariages en France en baisse depuis 2013 - Les Bridgets\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/statistiques\\\/etude-statistiques-couple\\\/le-nombre-de-divorces-et-de-mariages-en-france-en-baisse-depuis-2013.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/statistiques\\\/etude-statistiques-couple\\\/le-nombre-de-divorces-et-de-mariages-en-france-en-baisse-depuis-2013.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2016\\\/03\\\/divorce-mariage-france.jpg\",\"datePublished\":\"2016-03-30T05:14:17+00:00\",\"dateModified\":\"2019-04-02T12:58:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/statistiques\\\/etude-statistiques-couple\\\/le-nombre-de-divorces-et-de-mariages-en-france-en-baisse-depuis-2013.html#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/statistiques\\\/etude-statistiques-couple\\\/le-nombre-de-divorces-et-de-mariages-en-france-en-baisse-depuis-2013.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/statistiques\\\/etude-statistiques-couple\\\/le-nombre-de-divorces-et-de-mariages-en-france-en-baisse-depuis-2013.html#primaryimage\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2016\\\/03\\\/divorce-mariage-france.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2016\\\/03\\\/divorce-mariage-france.jpg\",\"width\":750,\"height\":462},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/statistiques\\\/etude-statistiques-couple\\\/le-nombre-de-divorces-et-de-mariages-en-france-en-baisse-depuis-2013.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Les Bridgets\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Statistiques sur le couple &amp; celibat\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/category\\\/statistiques\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Statistiques sur le couple\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/category\\\/statistiques\\\/etude-statistiques-couple\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Le nombre de divorces et de mariages en France en baisse depuis 2013\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#website\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/\",\"name\":\"Les Bridgets\",\"description\":\"R\u00e9f\u00e9rences et r\u00e9flexions sur nos relations\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lesbridgets.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\",\"name\":\"Les Bridgets\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo-3-lesbridgets.png\",\"contentUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo-3-lesbridgets.png\",\"width\":251,\"height\":59,\"caption\":\"Les Bridgets\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Les.Bridgets\",\"https:\\\/\\\/x.com\\\/les_bridgets\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/person\\\/82a31c27ae0ddd23ee59e1e2ac5713ba\",\"name\":\"Bridget\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"caption\":\"Bridget\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le nombre de divorces et de mariages en France en baisse depuis 2013 - Les Bridgets","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/le-nombre-de-divorces-et-de-mariages-en-france-en-baisse-depuis-2013.html","og_locale":"fr_FR","og_type":"article","og_title":"Le nombre de divorces et de mariages en France en baisse depuis 2013 - Les Bridgets","og_description":"Voil\u00e0 un article du site que vous aimez bien \"Mariage puis divorce : les chiffres en France\" un article qui date de 2007 (que vous avez \u00e9t\u00e9 plus de 150 000 \u00e0 lire) dont il est temps de partager les nouveaux chiffres presque 10 ans apr\u00e8s ! Aussi surprenant que cela puisse para\u00eetre si on regarde les chiffres de l'Insee, le nombre de divorce\u00a0est en baisse depuis 2010 o\u00f9 ils \u00e9taient presque 134 000 \u00e0 divorcer contre 123 500 aujourd'hui. La raison est peut-\u00eatre qu'il y a de moins en moins de gens mari\u00e9s ?","og_url":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/le-nombre-de-divorces-et-de-mariages-en-france-en-baisse-depuis-2013.html","og_site_name":"Les Bridgets","article_publisher":"https:\/\/www.facebook.com\/Les.Bridgets","article_published_time":"2016-03-30T05:14:17+00:00","article_modified_time":"2019-04-02T12:58:20+00:00","og_image":[{"width":750,"height":462,"url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2016\/03\/divorce-mariage-france.jpg","type":"image\/jpeg"}],"author":"Bridget","twitter_card":"summary_large_image","twitter_creator":"@les_bridgets","twitter_site":"@les_bridgets","twitter_misc":{"\u00c9crit par":"Bridget","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/le-nombre-de-divorces-et-de-mariages-en-france-en-baisse-depuis-2013.html#article","isPartOf":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/le-nombre-de-divorces-et-de-mariages-en-france-en-baisse-depuis-2013.html"},"author":{"name":"Bridget","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/person\/82a31c27ae0ddd23ee59e1e2ac5713ba"},"headline":"Le nombre de divorces et de mariages en France en baisse depuis 2013","datePublished":"2016-03-30T05:14:17+00:00","dateModified":"2019-04-02T12:58:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/le-nombre-de-divorces-et-de-mariages-en-france-en-baisse-depuis-2013.html"},"wordCount":436,"commentCount":0,"publisher":{"@id":"https:\/\/www.lesbridgets.com\/#organization"},"image":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/le-nombre-de-divorces-et-de-mariages-en-france-en-baisse-depuis-2013.html#primaryimage"},"thumbnailUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2016\/03\/divorce-mariage-france.jpg","keywords":["divorce","mariage"],"articleSection":["Statistiques sur le couple"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/le-nombre-de-divorces-et-de-mariages-en-france-en-baisse-depuis-2013.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/le-nombre-de-divorces-et-de-mariages-en-france-en-baisse-depuis-2013.html","url":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/le-nombre-de-divorces-et-de-mariages-en-france-en-baisse-depuis-2013.html","name":"Le nombre de divorces et de mariages en France en baisse depuis 2013 - Les Bridgets","isPartOf":{"@id":"https:\/\/www.lesbridgets.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/le-nombre-de-divorces-et-de-mariages-en-france-en-baisse-depuis-2013.html#primaryimage"},"image":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/le-nombre-de-divorces-et-de-mariages-en-france-en-baisse-depuis-2013.html#primaryimage"},"thumbnailUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2016\/03\/divorce-mariage-france.jpg","datePublished":"2016-03-30T05:14:17+00:00","dateModified":"2019-04-02T12:58:20+00:00","breadcrumb":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/le-nombre-de-divorces-et-de-mariages-en-france-en-baisse-depuis-2013.html#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/le-nombre-de-divorces-et-de-mariages-en-france-en-baisse-depuis-2013.html"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/le-nombre-de-divorces-et-de-mariages-en-france-en-baisse-depuis-2013.html#primaryimage","url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2016\/03\/divorce-mariage-france.jpg","contentUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2016\/03\/divorce-mariage-france.jpg","width":750,"height":462},{"@type":"BreadcrumbList","@id":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/le-nombre-de-divorces-et-de-mariages-en-france-en-baisse-depuis-2013.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Les Bridgets","item":"https:\/\/www.lesbridgets.com\/"},{"@type":"ListItem","position":2,"name":"Statistiques sur le couple &amp; celibat","item":"https:\/\/www.lesbridgets.com\/index.php\/category\/statistiques"},{"@type":"ListItem","position":3,"name":"Statistiques sur le couple","item":"https:\/\/www.lesbridgets.com\/index.php\/category\/statistiques\/etude-statistiques-couple"},{"@type":"ListItem","position":4,"name":"Le nombre de divorces et de mariages en France en baisse depuis 2013"}]},{"@type":"WebSite","@id":"https:\/\/www.lesbridgets.com\/#website","url":"https:\/\/www.lesbridgets.com\/","name":"Les Bridgets","description":"R\u00e9f\u00e9rences et r\u00e9flexions sur nos relations","publisher":{"@id":"https:\/\/www.lesbridgets.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lesbridgets.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lesbridgets.com\/#organization","name":"Les Bridgets","url":"https:\/\/www.lesbridgets.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2022\/07\/cropped-logo-3-lesbridgets.png","contentUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2022\/07\/cropped-logo-3-lesbridgets.png","width":251,"height":59,"caption":"Les Bridgets"},"image":{"@id":"https:\/\/www.lesbridgets.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Les.Bridgets","https:\/\/x.com\/les_bridgets"]},{"@type":"Person","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/person\/82a31c27ae0ddd23ee59e1e2ac5713ba","name":"Bridget","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","caption":"Bridget"}}]}},"modified_by":"Bridget","_links":{"self":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/2016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/comments?post=2016"}],"version-history":[{"count":2,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/2016\/revisions"}],"predecessor-version":[{"id":246623,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/2016\/revisions\/246623"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/media\/2015"}],"wp:attachment":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/media?parent=2016"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/categories?post=2016"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/tags?post=2016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}