{"id":2004,"date":"2016-02-28T16:53:21","date_gmt":"2016-02-28T15:53:21","guid":{"rendered":"http:\/\/lesbridg.cluster015.ovh.net\/wordpress\/index.php\/serie-couple-celibataire\/on-a-regarde-la-saison-1-de-la-serie-love-par-jude-appatow.html"},"modified":"2016-02-28T16:53:21","modified_gmt":"2016-02-28T15:53:21","slug":"on-a-regarde-la-saison-1-de-la-serie-love-par-jude-appatow","status":"publish","type":"post","link":"https:\/\/www.lesbridgets.com\/index.php\/references\/serie-couple-celibataire\/on-a-regarde-la-saison-1-de-la-serie-love-par-jude-appatow.html","title":{"rendered":"On a regard\u00e9 la Saison 1 de la s\u00e9rie Love par Judd Apatow"},"content":{"rendered":"<p>On est toujours \u00e0 la recherche de nouvelle s\u00e9rie qui parle de relations amoureuses alors forc\u00e9ment quand on a appris la sortie de la s\u00e9rie Love r\u00e9alis\u00e9 par Judd Apatow, on \u00e9tait press\u00e9 de la voir surtout que beaucoup de sites en fond des \u00e9loges.<\/p>\n<p>C&rsquo;\u00e9tait assez mal parti, beaucoup nous on dit s&rsquo;\u00eatre ennuy\u00e9 et avoir abandonn\u00e9 apr\u00e8s le 2 ou 3\u00e8me \u00e9pisode et on a vite compris pourquoi.<\/p>\n<h1>Notre avis sur la s\u00e9rie Love de Netflix<\/h1>\n<p>La s\u00e9rie met beaucoup de temps \u00e0 d\u00e9marrer. L&rsquo;acteur Paul Rust a un cot\u00e9 Nerd dans l&rsquo;esprit de The Bing Bang Theory avec un sc\u00e9nariste qui veut lui donner un certain sex appeal, tombeur qu&rsquo;on a du mal \u00e0 accepter.<br \/>M\u00eame si il est attendrissant, on a vraiment du mal \u00e0 s&rsquo;imaginer craquer pour lui.<\/p>\n<p>A l&rsquo;inverse Gillian Jacobs dans le r\u00f4le de Mickey (d\u00e9couverte dans Community) m\u00eame si moins embellie que dans la pr\u00e9c\u00e9dente s\u00e9rie, on a du mal \u00e0 croire que tous ses exs ont tous des physiques de gros nounours pas franchement attirants. Certes comme pour Gus, on finit par l&rsquo;accepter ou presque.<\/p>\n<div>\u00a0<\/div>\n<h1>Alors finalement pourquoi on doit continuer de la regarder ?<\/h1>\n<div>Parce que Judd Apatow a ce pouvoir parfois de toucher l\u00e0 o\u00f9 il faut, comme pour la sc\u00e8ne du plan \u00e0 3 ou encore celle du sextoy avec le chat \u00e0 c\u00f4t\u00e9 sur le lit.<\/div>\n<div>Il est parfois dans le r\u00e9el et \u00e7a on aime.<\/div>\n<div>\u00a0<\/div>\n<div>Pour l&rsquo;instant ce n&rsquo;est pas la s\u00e9rie inoubliable de l&rsquo;ann\u00e9e mais elle vaut la peine de s&rsquo;accrocher un peu jusqu&rsquo;au 5\u00e8me \u00e9pisode de cette premi\u00e8re saison (oui on est d&rsquo;accord \u00e7a fait un peu long).<\/div>\n<p><iframe loading=\"lazy\" style=\"display: block; margin-left: auto; margin-right: auto;\" src=\"https:\/\/www.youtube.com\/embed\/Ym3LoSj9Xj8\" width=\"750\" height=\"422\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Jud Apatow sc\u00e9nariste d\u00e9j\u00e0 sur <a href=\"https:\/\/www.lesbridgets.com\/index.php\/Serie\/On-avait-Sex-and-the-City-elles-ont-Girls.html\" target=\"_blank\" rel=\"alternate\">Girlz on s&rsquo;\u00e9tait dit que \u00e7a ne nous parlait pas<\/a>\u00a0parce que c&rsquo;\u00e9tait pas des trentenaires. Cette fois dans Love, ce sont des trentenaires Gus a 34 ans et pourtant on accroche pas plus que \u00e7a. C&rsquo;est bien dommage parce qu&rsquo;il y a un vrai potentiel. Saison 2 \u00e0 suivre si une autre s\u00e9rie ne nous a pas plus inspir\u00e9 d&rsquo;ici l\u00e0 comme You&rsquo;re The Worst.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>On est toujours \u00e0 la recherche de nouvelle s\u00e9rie qui parle de relations amoureuses alors forc\u00e9ment quand on a appris la sortie de la s\u00e9rie Love r\u00e9alis\u00e9 par Judd Apatow, on \u00e9tait press\u00e9 de la voir surtout que beaucoup de sites en fond des \u00e9loges.<\/p>\n<p>C&rsquo;\u00e9tait assez mal parti, beaucoup nous on dit s&rsquo;\u00eatre ennuy\u00e9 et avoir abandonn\u00e9 apr\u00e8s le 2 ou 3\u00e8me \u00e9pisode et on a vite compris pourquoi.<\/p>\n","protected":false},"author":2,"featured_media":2003,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"om_disable_all_campaigns":false,"_lmt_disableupdate":"","_lmt_disable":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[43],"tags":[99],"class_list":["post-2004","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-serie-couple-celibataire","tag-serie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>On a regard\u00e9 la Saison 1 de la s\u00e9rie Love par Judd Apatow - Les Bridgets<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lesbridgets.com\/index.php\/references\/serie-couple-celibataire\/on-a-regarde-la-saison-1-de-la-serie-love-par-jude-appatow.html\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"On a regard\u00e9 la Saison 1 de la s\u00e9rie Love par Judd Apatow - Les Bridgets\" \/>\n<meta property=\"og:description\" content=\"On est toujours \u00e0 la recherche de nouvelle s\u00e9rie qui parle de relations amoureuses alors forc\u00e9ment quand on a appris la sortie de la s\u00e9rie Love r\u00e9alis\u00e9 par Judd Apatow, on \u00e9tait press\u00e9 de la voir surtout que beaucoup de sites en fond des \u00e9loges.C&#039;\u00e9tait assez mal parti, beaucoup nous on dit s&#039;\u00eatre ennuy\u00e9 et avoir abandonn\u00e9 apr\u00e8s le 2 ou 3\u00e8me \u00e9pisode et on a vite compris pourquoi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lesbridgets.com\/index.php\/references\/serie-couple-celibataire\/on-a-regarde-la-saison-1-de-la-serie-love-par-jude-appatow.html\" \/>\n<meta property=\"og:site_name\" content=\"Les Bridgets\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Les.Bridgets\" \/>\n<meta property=\"article:published_time\" content=\"2016-02-28T15:53:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2016\/02\/avis-love-serie-netflix.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"523\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bridget\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@les_bridgets\" \/>\n<meta name=\"twitter:site\" content=\"@les_bridgets\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bridget\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/serie-couple-celibataire\\\/on-a-regarde-la-saison-1-de-la-serie-love-par-jude-appatow.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/serie-couple-celibataire\\\/on-a-regarde-la-saison-1-de-la-serie-love-par-jude-appatow.html\"},\"author\":{\"name\":\"Bridget\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/person\\\/82a31c27ae0ddd23ee59e1e2ac5713ba\"},\"headline\":\"On a regard\u00e9 la Saison 1 de la s\u00e9rie Love par Judd Apatow\",\"datePublished\":\"2016-02-28T15:53:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/serie-couple-celibataire\\\/on-a-regarde-la-saison-1-de-la-serie-love-par-jude-appatow.html\"},\"wordCount\":390,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/serie-couple-celibataire\\\/on-a-regarde-la-saison-1-de-la-serie-love-par-jude-appatow.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/avis-love-serie-netflix.jpg\",\"keywords\":[\"serie\"],\"articleSection\":[\"S\u00e9rie\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/serie-couple-celibataire\\\/on-a-regarde-la-saison-1-de-la-serie-love-par-jude-appatow.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/serie-couple-celibataire\\\/on-a-regarde-la-saison-1-de-la-serie-love-par-jude-appatow.html\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/serie-couple-celibataire\\\/on-a-regarde-la-saison-1-de-la-serie-love-par-jude-appatow.html\",\"name\":\"On a regard\u00e9 la Saison 1 de la s\u00e9rie Love par Judd Apatow - Les Bridgets\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/serie-couple-celibataire\\\/on-a-regarde-la-saison-1-de-la-serie-love-par-jude-appatow.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/serie-couple-celibataire\\\/on-a-regarde-la-saison-1-de-la-serie-love-par-jude-appatow.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/avis-love-serie-netflix.jpg\",\"datePublished\":\"2016-02-28T15:53:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/serie-couple-celibataire\\\/on-a-regarde-la-saison-1-de-la-serie-love-par-jude-appatow.html#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/serie-couple-celibataire\\\/on-a-regarde-la-saison-1-de-la-serie-love-par-jude-appatow.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/serie-couple-celibataire\\\/on-a-regarde-la-saison-1-de-la-serie-love-par-jude-appatow.html#primaryimage\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/avis-love-serie-netflix.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/avis-love-serie-netflix.jpg\",\"width\":750,\"height\":523},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/serie-couple-celibataire\\\/on-a-regarde-la-saison-1-de-la-serie-love-par-jude-appatow.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Les Bridgets\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00e9f\u00e9rences sur le couple et le c\u00e9libat\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/category\\\/references\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"S\u00e9rie\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/category\\\/references\\\/serie-couple-celibataire\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"On a regard\u00e9 la Saison 1 de la s\u00e9rie Love par Judd Apatow\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#website\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/\",\"name\":\"Les Bridgets\",\"description\":\"R\u00e9f\u00e9rences et r\u00e9flexions sur nos relations\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lesbridgets.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\",\"name\":\"Les Bridgets\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo-3-lesbridgets.png\",\"contentUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo-3-lesbridgets.png\",\"width\":251,\"height\":59,\"caption\":\"Les Bridgets\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Les.Bridgets\",\"https:\\\/\\\/x.com\\\/les_bridgets\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/person\\\/82a31c27ae0ddd23ee59e1e2ac5713ba\",\"name\":\"Bridget\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"caption\":\"Bridget\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"On a regard\u00e9 la Saison 1 de la s\u00e9rie Love par Judd Apatow - Les Bridgets","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lesbridgets.com\/index.php\/references\/serie-couple-celibataire\/on-a-regarde-la-saison-1-de-la-serie-love-par-jude-appatow.html","og_locale":"fr_FR","og_type":"article","og_title":"On a regard\u00e9 la Saison 1 de la s\u00e9rie Love par Judd Apatow - Les Bridgets","og_description":"On est toujours \u00e0 la recherche de nouvelle s\u00e9rie qui parle de relations amoureuses alors forc\u00e9ment quand on a appris la sortie de la s\u00e9rie Love r\u00e9alis\u00e9 par Judd Apatow, on \u00e9tait press\u00e9 de la voir surtout que beaucoup de sites en fond des \u00e9loges.C'\u00e9tait assez mal parti, beaucoup nous on dit s'\u00eatre ennuy\u00e9 et avoir abandonn\u00e9 apr\u00e8s le 2 ou 3\u00e8me \u00e9pisode et on a vite compris pourquoi.","og_url":"https:\/\/www.lesbridgets.com\/index.php\/references\/serie-couple-celibataire\/on-a-regarde-la-saison-1-de-la-serie-love-par-jude-appatow.html","og_site_name":"Les Bridgets","article_publisher":"https:\/\/www.facebook.com\/Les.Bridgets","article_published_time":"2016-02-28T15:53:21+00:00","og_image":[{"width":750,"height":523,"url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2016\/02\/avis-love-serie-netflix.jpg","type":"image\/jpeg"}],"author":"Bridget","twitter_card":"summary_large_image","twitter_creator":"@les_bridgets","twitter_site":"@les_bridgets","twitter_misc":{"\u00c9crit par":"Bridget","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/serie-couple-celibataire\/on-a-regarde-la-saison-1-de-la-serie-love-par-jude-appatow.html#article","isPartOf":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/serie-couple-celibataire\/on-a-regarde-la-saison-1-de-la-serie-love-par-jude-appatow.html"},"author":{"name":"Bridget","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/person\/82a31c27ae0ddd23ee59e1e2ac5713ba"},"headline":"On a regard\u00e9 la Saison 1 de la s\u00e9rie Love par Judd Apatow","datePublished":"2016-02-28T15:53:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/serie-couple-celibataire\/on-a-regarde-la-saison-1-de-la-serie-love-par-jude-appatow.html"},"wordCount":390,"commentCount":0,"publisher":{"@id":"https:\/\/www.lesbridgets.com\/#organization"},"image":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/serie-couple-celibataire\/on-a-regarde-la-saison-1-de-la-serie-love-par-jude-appatow.html#primaryimage"},"thumbnailUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2016\/02\/avis-love-serie-netflix.jpg","keywords":["serie"],"articleSection":["S\u00e9rie"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.lesbridgets.com\/index.php\/references\/serie-couple-celibataire\/on-a-regarde-la-saison-1-de-la-serie-love-par-jude-appatow.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/serie-couple-celibataire\/on-a-regarde-la-saison-1-de-la-serie-love-par-jude-appatow.html","url":"https:\/\/www.lesbridgets.com\/index.php\/references\/serie-couple-celibataire\/on-a-regarde-la-saison-1-de-la-serie-love-par-jude-appatow.html","name":"On a regard\u00e9 la Saison 1 de la s\u00e9rie Love par Judd Apatow - Les Bridgets","isPartOf":{"@id":"https:\/\/www.lesbridgets.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/serie-couple-celibataire\/on-a-regarde-la-saison-1-de-la-serie-love-par-jude-appatow.html#primaryimage"},"image":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/serie-couple-celibataire\/on-a-regarde-la-saison-1-de-la-serie-love-par-jude-appatow.html#primaryimage"},"thumbnailUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2016\/02\/avis-love-serie-netflix.jpg","datePublished":"2016-02-28T15:53:21+00:00","breadcrumb":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/serie-couple-celibataire\/on-a-regarde-la-saison-1-de-la-serie-love-par-jude-appatow.html#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lesbridgets.com\/index.php\/references\/serie-couple-celibataire\/on-a-regarde-la-saison-1-de-la-serie-love-par-jude-appatow.html"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/serie-couple-celibataire\/on-a-regarde-la-saison-1-de-la-serie-love-par-jude-appatow.html#primaryimage","url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2016\/02\/avis-love-serie-netflix.jpg","contentUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2016\/02\/avis-love-serie-netflix.jpg","width":750,"height":523},{"@type":"BreadcrumbList","@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/serie-couple-celibataire\/on-a-regarde-la-saison-1-de-la-serie-love-par-jude-appatow.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Les Bridgets","item":"https:\/\/www.lesbridgets.com\/"},{"@type":"ListItem","position":2,"name":"R\u00e9f\u00e9rences sur le couple et le c\u00e9libat","item":"https:\/\/www.lesbridgets.com\/index.php\/category\/references"},{"@type":"ListItem","position":3,"name":"S\u00e9rie","item":"https:\/\/www.lesbridgets.com\/index.php\/category\/references\/serie-couple-celibataire"},{"@type":"ListItem","position":4,"name":"On a regard\u00e9 la Saison 1 de la s\u00e9rie Love par Judd Apatow"}]},{"@type":"WebSite","@id":"https:\/\/www.lesbridgets.com\/#website","url":"https:\/\/www.lesbridgets.com\/","name":"Les Bridgets","description":"R\u00e9f\u00e9rences et r\u00e9flexions sur nos relations","publisher":{"@id":"https:\/\/www.lesbridgets.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lesbridgets.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lesbridgets.com\/#organization","name":"Les Bridgets","url":"https:\/\/www.lesbridgets.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2022\/07\/cropped-logo-3-lesbridgets.png","contentUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2022\/07\/cropped-logo-3-lesbridgets.png","width":251,"height":59,"caption":"Les Bridgets"},"image":{"@id":"https:\/\/www.lesbridgets.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Les.Bridgets","https:\/\/x.com\/les_bridgets"]},{"@type":"Person","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/person\/82a31c27ae0ddd23ee59e1e2ac5713ba","name":"Bridget","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","caption":"Bridget"}}]}},"modified_by":null,"_links":{"self":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/2004","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/comments?post=2004"}],"version-history":[{"count":0,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/2004\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/media\/2003"}],"wp:attachment":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/media?parent=2004"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/categories?post=2004"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/tags?post=2004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}