{"id":1915,"date":"2015-11-10T09:12:32","date_gmt":"2015-11-10T08:12:32","guid":{"rendered":"http:\/\/lesbridg.cluster015.ovh.net\/wordpress\/index.php\/rencontres-virtuelles\/10-raisons-pourquoi-on-ne-repond-pas-sur-les-sites-de-rencontres.html"},"modified":"2025-05-17T19:55:38","modified_gmt":"2025-05-17T17:55:38","slug":"10-raisons-pourquoi-on-ne-repond-pas-sur-les-sites-de-rencontres","status":"publish","type":"post","link":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rencontres-virtuelles\/10-raisons-pourquoi-on-ne-repond-pas-sur-les-sites-de-rencontres.html","title":{"rendered":"10 raisons pourquoi on ne r\u00e9pond pas sur les sites de rencontres"},"content":{"rendered":"<p>Un des gros probl\u00e8mes des sites de rencontres que l&rsquo;on constate encore plus\u00a0sur les applications de dating comme <a href=\"https:\/\/www.lesbridgets.com\/index.php\/rencontres-virtuelles\/tinder-les-amis-de-nos-amis-qu-ils-n-avaient-pas-penses-a-nous-presenter.html\" target=\"_blank\" rel=\"alternate noopener\">Tinder<\/a>, est le nombre de personnes qui ne r\u00e9pondent pas.<br \/>\nPourtant parfois il y a eu \u00ab\u00a0charme\u00a0\u00bb, \u00ab\u00a0match\u00a0\u00bb et pas de r\u00e9ponse \u00e0 votre \u00ab\u00a0Hello,\u00a0\u00e7a va ?\u00a0\u00bb. On a r\u00e9fl\u00e9chi\u00a0entre nous pour\u00a0vous donner de vraies explications\u00a0\u00a0parce que nous faisons aussi parties de celles qui ne r\u00e9pondent pas et parfois aussi de celles qui sont blas\u00e9es parce que pour une pour une fois qu&rsquo;on envoie le message la premi\u00e8re, il ne nous r\u00e9pond pas non plus.<\/p>\n<h1>1. Elle ne re\u00e7oit pas les notifications<\/h1>\n<p>Vraie raison, entendue \u00e0 plusieurs reprises, oui beaucoup de personnes ne sont pas encore au point avec la technologie. Elle a lanc\u00e9 le site, l&rsquo;application une fois ou deux et puis elle s&rsquo;est dit que \u00e7a ne marchait pas et ne s&rsquo;est jamais reconnect\u00e9e.<\/p>\n<h1>2. Un autre monopolise son attention<\/h1>\n<p>C&rsquo;est bien connu, les femmes sont hyper sollicit\u00e9es. Un a \u00e9t\u00e9 plus convainquant et elle se concentre sur lui (pour le moment ?).<\/p>\n<h1>3. Elle n&rsquo;a plus de smartphone<\/h1>\n<p>Elle avait install\u00e9 son application sur son iPhone et on lui a vol\u00e9, elle l&rsquo;a cass\u00e9e. Bref elle n&rsquo;a plus le moyen de consulter ses notifications (pour le moment ?).<\/p>\n<h1>4. Elle est occup\u00e9e quand elle re\u00e7oit votre message et oublie de vous r\u00e9pondre plus tard<\/h1>\n<p>Vous lui envoyez un message \u00e0 0h52, elle dormait d\u00e9j\u00e0. Elle se r\u00e9veille, voit (ou pas) votre notification et pars au boulot.<br \/>\nN&rsquo;h\u00e9sitez pas \u00e0 lui renvoyer un petit mot si vous n&rsquo;avez pas de news dans les\u00a024h et apr\u00e8s laissez tomber.<\/p>\n<p><center><a href=\"https:\/\/tracking.publicidees.com\/clic.php?partid=41407&amp;progid=524&amp;promoid=74381\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/tracking.publicidees.com\/banner.php?partid=41407&amp;progid=524&amp;promoid=74381\" border=\"0\" \/><\/a><\/center><\/p>\n<h1>5. Elle s&rsquo;est inscrite pour son \u00e9go<\/h1>\n<p>Encore plus valable avec les applications telle que Tinder, elle s&rsquo;est inscrite pour voir si elle plaisait, ce qui est visiblement le cas mais n&rsquo;a pas l&rsquo;attention de faire des rencontres.<\/p>\n<h1>6. Elle s&rsquo;est inscrite sans conviction<\/h1>\n<p>Tout le monde lui en a parl\u00e9 mais elle n&rsquo;est pas motiv\u00e9e et n&rsquo;y croit pas. A vous de la convaincre ?<br \/>\nElle avait envie de faire des rencontres online et puis finalement non.<\/p>\n<p>Sur un \u00e9lan d&rsquo;un dimanche soir un peu d\u00e9primant, elle a r\u00e9activ\u00e9 son compte adopte un mec. Elle a charm\u00e9 2\/3 profils puis finalement elle n&rsquo;est pas plus motiv\u00e9e que \u00e7a.<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" src=\"https:\/\/www.tools-affil2.com\/rtb\/index.php?comfrom=964141&amp;r=5cc806516cfde25c8a0b8216fc382b73&amp;p=43328&amp;cf0=fx&amp;fa=true&amp;cf2=&amp;cfsa2=&amp;brand=y&amp;aabd2=&amp;aabs=\" width=\"728\" height=\"90\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" data-mce-fragment=\"1\"><\/iframe><\/p>\n<h1>7. Elle n&rsquo;a pas aim\u00e9 votre phrase d&rsquo;accroche<\/h1>\n<p>Votre profil \u00e9tait chouette mais le \u00ab\u00a0Salu, sa va\u00a0\u00bb l&rsquo;a quelques peu refroidi. Oui un rien et vous \u00eates \u00e9limin\u00e9 parmi ses centaines de matchs.<\/p>\n<h1>8. Son doigt a gliss\u00e9<\/h1>\n<p>Elle \u00e9tait \u00e0 son 128eme profil sur Tinder et elle a lik\u00e9 le votre\u00a0par inadvertance. Vous lui plaisiez (un peu) et apr\u00e8s avoir bien regard\u00e9 votre profil, finalement non.<\/p>\n<h1>9. Elle est morte<\/h1>\n<p>Certes glauque mais vraie r\u00e9ponse comme Carrie dans sex and the city qui pr\u00e9f\u00e8re se dire qu&rsquo;il est mort si un mec ne la rappelle pas. Il n&rsquo;y a aucun moyen de supprimer le compte d&rsquo;une personne morte sur un site de rencontre.<\/p>\n<h1>10. Elle n&rsquo;existe pas.<\/h1>\n<p>Malheureusement s\u00fbrement un des plus courants, son profil est un faux.\u00a0Ils sont tr\u00e8s nombreux surtout au lancement d&rsquo;un nouveau service de rencontres.<br \/>\nImaginez vous faites une recherche pour voir les profils \u00e0 5km de vous dans le 4\u00e8me arrondissement de Paris et seulement 2 profils sortent ?<br \/>\nCe ne serait pas cr\u00e9dible.<\/p>\n<p>On aurait pu au moins trouver 5 autres raisons suppl\u00e9mentaires mais si vous ne devez retenir qu&rsquo;un conseil :<br \/>\nNe vous d\u00e9couragez pas, jusqu&rsquo;au jour o\u00f9 vous tirerez le bon num\u00e9ro.<br \/>\nEt allez parler aux femmes dans la vraie vie, vous avez BEAUCOUP plus de chances que \u00e7a fonctionne et vous perdrez BEAUCOUP MOINS de temps.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un des gros probl\u00e8mes des sites de rencontres que l&rsquo;on constate encore plus\u00a0sur les applications de dating comme <a href=\"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rencontres-virtuelles\/tinder-les-amis-de-nos-amis-qu-ils-n-avaient-pas-penses-a-nous-presenter.html\" target=\"_blank\" rel=\"alternate noopener\">Tinder<\/a>, est le nombre de personnes qui ne r\u00e9pondent pas. <br \/>Pourtant parfois il y a eu \u00ab\u00a0charme\u00a0\u00bb, \u00ab\u00a0match\u00a0\u00bb et pas de r\u00e9ponse \u00e0 votre \u00ab\u00a0Hello,\u00a0\u00e7a va ?\u00a0\u00bb. On a r\u00e9fl\u00e9chi\u00a0entre nous pour\u00a0vous donner de vraies explications\u00a0\u00a0parce que nous faisons aussi parties de celles qui ne r\u00e9pondent pas et parfois aussi de celles qui sont blas\u00e9es parce que pour une pour une fois qu&rsquo;on envoie le message la premi\u00e8re, il ne nous r\u00e9pond pas non plus.<\/p>\n","protected":false},"author":2,"featured_media":1914,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"om_disable_all_campaigns":false,"_lmt_disableupdate":"no","_lmt_disable":"no","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[23],"tags":[605,521],"class_list":["post-1915","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rencontres-virtuelles","tag-sites-de-rencontres","tag-tinder"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>10 raisons pourquoi on ne r\u00e9pond pas sur les sites de rencontres - Les Bridgets<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rencontres-virtuelles\/10-raisons-pourquoi-on-ne-repond-pas-sur-les-sites-de-rencontres.html\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"10 raisons pourquoi on ne r\u00e9pond pas sur les sites de rencontres - Les Bridgets\" \/>\n<meta property=\"og:description\" content=\"Un des gros probl\u00e8mes des sites de rencontres que l&#039;on constate encore plus\u00a0sur les applications de dating comme Tinder, est le nombre de personnes qui ne r\u00e9pondent pas. Pourtant parfois il y a eu &quot;charme&quot;, &quot;match&quot; et pas de r\u00e9ponse \u00e0 votre &quot;Hello,\u00a0\u00e7a va ?&quot;. On a r\u00e9fl\u00e9chi\u00a0entre nous pour\u00a0vous donner de vraies explications\u00a0\u00a0parce que nous faisons aussi parties de celles qui ne r\u00e9pondent pas et parfois aussi de celles qui sont blas\u00e9es parce que pour une pour une fois qu&#039;on envoie le message la premi\u00e8re, il ne nous r\u00e9pond pas non plus.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rencontres-virtuelles\/10-raisons-pourquoi-on-ne-repond-pas-sur-les-sites-de-rencontres.html\" \/>\n<meta property=\"og:site_name\" content=\"Les Bridgets\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Les.Bridgets\" \/>\n<meta property=\"article:published_time\" content=\"2015-11-10T08:12:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-17T17:55:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2015\/11\/pourquoi-pas-reponse-sites-rencontre.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"574\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bridget\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@les_bridgets\" \/>\n<meta name=\"twitter:site\" content=\"@les_bridgets\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bridget\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/rencontres-virtuelles\\\/10-raisons-pourquoi-on-ne-repond-pas-sur-les-sites-de-rencontres.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/rencontres-virtuelles\\\/10-raisons-pourquoi-on-ne-repond-pas-sur-les-sites-de-rencontres.html\"},\"author\":{\"name\":\"Bridget\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/person\\\/82a31c27ae0ddd23ee59e1e2ac5713ba\"},\"headline\":\"10 raisons pourquoi on ne r\u00e9pond pas sur les sites de rencontres\",\"datePublished\":\"2015-11-10T08:12:32+00:00\",\"dateModified\":\"2025-05-17T17:55:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/rencontres-virtuelles\\\/10-raisons-pourquoi-on-ne-repond-pas-sur-les-sites-de-rencontres.html\"},\"wordCount\":661,\"commentCount\":30,\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/rencontres-virtuelles\\\/10-raisons-pourquoi-on-ne-repond-pas-sur-les-sites-de-rencontres.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/pourquoi-pas-reponse-sites-rencontre.jpg\",\"keywords\":[\"sites de rencontres\",\"tinder\"],\"articleSection\":[\"Rencontres en ligne\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/rencontres-virtuelles\\\/10-raisons-pourquoi-on-ne-repond-pas-sur-les-sites-de-rencontres.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/rencontres-virtuelles\\\/10-raisons-pourquoi-on-ne-repond-pas-sur-les-sites-de-rencontres.html\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/rencontres-virtuelles\\\/10-raisons-pourquoi-on-ne-repond-pas-sur-les-sites-de-rencontres.html\",\"name\":\"10 raisons pourquoi on ne r\u00e9pond pas sur les sites de rencontres - Les Bridgets\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/rencontres-virtuelles\\\/10-raisons-pourquoi-on-ne-repond-pas-sur-les-sites-de-rencontres.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/rencontres-virtuelles\\\/10-raisons-pourquoi-on-ne-repond-pas-sur-les-sites-de-rencontres.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/pourquoi-pas-reponse-sites-rencontre.jpg\",\"datePublished\":\"2015-11-10T08:12:32+00:00\",\"dateModified\":\"2025-05-17T17:55:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/rencontres-virtuelles\\\/10-raisons-pourquoi-on-ne-repond-pas-sur-les-sites-de-rencontres.html#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/rencontres-virtuelles\\\/10-raisons-pourquoi-on-ne-repond-pas-sur-les-sites-de-rencontres.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/rencontres-virtuelles\\\/10-raisons-pourquoi-on-ne-repond-pas-sur-les-sites-de-rencontres.html#primaryimage\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/pourquoi-pas-reponse-sites-rencontre.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/pourquoi-pas-reponse-sites-rencontre.jpg\",\"width\":750,\"height\":574},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/rencontres-virtuelles\\\/10-raisons-pourquoi-on-ne-repond-pas-sur-les-sites-de-rencontres.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Les Bridgets\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conseils sur l'amour, le couple &amp; les c\u00e9libataires\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/category\\\/conseils-relations\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Rencontres en ligne\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/category\\\/conseils-relations\\\/rencontres-virtuelles\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"10 raisons pourquoi on ne r\u00e9pond pas sur les sites de rencontres\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#website\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/\",\"name\":\"Les Bridgets\",\"description\":\"R\u00e9f\u00e9rences et r\u00e9flexions sur nos relations\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lesbridgets.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\",\"name\":\"Les Bridgets\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo-3-lesbridgets.png\",\"contentUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo-3-lesbridgets.png\",\"width\":251,\"height\":59,\"caption\":\"Les Bridgets\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Les.Bridgets\",\"https:\\\/\\\/x.com\\\/les_bridgets\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/person\\\/82a31c27ae0ddd23ee59e1e2ac5713ba\",\"name\":\"Bridget\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"caption\":\"Bridget\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"10 raisons pourquoi on ne r\u00e9pond pas sur les sites de rencontres - Les Bridgets","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rencontres-virtuelles\/10-raisons-pourquoi-on-ne-repond-pas-sur-les-sites-de-rencontres.html","og_locale":"fr_FR","og_type":"article","og_title":"10 raisons pourquoi on ne r\u00e9pond pas sur les sites de rencontres - Les Bridgets","og_description":"Un des gros probl\u00e8mes des sites de rencontres que l'on constate encore plus\u00a0sur les applications de dating comme Tinder, est le nombre de personnes qui ne r\u00e9pondent pas. Pourtant parfois il y a eu \"charme\", \"match\" et pas de r\u00e9ponse \u00e0 votre \"Hello,\u00a0\u00e7a va ?\". On a r\u00e9fl\u00e9chi\u00a0entre nous pour\u00a0vous donner de vraies explications\u00a0\u00a0parce que nous faisons aussi parties de celles qui ne r\u00e9pondent pas et parfois aussi de celles qui sont blas\u00e9es parce que pour une pour une fois qu'on envoie le message la premi\u00e8re, il ne nous r\u00e9pond pas non plus.","og_url":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rencontres-virtuelles\/10-raisons-pourquoi-on-ne-repond-pas-sur-les-sites-de-rencontres.html","og_site_name":"Les Bridgets","article_publisher":"https:\/\/www.facebook.com\/Les.Bridgets","article_published_time":"2015-11-10T08:12:32+00:00","article_modified_time":"2025-05-17T17:55:38+00:00","og_image":[{"width":750,"height":574,"url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2015\/11\/pourquoi-pas-reponse-sites-rencontre.jpg","type":"image\/jpeg"}],"author":"Bridget","twitter_card":"summary_large_image","twitter_creator":"@les_bridgets","twitter_site":"@les_bridgets","twitter_misc":{"\u00c9crit par":"Bridget","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rencontres-virtuelles\/10-raisons-pourquoi-on-ne-repond-pas-sur-les-sites-de-rencontres.html#article","isPartOf":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rencontres-virtuelles\/10-raisons-pourquoi-on-ne-repond-pas-sur-les-sites-de-rencontres.html"},"author":{"name":"Bridget","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/person\/82a31c27ae0ddd23ee59e1e2ac5713ba"},"headline":"10 raisons pourquoi on ne r\u00e9pond pas sur les sites de rencontres","datePublished":"2015-11-10T08:12:32+00:00","dateModified":"2025-05-17T17:55:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rencontres-virtuelles\/10-raisons-pourquoi-on-ne-repond-pas-sur-les-sites-de-rencontres.html"},"wordCount":661,"commentCount":30,"publisher":{"@id":"https:\/\/www.lesbridgets.com\/#organization"},"image":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rencontres-virtuelles\/10-raisons-pourquoi-on-ne-repond-pas-sur-les-sites-de-rencontres.html#primaryimage"},"thumbnailUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2015\/11\/pourquoi-pas-reponse-sites-rencontre.jpg","keywords":["sites de rencontres","tinder"],"articleSection":["Rencontres en ligne"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rencontres-virtuelles\/10-raisons-pourquoi-on-ne-repond-pas-sur-les-sites-de-rencontres.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rencontres-virtuelles\/10-raisons-pourquoi-on-ne-repond-pas-sur-les-sites-de-rencontres.html","url":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rencontres-virtuelles\/10-raisons-pourquoi-on-ne-repond-pas-sur-les-sites-de-rencontres.html","name":"10 raisons pourquoi on ne r\u00e9pond pas sur les sites de rencontres - Les Bridgets","isPartOf":{"@id":"https:\/\/www.lesbridgets.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rencontres-virtuelles\/10-raisons-pourquoi-on-ne-repond-pas-sur-les-sites-de-rencontres.html#primaryimage"},"image":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rencontres-virtuelles\/10-raisons-pourquoi-on-ne-repond-pas-sur-les-sites-de-rencontres.html#primaryimage"},"thumbnailUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2015\/11\/pourquoi-pas-reponse-sites-rencontre.jpg","datePublished":"2015-11-10T08:12:32+00:00","dateModified":"2025-05-17T17:55:38+00:00","breadcrumb":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rencontres-virtuelles\/10-raisons-pourquoi-on-ne-repond-pas-sur-les-sites-de-rencontres.html#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rencontres-virtuelles\/10-raisons-pourquoi-on-ne-repond-pas-sur-les-sites-de-rencontres.html"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rencontres-virtuelles\/10-raisons-pourquoi-on-ne-repond-pas-sur-les-sites-de-rencontres.html#primaryimage","url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2015\/11\/pourquoi-pas-reponse-sites-rencontre.jpg","contentUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2015\/11\/pourquoi-pas-reponse-sites-rencontre.jpg","width":750,"height":574},{"@type":"BreadcrumbList","@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rencontres-virtuelles\/10-raisons-pourquoi-on-ne-repond-pas-sur-les-sites-de-rencontres.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Les Bridgets","item":"https:\/\/www.lesbridgets.com\/"},{"@type":"ListItem","position":2,"name":"Conseils sur l'amour, le couple &amp; les c\u00e9libataires","item":"https:\/\/www.lesbridgets.com\/index.php\/category\/conseils-relations"},{"@type":"ListItem","position":3,"name":"Rencontres en ligne","item":"https:\/\/www.lesbridgets.com\/index.php\/category\/conseils-relations\/rencontres-virtuelles"},{"@type":"ListItem","position":4,"name":"10 raisons pourquoi on ne r\u00e9pond pas sur les sites de rencontres"}]},{"@type":"WebSite","@id":"https:\/\/www.lesbridgets.com\/#website","url":"https:\/\/www.lesbridgets.com\/","name":"Les Bridgets","description":"R\u00e9f\u00e9rences et r\u00e9flexions sur nos relations","publisher":{"@id":"https:\/\/www.lesbridgets.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lesbridgets.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lesbridgets.com\/#organization","name":"Les Bridgets","url":"https:\/\/www.lesbridgets.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2022\/07\/cropped-logo-3-lesbridgets.png","contentUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2022\/07\/cropped-logo-3-lesbridgets.png","width":251,"height":59,"caption":"Les Bridgets"},"image":{"@id":"https:\/\/www.lesbridgets.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Les.Bridgets","https:\/\/x.com\/les_bridgets"]},{"@type":"Person","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/person\/82a31c27ae0ddd23ee59e1e2ac5713ba","name":"Bridget","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","caption":"Bridget"}}]}},"modified_by":"Bridget","_links":{"self":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/1915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/comments?post=1915"}],"version-history":[{"count":8,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/1915\/revisions"}],"predecessor-version":[{"id":258191,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/1915\/revisions\/258191"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/media\/1914"}],"wp:attachment":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/media?parent=1915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/categories?post=1915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/tags?post=1915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}