{"id":1885,"date":"2016-01-05T19:55:00","date_gmt":"2016-01-05T18:55:00","guid":{"rendered":"http:\/\/lesbridg.cluster015.ovh.net\/wordpress\/index.php\/vivre-a-deux-en-couple-le-quotidien\/pourquoi-devenons-nous-dependant-d-une-autre-personne.html"},"modified":"2017-11-01T16:56:19","modified_gmt":"2017-11-01T15:56:19","slug":"pourquoi-devenons-nous-dependant-d-une-autre-personne","status":"publish","type":"post","link":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/vivre-a-deux-en-couple-le-quotidien\/pourquoi-devenons-nous-dependant-d-une-autre-personne.html","title":{"rendered":"Pourquoi devenons-nous d\u00e9pendant d&rsquo;une autre personne ?"},"content":{"rendered":"<p>La raison pour laquelle la relation amoureuse romantique est une exp\u00e9rience si intense et si universellement recherch\u00e9e est la suivante : elle semble lib\u00e9rer les gens d\u2019un sentiment profond\u00e9ment install\u00e9 de peur, de besoin, de manque et d\u2019incompl\u00e9tude. <br \/>Cet \u00e9tat \u00e9motionnel fait partie de la condition humaine dans sa phase non rachet\u00e9e et non r\u00e9alis\u00e9e. Il comporte aussi bien une dimension physique que psychologique. <\/p>\n<p><strong>Sur le plan physique, et de toute \u00e9vidence, vous n\u2019\u00eates pas complet et ne le serez jamais.<\/strong><br \/>Sur ce plan-l\u00e0, l\u2019aspiration \u00e0 la totalit\u00e9, \u00e0 la compl\u00e9tude, c\u2019est-\u00e0-dire le retour \u00e0 l\u2019Un, se manifeste sous la forme de l\u2019attraction sexuelle.<\/p>\n<p>Il existe une pulsion presque irr\u00e9sistible \u00e0 s\u2019unir avec l\u2019\u00e9nergie oppos\u00e9e ou l\u2019autre polarit\u00e9.<\/p>\n<p>Cette pulsion physique est d\u2019origine spirituelle. C\u2019est l\u2019aspiration \u00e0 mettre un terme \u00e0 la dualit\u00e9, \u00e0 revenir \u00e0 l\u2019\u00e9tat de compl\u00e9tude.\u00a0<\/p>\n<h1>Sur le plan physique, l\u2019union sexuelle est ce qui se rapproche le plus de cet \u00e9tat-l\u00e0.<\/h1>\n<p>Voil\u00e0 pourquoi celle-ci est l\u2019exp\u00e9rience la plus profond\u00e9ment satisfaisante que le plan physique puisse offrir. Mais l\u2019union sexuelle n\u2019est rien de plus qu\u2019un fugace aper\u00e7u de la totalit\u00e9, qu\u2019un moment d\u2019extase. <br \/>Tant et aussi longtemps que vous recherchez inconsciemment dans l\u2019union sexuelle votre porte de salut, vous visez \u00e0 mettre fin \u00e0 la dualit\u00e9 sur le plan de la forme, l\u00e0 o\u00f9 justement on ne peut la trouver. <br \/>Il vous est donn\u00e9 l\u00e0 un aper\u00e7u fugitif et fort all\u00e9chant du paradis, mais vous n\u2019avez pas le droit d\u2019y rester et vous vous retrouvez de nouveau dans un corps distinct.<\/p>\n<h1>Sur le plan psychologique, ce sentiment de manque et d\u2019incompl\u00e9tude est certainement encore plus grand que sur le plan physique.<\/h1>\n<p>Aussi longtemps que vous \u00eates identifi\u00e9 au mental, le sens que vous avez de votre moi provient de l\u2019ext\u00e9rieur. <br \/>En d\u2019autres termes, vous vous appropriez le sens de ce que vous \u00eates par le biais de choses qui, en fin de compte, n\u2019ont rien \u00e0 voir avec ce que vous \u00eates : <br \/><strong>votre r\u00f4le social, <br \/>vos possessions, <br \/>votre apparence physique, <br \/>vos r\u00e9ussites et vos \u00e9checs, <br \/>vos syst\u00e8mes de croyances, etc. <\/strong><\/p>\n<p>Ce faux moi, cr\u00e9\u00e9 par le mental, par l\u2019ego, se sent vuln\u00e9rable, peu assur\u00e9, et cherche sans arr\u00eat de nouvelles choses auxquelles s\u2019identifier afin de donner au mental l\u2019impression d\u2019exister. <br \/>Mais jamais rien ne suffit \u00e0 lui procurer une satisfaction durable. Sa peur perdure. Et son impression de manque et de besoin reste.<\/p>\n<h1>Puis cette relation si sp\u00e9ciale se pr\u00e9sente. Elle semble \u00eatre la r\u00e9ponse \u00e0 tous les probl\u00e8mes de l\u2019ego et combler tous ses besoins.<\/h1>\n<p>Du moins, c\u2019est ainsi que les choses paraissent au d\u00e9but. Toutes les autres choses qui venaient vous procurer le sens que vous aviez de votre moi auparavant deviennent dor\u00e9navant relativement insignifiantes. <br \/>Un seul objet d\u2019attention remplace alors tout le reste, donne un sens \u00e0 votre vie et vous permet de d\u00e9finir votre identit\u00e9 : la personne dont vous \u00eates amoureux. <br \/>Vous n\u2019\u00eates plus ce fragment isol\u00e9 dans un univers hostile. C\u2019est du moins l\u2019impression que vous avez.<\/p>\n<h1>Votre monde a maintenant un centre : la personne aim\u00e9e<\/h1>\n<p>Le fait que ce centre soit \u00e0 l\u2019ext\u00e9rieur de vous et que, par cons\u00e9quent, vous d\u00e9finissiez encore votre identit\u00e9 en fonction de quelque chose d\u2019ext\u00e9rieur \u00e0 vous, semble tout d\u2019abord ne pas avoir d\u2019importance. Ce qui compte, c\u2019est que les sentiments sous-jacents d\u2019incompl\u00e9tude, de peur, de manque et d\u2019insatisfaction si caract\u00e9ristiques de l\u2019ego soient disparus. <br \/>Le sont-ils vraiment ? Se sont-ils dissip\u00e9s ou existent-ils encore sous la surface de ce pr\u00e9tendu bonheur ?<\/p>\n<p>Si, dans vos relations, vous connaissez aussi bien l\u2019amour que son oppos\u00e9, c\u2019est-\u00e0-dire l\u2019hostilit\u00e9, la violence \u00e9motionnelle, etc., il est alors fort probable que vous confondiez amour et attachement de l\u2019ego, amour et d\u00e9pendance affective. <br \/>Il est impossible que vous aimiez votre partenaire \u00e0 un moment et l\u2019agressiez l\u2019instant d\u2019apr\u00e8s.<\/p>\n<h1>L\u2019amour vrai n\u2019a pas d\u2019ennemi.<\/h1>\n<p>Si votre \u00ab amour \u00bb en a un, c\u2019est que ce n\u2019est pas de l\u2019amour mais plut\u00f4t un grand besoin de l\u2019ego de se sentir plus compl\u00e8tement et plus profond\u00e9ment soi. Et ce besoin est temporairement combl\u00e9 par l\u2019autre. <\/p>\n<p>Pour l\u2019ego, il s\u2019agit d\u2019un succ\u00e9dan\u00e9 de salut, et pendant un certain temps, cela donne presque effectivement l\u2019impression qu\u2019il s\u2019agit de cela. <br \/>Mais vient un moment o\u00f9 votre partenaire adopte des comportements qui ne r\u00e9ussissent pas \u00e0 combler vos besoins, ou du moins ceux de votre ego.<\/p>\n<p>Les sentiments de peur, de souffrance et de manque qui font intrins\u00e8quement partie de l\u2019ego, mais qui \u00e9taient pass\u00e9s \u00e0 l\u2019arri\u00e8re-plan gr\u00e2ce \u00e0 la relation amoureuse, font de nouveau surface.<\/p>\n<h1>Comme avec toutes les autres d\u00e9pendances, vous \u00eates au septi\u00e8me ciel quand vous avez de la drogue, mais vient invariablement le moment o\u00f9 celle-ci n\u2019a plus d\u2019effet sur vous.<\/h1>\n<p>Quand ces \u00e9motions souffrantes refont surface, vous les sentez donc avec encore plus d\u2019acuit\u00e9 qu\u2019avant. Qui plus est, vous percevez maintenant votre partenaire comme \u00e9tant \u00e0 leur origine. <br \/>Cela veut dire que vous les projetez \u00e0 l\u2019ext\u00e9rieur et que vous agressez l\u2019autre avec toute la violence sauvage que votre douleur contient. <br \/>Cette agressivit\u00e9 peut \u00e9veiller la souffrance de votre partenaire, qui contre-attaquera. Rendu \u00e0 ce point-l\u00e0, l\u2019ego esp\u00e8re encore inconsciemment que son agressivit\u00e9 ou ses tentatives \u00e0 vouloir manipuler constitueront une punition suffisante qui am\u00e8nera l\u2019autre \u00e0 changer de comportement. <\/p>\n<p>Ceci lui permettra de se servir \u00e0 nouveau de ces comportements pour occulter votre souffrance.<\/p>\n<h1>Toute d\u00e9pendance na\u00eet d\u2019un refus inconscient \u00e0 faire face \u00e0 votre propre souffrance et \u00e0 la vivre.<\/h1>\n<p>Celle-ci commence et finit dans la souffrance. Quelle que soit la substance \u00e0 laquelle vous \u00eates accroch\u00e9 \u2013 l\u2019alcool, la nourriture, les drogues l\u00e9gales ou ill\u00e9gales, ou bien une personne -, vous vous servez de quelque chose ou de quelqu\u2019un pour dissimuler votre douleur. <br \/>C\u2019est pour cette raison qu\u2019apr\u00e8s l\u2019euphorie initiale il y a tellement de tourments et de souffrance dans les relations intimes. Mais ces derni\u00e8res n\u2019en sont pourtant pas la cause. Elles font simplement ressortir la souffrance et le tourment qui se trouvent d\u00e9j\u00e0 en vous.<\/p>\n<h1>Toutes les d\u00e9pendances agissent ainsi. Toutes les d\u00e9pendances atteignent un point o\u00f9 elles n\u2019ont plus d\u2019effet sur vous, vous ressentez alors la souffrance plus intens\u00e9ment que jamais. <\/p>\n<p>D\u2019ailleurs, la plupart des gens essaient toujours d\u2019\u00e9chapper au pr\u00e9sent et cherchent le salut dans le futur, quel qu\u2019il soit.<\/h1>\n<p>La premi\u00e8re chose sur laquelle ils pourraient buter s\u2019ils concentraient leur attention sur le moment pr\u00e9sent, c\u2019est leur propre souffrance. Et c\u2019est justement ce dont ils ont peur. <br \/>Si seulement ils savaient combien il est facile de trouver dans le pr\u00e9sent le pouvoir qui dissipe le pass\u00e9 et la souffrance, la r\u00e9alit\u00e9 qui met un terme \u00e0 l\u2019illusion. <br \/>Si seulement ils savaient \u00e0 quel point ils sont pr\u00e8s de leur propre r\u00e9alit\u00e9.<\/p>\n<h1>La r\u00e9ponse n\u2019est pas non plus d\u2019\u00e9viter les relations afin d\u2019\u00e9viter la souffrance.<\/h1>\n<p>Celle-ci est l\u00e0 de toute fa\u00e7on. Trois relations qui n\u2019ont pas fonctionn\u00e9 en autant d\u2019ann\u00e9es vous am\u00e8neront fort probablement plus \u00e0 vous r\u00e9veiller que trois ann\u00e9es sur une \u00eele d\u00e9serte ou reclus dans votre chambre. <br \/>Par contre, si vous r\u00e9ussissiez \u00e0 \u00eatre intens\u00e9ment pr\u00e9sent \u00e0 votre solitude, cette solution fonctionnerait peut-\u00eatre pour vous.<\/p>\n<p>\u00a0<\/p>\n<p>Ceci est un extrait du tr\u00e8s bon livre\u00a0<a href=\"https:\/\/www.lesbridgets.com\/index.php\/rencontre-seduction-drague-conseils\/apprendre-a-vivre-le-moment-present.html\" target=\"_blank\" rel=\"alternate\">dont je vous ai d\u00e9j\u00e0 parl\u00e9 \u00ab\u00a0Le pouvoir du moment pr\u00e9sent\u00a0\u00bb d&rsquo;Eckart Tolle<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La raison pour laquelle la relation amoureuse romantique est une exp\u00e9rience si intense et si universellement recherch\u00e9e est la suivante : elle semble lib\u00e9rer les gens d\u2019un sentiment profond\u00e9ment install\u00e9 de peur, de besoin, de manque et d\u2019incompl\u00e9tude. <br \/>Cet \u00e9tat \u00e9motionnel fait partie de la condition humaine dans sa phase non rachet\u00e9e et non r\u00e9alis\u00e9e. Il comporte aussi bien une dimension physique que psychologique. <\/p>\n<p><strong>Sur le plan physique, et de toute \u00e9vidence, vous n\u2019\u00eates pas complet et ne le serez jamais.<\/strong><br \/>Sur ce plan-l\u00e0, l\u2019aspiration \u00e0 la totalit\u00e9, \u00e0 la compl\u00e9tude, c\u2019est-\u00e0-dire le retour \u00e0 l\u2019Un, se manifeste sous la forme de l\u2019attraction sexuelle.<\/p>\n<p>Il existe une pulsion presque irr\u00e9sistible \u00e0 s\u2019unir avec l\u2019\u00e9nergie oppos\u00e9e ou l\u2019autre polarit\u00e9.<\/p>\n","protected":false},"author":2,"featured_media":1884,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"om_disable_all_campaigns":false,"_lmt_disableupdate":"","_lmt_disable":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[6],"tags":[52,788,46],"class_list":["post-1885","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vivre-a-deux-en-couple-le-quotidien","tag-amour","tag-dependance","tag-passion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pourquoi devenons-nous d\u00e9pendant d&#039;une autre personne ? - Les Bridgets<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/vivre-a-deux-en-couple-le-quotidien\/pourquoi-devenons-nous-dependant-d-une-autre-personne.html\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pourquoi devenons-nous d\u00e9pendant d&#039;une autre personne ? - Les Bridgets\" \/>\n<meta property=\"og:description\" content=\"La raison pour laquelle la relation amoureuse romantique est une exp\u00e9rience si intense et si universellement recherch\u00e9e est la suivante : elle semble lib\u00e9rer les gens d\u2019un sentiment profond\u00e9ment install\u00e9 de peur, de besoin, de manque et d\u2019incompl\u00e9tude. Cet \u00e9tat \u00e9motionnel fait partie de la condition humaine dans sa phase non rachet\u00e9e et non r\u00e9alis\u00e9e. Il comporte aussi bien une dimension physique que psychologique. Sur le plan physique, et de toute \u00e9vidence, vous n\u2019\u00eates pas complet et ne le serez jamais.Sur ce plan-l\u00e0, l\u2019aspiration \u00e0 la totalit\u00e9, \u00e0 la compl\u00e9tude, c\u2019est-\u00e0-dire le retour \u00e0 l\u2019Un, se manifeste sous la forme de l\u2019attraction sexuelle.Il existe une pulsion presque irr\u00e9sistible \u00e0 s\u2019unir avec l\u2019\u00e9nergie oppos\u00e9e ou l\u2019autre polarit\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/vivre-a-deux-en-couple-le-quotidien\/pourquoi-devenons-nous-dependant-d-une-autre-personne.html\" \/>\n<meta property=\"og:site_name\" content=\"Les Bridgets\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Les.Bridgets\" \/>\n<meta property=\"article:published_time\" content=\"2016-01-05T18:55:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-01T15:56:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2016\/01\/dependance-affective-comprendre.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1195\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bridget\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@les_bridgets\" \/>\n<meta name=\"twitter:site\" content=\"@les_bridgets\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bridget\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/vivre-a-deux-en-couple-le-quotidien\\\/pourquoi-devenons-nous-dependant-d-une-autre-personne.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/vivre-a-deux-en-couple-le-quotidien\\\/pourquoi-devenons-nous-dependant-d-une-autre-personne.html\"},\"author\":{\"name\":\"Bridget\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/person\\\/82a31c27ae0ddd23ee59e1e2ac5713ba\"},\"headline\":\"Pourquoi devenons-nous d\u00e9pendant d&rsquo;une autre personne ?\",\"datePublished\":\"2016-01-05T18:55:00+00:00\",\"dateModified\":\"2017-11-01T15:56:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/vivre-a-deux-en-couple-le-quotidien\\\/pourquoi-devenons-nous-dependant-d-une-autre-personne.html\"},\"wordCount\":1348,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/vivre-a-deux-en-couple-le-quotidien\\\/pourquoi-devenons-nous-dependant-d-une-autre-personne.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/dependance-affective-comprendre.jpeg\",\"keywords\":[\"amour\",\"d\u00e9pendance\",\"passion\"],\"articleSection\":[\"Vivre en couple\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/vivre-a-deux-en-couple-le-quotidien\\\/pourquoi-devenons-nous-dependant-d-une-autre-personne.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/vivre-a-deux-en-couple-le-quotidien\\\/pourquoi-devenons-nous-dependant-d-une-autre-personne.html\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/vivre-a-deux-en-couple-le-quotidien\\\/pourquoi-devenons-nous-dependant-d-une-autre-personne.html\",\"name\":\"Pourquoi devenons-nous d\u00e9pendant d'une autre personne ? - Les Bridgets\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/vivre-a-deux-en-couple-le-quotidien\\\/pourquoi-devenons-nous-dependant-d-une-autre-personne.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/vivre-a-deux-en-couple-le-quotidien\\\/pourquoi-devenons-nous-dependant-d-une-autre-personne.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/dependance-affective-comprendre.jpeg\",\"datePublished\":\"2016-01-05T18:55:00+00:00\",\"dateModified\":\"2017-11-01T15:56:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/vivre-a-deux-en-couple-le-quotidien\\\/pourquoi-devenons-nous-dependant-d-une-autre-personne.html#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/vivre-a-deux-en-couple-le-quotidien\\\/pourquoi-devenons-nous-dependant-d-une-autre-personne.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/vivre-a-deux-en-couple-le-quotidien\\\/pourquoi-devenons-nous-dependant-d-une-autre-personne.html#primaryimage\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/dependance-affective-comprendre.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/dependance-affective-comprendre.jpeg\",\"width\":1195,\"height\":627},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/vivre-a-deux-en-couple-le-quotidien\\\/pourquoi-devenons-nous-dependant-d-une-autre-personne.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Les Bridgets\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conseils sur l'amour, le couple &amp; les c\u00e9libataires\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/category\\\/conseils-relations\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Vivre en couple\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/category\\\/conseils-relations\\\/vivre-a-deux-en-couple-le-quotidien\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Pourquoi devenons-nous d\u00e9pendant d&rsquo;une autre personne ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#website\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/\",\"name\":\"Les Bridgets\",\"description\":\"R\u00e9f\u00e9rences et r\u00e9flexions sur nos relations\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lesbridgets.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\",\"name\":\"Les Bridgets\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo-3-lesbridgets.png\",\"contentUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo-3-lesbridgets.png\",\"width\":251,\"height\":59,\"caption\":\"Les Bridgets\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Les.Bridgets\",\"https:\\\/\\\/x.com\\\/les_bridgets\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/person\\\/82a31c27ae0ddd23ee59e1e2ac5713ba\",\"name\":\"Bridget\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"caption\":\"Bridget\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pourquoi devenons-nous d\u00e9pendant d'une autre personne ? - Les Bridgets","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/vivre-a-deux-en-couple-le-quotidien\/pourquoi-devenons-nous-dependant-d-une-autre-personne.html","og_locale":"fr_FR","og_type":"article","og_title":"Pourquoi devenons-nous d\u00e9pendant d'une autre personne ? - Les Bridgets","og_description":"La raison pour laquelle la relation amoureuse romantique est une exp\u00e9rience si intense et si universellement recherch\u00e9e est la suivante : elle semble lib\u00e9rer les gens d\u2019un sentiment profond\u00e9ment install\u00e9 de peur, de besoin, de manque et d\u2019incompl\u00e9tude. Cet \u00e9tat \u00e9motionnel fait partie de la condition humaine dans sa phase non rachet\u00e9e et non r\u00e9alis\u00e9e. Il comporte aussi bien une dimension physique que psychologique. Sur le plan physique, et de toute \u00e9vidence, vous n\u2019\u00eates pas complet et ne le serez jamais.Sur ce plan-l\u00e0, l\u2019aspiration \u00e0 la totalit\u00e9, \u00e0 la compl\u00e9tude, c\u2019est-\u00e0-dire le retour \u00e0 l\u2019Un, se manifeste sous la forme de l\u2019attraction sexuelle.Il existe une pulsion presque irr\u00e9sistible \u00e0 s\u2019unir avec l\u2019\u00e9nergie oppos\u00e9e ou l\u2019autre polarit\u00e9.","og_url":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/vivre-a-deux-en-couple-le-quotidien\/pourquoi-devenons-nous-dependant-d-une-autre-personne.html","og_site_name":"Les Bridgets","article_publisher":"https:\/\/www.facebook.com\/Les.Bridgets","article_published_time":"2016-01-05T18:55:00+00:00","article_modified_time":"2017-11-01T15:56:19+00:00","og_image":[{"width":1195,"height":627,"url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2016\/01\/dependance-affective-comprendre.jpeg","type":"image\/jpeg"}],"author":"Bridget","twitter_card":"summary_large_image","twitter_creator":"@les_bridgets","twitter_site":"@les_bridgets","twitter_misc":{"\u00c9crit par":"Bridget","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/vivre-a-deux-en-couple-le-quotidien\/pourquoi-devenons-nous-dependant-d-une-autre-personne.html#article","isPartOf":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/vivre-a-deux-en-couple-le-quotidien\/pourquoi-devenons-nous-dependant-d-une-autre-personne.html"},"author":{"name":"Bridget","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/person\/82a31c27ae0ddd23ee59e1e2ac5713ba"},"headline":"Pourquoi devenons-nous d\u00e9pendant d&rsquo;une autre personne ?","datePublished":"2016-01-05T18:55:00+00:00","dateModified":"2017-11-01T15:56:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/vivre-a-deux-en-couple-le-quotidien\/pourquoi-devenons-nous-dependant-d-une-autre-personne.html"},"wordCount":1348,"commentCount":1,"publisher":{"@id":"https:\/\/www.lesbridgets.com\/#organization"},"image":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/vivre-a-deux-en-couple-le-quotidien\/pourquoi-devenons-nous-dependant-d-une-autre-personne.html#primaryimage"},"thumbnailUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2016\/01\/dependance-affective-comprendre.jpeg","keywords":["amour","d\u00e9pendance","passion"],"articleSection":["Vivre en couple"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/vivre-a-deux-en-couple-le-quotidien\/pourquoi-devenons-nous-dependant-d-une-autre-personne.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/vivre-a-deux-en-couple-le-quotidien\/pourquoi-devenons-nous-dependant-d-une-autre-personne.html","url":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/vivre-a-deux-en-couple-le-quotidien\/pourquoi-devenons-nous-dependant-d-une-autre-personne.html","name":"Pourquoi devenons-nous d\u00e9pendant d'une autre personne ? - Les Bridgets","isPartOf":{"@id":"https:\/\/www.lesbridgets.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/vivre-a-deux-en-couple-le-quotidien\/pourquoi-devenons-nous-dependant-d-une-autre-personne.html#primaryimage"},"image":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/vivre-a-deux-en-couple-le-quotidien\/pourquoi-devenons-nous-dependant-d-une-autre-personne.html#primaryimage"},"thumbnailUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2016\/01\/dependance-affective-comprendre.jpeg","datePublished":"2016-01-05T18:55:00+00:00","dateModified":"2017-11-01T15:56:19+00:00","breadcrumb":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/vivre-a-deux-en-couple-le-quotidien\/pourquoi-devenons-nous-dependant-d-une-autre-personne.html#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/vivre-a-deux-en-couple-le-quotidien\/pourquoi-devenons-nous-dependant-d-une-autre-personne.html"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/vivre-a-deux-en-couple-le-quotidien\/pourquoi-devenons-nous-dependant-d-une-autre-personne.html#primaryimage","url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2016\/01\/dependance-affective-comprendre.jpeg","contentUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2016\/01\/dependance-affective-comprendre.jpeg","width":1195,"height":627},{"@type":"BreadcrumbList","@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/vivre-a-deux-en-couple-le-quotidien\/pourquoi-devenons-nous-dependant-d-une-autre-personne.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Les Bridgets","item":"https:\/\/www.lesbridgets.com\/"},{"@type":"ListItem","position":2,"name":"Conseils sur l'amour, le couple &amp; les c\u00e9libataires","item":"https:\/\/www.lesbridgets.com\/index.php\/category\/conseils-relations"},{"@type":"ListItem","position":3,"name":"Vivre en couple","item":"https:\/\/www.lesbridgets.com\/index.php\/category\/conseils-relations\/vivre-a-deux-en-couple-le-quotidien"},{"@type":"ListItem","position":4,"name":"Pourquoi devenons-nous d\u00e9pendant d&rsquo;une autre personne ?"}]},{"@type":"WebSite","@id":"https:\/\/www.lesbridgets.com\/#website","url":"https:\/\/www.lesbridgets.com\/","name":"Les Bridgets","description":"R\u00e9f\u00e9rences et r\u00e9flexions sur nos relations","publisher":{"@id":"https:\/\/www.lesbridgets.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lesbridgets.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lesbridgets.com\/#organization","name":"Les Bridgets","url":"https:\/\/www.lesbridgets.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2022\/07\/cropped-logo-3-lesbridgets.png","contentUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2022\/07\/cropped-logo-3-lesbridgets.png","width":251,"height":59,"caption":"Les Bridgets"},"image":{"@id":"https:\/\/www.lesbridgets.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Les.Bridgets","https:\/\/x.com\/les_bridgets"]},{"@type":"Person","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/person\/82a31c27ae0ddd23ee59e1e2ac5713ba","name":"Bridget","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","caption":"Bridget"}}]}},"modified_by":null,"_links":{"self":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/1885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/comments?post=1885"}],"version-history":[{"count":2,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/1885\/revisions"}],"predecessor-version":[{"id":242103,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/1885\/revisions\/242103"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/media\/1884"}],"wp:attachment":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/media?parent=1885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/categories?post=1885"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/tags?post=1885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}