{"id":184,"date":"2008-01-20T20:35:11","date_gmt":"2008-01-20T19:35:11","guid":{"rendered":"http:\/\/lesbridg.cluster015.ovh.net\/wordpress\/index.php\/celibat-etre-celibataire-vivre-seule\/quand-lhorloge-biologique-vous-rappelle-a-lordre.html"},"modified":"2019-05-07T15:45:30","modified_gmt":"2019-05-07T13:45:30","slug":"quand-l-horloge-biologique-vous-rappelle-a-l-ordre","status":"publish","type":"post","link":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/quand-l-horloge-biologique-vous-rappelle-a-l-ordre.html","title":{"rendered":"Quand l&rsquo;horloge biologique vous rappelle \u00e0 l&rsquo;ordre&#8230;"},"content":{"rendered":"<p>Apr\u00e8s plusieurs <a href=\"https:\/\/www.lesbridgets.com\/index.php\/forums\" target=\"_blank\" rel=\"noopener noreferrer\">discussions \u00e0 ce sujet sur le forum<\/a> , voici quelques informations sur l&rsquo;\u00e2ge maximum pour avoir des enfants, le taux de fertilit\u00e9 qui diminue avec l&rsquo;\u00e2ge. Pour tous ceux et celles qui pensent \u00e0 leur horloge biologique pas que en se rasant \ud83d\ude09<\/p>\n<h3>A l&rsquo;heure o\u00f9 l&rsquo;\u00e2ge du premi\u00e8re enfant est de presque 30 ans dans le dernier recensement de 2007 en France, nombreuses sont les causes de ne pas encore avoir d&rsquo;enfants d\u00e9passer la trentaine.<\/h3>\n<p>C\u2019est le paradoxe de notre \u00e9poque, on reste jeune plus longtemps et les femmes pensent qu\u2019elles ont du temps pour penser \u00e0 avoir des enfants. Mais il y a de plus en plus de bonnes raisons pour les femmes de ne pas d\u00e9cider d\u2019une maternit\u00e9 plus t\u00f4t :<\/p>\n<ul>\n<li>les \u00e9tudes prolong\u00e9es<\/li>\n<li>l\u2019instabilit\u00e9 du march\u00e9 du travail<\/li>\n<li>l\u2019hostilit\u00e9 des employeurs lors de la survenue d\u2019une grossesse<\/li>\n<li>mais surtout le fait de n&rsquo;avoir toujours pas rencontr\u00e9 l\u2019homme de leur vie ou en tous cas \u00ab un p\u00e8re possible \u00bb.<\/li>\n<\/ul>\n<h2>Mais la nature n&rsquo;a pas suivi l&rsquo;\u00e9volution de notre soci\u00e9t\u00e9<\/h2>\n<p>La physiologie n\u2019a h\u00e9las pas suivi les changements des pratiques sociales. En effet, les \u00e9tudes le montrent, avoir des enfants apr\u00e8s 38 ans et au-del\u00e0, est certes parfois possible mais souvent bien difficile voire impossible.<\/p>\n<p>Le pourcentage d&rsquo;avoir des enfants selon l&rsquo;\u00e2ge diminue fortement plus l&rsquo;\u00e2ge avance<\/p>\n<ul>\n<li>25% de chance de concevoir chaque mois \u00e0 25 ans<\/li>\n<li>mais seulement 12% \u00e0 35 ans<\/li>\n<li>et 6% \u00e0 40 ans.<\/li>\n<\/ul>\n<p>Et l\u00e0 franchement je ne pensais pas que l&rsquo;\u00e9cart \u00e9tait aussi important entre 25 et 40 ans.<\/p>\n<p>Quelques histoires spectaculaires, largement m\u00e9diatis\u00e9es, de grossesses de grand-m\u00e8res de 60 ans et plus ont fait croire que les techniques sophistiqu\u00e9es de procr\u00e9ation assist\u00e9e gommeraient les effets de l\u2019\u00e2ge.<br \/>\nLa r\u00e9alit\u00e9 des chiffres d\u00e9montre que c\u2019est loin d\u2019\u00eatre vrai. Les taux de succ\u00e8s dans ces services, m\u00eame les meilleurs, chutent \u00e0 35 ans et d\u00e9gringolent de fa\u00e7on catastrophique \u00e0 42 ans.<\/p>\n<h2>Et chez les hommes, y&rsquo;a t-il un \u00e2ge ou il est compliqu\u00e9 d&rsquo;avoir des enfants?<\/h2>\n<p>Quant \u00e0 l\u2019effet de l\u2019\u00e2ge sur la fertilit\u00e9 des hommes, le moins que l\u2019on puisse dire c\u2019est le grand silence qui l\u2019entoure et pourtant \u00e7a existe.<br \/>\nLes hommes de plus de 45 ans mettent 5 fois plus longtemps \u00e0 concevoir que ceux de moins de 25 ans\u2026 m\u00eame si certains papas c\u00e9l\u00e8bres et largement sexag\u00e9naires nous font croire que l\u2019\u00e2ge et la fertilit\u00e9 sont seulement une histoire de femmes.<\/p>\n<p>&nbsp;<\/p>\n<p>Source de l&rsquo;article :<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s plusieurs <a href=\"index.php\/Points-de-vue-de-celibataires\/536-L-horloge-biologique-quand-tu-nous-tiens.html\" target=\"_blank\" mce_href=\"index.php\/Points-de-vue-de-celibataires\/536-L-horloge-biologique-quand-tu-nous-tiens.html\" rel=\"noopener noreferrer\">discussions \u00e0 ce sujet sur le forum<\/a> , voici quelques informations sur l&rsquo;\u00e2ge maximum pour avoir des enfants, le taux de fertilit\u00e9 qui diminue avec l&rsquo;\u00e2ge. Pour tous ceux et celles qui pensent \u00e0 leur horloge biologique pas que en se rasant \ud83d\ude09<\/p>\n","protected":false},"author":2,"featured_media":183,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"om_disable_all_campaigns":false,"_lmt_disableupdate":"no","_lmt_disable":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[7],"tags":[96,1092],"class_list":["post-184","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-celibataire","tag-horloge-biologique","tag-maternite"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quand l&#039;horloge biologique vous rappelle \u00e0 l&#039;ordre... - Les Bridgets<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/quand-l-horloge-biologique-vous-rappelle-a-l-ordre.html\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quand l&#039;horloge biologique vous rappelle \u00e0 l&#039;ordre... - Les Bridgets\" \/>\n<meta property=\"og:description\" content=\"Apr\u00e8s plusieurs discussions \u00e0 ce sujet sur le forum , voici quelques informations sur l&#039;\u00e2ge maximum pour avoir des enfants, le taux de fertilit\u00e9 qui diminue avec l&#039;\u00e2ge. Pour tous ceux et celles qui pensent \u00e0 leur horloge biologique pas que en se rasant ;-)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/quand-l-horloge-biologique-vous-rappelle-a-l-ordre.html\" \/>\n<meta property=\"og:site_name\" content=\"Les Bridgets\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Les.Bridgets\" \/>\n<meta property=\"article:published_time\" content=\"2008-01-20T19:35:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-07T13:45:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2008\/01\/ventre-femme-enceinte.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"230\" \/>\n\t<meta property=\"og:image:height\" content=\"153\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bridget\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@les_bridgets\" \/>\n<meta name=\"twitter:site\" content=\"@les_bridgets\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bridget\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/celibataire\\\/quand-l-horloge-biologique-vous-rappelle-a-l-ordre.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/celibataire\\\/quand-l-horloge-biologique-vous-rappelle-a-l-ordre.html\"},\"author\":{\"name\":\"Bridget\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/person\\\/82a31c27ae0ddd23ee59e1e2ac5713ba\"},\"headline\":\"Quand l&rsquo;horloge biologique vous rappelle \u00e0 l&rsquo;ordre&#8230;\",\"datePublished\":\"2008-01-20T19:35:11+00:00\",\"dateModified\":\"2019-05-07T13:45:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/celibataire\\\/quand-l-horloge-biologique-vous-rappelle-a-l-ordre.html\"},\"wordCount\":444,\"commentCount\":4,\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/celibataire\\\/quand-l-horloge-biologique-vous-rappelle-a-l-ordre.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2008\\\/01\\\/ventre-femme-enceinte.jpg\",\"keywords\":[\"horloge biologique\",\"maternit\u00e9\"],\"articleSection\":[\"Etre c\u00e9libataire - vivre seule\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/celibataire\\\/quand-l-horloge-biologique-vous-rappelle-a-l-ordre.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/celibataire\\\/quand-l-horloge-biologique-vous-rappelle-a-l-ordre.html\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/celibataire\\\/quand-l-horloge-biologique-vous-rappelle-a-l-ordre.html\",\"name\":\"Quand l'horloge biologique vous rappelle \u00e0 l'ordre... - Les Bridgets\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/celibataire\\\/quand-l-horloge-biologique-vous-rappelle-a-l-ordre.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/celibataire\\\/quand-l-horloge-biologique-vous-rappelle-a-l-ordre.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2008\\\/01\\\/ventre-femme-enceinte.jpg\",\"datePublished\":\"2008-01-20T19:35:11+00:00\",\"dateModified\":\"2019-05-07T13:45:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/celibataire\\\/quand-l-horloge-biologique-vous-rappelle-a-l-ordre.html#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/celibataire\\\/quand-l-horloge-biologique-vous-rappelle-a-l-ordre.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/celibataire\\\/quand-l-horloge-biologique-vous-rappelle-a-l-ordre.html#primaryimage\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2008\\\/01\\\/ventre-femme-enceinte.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2008\\\/01\\\/ventre-femme-enceinte.jpg\",\"width\":230,\"height\":153,\"caption\":\"Ventre femme enceinte\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/celibataire\\\/quand-l-horloge-biologique-vous-rappelle-a-l-ordre.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Les Bridgets\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conseils sur l'amour, le couple &amp; les c\u00e9libataires\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/category\\\/conseils-relations\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Etre c\u00e9libataire - vivre seule\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/category\\\/conseils-relations\\\/celibataire\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Quand l&rsquo;horloge biologique vous rappelle \u00e0 l&rsquo;ordre&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#website\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/\",\"name\":\"Les Bridgets\",\"description\":\"R\u00e9f\u00e9rences et r\u00e9flexions sur nos relations\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lesbridgets.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\",\"name\":\"Les Bridgets\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo-3-lesbridgets.png\",\"contentUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo-3-lesbridgets.png\",\"width\":251,\"height\":59,\"caption\":\"Les Bridgets\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Les.Bridgets\",\"https:\\\/\\\/x.com\\\/les_bridgets\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/person\\\/82a31c27ae0ddd23ee59e1e2ac5713ba\",\"name\":\"Bridget\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"caption\":\"Bridget\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quand l'horloge biologique vous rappelle \u00e0 l'ordre... - Les Bridgets","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/quand-l-horloge-biologique-vous-rappelle-a-l-ordre.html","og_locale":"fr_FR","og_type":"article","og_title":"Quand l'horloge biologique vous rappelle \u00e0 l'ordre... - Les Bridgets","og_description":"Apr\u00e8s plusieurs discussions \u00e0 ce sujet sur le forum , voici quelques informations sur l'\u00e2ge maximum pour avoir des enfants, le taux de fertilit\u00e9 qui diminue avec l'\u00e2ge. Pour tous ceux et celles qui pensent \u00e0 leur horloge biologique pas que en se rasant ;-)","og_url":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/quand-l-horloge-biologique-vous-rappelle-a-l-ordre.html","og_site_name":"Les Bridgets","article_publisher":"https:\/\/www.facebook.com\/Les.Bridgets","article_published_time":"2008-01-20T19:35:11+00:00","article_modified_time":"2019-05-07T13:45:30+00:00","og_image":[{"width":230,"height":153,"url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2008\/01\/ventre-femme-enceinte.jpg","type":"image\/jpeg"}],"author":"Bridget","twitter_card":"summary_large_image","twitter_creator":"@les_bridgets","twitter_site":"@les_bridgets","twitter_misc":{"\u00c9crit par":"Bridget","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/quand-l-horloge-biologique-vous-rappelle-a-l-ordre.html#article","isPartOf":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/quand-l-horloge-biologique-vous-rappelle-a-l-ordre.html"},"author":{"name":"Bridget","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/person\/82a31c27ae0ddd23ee59e1e2ac5713ba"},"headline":"Quand l&rsquo;horloge biologique vous rappelle \u00e0 l&rsquo;ordre&#8230;","datePublished":"2008-01-20T19:35:11+00:00","dateModified":"2019-05-07T13:45:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/quand-l-horloge-biologique-vous-rappelle-a-l-ordre.html"},"wordCount":444,"commentCount":4,"publisher":{"@id":"https:\/\/www.lesbridgets.com\/#organization"},"image":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/quand-l-horloge-biologique-vous-rappelle-a-l-ordre.html#primaryimage"},"thumbnailUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2008\/01\/ventre-femme-enceinte.jpg","keywords":["horloge biologique","maternit\u00e9"],"articleSection":["Etre c\u00e9libataire - vivre seule"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/quand-l-horloge-biologique-vous-rappelle-a-l-ordre.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/quand-l-horloge-biologique-vous-rappelle-a-l-ordre.html","url":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/quand-l-horloge-biologique-vous-rappelle-a-l-ordre.html","name":"Quand l'horloge biologique vous rappelle \u00e0 l'ordre... - Les Bridgets","isPartOf":{"@id":"https:\/\/www.lesbridgets.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/quand-l-horloge-biologique-vous-rappelle-a-l-ordre.html#primaryimage"},"image":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/quand-l-horloge-biologique-vous-rappelle-a-l-ordre.html#primaryimage"},"thumbnailUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2008\/01\/ventre-femme-enceinte.jpg","datePublished":"2008-01-20T19:35:11+00:00","dateModified":"2019-05-07T13:45:30+00:00","breadcrumb":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/quand-l-horloge-biologique-vous-rappelle-a-l-ordre.html#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/quand-l-horloge-biologique-vous-rappelle-a-l-ordre.html"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/quand-l-horloge-biologique-vous-rappelle-a-l-ordre.html#primaryimage","url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2008\/01\/ventre-femme-enceinte.jpg","contentUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2008\/01\/ventre-femme-enceinte.jpg","width":230,"height":153,"caption":"Ventre femme enceinte"},{"@type":"BreadcrumbList","@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/quand-l-horloge-biologique-vous-rappelle-a-l-ordre.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Les Bridgets","item":"https:\/\/www.lesbridgets.com\/"},{"@type":"ListItem","position":2,"name":"Conseils sur l'amour, le couple &amp; les c\u00e9libataires","item":"https:\/\/www.lesbridgets.com\/index.php\/category\/conseils-relations"},{"@type":"ListItem","position":3,"name":"Etre c\u00e9libataire - vivre seule","item":"https:\/\/www.lesbridgets.com\/index.php\/category\/conseils-relations\/celibataire"},{"@type":"ListItem","position":4,"name":"Quand l&rsquo;horloge biologique vous rappelle \u00e0 l&rsquo;ordre&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/www.lesbridgets.com\/#website","url":"https:\/\/www.lesbridgets.com\/","name":"Les Bridgets","description":"R\u00e9f\u00e9rences et r\u00e9flexions sur nos relations","publisher":{"@id":"https:\/\/www.lesbridgets.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lesbridgets.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lesbridgets.com\/#organization","name":"Les Bridgets","url":"https:\/\/www.lesbridgets.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2022\/07\/cropped-logo-3-lesbridgets.png","contentUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2022\/07\/cropped-logo-3-lesbridgets.png","width":251,"height":59,"caption":"Les Bridgets"},"image":{"@id":"https:\/\/www.lesbridgets.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Les.Bridgets","https:\/\/x.com\/les_bridgets"]},{"@type":"Person","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/person\/82a31c27ae0ddd23ee59e1e2ac5713ba","name":"Bridget","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","caption":"Bridget"}}]}},"modified_by":"Bridget","_links":{"self":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/comments?post=184"}],"version-history":[{"count":4,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/184\/revisions"}],"predecessor-version":[{"id":247606,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/184\/revisions\/247606"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/media\/183"}],"wp:attachment":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/media?parent=184"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/categories?post=184"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/tags?post=184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}