{"id":1760,"date":"2005-04-18T07:52:29","date_gmt":"2005-04-18T05:52:29","guid":{"rendered":"http:\/\/lesbridg.cluster015.ovh.net\/wordpress\/index.php\/message-special-de-l-equipe\/contact-les-bridgets.html"},"modified":"2025-04-24T20:24:30","modified_gmt":"2025-04-24T18:24:30","slug":"contact-les-bridgets","status":"publish","type":"post","link":"https:\/\/www.lesbridgets.com\/index.php\/message-de-l-equipe-edito-news-exclus\/message-special-de-l-equipe\/contact-les-bridgets.html","title":{"rendered":"Nous contacter"},"content":{"rendered":"<p style=\"text-align: left;\">Pour toutes remarques, questions (demandes en mariage),\u00a0commentaires, dons (si vous avez un appartement ou une maison on est pas contre), envoyez-nous votre petit po\u00e8me en utilisant cette adresse mail : <strong>contact.at.lesbridgets.com<\/strong><\/p>\n<div>\n<div>Nous r\u00e9pondons \u00e0 tous donc si vous ne recevez rien de notre part dans les jours qui suivent (peut-\u00eatre votre mail serait pass\u00e9 en spam), n&rsquo;h\u00e9sitez pas \u00e0 nous faire un petit signe sur <a href=\"https:\/\/www.facebook.com\/Les.Bridgets\" target=\"_blank\" rel=\"alternate noopener\">facebook<\/a>\u00a0et <a href=\"https:\/\/www.instagram.com\/les_bridgets\/\" target=\"_blank\" rel=\"noopener\">Instagram<\/a>.<\/div>\n<div><\/div>\n<\/div>\n<div><\/div>\n<div>\n<div><\/div>\n<div style=\"text-align: center;\">Merci<\/div>\n<\/div>\n<p style=\"text-align: center;\">\n","protected":false},"excerpt":{"rendered":"<p>Pour toutes remarques, questions (demandes en mariage),\u00a0commentaires, dons (si vous avez un appartement ou une maison on est pas contre), envoyez-nous votre petit po\u00e8me en&hellip; <\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"om_disable_all_campaigns":false,"_lmt_disableupdate":"","_lmt_disable":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-1760","post","type-post","status-publish","format-standard","hentry","category-message-special-de-l-equipe"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nous contacter - Les Bridgets<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lesbridgets.com\/index.php\/message-de-l-equipe-edito-news-exclus\/message-special-de-l-equipe\/contact-les-bridgets.html\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nous contacter - Les Bridgets\" \/>\n<meta property=\"og:description\" content=\"Pour toutes remarques, questions (demandes en mariage),\u00a0commentaires, dons (si vous avez un appartement ou une maison on est pas contre), envoyez-nous votre petit po\u00e8me en&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lesbridgets.com\/index.php\/message-de-l-equipe-edito-news-exclus\/message-special-de-l-equipe\/contact-les-bridgets.html\" \/>\n<meta property=\"og:site_name\" content=\"Les Bridgets\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Les.Bridgets\" \/>\n<meta property=\"article:published_time\" content=\"2005-04-18T05:52:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-24T18:24:30+00:00\" \/>\n<meta name=\"author\" content=\"Bridget\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@les_bridgets\" \/>\n<meta name=\"twitter:site\" content=\"@les_bridgets\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bridget\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/message-de-l-equipe-edito-news-exclus\\\/message-special-de-l-equipe\\\/contact-les-bridgets.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/message-de-l-equipe-edito-news-exclus\\\/message-special-de-l-equipe\\\/contact-les-bridgets.html\"},\"author\":{\"name\":\"Bridget\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/person\\\/82a31c27ae0ddd23ee59e1e2ac5713ba\"},\"headline\":\"Nous contacter\",\"datePublished\":\"2005-04-18T05:52:29+00:00\",\"dateModified\":\"2025-04-24T18:24:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/message-de-l-equipe-edito-news-exclus\\\/message-special-de-l-equipe\\\/contact-les-bridgets.html\"},\"wordCount\":77,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\"},\"articleSection\":[\"Message sp\u00e9cial de l'\u00e9quipe\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/message-de-l-equipe-edito-news-exclus\\\/message-special-de-l-equipe\\\/contact-les-bridgets.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/message-de-l-equipe-edito-news-exclus\\\/message-special-de-l-equipe\\\/contact-les-bridgets.html\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/message-de-l-equipe-edito-news-exclus\\\/message-special-de-l-equipe\\\/contact-les-bridgets.html\",\"name\":\"Nous contacter - Les Bridgets\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#website\"},\"datePublished\":\"2005-04-18T05:52:29+00:00\",\"dateModified\":\"2025-04-24T18:24:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/message-de-l-equipe-edito-news-exclus\\\/message-special-de-l-equipe\\\/contact-les-bridgets.html#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/message-de-l-equipe-edito-news-exclus\\\/message-special-de-l-equipe\\\/contact-les-bridgets.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/message-de-l-equipe-edito-news-exclus\\\/message-special-de-l-equipe\\\/contact-les-bridgets.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Les Bridgets\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Message de l'\u00e9quipe - News\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/category\\\/message-de-l-equipe-edito-news-exclus\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Message sp\u00e9cial de l'\u00e9quipe\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/category\\\/message-de-l-equipe-edito-news-exclus\\\/message-special-de-l-equipe\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Nous contacter\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#website\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/\",\"name\":\"Les Bridgets\",\"description\":\"R\u00e9f\u00e9rences et r\u00e9flexions sur nos relations\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lesbridgets.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\",\"name\":\"Les Bridgets\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo-3-lesbridgets.png\",\"contentUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo-3-lesbridgets.png\",\"width\":251,\"height\":59,\"caption\":\"Les Bridgets\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Les.Bridgets\",\"https:\\\/\\\/x.com\\\/les_bridgets\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/person\\\/82a31c27ae0ddd23ee59e1e2ac5713ba\",\"name\":\"Bridget\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"caption\":\"Bridget\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nous contacter - Les Bridgets","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lesbridgets.com\/index.php\/message-de-l-equipe-edito-news-exclus\/message-special-de-l-equipe\/contact-les-bridgets.html","og_locale":"fr_FR","og_type":"article","og_title":"Nous contacter - Les Bridgets","og_description":"Pour toutes remarques, questions (demandes en mariage),\u00a0commentaires, dons (si vous avez un appartement ou une maison on est pas contre), envoyez-nous votre petit po\u00e8me en&hellip;","og_url":"https:\/\/www.lesbridgets.com\/index.php\/message-de-l-equipe-edito-news-exclus\/message-special-de-l-equipe\/contact-les-bridgets.html","og_site_name":"Les Bridgets","article_publisher":"https:\/\/www.facebook.com\/Les.Bridgets","article_published_time":"2005-04-18T05:52:29+00:00","article_modified_time":"2025-04-24T18:24:30+00:00","author":"Bridget","twitter_card":"summary_large_image","twitter_creator":"@les_bridgets","twitter_site":"@les_bridgets","twitter_misc":{"\u00c9crit par":"Bridget","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lesbridgets.com\/index.php\/message-de-l-equipe-edito-news-exclus\/message-special-de-l-equipe\/contact-les-bridgets.html#article","isPartOf":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/message-de-l-equipe-edito-news-exclus\/message-special-de-l-equipe\/contact-les-bridgets.html"},"author":{"name":"Bridget","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/person\/82a31c27ae0ddd23ee59e1e2ac5713ba"},"headline":"Nous contacter","datePublished":"2005-04-18T05:52:29+00:00","dateModified":"2025-04-24T18:24:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/message-de-l-equipe-edito-news-exclus\/message-special-de-l-equipe\/contact-les-bridgets.html"},"wordCount":77,"commentCount":0,"publisher":{"@id":"https:\/\/www.lesbridgets.com\/#organization"},"articleSection":["Message sp\u00e9cial de l'\u00e9quipe"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.lesbridgets.com\/index.php\/message-de-l-equipe-edito-news-exclus\/message-special-de-l-equipe\/contact-les-bridgets.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.lesbridgets.com\/index.php\/message-de-l-equipe-edito-news-exclus\/message-special-de-l-equipe\/contact-les-bridgets.html","url":"https:\/\/www.lesbridgets.com\/index.php\/message-de-l-equipe-edito-news-exclus\/message-special-de-l-equipe\/contact-les-bridgets.html","name":"Nous contacter - Les Bridgets","isPartOf":{"@id":"https:\/\/www.lesbridgets.com\/#website"},"datePublished":"2005-04-18T05:52:29+00:00","dateModified":"2025-04-24T18:24:30+00:00","breadcrumb":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/message-de-l-equipe-edito-news-exclus\/message-special-de-l-equipe\/contact-les-bridgets.html#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lesbridgets.com\/index.php\/message-de-l-equipe-edito-news-exclus\/message-special-de-l-equipe\/contact-les-bridgets.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.lesbridgets.com\/index.php\/message-de-l-equipe-edito-news-exclus\/message-special-de-l-equipe\/contact-les-bridgets.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Les Bridgets","item":"https:\/\/www.lesbridgets.com\/"},{"@type":"ListItem","position":2,"name":"Message de l'\u00e9quipe - News","item":"https:\/\/www.lesbridgets.com\/index.php\/category\/message-de-l-equipe-edito-news-exclus"},{"@type":"ListItem","position":3,"name":"Message sp\u00e9cial de l'\u00e9quipe","item":"https:\/\/www.lesbridgets.com\/index.php\/category\/message-de-l-equipe-edito-news-exclus\/message-special-de-l-equipe"},{"@type":"ListItem","position":4,"name":"Nous contacter"}]},{"@type":"WebSite","@id":"https:\/\/www.lesbridgets.com\/#website","url":"https:\/\/www.lesbridgets.com\/","name":"Les Bridgets","description":"R\u00e9f\u00e9rences et r\u00e9flexions sur nos relations","publisher":{"@id":"https:\/\/www.lesbridgets.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lesbridgets.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lesbridgets.com\/#organization","name":"Les Bridgets","url":"https:\/\/www.lesbridgets.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2022\/07\/cropped-logo-3-lesbridgets.png","contentUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2022\/07\/cropped-logo-3-lesbridgets.png","width":251,"height":59,"caption":"Les Bridgets"},"image":{"@id":"https:\/\/www.lesbridgets.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Les.Bridgets","https:\/\/x.com\/les_bridgets"]},{"@type":"Person","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/person\/82a31c27ae0ddd23ee59e1e2ac5713ba","name":"Bridget","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","caption":"Bridget"}}]}},"modified_by":"Bridget","_links":{"self":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/1760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/comments?post=1760"}],"version-history":[{"count":7,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/1760\/revisions"}],"predecessor-version":[{"id":257963,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/1760\/revisions\/257963"}],"wp:attachment":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/media?parent=1760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/categories?post=1760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/tags?post=1760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}