{"id":172,"date":"2007-12-31T01:00:00","date_gmt":"2007-12-31T00:00:00","guid":{"rendered":"http:\/\/lesbridg.cluster015.ovh.net\/wordpress\/index.php\/etude-statistiques-sur-le-couple\/les-fellations-provoquent-des-cancers-de-la-gorge.html"},"modified":"2023-01-31T10:18:44","modified_gmt":"2023-01-31T09:18:44","slug":"les-fellations-provoquent-des-cancers-de-la-gorge","status":"publish","type":"post","link":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/les-fellations-provoquent-des-cancers-de-la-gorge.html","title":{"rendered":"Pourquoi les fellations peuvent provoquer des cancers de la gorge"},"content":{"rendered":"<p>Une \u00e9tude scientifique am\u00e9ricaine publi\u00e9e dans le New England Journal of Medicine d\u00e9montre que certaines tumeurs canc\u00e9reuses de la gorge sont provoqu\u00e9es par des papillomavirus.<\/p>\n<p>Selon cette \u00e9tude, nous courons plus de risque d&rsquo;avoir un cancer de la gorge en ayant des relations bucco-g\u00e9nitales avec plusieurs partenaires qu&rsquo;en fumant ou en buvant.<\/p>\n<h2>Les risques augmentent nettement pour les personnes ayant des relations sexuelles bucco-g\u00e9nitales<\/h2>\n<p>Les papillomavirus humains, responsables de la plupart des cancers ut\u00e9rins, sont aussi li\u00e9s \u00e0 certaines tumeurs canc\u00e9reuses de la gorge.<br \/>\nLe risque que ces tumeurs se d\u00e9veloppent augmenterait nettement pour les personnes ayant des relations sexuelles bucco-g\u00e9nitales (fellation et cunnilingus), selon une \u00e9tude publi\u00e9e dans le New England Journal of Medicine.<\/p>\n<p>M\u00eame sans fumer ou consommer de l\u2019alcool, le fait d\u2019avoir une infection de la bouche avec des papillomavirus et des relations sexuelles bucco-g\u00e9nitales avec de multiples partenaires para\u00eet constituer le principal facteur de risque de certains types de cancer assez rares de la gorge, ont conclu des chercheurs de la facult\u00e9 de m\u00e9decine de l\u2019universit\u00e9 Johns Hopkins (Maryland).<\/p>\n<h3>\u00ab\u00a0<strong>Le public devrait toutefois \u00eatre rassur\u00e9 car le cancer de l\u2019oropharynx (situ\u00e9 \u00e0 l\u2019arri\u00e8re de la langue) est relativement rare et la grande majorit\u00e9 des personnes ayant une infection buccale avec des papillomavirus ne d\u00e9velopperont probablement pas un cancer de la gorge<\/strong>\u00ab\u00a0,<\/h3>\n<p>explique le Dr Maura Gillison, \u00e9pid\u00e9miologiste et principal auteur de cette recherche.<\/p>\n<p>Son \u00e9tude a port\u00e9 sur 86 hommes et 14 femmes qui venaient d\u2019\u00eatre diagnostiqu\u00e9s d\u2019un cancer de l\u2019oropharynx et qui \u00e9taient d\u00e9j\u00e0 infect\u00e9s par des papillomavirus.<\/p>\n<p>Ils avaient 32 fois plus de risques de d\u00e9velopper ce cancer. Ce taux est :<\/p>\n<ul>\n<li>3 fois plus \u00e9lev\u00e9 que pour les fumeurs<\/li>\n<li>et 2 fois et demi plus \u00e9lev\u00e9 que pour les personnes buvant r\u00e9guli\u00e8rement de l\u2019alcool, pr\u00e9cise le Dr Gillison.<\/li>\n<\/ul>\n<p>Les participants \u00e0 cette \u00e9tude ayant indiqu\u00e9 avoir eu des relations bucco-g\u00e9nitales avec plus de 6 partenaires durant leur vie, avaient 8,6 fois plus de risques d\u2019avoir un cancer li\u00e9 \u00e0 une infection avec des papillomavirus.<\/p>\n<p>Cette recherche montre aussi que le fait de fumer ou de boire de l\u2019alcool n\u2019a pas accru les risques de cancer de la gorge chez ceux ayant une infection de la bouche avec des papillomavirus.<br \/>\nEt le Dr Gillison d\u2019affirmer : \u00ab\u00a0C\u2019est bien le virus qui provoque le cancer\u00a0\u00bb.<\/p>\n<h2>\u00c0 \u00e9couter notre interview aupr\u00e8s d&rsquo;une gyn\u00e9cologue au sujet du papillomavirus<\/h2>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/1WOZtFW36XA\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<h2>Gardasil : l\u2019efficacit\u00e9 du vaccin contre le papillomavirus d\u00e9montr\u00e9e<\/h2>\n<p>Le 1er vaccin contre le cancer du col de l\u2019ut\u00e9rus, commercialis\u00e9 depuis 2006, est efficace \u00e0 pr\u00e8s de 100% contre les types de papillomavirus responsables de la plupart des tumeurs canc\u00e9reuses ut\u00e9rines.<\/p>\n<p>Le vaccin \u00ab\u00a0est efficace \u00e0 98% et sans danger comme le montre la raret\u00e9 des cas d\u2019effets secondaires s\u00e9v\u00e8res\u00a0\u00bb, selon le Dr Kevin Ault, professeur de gyn\u00e9cologie \u00e0 Atlanta, qui a contribu\u00e9 \u00e0 l\u2019\u00e9laboration du vaccin et \u00e0 l\u2019\u00e9tude parue dans le New England Journal of Medicine.<\/p>\n<p>L\u2019essai a montr\u00e9 que le vaccin \u00e9tait pr\u00e8s de 100 % efficace contre les types 16 et 18 de papillomavirus, responsables de 70% des cancers ut\u00e9rins.<br \/>\nIl a aussi \u00e9t\u00e9 efficace contre les types 6 et 11 qui causent 90% des verrues de l\u2019anus et des organes g\u00e9nitaux.<\/p>\n<p>Consulter l&rsquo;origine de ce communiqu\u00e9 de de l&rsquo;\u00c9cole de m\u00e9decine de l&rsquo;Universit\u00e9 Johns Hopkins \u00ab\u00a0Un lien entre les relations bucco-g\u00e9nitales et le cancer de la gorge\u00a0\u00bb en anglais.<\/p>\n<h2>Conclusion<\/h2>\n<p>Nous vous laissons en tirer les conclusions qu&rsquo;il faut.<\/p>\n<p>On ne rappellera jamais assez qu&rsquo;un acte sexuel comme la fellation, peut transmettre \u00e9galement des MST (comme le virus du Sida) d&rsquo;ailleurs comme tout autres rapports sexuels, il est important de se prot\u00e9ger.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une \u00e9tude scientifique am\u00e9ricaine publi\u00e9e dans le <strong>New England Journal of Medicine\u00a0<\/strong>d\u00e9montre que certaines tumeurs canc\u00e9reuses de la gorge sont provoqu\u00e9es par des papillomavirus.<\/p>\n<p> Selon cette \u00e9tude, nous courons plus de risque d&rsquo;avoir un cancer de la gorge en ayant des relations bucco-g\u00e9nitales avec plusieurs partenaires qu&rsquo;en fumant ou en buvant.<\/p>\n","protected":false},"author":2,"featured_media":246794,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"om_disable_all_campaigns":false,"_lmt_disableupdate":"no","_lmt_disable":"no","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[9],"tags":[143,141,142],"class_list":["post-172","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-etude-statistiques-couple","tag-cancer","tag-papillomavirus","tag-prevention"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pourquoi les fellations peuvent provoquer des cancers de la gorge - Les Bridgets<\/title>\n<meta name=\"description\" content=\"Une \u00e9tude scientifique am\u00e9ricaine publi\u00e9e en 2007 d\u00e9montre que certains cancers de la gorge sont provoqu\u00e9s par des papillomavirus.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/les-fellations-provoquent-des-cancers-de-la-gorge.html\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pourquoi les fellations peuvent provoquer des cancers de la gorge - Les Bridgets\" \/>\n<meta property=\"og:description\" content=\"Une \u00e9tude scientifique am\u00e9ricaine publi\u00e9e en 2007 d\u00e9montre que certains cancers de la gorge sont provoqu\u00e9s par des papillomavirus.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/les-fellations-provoquent-des-cancers-de-la-gorge.html\" \/>\n<meta property=\"og:site_name\" content=\"Les Bridgets\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Les.Bridgets\" \/>\n<meta property=\"article:published_time\" content=\"2007-12-31T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-31T09:18:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2007\/12\/fellations-cancer-gorge-hpv.png\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"472\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Bridget\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@les_bridgets\" \/>\n<meta name=\"twitter:site\" content=\"@les_bridgets\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bridget\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/statistiques\\\/etude-statistiques-couple\\\/les-fellations-provoquent-des-cancers-de-la-gorge.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/statistiques\\\/etude-statistiques-couple\\\/les-fellations-provoquent-des-cancers-de-la-gorge.html\"},\"author\":{\"name\":\"Bridget\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/person\\\/82a31c27ae0ddd23ee59e1e2ac5713ba\"},\"headline\":\"Pourquoi les fellations peuvent provoquer des cancers de la gorge\",\"datePublished\":\"2007-12-31T00:00:00+00:00\",\"dateModified\":\"2023-01-31T09:18:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/statistiques\\\/etude-statistiques-couple\\\/les-fellations-provoquent-des-cancers-de-la-gorge.html\"},\"wordCount\":652,\"commentCount\":17,\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/statistiques\\\/etude-statistiques-couple\\\/les-fellations-provoquent-des-cancers-de-la-gorge.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2007\\\/12\\\/fellations-cancer-gorge-hpv.png\",\"keywords\":[\"cancer\",\"papillomavirus\",\"prevention\"],\"articleSection\":[\"Statistiques sur le couple\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/statistiques\\\/etude-statistiques-couple\\\/les-fellations-provoquent-des-cancers-de-la-gorge.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/statistiques\\\/etude-statistiques-couple\\\/les-fellations-provoquent-des-cancers-de-la-gorge.html\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/statistiques\\\/etude-statistiques-couple\\\/les-fellations-provoquent-des-cancers-de-la-gorge.html\",\"name\":\"Pourquoi les fellations peuvent provoquer des cancers de la gorge - Les Bridgets\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/statistiques\\\/etude-statistiques-couple\\\/les-fellations-provoquent-des-cancers-de-la-gorge.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/statistiques\\\/etude-statistiques-couple\\\/les-fellations-provoquent-des-cancers-de-la-gorge.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2007\\\/12\\\/fellations-cancer-gorge-hpv.png\",\"datePublished\":\"2007-12-31T00:00:00+00:00\",\"dateModified\":\"2023-01-31T09:18:44+00:00\",\"description\":\"Une \u00e9tude scientifique am\u00e9ricaine publi\u00e9e en 2007 d\u00e9montre que certains cancers de la gorge sont provoqu\u00e9s par des papillomavirus.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/statistiques\\\/etude-statistiques-couple\\\/les-fellations-provoquent-des-cancers-de-la-gorge.html#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/statistiques\\\/etude-statistiques-couple\\\/les-fellations-provoquent-des-cancers-de-la-gorge.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/statistiques\\\/etude-statistiques-couple\\\/les-fellations-provoquent-des-cancers-de-la-gorge.html#primaryimage\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2007\\\/12\\\/fellations-cancer-gorge-hpv.png\",\"contentUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2007\\\/12\\\/fellations-cancer-gorge-hpv.png\",\"width\":750,\"height\":472},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/statistiques\\\/etude-statistiques-couple\\\/les-fellations-provoquent-des-cancers-de-la-gorge.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Les Bridgets\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Statistiques sur le couple &amp; celibat\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/category\\\/statistiques\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Statistiques sur le couple\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/category\\\/statistiques\\\/etude-statistiques-couple\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Pourquoi les fellations peuvent provoquer des cancers de la gorge\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#website\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/\",\"name\":\"Les Bridgets\",\"description\":\"R\u00e9f\u00e9rences et r\u00e9flexions sur nos relations\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lesbridgets.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\",\"name\":\"Les Bridgets\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo-3-lesbridgets.png\",\"contentUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo-3-lesbridgets.png\",\"width\":251,\"height\":59,\"caption\":\"Les Bridgets\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Les.Bridgets\",\"https:\\\/\\\/x.com\\\/les_bridgets\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/person\\\/82a31c27ae0ddd23ee59e1e2ac5713ba\",\"name\":\"Bridget\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"caption\":\"Bridget\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pourquoi les fellations peuvent provoquer des cancers de la gorge - Les Bridgets","description":"Une \u00e9tude scientifique am\u00e9ricaine publi\u00e9e en 2007 d\u00e9montre que certains cancers de la gorge sont provoqu\u00e9s par des papillomavirus.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/les-fellations-provoquent-des-cancers-de-la-gorge.html","og_locale":"fr_FR","og_type":"article","og_title":"Pourquoi les fellations peuvent provoquer des cancers de la gorge - Les Bridgets","og_description":"Une \u00e9tude scientifique am\u00e9ricaine publi\u00e9e en 2007 d\u00e9montre que certains cancers de la gorge sont provoqu\u00e9s par des papillomavirus.","og_url":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/les-fellations-provoquent-des-cancers-de-la-gorge.html","og_site_name":"Les Bridgets","article_publisher":"https:\/\/www.facebook.com\/Les.Bridgets","article_published_time":"2007-12-31T00:00:00+00:00","article_modified_time":"2023-01-31T09:18:44+00:00","og_image":[{"width":750,"height":472,"url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2007\/12\/fellations-cancer-gorge-hpv.png","type":"image\/png"}],"author":"Bridget","twitter_card":"summary_large_image","twitter_creator":"@les_bridgets","twitter_site":"@les_bridgets","twitter_misc":{"\u00c9crit par":"Bridget","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/les-fellations-provoquent-des-cancers-de-la-gorge.html#article","isPartOf":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/les-fellations-provoquent-des-cancers-de-la-gorge.html"},"author":{"name":"Bridget","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/person\/82a31c27ae0ddd23ee59e1e2ac5713ba"},"headline":"Pourquoi les fellations peuvent provoquer des cancers de la gorge","datePublished":"2007-12-31T00:00:00+00:00","dateModified":"2023-01-31T09:18:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/les-fellations-provoquent-des-cancers-de-la-gorge.html"},"wordCount":652,"commentCount":17,"publisher":{"@id":"https:\/\/www.lesbridgets.com\/#organization"},"image":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/les-fellations-provoquent-des-cancers-de-la-gorge.html#primaryimage"},"thumbnailUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2007\/12\/fellations-cancer-gorge-hpv.png","keywords":["cancer","papillomavirus","prevention"],"articleSection":["Statistiques sur le couple"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/les-fellations-provoquent-des-cancers-de-la-gorge.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/les-fellations-provoquent-des-cancers-de-la-gorge.html","url":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/les-fellations-provoquent-des-cancers-de-la-gorge.html","name":"Pourquoi les fellations peuvent provoquer des cancers de la gorge - Les Bridgets","isPartOf":{"@id":"https:\/\/www.lesbridgets.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/les-fellations-provoquent-des-cancers-de-la-gorge.html#primaryimage"},"image":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/les-fellations-provoquent-des-cancers-de-la-gorge.html#primaryimage"},"thumbnailUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2007\/12\/fellations-cancer-gorge-hpv.png","datePublished":"2007-12-31T00:00:00+00:00","dateModified":"2023-01-31T09:18:44+00:00","description":"Une \u00e9tude scientifique am\u00e9ricaine publi\u00e9e en 2007 d\u00e9montre que certains cancers de la gorge sont provoqu\u00e9s par des papillomavirus.","breadcrumb":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/les-fellations-provoquent-des-cancers-de-la-gorge.html#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/les-fellations-provoquent-des-cancers-de-la-gorge.html"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/les-fellations-provoquent-des-cancers-de-la-gorge.html#primaryimage","url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2007\/12\/fellations-cancer-gorge-hpv.png","contentUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2007\/12\/fellations-cancer-gorge-hpv.png","width":750,"height":472},{"@type":"BreadcrumbList","@id":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-couple\/les-fellations-provoquent-des-cancers-de-la-gorge.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Les Bridgets","item":"https:\/\/www.lesbridgets.com\/"},{"@type":"ListItem","position":2,"name":"Statistiques sur le couple &amp; celibat","item":"https:\/\/www.lesbridgets.com\/index.php\/category\/statistiques"},{"@type":"ListItem","position":3,"name":"Statistiques sur le couple","item":"https:\/\/www.lesbridgets.com\/index.php\/category\/statistiques\/etude-statistiques-couple"},{"@type":"ListItem","position":4,"name":"Pourquoi les fellations peuvent provoquer des cancers de la gorge"}]},{"@type":"WebSite","@id":"https:\/\/www.lesbridgets.com\/#website","url":"https:\/\/www.lesbridgets.com\/","name":"Les Bridgets","description":"R\u00e9f\u00e9rences et r\u00e9flexions sur nos relations","publisher":{"@id":"https:\/\/www.lesbridgets.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lesbridgets.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lesbridgets.com\/#organization","name":"Les Bridgets","url":"https:\/\/www.lesbridgets.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2022\/07\/cropped-logo-3-lesbridgets.png","contentUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2022\/07\/cropped-logo-3-lesbridgets.png","width":251,"height":59,"caption":"Les Bridgets"},"image":{"@id":"https:\/\/www.lesbridgets.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Les.Bridgets","https:\/\/x.com\/les_bridgets"]},{"@type":"Person","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/person\/82a31c27ae0ddd23ee59e1e2ac5713ba","name":"Bridget","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","caption":"Bridget"}}]}},"modified_by":"Bridget","_links":{"self":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/comments?post=172"}],"version-history":[{"count":11,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/172\/revisions"}],"predecessor-version":[{"id":256361,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/172\/revisions\/256361"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/media\/246794"}],"wp:attachment":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/media?parent=172"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/categories?post=172"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/tags?post=172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}