{"id":1614,"date":"2015-01-09T11:10:18","date_gmt":"2015-01-09T10:10:18","guid":{"rendered":"http:\/\/lesbridg.cluster015.ovh.net\/wordpress\/index.php\/rencontres-virtuelles\/notre-avis-sur-le-site-de-rencontres-pof-plenty-of-fish.html"},"modified":"2022-07-14T14:03:17","modified_gmt":"2022-07-14T12:03:17","slug":"pof-notre-avis-sur-le-site-de-rencontres-pof-plenty-of-fish","status":"publish","type":"post","link":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rencontres-virtuelles\/pof-notre-avis-sur-le-site-de-rencontres-pof-plenty-of-fish.html","title":{"rendered":"POF : Notre avis sur le site de rencontres Plenty of fish"},"content":{"rendered":"<p>Malgr\u00e9 notre veille permanente sur le sujet, on a d\u00e9couvert le site de rencontres POF seulement en ce d\u00e9but d&rsquo;ann\u00e9e en lisant les sites de rencontres les plus recherch\u00e9s dans le monde sur Google en 2014.<br \/>\nAlors on s&rsquo;est senti obliger de voir ce qu&rsquo;il en \u00e9tait. On a donc test\u00e9 le site de rencontres POF pendant quelques jours. Parce que oui quelques jours \u00e7a suffit.<\/p>\n<h2>Tout d&rsquo;abord pourquoi ce nom si bizarre, POF?<\/h2>\n<p>POF est l&rsquo;abr\u00e9viation Plenty of Fish. 3 mois de <a href=\"https:\/\/www.lesbridgets.com\/index.php\/soirees-voyages-rencontres\/idee-vacances-en-solo-mais-culturel-le-sejour-linguistique.html\" target=\"_blank\" rel=\"noopener noreferrer\">s\u00e9jour linguistique<\/a> et sans dictionnaire on peut vous le traduire litt\u00e9ralement par \u00ab\u00a0Beaucoup de poissons\u00a0\u00bb.<br \/>\nUn site qui porte bien son nom parce que vous vous retrouvez rapidement immerg\u00e9e ou plut\u00f4t attaqu\u00e9e par un banc de thons .<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-1613\" style=\"display: block; margin-left: auto; margin-right: auto;\" title=\"pof avis plenty of fish\" src=\"http:\/\/lesbridg.cluster015.ovh.net\/wordpress\/wp-content\/uploads\/2015\/01\/pof-thon-fish-avis.jpg\" alt=\"\" width=\"550\" height=\"411\" border=\"0\" srcset=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2015\/01\/pof-thon-fish-avis.jpg 550w, https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2015\/01\/pof-thon-fish-avis-300x224.jpg 300w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/p>\n<p>Enfin rapidement pas tant que \u00e7a, l\u00e0 o\u00f9 l&rsquo;on est de plus en plus habitu\u00e9 aux applications comme <a href=\"https:\/\/www.lesbridgets.com\/index.php\/rencontres-virtuelles\/tinder-les-amis-de-nos-amis-qu-ils-n-avaient-pas-penses-a-nous-presenter.html\" target=\"_blank\" rel=\"noopener noreferrer\">Tinder<\/a> ou <a href=\"index.php\/Rencontres-virtuelles\/Notre-avis-sur-Happn-qui-permet-de-retrouver-ceux-que-nous-avons-croise.html\" target=\"_blank\" rel=\"noopener noreferrer\">Happn<\/a> o\u00f9 il suffit juste de synchroniser son compte facebook et mettre quelques lignes en description, sur POF apr\u00e8s vous avoir fait remplir quelques champs pour aller \u00e0 l&rsquo;\u00e9tape suivante vous arrivez directement sur un gros formulaire avec beaucoup de questions aux champs TOUS obligatoires et du type :<\/p>\n<h2>\u00ab\u00a0Combien de temps a dur\u00e9 votre plus longue relation ?\u00a0\u00bb<\/h2>\n<p>\u00ab\u00a0Quels sont vos revenus\u00a0\u00bb<\/p>\n<p>Et une premi\u00e8re dans un site de rencontre les questions au sujet de vos parents :<br \/>\n<em>Ils sont encore mari\u00e9, divorc\u00e9, l&rsquo;un d&rsquo;eux est d\u00e9c\u00e9d\u00e9 &#8230; ? Combien d&rsquo;enfant ils ont eu ? <\/em><br \/>\n<em>et vous \u00eates le combien dans la fraterie ?<\/em><\/p>\n<p>Une autre question assez perturbante : <em>Sortiriez-vous avec un membre qui dit \u00eatre corpulent ou avoir quelques kilos en trop?<\/em><br \/>\nSuggestions de r\u00e9ponse :<br \/>\n<em>&#8211; oui <\/em><br \/>\n<em>&#8211; non <\/em><br \/>\n<em>&#8211; je ne sors uniquement avec des membres corpulents ou avec quelques kilos en trop<\/em><\/p>\n<p>Des questions obligatoires parce que l&rsquo;utilisation du site (pratiquement) enti\u00e8rement gratuite et qu&rsquo;ils pourront s\u00fbrement revendre vos infos pour des \u00e9tudes de sondages quelconque.<\/p>\n<h2>Voil\u00e0 vous \u00eates fich\u00e9e sur POF et maintenant?<\/h2>\n<p>Vous \u00eates \u00e0 nouveau face \u00e0 un autre et plus long questionnaire pour essayer de comprendre vos attentes et vous proposez des profils qui vous correspondent le plus. J&rsquo;ai jou\u00e9 le jeu.<br \/>\nJ&rsquo;ai rempli sinc\u00e8rement chaque question.<br \/>\nComme une sorte de test f\u00e9minin, au final on vous donne votre profil psychologique, le profil de partenaire que vous recherchez et ce sur quoi vous avez tendance \u00e0 vous diriger.<\/p>\n<p>S&rsquo;en suit une aussi longue page de questions mais cette fois avec un r\u00e9sultat totalement en anglais. (pas de moyen pour traduire la version fran\u00e7aise jusqu&rsquo;au bout)<br \/>\nAlors que vous n&rsquo;avez m\u00eame pas eu le temps de commencer une recherche, vous avez d\u00e9j\u00e0 30 notifications.<br \/>\nPuis 5 minutes apr\u00e8s, 50.<br \/>\nEt \u00e7a n&rsquo;arr\u00eate pas en une journ\u00e9e plus de 250 messages sans parler des \u00ab\u00a0coucou\u00a0\u00bb et de \u00ab\u00a0demandes de rencontres\u00a0\u00bb (qui pour info les femmes ne peuvent pas consulter sans payer donc messieurs qui \u00eates extr\u00eamement nombreux sur POF, un conseil arr\u00eatez d&rsquo;envoyer des demandes de rencontres \u00e7a ne sert \u00e0 rien)<\/p>\n<h2>Bilan du test<\/h2>\n<p>Tout de suite, c&rsquo;est tr\u00e8s oppressant de se sentir aussi sollicit\u00e9e, de pas pouvoir r\u00e9pondre \u00e0 chacun car oui j&rsquo;ai pris le temps de lire et d&rsquo;aller voir chaque profil les premi\u00e8res heures et apr\u00e8s cela devenait impossible.<br \/>\nPuis j&rsquo;ai vite d\u00e9sactiv\u00e9 toutes les alertes mails pour n&rsquo;avoir que les notifications de l&rsquo;application (qui elle aussi est gratuite).<br \/>\nPour enfin craquer et supprimer l&rsquo;appli car on y retrouve les m\u00eames profils que sur <a href=\"https:\/\/www.lesbridgets.com\/index.php\/rencontres-virtuelles\/badoo-notre-avis-sur-les-pratiques-douteuses-de-recrutement-du-site-et-de-l-application-de-rencontre.html\" target=\"_blank\" rel=\"alternate noopener noreferrer\">Badoo <\/a>et donc <a href=\"index.php\/Rencontres-virtuelles\/LOVOO-l-application-de-rencontres-relou-des-beaufs.html\" target=\"_blank\" rel=\"noopener noreferrer\">l&rsquo;application Lovoo<\/a>.<br \/>\nDes hommes torses nus en selfie dans la salle de bain, sur le capot d&rsquo;une voiture, ou par exemple torse nu avec un casque devant sa moto (tout ce que je d\u00e9conseillais dans ma vid\u00e9o sur \u00ab\u00a0<a href=\"index.php\/Rencontres-virtuelles\/Video-7-erreurs-a-ne-pas-faire-pour-choisir-sa-photo-sur-un-site-de-rencontres.html\" target=\"_blank\" rel=\"noopener noreferrer\">7 erreurs \u00e0 ne pas faire pour sa photo sur un site de rencontres<\/a>\u00ab\u00a0.<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" src=\"https:\/\/www.tools-affil2.com\/rtb\/index.php?comfrom=964141&amp;r=5cc806516cfde25c8a0b8216fc382b73&amp;p=43328&amp;cf0=fx&amp;fa=true&amp;cf2=&amp;cfsa2=&amp;brand=y&amp;aabd2=&amp;aabs=\" width=\"728\" height=\"90\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Malgr\u00e9 notre veille permanente sur le sujet, on a d\u00e9couvert le site de rencontres POF seulement en ce d\u00e9but d&rsquo;ann\u00e9e en lisant les sites de rencontres les plus recherch\u00e9s dans le monde sur Google en 2014. <br \/>Alors on s&rsquo;est senti obliger de voir ce qu&rsquo;il en \u00e9tait. On a donc test\u00e9 le site de rencontres POF pendant quelques jours. Parce que oui quelques jours \u00e7a suffit.<\/p>\n","protected":false},"author":2,"featured_media":247988,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"om_disable_all_campaigns":false,"_lmt_disableupdate":"no","_lmt_disable":"no","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[23],"tags":[470,669,574],"class_list":["post-1614","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rencontres-virtuelles","tag-gratuit","tag-site-de-rencontre-avis","tag-site-de-rencontres-gratuit"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>POF : Notre avis sur le site de rencontres Plenty of fish - Les Bridgets<\/title>\n<meta name=\"description\" content=\"POF et l&#039;application de rencontre qui a \u00e9t\u00e9 la plus recherch\u00e9e en 2014 sur Google, il \u00e9tait temps de la tester, de comprendre cette popularit\u00e9 et vous donner notre avis.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rencontres-virtuelles\/pof-notre-avis-sur-le-site-de-rencontres-pof-plenty-of-fish.html\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"POF : Notre avis sur le site de rencontres Plenty of fish - Les Bridgets\" \/>\n<meta property=\"og:description\" content=\"POF et l&#039;application de rencontre qui a \u00e9t\u00e9 la plus recherch\u00e9e en 2014 sur Google, il \u00e9tait temps de la tester, de comprendre cette popularit\u00e9 et vous donner notre avis.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rencontres-virtuelles\/pof-notre-avis-sur-le-site-de-rencontres-pof-plenty-of-fish.html\" \/>\n<meta property=\"og:site_name\" content=\"Les Bridgets\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Les.Bridgets\" \/>\n<meta property=\"article:published_time\" content=\"2015-01-09T10:10:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-14T12:03:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2015\/01\/avis-site-rencontres-pof.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"373\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bridget\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@les_bridgets\" \/>\n<meta name=\"twitter:site\" content=\"@les_bridgets\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bridget\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/rencontres-virtuelles\\\/pof-notre-avis-sur-le-site-de-rencontres-pof-plenty-of-fish.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/rencontres-virtuelles\\\/pof-notre-avis-sur-le-site-de-rencontres-pof-plenty-of-fish.html\"},\"author\":{\"name\":\"Bridget\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/person\\\/82a31c27ae0ddd23ee59e1e2ac5713ba\"},\"headline\":\"POF : Notre avis sur le site de rencontres Plenty of fish\",\"datePublished\":\"2015-01-09T10:10:18+00:00\",\"dateModified\":\"2022-07-14T12:03:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/rencontres-virtuelles\\\/pof-notre-avis-sur-le-site-de-rencontres-pof-plenty-of-fish.html\"},\"wordCount\":675,\"commentCount\":32,\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/rencontres-virtuelles\\\/pof-notre-avis-sur-le-site-de-rencontres-pof-plenty-of-fish.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/avis-site-rencontres-pof.jpg\",\"keywords\":[\"gratuit\",\"site de rencontre avis\",\"site de rencontres gratuit\"],\"articleSection\":[\"Rencontres en ligne\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/rencontres-virtuelles\\\/pof-notre-avis-sur-le-site-de-rencontres-pof-plenty-of-fish.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/rencontres-virtuelles\\\/pof-notre-avis-sur-le-site-de-rencontres-pof-plenty-of-fish.html\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/rencontres-virtuelles\\\/pof-notre-avis-sur-le-site-de-rencontres-pof-plenty-of-fish.html\",\"name\":\"POF : Notre avis sur le site de rencontres Plenty of fish - Les Bridgets\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/rencontres-virtuelles\\\/pof-notre-avis-sur-le-site-de-rencontres-pof-plenty-of-fish.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/rencontres-virtuelles\\\/pof-notre-avis-sur-le-site-de-rencontres-pof-plenty-of-fish.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/avis-site-rencontres-pof.jpg\",\"datePublished\":\"2015-01-09T10:10:18+00:00\",\"dateModified\":\"2022-07-14T12:03:17+00:00\",\"description\":\"POF et l'application de rencontre qui a \u00e9t\u00e9 la plus recherch\u00e9e en 2014 sur Google, il \u00e9tait temps de la tester, de comprendre cette popularit\u00e9 et vous donner notre avis.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/rencontres-virtuelles\\\/pof-notre-avis-sur-le-site-de-rencontres-pof-plenty-of-fish.html#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/rencontres-virtuelles\\\/pof-notre-avis-sur-le-site-de-rencontres-pof-plenty-of-fish.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/rencontres-virtuelles\\\/pof-notre-avis-sur-le-site-de-rencontres-pof-plenty-of-fish.html#primaryimage\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/avis-site-rencontres-pof.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/avis-site-rencontres-pof.jpg\",\"width\":800,\"height\":373},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/rencontres-virtuelles\\\/pof-notre-avis-sur-le-site-de-rencontres-pof-plenty-of-fish.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Les Bridgets\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conseils sur l'amour, le couple &amp; les c\u00e9libataires\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/category\\\/conseils-relations\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Rencontres en ligne\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/category\\\/conseils-relations\\\/rencontres-virtuelles\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"POF : Notre avis sur le site de rencontres Plenty of fish\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#website\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/\",\"name\":\"Les Bridgets\",\"description\":\"R\u00e9f\u00e9rences et r\u00e9flexions sur nos relations\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lesbridgets.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\",\"name\":\"Les Bridgets\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo-3-lesbridgets.png\",\"contentUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo-3-lesbridgets.png\",\"width\":251,\"height\":59,\"caption\":\"Les Bridgets\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Les.Bridgets\",\"https:\\\/\\\/x.com\\\/les_bridgets\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/person\\\/82a31c27ae0ddd23ee59e1e2ac5713ba\",\"name\":\"Bridget\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"caption\":\"Bridget\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"POF : Notre avis sur le site de rencontres Plenty of fish - Les Bridgets","description":"POF et l'application de rencontre qui a \u00e9t\u00e9 la plus recherch\u00e9e en 2014 sur Google, il \u00e9tait temps de la tester, de comprendre cette popularit\u00e9 et vous donner notre avis.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rencontres-virtuelles\/pof-notre-avis-sur-le-site-de-rencontres-pof-plenty-of-fish.html","og_locale":"fr_FR","og_type":"article","og_title":"POF : Notre avis sur le site de rencontres Plenty of fish - Les Bridgets","og_description":"POF et l'application de rencontre qui a \u00e9t\u00e9 la plus recherch\u00e9e en 2014 sur Google, il \u00e9tait temps de la tester, de comprendre cette popularit\u00e9 et vous donner notre avis.","og_url":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rencontres-virtuelles\/pof-notre-avis-sur-le-site-de-rencontres-pof-plenty-of-fish.html","og_site_name":"Les Bridgets","article_publisher":"https:\/\/www.facebook.com\/Les.Bridgets","article_published_time":"2015-01-09T10:10:18+00:00","article_modified_time":"2022-07-14T12:03:17+00:00","og_image":[{"width":800,"height":373,"url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2015\/01\/avis-site-rencontres-pof.jpg","type":"image\/jpeg"}],"author":"Bridget","twitter_card":"summary_large_image","twitter_creator":"@les_bridgets","twitter_site":"@les_bridgets","twitter_misc":{"\u00c9crit par":"Bridget","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rencontres-virtuelles\/pof-notre-avis-sur-le-site-de-rencontres-pof-plenty-of-fish.html#article","isPartOf":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rencontres-virtuelles\/pof-notre-avis-sur-le-site-de-rencontres-pof-plenty-of-fish.html"},"author":{"name":"Bridget","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/person\/82a31c27ae0ddd23ee59e1e2ac5713ba"},"headline":"POF : Notre avis sur le site de rencontres Plenty of fish","datePublished":"2015-01-09T10:10:18+00:00","dateModified":"2022-07-14T12:03:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rencontres-virtuelles\/pof-notre-avis-sur-le-site-de-rencontres-pof-plenty-of-fish.html"},"wordCount":675,"commentCount":32,"publisher":{"@id":"https:\/\/www.lesbridgets.com\/#organization"},"image":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rencontres-virtuelles\/pof-notre-avis-sur-le-site-de-rencontres-pof-plenty-of-fish.html#primaryimage"},"thumbnailUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2015\/01\/avis-site-rencontres-pof.jpg","keywords":["gratuit","site de rencontre avis","site de rencontres gratuit"],"articleSection":["Rencontres en ligne"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rencontres-virtuelles\/pof-notre-avis-sur-le-site-de-rencontres-pof-plenty-of-fish.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rencontres-virtuelles\/pof-notre-avis-sur-le-site-de-rencontres-pof-plenty-of-fish.html","url":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rencontres-virtuelles\/pof-notre-avis-sur-le-site-de-rencontres-pof-plenty-of-fish.html","name":"POF : Notre avis sur le site de rencontres Plenty of fish - Les Bridgets","isPartOf":{"@id":"https:\/\/www.lesbridgets.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rencontres-virtuelles\/pof-notre-avis-sur-le-site-de-rencontres-pof-plenty-of-fish.html#primaryimage"},"image":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rencontres-virtuelles\/pof-notre-avis-sur-le-site-de-rencontres-pof-plenty-of-fish.html#primaryimage"},"thumbnailUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2015\/01\/avis-site-rencontres-pof.jpg","datePublished":"2015-01-09T10:10:18+00:00","dateModified":"2022-07-14T12:03:17+00:00","description":"POF et l'application de rencontre qui a \u00e9t\u00e9 la plus recherch\u00e9e en 2014 sur Google, il \u00e9tait temps de la tester, de comprendre cette popularit\u00e9 et vous donner notre avis.","breadcrumb":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rencontres-virtuelles\/pof-notre-avis-sur-le-site-de-rencontres-pof-plenty-of-fish.html#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rencontres-virtuelles\/pof-notre-avis-sur-le-site-de-rencontres-pof-plenty-of-fish.html"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rencontres-virtuelles\/pof-notre-avis-sur-le-site-de-rencontres-pof-plenty-of-fish.html#primaryimage","url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2015\/01\/avis-site-rencontres-pof.jpg","contentUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2015\/01\/avis-site-rencontres-pof.jpg","width":800,"height":373},{"@type":"BreadcrumbList","@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/rencontres-virtuelles\/pof-notre-avis-sur-le-site-de-rencontres-pof-plenty-of-fish.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Les Bridgets","item":"https:\/\/www.lesbridgets.com\/"},{"@type":"ListItem","position":2,"name":"Conseils sur l'amour, le couple &amp; les c\u00e9libataires","item":"https:\/\/www.lesbridgets.com\/index.php\/category\/conseils-relations"},{"@type":"ListItem","position":3,"name":"Rencontres en ligne","item":"https:\/\/www.lesbridgets.com\/index.php\/category\/conseils-relations\/rencontres-virtuelles"},{"@type":"ListItem","position":4,"name":"POF : Notre avis sur le site de rencontres Plenty of fish"}]},{"@type":"WebSite","@id":"https:\/\/www.lesbridgets.com\/#website","url":"https:\/\/www.lesbridgets.com\/","name":"Les Bridgets","description":"R\u00e9f\u00e9rences et r\u00e9flexions sur nos relations","publisher":{"@id":"https:\/\/www.lesbridgets.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lesbridgets.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lesbridgets.com\/#organization","name":"Les Bridgets","url":"https:\/\/www.lesbridgets.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2022\/07\/cropped-logo-3-lesbridgets.png","contentUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2022\/07\/cropped-logo-3-lesbridgets.png","width":251,"height":59,"caption":"Les Bridgets"},"image":{"@id":"https:\/\/www.lesbridgets.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Les.Bridgets","https:\/\/x.com\/les_bridgets"]},{"@type":"Person","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/person\/82a31c27ae0ddd23ee59e1e2ac5713ba","name":"Bridget","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","caption":"Bridget"}}]}},"modified_by":"Bridget","_links":{"self":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/1614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/comments?post=1614"}],"version-history":[{"count":8,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/1614\/revisions"}],"predecessor-version":[{"id":255859,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/1614\/revisions\/255859"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/media\/247988"}],"wp:attachment":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/media?parent=1614"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/categories?post=1614"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/tags?post=1614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}