{"id":151,"date":"2008-12-23T02:00:00","date_gmt":"2008-12-23T01:00:00","guid":{"rendered":"http:\/\/lesbridg.cluster015.ovh.net\/wordpress\/index.php\/celibat-etre-celibataire-vivre-seule\/feter-noel-quand-on-est-celibataire-pas-forcement-une-periode-attendue.html"},"modified":"2019-12-20T11:25:28","modified_gmt":"2019-12-20T10:25:28","slug":"feter-noel-quand-on-est-celibataire-pas-forcement-une-periode-attendue","status":"publish","type":"post","link":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/feter-noel-quand-on-est-celibataire-pas-forcement-une-periode-attendue.html","title":{"rendered":"F\u00eater No\u00ebl quand on est c\u00e9libataire pas forc\u00e9ment une p\u00e9riode attendue"},"content":{"rendered":"<p>F\u00eater No\u00ebl et les f\u00eates de fin d&rsquo;ann\u00e9e quand on est c\u00e9libataire n&rsquo;est pas forc\u00e9ment une p\u00e9riode tant attendue.<br \/>\nC&rsquo;est ce que r\u00e9v\u00e8le, une \u00e9tude de 2008 qui a interrog\u00e9 des c\u00e9libataires fran\u00e7ais sur leur vision de No\u00ebl.<\/p>\n<p>Tout d&rsquo;abord ils sont de plus en plus nombreux \u00e0 anticiper cette p\u00e9riode en essayant de trouver des solutions pour ne pas d\u00e9primer seul ce jour l\u00e0.<!-- END CODE NetAffiliation --><\/p>\n<h2>Clairement quand on est c\u00e9libataire, on aime pas vraiment No\u00ebl<\/h2>\n<ul>\n<li>Seulement 13,7 % des femmes c\u00e9libataires d\u00e9clarent aimer les f\u00eates de No\u00ebl en d\u00e9pit de leur situation.<\/li>\n<\/ul>\n<p>et cette tendance se renforce chez les hommes :<\/p>\n<ul>\n<li>ils sont 17,6 % aujourd&rsquo;hui, contre 14 % l&rsquo;ann\u00e9e derni\u00e8re.<\/li>\n<\/ul>\n<p>C&rsquo;est quand m\u00eame tr\u00e8s peu, proportionnellement aux nombres restants, mais c&rsquo;est compr\u00e9hensible lorsqu&rsquo;on est c\u00e9libataire sans enfant, la f\u00eate est tout de suite moins sympathique surtout si les repas de famille ne sont pas tr\u00e8s joyeux et encore si il y en a.<\/p>\n<p style=\"text-align: center;\">Vous pouvez rencontrer d&rsquo;autres personnes seules sur les sites de rencontres<br \/>\ncomme <a href=\"https:\/\/tracking.publicidees.com\/clic.php?promoid=158765&amp;progid=5383&amp;partid=41407\" target=\"_blank\" rel=\"noopener noreferrer\">DisonsDemain<\/a><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/tracking.publicidees.com\/link.php?promoid=158765&amp;progid=5383&amp;partid=41407\" width=\"1\" height=\"1\"> pour les plus de 50 ans.<br \/>\n<a href=\"https:\/\/tracking.publicidees.com\/clic.php?partid=41407&amp;progid=5383&amp;promoid=158769\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/tracking.publicidees.com\/banner.php?partid=41407&amp;progid=5383&amp;promoid=158769\" border=\"0\"><\/a><\/p>\n<h2>Apparemment la magie op\u00e8re donc un peu plus chez les hommes.<\/h2>\n<p>Ils acceptent de plus en plus leur c\u00e9libat \u00e0 No\u00ebl.<\/p>\n<ul>\n<li>Si les hommes sont 21,3 % \u00e0 ressentir de la peine \u00e0 cette p\u00e9riode, ils \u00e9taient 30,5 % en 2006 !<\/li>\n<\/ul>\n<p>Alors que les femmes sont plus nombreuses \u00e0 redouter No\u00ebl :<\/p>\n<ul>\n<li>Elles sont pass\u00e9es de 22,5 % \u00e0 5,7 %.<\/li>\n<\/ul>\n<h3>\u00c0 \u00e9couter le message positif de Lucie qui a f\u00eat\u00e9 No\u00ebl seule plusieurs fois, notamment en voyage :<\/h3>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/hp67gmuxYh0\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p style=\"text-align: left;\">Une hausse sensible, alors que de petits rem\u00e8des anti-blues voient le jour&#8230;<\/p>\n<ul>\n<li>Les c\u00e9libataires fran\u00e7ais sont 8 % \u00e0 d\u00e9clarer mettre en place des strat\u00e9gies, contre 4.5 % des hommes et 7 % des femmes en 2006.<\/li>\n<\/ul>\n<p>Mais si No\u00ebl appara\u00eet comme une \u00e9preuve pour une majorit\u00e9 de c\u00e9libataires, c&rsquo;est le Nouvel An qu&rsquo;ils redoutent le plus !<\/p>\n<p>L&rsquo;\u00e9cart se resserre entre les hommes et les femmes \u00e0 ce sujet, puisqu&rsquo;ils \u00e9taient<\/p>\n<ul>\n<li>18 % d&rsquo;hommes et 32 % de femmes \u00e0 redouter le passage \u00e0 la nouvelle ann\u00e9e, alors qu&rsquo;\u00e0 no\u00ebl&nbsp;ils se rejoignent \u00e0 21,3 % et 27,8 %.<\/li>\n<\/ul>\n<p>Ce qui est surprenant c&rsquo;est que normalement le nouvel an se f\u00eate entre amis, c&rsquo;est l&rsquo;occasion de faire la f\u00eate donc il faut le prendre comme une grosse fiesta annuelle m\u00eame avouons le, le nouvel an est rarement \u00e0 la hauteur de ce qu&rsquo;on attendait.<\/p>\n<p>Alors peut-\u00eatre que la raison du blues des c\u00e9libataires au nouvel an, et peut-\u00eatre de voir une ann\u00e9e de plus de c\u00e9libat s&rsquo;\u00e9couler ?<\/p>\n<p>Les hommes seraient-ils r\u00e9solument plus optimistes ?<\/p>\n<ul>\n<li>11 % des hommes et 5,3 % des femmes c\u00e9libataires, d\u00e9clarent que No\u00ebl n&rsquo;est, de toute fa\u00e7on, pas tr\u00e8s important pour eux !<\/li>\n<\/ul>\n<p>En effet, beaucoup arriver \u00e0 l&rsquo;\u00e2ge d&rsquo;adulte, ne voient plus trop d&rsquo;int\u00e9r\u00eat \u00e0 f\u00eater No\u00ebl lorsque l&rsquo;on n&rsquo;a pas d&rsquo;enfant<\/p>\n<h2>Conseils pour les c\u00e9libataires<\/h2>\n<p>Un conseil : anticipez votre soir\u00e9e de No\u00ebl vous avez s\u00fbrement des copines et copains c\u00e9libataires qui eux aussi appr\u00e9hendent ce moment.<br \/>\nFaites vous une bonne bouffe entre amis et renseignez vous des bars ou pubs qui seraient susceptibles d&rsquo;\u00eatre ouverts un soir comme celui l\u00e0.<\/p>\n<p>Vu le nombre de c\u00e9libataires en France, il ne faut pas s&rsquo;inqui\u00e9ter il y en d&rsquo;autres comme vous qui n&rsquo;ont pas envie de se morfondre chez eux. Farfouiller un peu sur le web et vous trouverez de multiples soir\u00e9es organis\u00e9es le 24 au soir.<\/p>\n<p>Pour trouver d&rsquo;autres c\u00e9libataires partout en France et en Europe&nbsp; :<\/p>\n<p style=\"text-align: center;\"><a class=\"fasc-button fasc-size-medium fasc-type-flat fasc-ico-before dashicons-admin-links\" style=\"background-color: #f0056b; color: #ffffff;\" target=\"_blank\" rel=\"nofollow noopener noreferrer\" href=\"https:\/\/tracking.publicidees.com\/clic.php?promoid=55044&amp;progid=2167&amp;partid=41407\">inscrivez vous sur meetic<\/a><\/p>\n<p>Qui sait peut-\u00eatre que vous ne serez plus c\u00e9libataire pour le No\u00ebl 2020 \ud83d\ude42<\/p>\n<p>Et sinon on vous invite \u00e0 lire notre article : <a href=\"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/que-faire-a-noel-quand-on-est-tout-seul.html\" target=\"_blank\" rel=\"noopener noreferrer\">Que faire \u00e0 No\u00ebl quand on est tout.e seul.e<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>F\u00eater No\u00ebl et les f\u00eates de fin d&rsquo;ann\u00e9e quand on est c\u00e9libataire n&rsquo;est pas forc\u00e9ment une p\u00e9riode tant attendue. <br \/>C&rsquo;est ce que r\u00e9v\u00e8le, le site Parship.fr qui effectue depuis plusieurs ann\u00e9es des sondages sur la vision de No\u00ebl des c\u00e9libataires fran\u00e7ais.<\/p>\n","protected":false},"author":2,"featured_media":248040,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"om_disable_all_campaigns":false,"_lmt_disableupdate":"no","_lmt_disable":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[7],"tags":[136,90,1136,1137,135],"class_list":["post-151","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-celibataire","tag-celibataires","tag-noel","tag-noel-seule","tag-que-faire-a-noel","tag-solitude"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>F\u00eater No\u00ebl quand on est c\u00e9libataire pas forc\u00e9ment une p\u00e9riode attendue - Les Bridgets<\/title>\n<meta name=\"description\" content=\"Quelques chiffres sur la vision de No\u00ebl des hommes et femmes c\u00e9libataires.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/feter-noel-quand-on-est-celibataire-pas-forcement-une-periode-attendue.html\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"F\u00eater No\u00ebl quand on est c\u00e9libataire pas forc\u00e9ment une p\u00e9riode attendue - Les Bridgets\" \/>\n<meta property=\"og:description\" content=\"Quelques chiffres sur la vision de No\u00ebl des hommes et femmes c\u00e9libataires.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/feter-noel-quand-on-est-celibataire-pas-forcement-une-periode-attendue.html\" \/>\n<meta property=\"og:site_name\" content=\"Les Bridgets\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Les.Bridgets\" \/>\n<meta property=\"article:published_time\" content=\"2008-12-23T01:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-12-20T10:25:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2008\/12\/celibataire-noel-statistiques.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bridget\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@les_bridgets\" \/>\n<meta name=\"twitter:site\" content=\"@les_bridgets\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bridget\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/celibataire\\\/feter-noel-quand-on-est-celibataire-pas-forcement-une-periode-attendue.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/celibataire\\\/feter-noel-quand-on-est-celibataire-pas-forcement-une-periode-attendue.html\"},\"author\":{\"name\":\"Bridget\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/person\\\/82a31c27ae0ddd23ee59e1e2ac5713ba\"},\"headline\":\"F\u00eater No\u00ebl quand on est c\u00e9libataire pas forc\u00e9ment une p\u00e9riode attendue\",\"datePublished\":\"2008-12-23T01:00:00+00:00\",\"dateModified\":\"2019-12-20T10:25:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/celibataire\\\/feter-noel-quand-on-est-celibataire-pas-forcement-une-periode-attendue.html\"},\"wordCount\":679,\"commentCount\":9,\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/celibataire\\\/feter-noel-quand-on-est-celibataire-pas-forcement-une-periode-attendue.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2008\\\/12\\\/celibataire-noel-statistiques.jpg\",\"keywords\":[\"celibataires\",\"noel\",\"no\u00ebl seule\",\"que faire \u00e0 noel\",\"solitude\"],\"articleSection\":[\"Etre c\u00e9libataire - vivre seule\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/celibataire\\\/feter-noel-quand-on-est-celibataire-pas-forcement-une-periode-attendue.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/celibataire\\\/feter-noel-quand-on-est-celibataire-pas-forcement-une-periode-attendue.html\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/celibataire\\\/feter-noel-quand-on-est-celibataire-pas-forcement-une-periode-attendue.html\",\"name\":\"F\u00eater No\u00ebl quand on est c\u00e9libataire pas forc\u00e9ment une p\u00e9riode attendue - Les Bridgets\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/celibataire\\\/feter-noel-quand-on-est-celibataire-pas-forcement-une-periode-attendue.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/celibataire\\\/feter-noel-quand-on-est-celibataire-pas-forcement-une-periode-attendue.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2008\\\/12\\\/celibataire-noel-statistiques.jpg\",\"datePublished\":\"2008-12-23T01:00:00+00:00\",\"dateModified\":\"2019-12-20T10:25:28+00:00\",\"description\":\"Quelques chiffres sur la vision de No\u00ebl des hommes et femmes c\u00e9libataires.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/celibataire\\\/feter-noel-quand-on-est-celibataire-pas-forcement-une-periode-attendue.html#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/celibataire\\\/feter-noel-quand-on-est-celibataire-pas-forcement-une-periode-attendue.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/celibataire\\\/feter-noel-quand-on-est-celibataire-pas-forcement-une-periode-attendue.html#primaryimage\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2008\\\/12\\\/celibataire-noel-statistiques.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2008\\\/12\\\/celibataire-noel-statistiques.jpg\",\"width\":800,\"height\":533},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/conseils-relations\\\/celibataire\\\/feter-noel-quand-on-est-celibataire-pas-forcement-une-periode-attendue.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Les Bridgets\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conseils sur l'amour, le couple &amp; les c\u00e9libataires\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/category\\\/conseils-relations\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Etre c\u00e9libataire - vivre seule\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/category\\\/conseils-relations\\\/celibataire\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"F\u00eater No\u00ebl quand on est c\u00e9libataire pas forc\u00e9ment une p\u00e9riode attendue\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#website\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/\",\"name\":\"Les Bridgets\",\"description\":\"R\u00e9f\u00e9rences et r\u00e9flexions sur nos relations\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lesbridgets.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\",\"name\":\"Les Bridgets\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo-3-lesbridgets.png\",\"contentUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo-3-lesbridgets.png\",\"width\":251,\"height\":59,\"caption\":\"Les Bridgets\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Les.Bridgets\",\"https:\\\/\\\/x.com\\\/les_bridgets\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/person\\\/82a31c27ae0ddd23ee59e1e2ac5713ba\",\"name\":\"Bridget\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"caption\":\"Bridget\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"F\u00eater No\u00ebl quand on est c\u00e9libataire pas forc\u00e9ment une p\u00e9riode attendue - Les Bridgets","description":"Quelques chiffres sur la vision de No\u00ebl des hommes et femmes c\u00e9libataires.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/feter-noel-quand-on-est-celibataire-pas-forcement-une-periode-attendue.html","og_locale":"fr_FR","og_type":"article","og_title":"F\u00eater No\u00ebl quand on est c\u00e9libataire pas forc\u00e9ment une p\u00e9riode attendue - Les Bridgets","og_description":"Quelques chiffres sur la vision de No\u00ebl des hommes et femmes c\u00e9libataires.","og_url":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/feter-noel-quand-on-est-celibataire-pas-forcement-une-periode-attendue.html","og_site_name":"Les Bridgets","article_publisher":"https:\/\/www.facebook.com\/Les.Bridgets","article_published_time":"2008-12-23T01:00:00+00:00","article_modified_time":"2019-12-20T10:25:28+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2008\/12\/celibataire-noel-statistiques.jpg","type":"image\/jpeg"}],"author":"Bridget","twitter_card":"summary_large_image","twitter_creator":"@les_bridgets","twitter_site":"@les_bridgets","twitter_misc":{"\u00c9crit par":"Bridget","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/feter-noel-quand-on-est-celibataire-pas-forcement-une-periode-attendue.html#article","isPartOf":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/feter-noel-quand-on-est-celibataire-pas-forcement-une-periode-attendue.html"},"author":{"name":"Bridget","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/person\/82a31c27ae0ddd23ee59e1e2ac5713ba"},"headline":"F\u00eater No\u00ebl quand on est c\u00e9libataire pas forc\u00e9ment une p\u00e9riode attendue","datePublished":"2008-12-23T01:00:00+00:00","dateModified":"2019-12-20T10:25:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/feter-noel-quand-on-est-celibataire-pas-forcement-une-periode-attendue.html"},"wordCount":679,"commentCount":9,"publisher":{"@id":"https:\/\/www.lesbridgets.com\/#organization"},"image":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/feter-noel-quand-on-est-celibataire-pas-forcement-une-periode-attendue.html#primaryimage"},"thumbnailUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2008\/12\/celibataire-noel-statistiques.jpg","keywords":["celibataires","noel","no\u00ebl seule","que faire \u00e0 noel","solitude"],"articleSection":["Etre c\u00e9libataire - vivre seule"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/feter-noel-quand-on-est-celibataire-pas-forcement-une-periode-attendue.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/feter-noel-quand-on-est-celibataire-pas-forcement-une-periode-attendue.html","url":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/feter-noel-quand-on-est-celibataire-pas-forcement-une-periode-attendue.html","name":"F\u00eater No\u00ebl quand on est c\u00e9libataire pas forc\u00e9ment une p\u00e9riode attendue - Les Bridgets","isPartOf":{"@id":"https:\/\/www.lesbridgets.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/feter-noel-quand-on-est-celibataire-pas-forcement-une-periode-attendue.html#primaryimage"},"image":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/feter-noel-quand-on-est-celibataire-pas-forcement-une-periode-attendue.html#primaryimage"},"thumbnailUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2008\/12\/celibataire-noel-statistiques.jpg","datePublished":"2008-12-23T01:00:00+00:00","dateModified":"2019-12-20T10:25:28+00:00","description":"Quelques chiffres sur la vision de No\u00ebl des hommes et femmes c\u00e9libataires.","breadcrumb":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/feter-noel-quand-on-est-celibataire-pas-forcement-une-periode-attendue.html#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/feter-noel-quand-on-est-celibataire-pas-forcement-une-periode-attendue.html"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/feter-noel-quand-on-est-celibataire-pas-forcement-une-periode-attendue.html#primaryimage","url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2008\/12\/celibataire-noel-statistiques.jpg","contentUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2008\/12\/celibataire-noel-statistiques.jpg","width":800,"height":533},{"@type":"BreadcrumbList","@id":"https:\/\/www.lesbridgets.com\/index.php\/conseils-relations\/celibataire\/feter-noel-quand-on-est-celibataire-pas-forcement-une-periode-attendue.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Les Bridgets","item":"https:\/\/www.lesbridgets.com\/"},{"@type":"ListItem","position":2,"name":"Conseils sur l'amour, le couple &amp; les c\u00e9libataires","item":"https:\/\/www.lesbridgets.com\/index.php\/category\/conseils-relations"},{"@type":"ListItem","position":3,"name":"Etre c\u00e9libataire - vivre seule","item":"https:\/\/www.lesbridgets.com\/index.php\/category\/conseils-relations\/celibataire"},{"@type":"ListItem","position":4,"name":"F\u00eater No\u00ebl quand on est c\u00e9libataire pas forc\u00e9ment une p\u00e9riode attendue"}]},{"@type":"WebSite","@id":"https:\/\/www.lesbridgets.com\/#website","url":"https:\/\/www.lesbridgets.com\/","name":"Les Bridgets","description":"R\u00e9f\u00e9rences et r\u00e9flexions sur nos relations","publisher":{"@id":"https:\/\/www.lesbridgets.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lesbridgets.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lesbridgets.com\/#organization","name":"Les Bridgets","url":"https:\/\/www.lesbridgets.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2022\/07\/cropped-logo-3-lesbridgets.png","contentUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2022\/07\/cropped-logo-3-lesbridgets.png","width":251,"height":59,"caption":"Les Bridgets"},"image":{"@id":"https:\/\/www.lesbridgets.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Les.Bridgets","https:\/\/x.com\/les_bridgets"]},{"@type":"Person","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/person\/82a31c27ae0ddd23ee59e1e2ac5713ba","name":"Bridget","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","caption":"Bridget"}}]}},"modified_by":"Bridget","_links":{"self":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/comments?post=151"}],"version-history":[{"count":13,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/151\/revisions"}],"predecessor-version":[{"id":250250,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/151\/revisions\/250250"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/media\/248040"}],"wp:attachment":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/media?parent=151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/categories?post=151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/tags?post=151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}