{"id":1430,"date":"2014-02-25T14:15:28","date_gmt":"2014-02-25T13:15:28","guid":{"rendered":"http:\/\/lesbridg.cluster015.ovh.net\/wordpress\/index.php\/a-voir-sur-le-web\/vos-3-kifs-par-jour.html"},"modified":"2014-02-25T14:15:28","modified_gmt":"2014-02-25T13:15:28","slug":"vos-3-kifs-par-jour","status":"publish","type":"post","link":"https:\/\/www.lesbridgets.com\/index.php\/sur-le-web\/a-voir-sur-le-web\/vos-3-kifs-par-jour.html","title":{"rendered":"Rep\u00e9rez ses 3 kifs par jour pour vivre plus heureux et plus longtemps"},"content":{"rendered":"<p>Cela fait d\u00e9j\u00e0 quelques temps que j&rsquo;ai d\u00e9couvert cette vid\u00e9o de\u00a0Florence Servan-Schreiber,\u00a0journaliste et dipl\u00f4m\u00e9e de la JFK University qui a particip\u00e9 \u00e0 un TedX en 2012 pour parler pendant un peu plus de 12 minutes du pouvoir de la Gratitude.<\/p>\n<p>Depuis que je l&rsquo;ai vue, ses paroles trottent quotidiennement dans ma t\u00eate et surtout son histoire des 3 kifs auxquels je pense souvent avant de m&rsquo;endormir.<\/p>\n<p><span style=\"line-height: 1.3em;\">Elle parle de ces petites choses dont on devrait plus souvent s&rsquo;\u00e9merveiller. Et du pouvoir de long\u00e9vit\u00e9 des gens heureux qui vivraient 7 ans de plus en moyenne que les autres.<\/span><\/p>\n<p>Mais aussi que lorsque nous pensons \u00e0 des moments de gratitude, il\u00a0<span style=\"line-height: 1.3em;\">nous est impossible de sentir du ressentiment ou encore de la col\u00e8re.<br \/><\/span><\/p>\n<h2><span style=\"line-height: 1.3em;\"><br \/>Un aper\u00e7u des nombreuses choses dont elle parle qui ne sont pas forc\u00e9ment \u00e9videntes pour tous et qui peuvent changer votre vie.<\/span><\/h2>\n<p>Le son de la vid\u00e9o n&rsquo;est pas tr\u00e8s fort donc \u00e0 \u00e9couter au calme ou avec un casque<\/p>\n<p><iframe loading=\"lazy\" style=\"display: block; margin-left: auto; margin-right: auto;\" src=\"http:\/\/www.youtube.com\/embed\/nZUfJpVxUNI\" frameborder=\"0\" width=\"530\" height=\"298\"><\/iframe><\/p>\n<p><iframe loading=\"lazy\" style=\"width: 120px; height: 240px; float: right;\" src=\"http:\/\/ws-eu.amazon-adsystem.com\/widgets\/q?ServiceVersion=20070822&amp;OneJS=1&amp;Operation=GetAdHtml&amp;MarketPlace=FR&amp;source=ac&amp;ref=qf_sp_asin_til&amp;ad_type=product_link&amp;tracking_id=lesbricomcomp-21&amp;marketplace=amazon&amp;region=FR&amp;placement=250109607X&amp;asins=250109607X&amp;linkId=NFXCS7ARYIIMSSAQ&amp;show_border=true&amp;link_opens_in_new_window=true&amp;price_color=333333&amp;title_color=C00076&amp;bg_color=FFFFFF\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" width=\"320\" height=\"240\"><\/iframe><\/p>\n<p>Alors dites-vous assez aux gens que vous les aimez ? Profitez-vous assez de ces petites choses de notre quotidien ?<br \/>Tout comme moi, vous avez envie de faire votre carnet des 3 kifs ?<\/p>\n<p>Et si la vid\u00e9o ne vous a pas suffit, elle a fait un livre 3 kifs par jour et autres rituels recommand\u00e9s par la sciences pour cultiver le bonheur.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cela fait d\u00e9j\u00e0 quelques temps que j&rsquo;ai d\u00e9couvert cette vid\u00e9o de\u00a0Florence Servan-Schreiber,\u00a0journaliste et dipl\u00f4m\u00e9e de la JFK University qui a particip\u00e9 \u00e0 un TedX en 2012 pour parler pendant un peu plus de 12 minutes du pouvoir de la Gratitude.<\/p>\n<p>Depuis que je l&rsquo;ai vue, ses paroles trottent quotidiennement dans ma t\u00eate et surtout son histoire des 3 kifs auxquels je pense souvent avant de m&rsquo;endormir.<\/p>\n","protected":false},"author":2,"featured_media":1429,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"om_disable_all_campaigns":false,"_lmt_disableupdate":"","_lmt_disable":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[17],"tags":[263,265,478],"class_list":["post-1430","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-voir-sur-le-web","tag-bien-etre","tag-bonheur","tag-tedx"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rep\u00e9rez ses 3 kifs par jour pour vivre plus heureux et plus longtemps - Les Bridgets<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lesbridgets.com\/index.php\/sur-le-web\/a-voir-sur-le-web\/vos-3-kifs-par-jour.html\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rep\u00e9rez ses 3 kifs par jour pour vivre plus heureux et plus longtemps - Les Bridgets\" \/>\n<meta property=\"og:description\" content=\"Cela fait d\u00e9j\u00e0 quelques temps que j&#039;ai d\u00e9couvert cette vid\u00e9o de\u00a0Florence Servan-Schreiber,\u00a0journaliste et dipl\u00f4m\u00e9e de la JFK University qui a particip\u00e9 \u00e0 un TedX en 2012 pour parler pendant un peu plus de 12 minutes du pouvoir de la Gratitude. Depuis que je l&#039;ai vue, ses paroles trottent quotidiennement dans ma t\u00eate et surtout son histoire des 3 kifs auxquels je pense souvent avant de m&#039;endormir.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lesbridgets.com\/index.php\/sur-le-web\/a-voir-sur-le-web\/vos-3-kifs-par-jour.html\" \/>\n<meta property=\"og:site_name\" content=\"Les Bridgets\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Les.Bridgets\" \/>\n<meta property=\"article:published_time\" content=\"2014-02-25T13:15:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2014\/02\/gratitude-bonheur-kif.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"260\" \/>\n\t<meta property=\"og:image:height\" content=\"188\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bridget\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@les_bridgets\" \/>\n<meta name=\"twitter:site\" content=\"@les_bridgets\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bridget\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/sur-le-web\\\/a-voir-sur-le-web\\\/vos-3-kifs-par-jour.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/sur-le-web\\\/a-voir-sur-le-web\\\/vos-3-kifs-par-jour.html\"},\"author\":{\"name\":\"Bridget\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/person\\\/82a31c27ae0ddd23ee59e1e2ac5713ba\"},\"headline\":\"Rep\u00e9rez ses 3 kifs par jour pour vivre plus heureux et plus longtemps\",\"datePublished\":\"2014-02-25T13:15:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/sur-le-web\\\/a-voir-sur-le-web\\\/vos-3-kifs-par-jour.html\"},\"wordCount\":246,\"commentCount\":3,\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/sur-le-web\\\/a-voir-sur-le-web\\\/vos-3-kifs-par-jour.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/gratitude-bonheur-kif.jpg\",\"keywords\":[\"bien \u00eatre\",\"bonheur\",\"tedx\"],\"articleSection\":[\"A voir sur le web\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/sur-le-web\\\/a-voir-sur-le-web\\\/vos-3-kifs-par-jour.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/sur-le-web\\\/a-voir-sur-le-web\\\/vos-3-kifs-par-jour.html\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/sur-le-web\\\/a-voir-sur-le-web\\\/vos-3-kifs-par-jour.html\",\"name\":\"Rep\u00e9rez ses 3 kifs par jour pour vivre plus heureux et plus longtemps - Les Bridgets\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/sur-le-web\\\/a-voir-sur-le-web\\\/vos-3-kifs-par-jour.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/sur-le-web\\\/a-voir-sur-le-web\\\/vos-3-kifs-par-jour.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/gratitude-bonheur-kif.jpg\",\"datePublished\":\"2014-02-25T13:15:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/sur-le-web\\\/a-voir-sur-le-web\\\/vos-3-kifs-par-jour.html#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/sur-le-web\\\/a-voir-sur-le-web\\\/vos-3-kifs-par-jour.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/sur-le-web\\\/a-voir-sur-le-web\\\/vos-3-kifs-par-jour.html#primaryimage\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/gratitude-bonheur-kif.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/gratitude-bonheur-kif.jpg\",\"width\":260,\"height\":188,\"caption\":\"gratitude bonheur kif conseils\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/sur-le-web\\\/a-voir-sur-le-web\\\/vos-3-kifs-par-jour.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Les Bridgets\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sur le Web\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/category\\\/sur-le-web\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"A voir sur le web\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/category\\\/sur-le-web\\\/a-voir-sur-le-web\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Rep\u00e9rez ses 3 kifs par jour pour vivre plus heureux et plus longtemps\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#website\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/\",\"name\":\"Les Bridgets\",\"description\":\"R\u00e9f\u00e9rences et r\u00e9flexions sur nos relations\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lesbridgets.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\",\"name\":\"Les Bridgets\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo-3-lesbridgets.png\",\"contentUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo-3-lesbridgets.png\",\"width\":251,\"height\":59,\"caption\":\"Les Bridgets\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Les.Bridgets\",\"https:\\\/\\\/x.com\\\/les_bridgets\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/person\\\/82a31c27ae0ddd23ee59e1e2ac5713ba\",\"name\":\"Bridget\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"caption\":\"Bridget\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rep\u00e9rez ses 3 kifs par jour pour vivre plus heureux et plus longtemps - Les Bridgets","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lesbridgets.com\/index.php\/sur-le-web\/a-voir-sur-le-web\/vos-3-kifs-par-jour.html","og_locale":"fr_FR","og_type":"article","og_title":"Rep\u00e9rez ses 3 kifs par jour pour vivre plus heureux et plus longtemps - Les Bridgets","og_description":"Cela fait d\u00e9j\u00e0 quelques temps que j'ai d\u00e9couvert cette vid\u00e9o de\u00a0Florence Servan-Schreiber,\u00a0journaliste et dipl\u00f4m\u00e9e de la JFK University qui a particip\u00e9 \u00e0 un TedX en 2012 pour parler pendant un peu plus de 12 minutes du pouvoir de la Gratitude. Depuis que je l'ai vue, ses paroles trottent quotidiennement dans ma t\u00eate et surtout son histoire des 3 kifs auxquels je pense souvent avant de m'endormir.","og_url":"https:\/\/www.lesbridgets.com\/index.php\/sur-le-web\/a-voir-sur-le-web\/vos-3-kifs-par-jour.html","og_site_name":"Les Bridgets","article_publisher":"https:\/\/www.facebook.com\/Les.Bridgets","article_published_time":"2014-02-25T13:15:28+00:00","og_image":[{"width":260,"height":188,"url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2014\/02\/gratitude-bonheur-kif.jpg","type":"image\/jpeg"}],"author":"Bridget","twitter_card":"summary_large_image","twitter_creator":"@les_bridgets","twitter_site":"@les_bridgets","twitter_misc":{"\u00c9crit par":"Bridget","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lesbridgets.com\/index.php\/sur-le-web\/a-voir-sur-le-web\/vos-3-kifs-par-jour.html#article","isPartOf":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/sur-le-web\/a-voir-sur-le-web\/vos-3-kifs-par-jour.html"},"author":{"name":"Bridget","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/person\/82a31c27ae0ddd23ee59e1e2ac5713ba"},"headline":"Rep\u00e9rez ses 3 kifs par jour pour vivre plus heureux et plus longtemps","datePublished":"2014-02-25T13:15:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/sur-le-web\/a-voir-sur-le-web\/vos-3-kifs-par-jour.html"},"wordCount":246,"commentCount":3,"publisher":{"@id":"https:\/\/www.lesbridgets.com\/#organization"},"image":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/sur-le-web\/a-voir-sur-le-web\/vos-3-kifs-par-jour.html#primaryimage"},"thumbnailUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2014\/02\/gratitude-bonheur-kif.jpg","keywords":["bien \u00eatre","bonheur","tedx"],"articleSection":["A voir sur le web"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.lesbridgets.com\/index.php\/sur-le-web\/a-voir-sur-le-web\/vos-3-kifs-par-jour.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.lesbridgets.com\/index.php\/sur-le-web\/a-voir-sur-le-web\/vos-3-kifs-par-jour.html","url":"https:\/\/www.lesbridgets.com\/index.php\/sur-le-web\/a-voir-sur-le-web\/vos-3-kifs-par-jour.html","name":"Rep\u00e9rez ses 3 kifs par jour pour vivre plus heureux et plus longtemps - Les Bridgets","isPartOf":{"@id":"https:\/\/www.lesbridgets.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/sur-le-web\/a-voir-sur-le-web\/vos-3-kifs-par-jour.html#primaryimage"},"image":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/sur-le-web\/a-voir-sur-le-web\/vos-3-kifs-par-jour.html#primaryimage"},"thumbnailUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2014\/02\/gratitude-bonheur-kif.jpg","datePublished":"2014-02-25T13:15:28+00:00","breadcrumb":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/sur-le-web\/a-voir-sur-le-web\/vos-3-kifs-par-jour.html#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lesbridgets.com\/index.php\/sur-le-web\/a-voir-sur-le-web\/vos-3-kifs-par-jour.html"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesbridgets.com\/index.php\/sur-le-web\/a-voir-sur-le-web\/vos-3-kifs-par-jour.html#primaryimage","url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2014\/02\/gratitude-bonheur-kif.jpg","contentUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2014\/02\/gratitude-bonheur-kif.jpg","width":260,"height":188,"caption":"gratitude bonheur kif conseils"},{"@type":"BreadcrumbList","@id":"https:\/\/www.lesbridgets.com\/index.php\/sur-le-web\/a-voir-sur-le-web\/vos-3-kifs-par-jour.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Les Bridgets","item":"https:\/\/www.lesbridgets.com\/"},{"@type":"ListItem","position":2,"name":"Sur le Web","item":"https:\/\/www.lesbridgets.com\/index.php\/category\/sur-le-web"},{"@type":"ListItem","position":3,"name":"A voir sur le web","item":"https:\/\/www.lesbridgets.com\/index.php\/category\/sur-le-web\/a-voir-sur-le-web"},{"@type":"ListItem","position":4,"name":"Rep\u00e9rez ses 3 kifs par jour pour vivre plus heureux et plus longtemps"}]},{"@type":"WebSite","@id":"https:\/\/www.lesbridgets.com\/#website","url":"https:\/\/www.lesbridgets.com\/","name":"Les Bridgets","description":"R\u00e9f\u00e9rences et r\u00e9flexions sur nos relations","publisher":{"@id":"https:\/\/www.lesbridgets.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lesbridgets.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lesbridgets.com\/#organization","name":"Les Bridgets","url":"https:\/\/www.lesbridgets.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2022\/07\/cropped-logo-3-lesbridgets.png","contentUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2022\/07\/cropped-logo-3-lesbridgets.png","width":251,"height":59,"caption":"Les Bridgets"},"image":{"@id":"https:\/\/www.lesbridgets.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Les.Bridgets","https:\/\/x.com\/les_bridgets"]},{"@type":"Person","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/person\/82a31c27ae0ddd23ee59e1e2ac5713ba","name":"Bridget","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","caption":"Bridget"}}]}},"modified_by":null,"_links":{"self":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/1430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/comments?post=1430"}],"version-history":[{"count":0,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/1430\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/media\/1429"}],"wp:attachment":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/media?parent=1430"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/categories?post=1430"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/tags?post=1430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}