{"id":1154,"date":"2012-11-22T07:28:43","date_gmt":"2012-11-22T06:28:43","guid":{"rendered":"http:\/\/lesbridg.cluster015.ovh.net\/wordpress\/index.php\/films-romantiques-sur-le-couple-et-le-celibat\/populaire-un-soupcon-de-romantisme-dans-les-annees-50.html"},"modified":"2025-05-17T19:45:31","modified_gmt":"2025-05-17T17:45:31","slug":"populaire-un-soupcon-de-romantisme-dans-les-annees-50","status":"publish","type":"post","link":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/populaire-un-soupcon-de-romantisme-dans-les-annees-50.html","title":{"rendered":"Populaire, un soup\u00e7on de romantisme dans les ann\u00e9es 50"},"content":{"rendered":"<p>Ceux qui nous suivent sur Facebook, Twitter, et Instagram ont pu apercevoir quelques photos de mon d\u00e9jeuner avec l&rsquo;\u00e9quipe du film \u00ab\u00a0Populaire\u00a0\u00bb dont le c\u00e9l\u00e8bre <a href=\"http:\/\/instagram.com\/p\/SDWB8jOQ9T\/\" target=\"_blank\" rel=\"noopener noreferrer\">Romain Duris<\/a> que nous avons ador\u00e9 dans <a href=\"https:\/\/www.lesbridgets.com\/index.php\/films-romantiques-sur-le-couple-et-le-celibat\/comment-faire-pour-quelle-le-quitte-la-solution-faites-appel-a-larnacoeur.html\" target=\"_blank\" rel=\"noopener noreferrer\">L&rsquo;arnacoeur<\/a> au c\u00f4t\u00e9 de Vanessa Paradis et la s\u00e9duisante <a href=\"http:\/\/instagram.com\/p\/SDRlL1OQ6w\/\" target=\"_blank\" rel=\"noopener noreferrer\">D\u00e9borah Fran\u00e7ois<\/a> que vous avez pu voir dans le tr\u00e8s bon film Le premier jour du reste de ta vie.<\/p>\n<p>Populaire est un pari un peu fou pour Regis Roinsard qui r\u00e9alise ici son premier film.<\/p>\n<h2>Un film qui est bas\u00e9 principalement sur les comp\u00e9titions de dactylos entre secr\u00e9taires dans les ann\u00e9es 50.<\/h2>\n<p>Il a eu l&rsquo;id\u00e9e en 2004 lorsqu&rsquo;il est tomb\u00e9 sur un reportage \u00e0 la t\u00e9l\u00e9vision. Dis comme \u00e7a c&rsquo;est un peu fou, mais le producteur Alain Attal a tout de suite ador\u00e9 le sc\u00e9nario.<\/p>\n<p>Apr\u00e8s 3 ans de recherches : \u00e0 regarder de documentaires d&rsquo;\u00e9poque, rencontres pour obtenir des t\u00e9moignages et fouill\u00e9 de moults brocantes. Le r\u00e9alisateur a par exemple d\u00e9nich\u00e9 le tr\u00e8s rare et original morceau Le Tchatcha des secr\u00e9taires par Jack Ary qui trouve parfaitement sa place dans la BO.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-249090 size-full aligncenter\" src=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2012\/11\/deborah-francois-populaire-annees-50.png\" alt=\"\" width=\"800\" height=\"445\" srcset=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2012\/11\/deborah-francois-populaire-annees-50.png 800w, https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2012\/11\/deborah-francois-populaire-annees-50-300x167.png 300w, https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2012\/11\/deborah-francois-populaire-annees-50-768x427.png 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Pour les fans des ann\u00e9es 50\/60, il faut voir ce film. Les robes, les d\u00e9cors, le quotidien tout y est. L&rsquo;actrice principale Deborah Fran\u00e7ois est particuli\u00e8rement sublime.<\/p>\n<p>Et pour couronner le tout, c&rsquo;est une com\u00e9die romantique mais pas trop.<\/p>\n<h2>La bande annonce du film Populaire<\/h2>\n<p><center><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/xaVOWYk7LD4\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/center>Pas le film de l&rsquo;ann\u00e9e, mais les ingr\u00e9dients n\u00e9c\u00e9ssaire pour qu&rsquo;il soit agr\u00e9able \u00e0 regarder et qu&rsquo;on se projette le temps de 2 heures dans les ann\u00e9es o\u00f9 les femmes commen\u00e7aient \u00e0 s&rsquo;\u00e9manciper.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-249092 size-full aligncenter\" src=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2012\/11\/romain-duris-annees-50-acteur.png\" alt=\"\" width=\"800\" height=\"431\" srcset=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2012\/11\/romain-duris-annees-50-acteur.png 800w, https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2012\/11\/romain-duris-annees-50-acteur-300x162.png 300w, https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2012\/11\/romain-duris-annees-50-acteur-768x414.png 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ceux qui nous suivent sur <a href=\"https:\/\/www.facebook.com\/melanie.mage\" target=\"_blank\" mce_href=\"https:\/\/www.facebook.com\/melanie.mage\" rel=\"noopener noreferrer\">Facebook<\/a>, Twitter, et Instagram ont pu  apercevoir quelques photos de mon d\u00e9jeuner avec l&rsquo;\u00e9quipe du film  \u00ab\u00a0Populaire\u00a0\u00bb dont le c\u00e9l\u00e8bre <a href=\"http:\/\/instagram.com\/p\/SDWB8jOQ9T\/\" target=\"_blank\" mce_href=\"http:\/\/instagram.com\/p\/SDWB8jOQ9T\/\" rel=\"noopener noreferrer\">Romain Duris<\/a>  que nous avons ador\u00e9 dans  <a href=\"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/comment-faire-pour-quelle-le-quitte-la-solution-faites-appel-a-larnacoeur.html\" target=\"_blank\" mce_href=\"index.php\/Films-romantiques-sur-le-couple-et-le-celibat\/Comment-faire-pour-qu-elle-le-quitte-La-solution-faites-appel-a-l-Arnacoeur.html\" rel=\"noopener noreferrer\">L&rsquo;arnacoeur<\/a>  au c\u00f4t\u00e9 de Vanessa Paradis et la s\u00e9duisante <a href=\"http:\/\/instagram.com\/p\/SDRlL1OQ6w\/\" target=\"_blank\" mce_href=\"http:\/\/instagram.com\/p\/SDRlL1OQ6w\/\" rel=\"noopener noreferrer\">D\u00e9borah Fran\u00e7ois<\/a>   que vous avez pu voir dans le tr\u00e8s bon film Le premier jour du reste de ta vie.  <\/p>\n","protected":false},"author":2,"featured_media":249089,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"om_disable_all_campaigns":false,"_lmt_disableupdate":"no","_lmt_disable":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[28],"tags":[1260,285,316],"class_list":["post-1154","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-films","tag-annees-50","tag-histoire-vraie-film","tag-romain-duris"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Populaire, un soup\u00e7on de romantisme dans les ann\u00e9es 50 - Les Bridgets<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/populaire-un-soupcon-de-romantisme-dans-les-annees-50.html\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Populaire, un soup\u00e7on de romantisme dans les ann\u00e9es 50 - Les Bridgets\" \/>\n<meta property=\"og:description\" content=\"Ceux qui nous suivent sur Facebook, Twitter, et Instagram ont pu apercevoir quelques photos de mon d\u00e9jeuner avec l&#039;\u00e9quipe du film &quot;Populaire&quot; dont le c\u00e9l\u00e8bre Romain Duris que nous avons ador\u00e9 dans L&#039;arnacoeur au c\u00f4t\u00e9 de Vanessa Paradis et la s\u00e9duisante D\u00e9borah Fran\u00e7ois  que vous avez pu voir dans le tr\u00e8s bon film Le premier jour du reste de ta vie.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/populaire-un-soupcon-de-romantisme-dans-les-annees-50.html\" \/>\n<meta property=\"og:site_name\" content=\"Les Bridgets\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Les.Bridgets\" \/>\n<meta property=\"article:published_time\" content=\"2012-11-22T06:28:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-17T17:45:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2012\/11\/film-populaire-romain-duris.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Bridget\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@les_bridgets\" \/>\n<meta name=\"twitter:site\" content=\"@les_bridgets\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bridget\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/populaire-un-soupcon-de-romantisme-dans-les-annees-50.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/populaire-un-soupcon-de-romantisme-dans-les-annees-50.html\"},\"author\":{\"name\":\"Bridget\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/person\\\/82a31c27ae0ddd23ee59e1e2ac5713ba\"},\"headline\":\"Populaire, un soup\u00e7on de romantisme dans les ann\u00e9es 50\",\"datePublished\":\"2012-11-22T06:28:43+00:00\",\"dateModified\":\"2025-05-17T17:45:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/populaire-un-soupcon-de-romantisme-dans-les-annees-50.html\"},\"wordCount\":301,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/populaire-un-soupcon-de-romantisme-dans-les-annees-50.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2012\\\/11\\\/film-populaire-romain-duris.png\",\"keywords\":[\"ann\u00e9es 50\",\"histoire vraie film\",\"romain duris\"],\"articleSection\":[\"Film\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/populaire-un-soupcon-de-romantisme-dans-les-annees-50.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/populaire-un-soupcon-de-romantisme-dans-les-annees-50.html\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/populaire-un-soupcon-de-romantisme-dans-les-annees-50.html\",\"name\":\"Populaire, un soup\u00e7on de romantisme dans les ann\u00e9es 50 - Les Bridgets\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/populaire-un-soupcon-de-romantisme-dans-les-annees-50.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/populaire-un-soupcon-de-romantisme-dans-les-annees-50.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2012\\\/11\\\/film-populaire-romain-duris.png\",\"datePublished\":\"2012-11-22T06:28:43+00:00\",\"dateModified\":\"2025-05-17T17:45:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/populaire-un-soupcon-de-romantisme-dans-les-annees-50.html#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/populaire-un-soupcon-de-romantisme-dans-les-annees-50.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/populaire-un-soupcon-de-romantisme-dans-les-annees-50.html#primaryimage\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2012\\\/11\\\/film-populaire-romain-duris.png\",\"contentUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2012\\\/11\\\/film-populaire-romain-duris.png\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/references\\\/films\\\/populaire-un-soupcon-de-romantisme-dans-les-annees-50.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Les Bridgets\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00e9f\u00e9rences sur le couple et le c\u00e9libat\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/category\\\/references\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Film\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/category\\\/references\\\/films\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Populaire, un soup\u00e7on de romantisme dans les ann\u00e9es 50\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#website\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/\",\"name\":\"Les Bridgets\",\"description\":\"R\u00e9f\u00e9rences et r\u00e9flexions sur nos relations\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lesbridgets.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\",\"name\":\"Les Bridgets\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo-3-lesbridgets.png\",\"contentUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo-3-lesbridgets.png\",\"width\":251,\"height\":59,\"caption\":\"Les Bridgets\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Les.Bridgets\",\"https:\\\/\\\/x.com\\\/les_bridgets\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/person\\\/82a31c27ae0ddd23ee59e1e2ac5713ba\",\"name\":\"Bridget\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"caption\":\"Bridget\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Populaire, un soup\u00e7on de romantisme dans les ann\u00e9es 50 - Les Bridgets","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/populaire-un-soupcon-de-romantisme-dans-les-annees-50.html","og_locale":"fr_FR","og_type":"article","og_title":"Populaire, un soup\u00e7on de romantisme dans les ann\u00e9es 50 - Les Bridgets","og_description":"Ceux qui nous suivent sur Facebook, Twitter, et Instagram ont pu apercevoir quelques photos de mon d\u00e9jeuner avec l'\u00e9quipe du film \"Populaire\" dont le c\u00e9l\u00e8bre Romain Duris que nous avons ador\u00e9 dans L'arnacoeur au c\u00f4t\u00e9 de Vanessa Paradis et la s\u00e9duisante D\u00e9borah Fran\u00e7ois  que vous avez pu voir dans le tr\u00e8s bon film Le premier jour du reste de ta vie.","og_url":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/populaire-un-soupcon-de-romantisme-dans-les-annees-50.html","og_site_name":"Les Bridgets","article_publisher":"https:\/\/www.facebook.com\/Les.Bridgets","article_published_time":"2012-11-22T06:28:43+00:00","article_modified_time":"2025-05-17T17:45:31+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2012\/11\/film-populaire-romain-duris.png","type":"image\/png"}],"author":"Bridget","twitter_card":"summary_large_image","twitter_creator":"@les_bridgets","twitter_site":"@les_bridgets","twitter_misc":{"\u00c9crit par":"Bridget","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/populaire-un-soupcon-de-romantisme-dans-les-annees-50.html#article","isPartOf":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/populaire-un-soupcon-de-romantisme-dans-les-annees-50.html"},"author":{"name":"Bridget","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/person\/82a31c27ae0ddd23ee59e1e2ac5713ba"},"headline":"Populaire, un soup\u00e7on de romantisme dans les ann\u00e9es 50","datePublished":"2012-11-22T06:28:43+00:00","dateModified":"2025-05-17T17:45:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/populaire-un-soupcon-de-romantisme-dans-les-annees-50.html"},"wordCount":301,"commentCount":1,"publisher":{"@id":"https:\/\/www.lesbridgets.com\/#organization"},"image":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/populaire-un-soupcon-de-romantisme-dans-les-annees-50.html#primaryimage"},"thumbnailUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2012\/11\/film-populaire-romain-duris.png","keywords":["ann\u00e9es 50","histoire vraie film","romain duris"],"articleSection":["Film"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.lesbridgets.com\/index.php\/references\/films\/populaire-un-soupcon-de-romantisme-dans-les-annees-50.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/populaire-un-soupcon-de-romantisme-dans-les-annees-50.html","url":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/populaire-un-soupcon-de-romantisme-dans-les-annees-50.html","name":"Populaire, un soup\u00e7on de romantisme dans les ann\u00e9es 50 - Les Bridgets","isPartOf":{"@id":"https:\/\/www.lesbridgets.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/populaire-un-soupcon-de-romantisme-dans-les-annees-50.html#primaryimage"},"image":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/populaire-un-soupcon-de-romantisme-dans-les-annees-50.html#primaryimage"},"thumbnailUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2012\/11\/film-populaire-romain-duris.png","datePublished":"2012-11-22T06:28:43+00:00","dateModified":"2025-05-17T17:45:31+00:00","breadcrumb":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/populaire-un-soupcon-de-romantisme-dans-les-annees-50.html#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lesbridgets.com\/index.php\/references\/films\/populaire-un-soupcon-de-romantisme-dans-les-annees-50.html"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/populaire-un-soupcon-de-romantisme-dans-les-annees-50.html#primaryimage","url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2012\/11\/film-populaire-romain-duris.png","contentUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2012\/11\/film-populaire-romain-duris.png","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/www.lesbridgets.com\/index.php\/references\/films\/populaire-un-soupcon-de-romantisme-dans-les-annees-50.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Les Bridgets","item":"https:\/\/www.lesbridgets.com\/"},{"@type":"ListItem","position":2,"name":"R\u00e9f\u00e9rences sur le couple et le c\u00e9libat","item":"https:\/\/www.lesbridgets.com\/index.php\/category\/references"},{"@type":"ListItem","position":3,"name":"Film","item":"https:\/\/www.lesbridgets.com\/index.php\/category\/references\/films"},{"@type":"ListItem","position":4,"name":"Populaire, un soup\u00e7on de romantisme dans les ann\u00e9es 50"}]},{"@type":"WebSite","@id":"https:\/\/www.lesbridgets.com\/#website","url":"https:\/\/www.lesbridgets.com\/","name":"Les Bridgets","description":"R\u00e9f\u00e9rences et r\u00e9flexions sur nos relations","publisher":{"@id":"https:\/\/www.lesbridgets.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lesbridgets.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lesbridgets.com\/#organization","name":"Les Bridgets","url":"https:\/\/www.lesbridgets.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2022\/07\/cropped-logo-3-lesbridgets.png","contentUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2022\/07\/cropped-logo-3-lesbridgets.png","width":251,"height":59,"caption":"Les Bridgets"},"image":{"@id":"https:\/\/www.lesbridgets.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Les.Bridgets","https:\/\/x.com\/les_bridgets"]},{"@type":"Person","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/person\/82a31c27ae0ddd23ee59e1e2ac5713ba","name":"Bridget","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","caption":"Bridget"}}]}},"modified_by":"Bridget","_links":{"self":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/1154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/comments?post=1154"}],"version-history":[{"count":10,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/1154\/revisions"}],"predecessor-version":[{"id":258171,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/1154\/revisions\/258171"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/media\/249089"}],"wp:attachment":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/media?parent=1154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/categories?post=1154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/tags?post=1154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}