{"id":110,"date":"2007-11-24T11:31:46","date_gmt":"2007-11-24T10:31:46","guid":{"rendered":"http:\/\/lesbridg.cluster015.ovh.net\/wordpress\/index.php\/etude-statistiques-sur-les-celibataires\/qui-sont-les-hommes-daujourdhui.html"},"modified":"2019-07-18T11:49:17","modified_gmt":"2019-07-18T09:49:17","slug":"qui-sont-les-hommes-d-aujourdhui","status":"publish","type":"post","link":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-celibataires\/qui-sont-les-hommes-d-aujourdhui.html","title":{"rendered":"M\u00e9trosexuels, \u00fcbersexuels : Qui sont les hommes d&rsquo;aujourd&rsquo;hui ?"},"content":{"rendered":"<p>La liste des diff\u00e9rentes cat\u00e9gories dans lesquelles les agences de publicit\u00e9s vous casent \u00ab\u00a0Messieurs les hommes\u00a0\u00bb en 2007 :<\/p>\n<p>En 2005, David Beckam jonglant entre cheveux tress\u00e9s et cr\u00e2ne ras\u00e9, n&rsquo;h\u00e9sitant pas \u00e0 se maquiller le contour de l&rsquo;oeil, \u00e9tait l&rsquo;ic\u00f4ne de la nouvelle masculinit\u00e9.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-248132 size-full aligncenter\" src=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2007\/11\/david-beckham-et-ses-tresses.jpg\" alt=\"\" width=\"800\" height=\"465\" srcset=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2007\/11\/david-beckham-et-ses-tresses.jpg 800w, https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2007\/11\/david-beckham-et-ses-tresses-300x174.jpg 300w, https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2007\/11\/david-beckham-et-ses-tresses-768x446.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<h2>Qu&rsquo;est-ce qu&rsquo;un m\u00e9trosexuel ?<\/h2>\n<p>Baptis\u00e9 \u00ab<strong>m\u00e9trosexuel<\/strong>\u00bb, cet homme du 20\u00e8me si\u00e8cle naissant n&rsquo;avait plus peur de se perdre en terrain f\u00e9minin, se livrant \u00e0 des heures de shopping et se tartinant la figure de cr\u00e8me hydratante.<\/p>\n<p>L&rsquo;avantage du <strong>m\u00e9trosexuel<\/strong> \u00e9tait qu&rsquo;il \u00e9tait jeune, urbain et financi\u00e8rement ais\u00e9.<\/p>\n<h2>2 ans plus tard, fini le m\u00e9trosexuel et l&rsquo;<strong>\u00fcbersexuel, <\/strong>son cousin plus viril.<\/h2>\n<p>Des Etats-Unis \u00e0 l&rsquo;Europe, en passant par la France, le <strong>m\u00e9trosexuel <\/strong>existe bel et bien, mais en nombre limit\u00e9. Outre- Atlantique, l&rsquo;agence de publicit\u00e9 Leo Burnett les a estim\u00e9s \u00e0 moins d&rsquo;1 homme sur 5.<\/p>\n<p>A l&rsquo;oppos\u00e9, les <strong>n\u00e9omachos<\/strong>, sur lesquels la presse s&rsquo;est aussi beaucoup pench\u00e9e, ne seraient gu\u00e8re plus nombreux, de l&rsquo;ordre de 10 %.<br \/>\nSi on additionne \u00e0 ces derniers <strong>m\u00e9tro<\/strong> + <strong>\u00fcbersexuels<\/strong>, on arrive \u00e0 moins de 2 hommes sur 5.<\/p>\n<p><strong>L&rsquo;\u00fcbersexuel<\/strong> :<em> Terme invent\u00e9 par la publicitaire am\u00e9ricaine Maria Salzman, l&rsquo;\u00fcbersexuel (\u00fcber signifiant en allemand \u00ab au-dessus de \u00bb) est un homme \u00e0 l&rsquo;apparence <strong>macho ou virile<\/strong>, mais qui l&rsquo;entretient soigneusement. De type barbe de 3 jours, poils d\u00e9passant de la chemise, l&rsquo;homme se tourne un peu moins vers lui-m\u00eame et un peu plus vers les autres. Le nouvel id\u00e9al masculin caract\u00e9ris\u00e9 par une confiance absolue en soi sans \u00eatre odieux ou vain, une virilit\u00e9 \u00e0 toute \u00e9preuve, de la classe et un attachement \u00e0 la qualit\u00e9 de la vie.<br \/>\n<\/em><em>George Clooney ou Antonio Banderas en sont de bons exemples.\u00a0<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-248134 size-full aligncenter\" src=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2007\/11\/david-beckam-metrosexuel.jpg\" alt=\"\" width=\"800\" height=\"435\" srcset=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2007\/11\/david-beckam-metrosexuel.jpg 800w, https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2007\/11\/david-beckam-metrosexuel-300x163.jpg 300w, https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2007\/11\/david-beckam-metrosexuel-768x418.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<h2>Alors, \u00e0 quoi ressemble l&rsquo;homme de 2007 ?<\/h2>\n<p>Durant la d\u00e9cennie 90, alors que les femmes ne cessent d&rsquo;affirmer leur ind\u00e9pendance, eux ne cessent de perdre de leur assurance.<br \/>\nLe sexe dit \u00ab fort \u00bb est malmen\u00e9 par les revendications f\u00e9minines, paum\u00e9 dans ses rep\u00e8res traditionnels.<br \/>\nCette p\u00e9riode de crise toucherait \u00e0 sa fin.<\/p>\n<p><strong>\u00abLes hommes semblent se reconstruire dans un rapport d&rsquo;\u00e9galit\u00e9 avec les femmes et autour d&rsquo;une virilit\u00e9 positive, d\u00e9barrass\u00e9e de ses aspects les plus n\u00e9gatifs \u00bb, estime le publicitaire Nicolas Riou.<\/strong><\/p>\n<h3><strong>Les 20-30 ans en sont un exemple :<\/strong><\/h3>\n<p>Bien plus soucieux de leur apparence que leurs p\u00e8res ou leurs grands-p\u00e8res, <strong>ils font davantage les magasins, comme leurs soeurs<\/strong>, qu&rsquo;ils suivent chez H &amp; M. Mais cela ne les emp\u00eache pas de <strong>se vautrer dans un canap\u00e9 pour regarder un match \u00e0 la t\u00e9l\u00e9 en buvant une bi\u00e8re.<\/strong><\/p>\n<h2>Dans quelle cat\u00e9gorie d&rsquo;homme \u00eates-vous?<\/h2>\n<p>Pour s&rsquo;y retrouver dans ce large spectre de la masculinit\u00e9, Mondadori a class\u00e9 les hommes de 2007 en 5 cat\u00e9gories :<\/p>\n<ul>\n<li>Les \u00ab<strong> zappeurs cam\u00e9l\u00e9ons<\/strong> \u00bb (16 %) = Jeunes et grands consommateurs de nouvelles technologies, ils seraient l&rsquo;avant-garde de cette \u00ab masculinit\u00e9 r\u00e9concili\u00e9e \u00bb.<br \/>\nDans un refus du masculin traditionnel, ils s&rsquo;amusent \u00e0 collectionner des identit\u00e9s hybrides conjuguant les contraires (masculin\/f\u00e9minin, macho\/gay, nature\/techno, etc.).<\/li>\n<\/ul>\n<ul>\n<li>2\u00e8me groupe : les<strong> \u00ab\u00a0n\u00e9omachos\u00a0\u00bb<\/strong> (10 %) = Eux se sentent davantage menac\u00e9s. Jeunes \u00e9galement (entre 18 et 29 ans), ils ont l&rsquo;impression que la vie n&rsquo;a plus aucun sens et sont nostalgiques du pass\u00e9 et d&rsquo;une virilit\u00e9 primale.<\/li>\n<\/ul>\n<ul>\n<li>3\u00e8me groupe : Un peu plus \u00e2g\u00e9s (22-39 ans), les <strong>\u00ab\u00a0winners attentionn\u00e9s<\/strong>\u00a0\u00bb (16 %) estiment qu&rsquo;un homme doit \u00eatre financi\u00e8rement puissant et r\u00e9ussir socialement. Ils recherchent un \u00e9quilibre entre travail, couple et copains.<\/li>\n<\/ul>\n<ul>\n<li>4\u00e8me groupe : A l&rsquo;inverse, les \u00ab\u00a0<strong>nouveaux sensibles<\/strong>\u00a0\u00bb (24 %) se posent beaucoup de questions. Autour de la quarantaine approchante (29-49 ans), ils se sentent fragiles, s&rsquo;\u00e9tant laiss\u00e9s gagner par les contraintes du travail et par la routine du couple. Ils sont \u00e0 la recherche de valeurs d&rsquo;intimit\u00e9 et veulent comprendre la complexit\u00e9 du monde.<\/li>\n<\/ul>\n<ul>\n<li>Enfin, 5\u00e8me et derni\u00e8re cat\u00e9gorie, les \u00ab\u00a0<strong> happy boomers<\/strong>\u00a0\u00bb (34 %) sont essentiellement issus de la g\u00e9n\u00e9ration des 50-60 ans. Ils se caract\u00e9risent par un individualisme h\u00e9doniste et libertaire. Optimistes, ils sont sensibles aux valeurs des institutions et privil\u00e9gient les produits.<\/li>\n<\/ul>\n<p>Pour les publicitaires, certes, les hommes sont de plus en plus nombreux \u00e0 s&rsquo;habiller seuls, de plus en plus nombreux \u00e0 \u00eatre les ultimes d\u00e9cideurs dans l&rsquo;achat d&rsquo;une chemise ou d&rsquo;un pantalon, mais la plupart d&rsquo;entre eux continuent de faire leurs courses avec leur femme.<\/p>\n<p>Encore merci pour nous les femmes, l&rsquo;homme garde encore un peu de sa virilit\u00e9. Ils sont quand m\u00eame forts ses publicitaires.Essayer de caser la plupart des hommes de votre entourage, et vous constaterez qu&rsquo;ils y rentrent pratiquement tous, faites l&rsquo;essai \ud83d\ude09<\/p>\n<p>Plus de d\u00e9tails sur l&rsquo;enqu\u00eate.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La liste des diff\u00e9rentes cat\u00e9gories dans lesquelles les agences de publicit\u00e9s vous casent \u00ab\u00a0Messieurs les hommes\u00a0\u00bb en 2007 :<\/p>\n","protected":false},"author":2,"featured_media":248129,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"om_disable_all_campaigns":false,"_lmt_disableupdate":"no","_lmt_disable":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[10],"tags":[116],"class_list":["post-110","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-etude-statistiques-celibataires","tag-nouvelle-expression"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00e9trosexuels, \u00fcbersexuels : Qui sont les hommes d&#039;aujourd&#039;hui ? - Les Bridgets<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-celibataires\/qui-sont-les-hommes-d-aujourdhui.html\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e9trosexuels, \u00fcbersexuels : Qui sont les hommes d&#039;aujourd&#039;hui ? - Les Bridgets\" \/>\n<meta property=\"og:description\" content=\"La liste des diff\u00e9rentes cat\u00e9gories dans lesquelles les agences de publicit\u00e9s vous casent &quot;Messieurs les hommes&quot; en 2007 :\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-celibataires\/qui-sont-les-hommes-d-aujourdhui.html\" \/>\n<meta property=\"og:site_name\" content=\"Les Bridgets\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Les.Bridgets\" \/>\n<meta property=\"article:published_time\" content=\"2007-11-24T10:31:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-18T09:49:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2007\/11\/GEORGE-CLOONEY-metrosexuel.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bridget\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@les_bridgets\" \/>\n<meta name=\"twitter:site\" content=\"@les_bridgets\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bridget\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/statistiques\\\/etude-statistiques-celibataires\\\/qui-sont-les-hommes-d-aujourdhui.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/statistiques\\\/etude-statistiques-celibataires\\\/qui-sont-les-hommes-d-aujourdhui.html\"},\"author\":{\"name\":\"Bridget\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/person\\\/82a31c27ae0ddd23ee59e1e2ac5713ba\"},\"headline\":\"M\u00e9trosexuels, \u00fcbersexuels : Qui sont les hommes d&rsquo;aujourd&rsquo;hui ?\",\"datePublished\":\"2007-11-24T10:31:46+00:00\",\"dateModified\":\"2019-07-18T09:49:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/statistiques\\\/etude-statistiques-celibataires\\\/qui-sont-les-hommes-d-aujourdhui.html\"},\"wordCount\":810,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/statistiques\\\/etude-statistiques-celibataires\\\/qui-sont-les-hommes-d-aujourdhui.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2007\\\/11\\\/GEORGE-CLOONEY-metrosexuel.jpg\",\"keywords\":[\"nouvelle expression\"],\"articleSection\":[\"Statistiques sur les c\u00e9libataires\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/statistiques\\\/etude-statistiques-celibataires\\\/qui-sont-les-hommes-d-aujourdhui.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/statistiques\\\/etude-statistiques-celibataires\\\/qui-sont-les-hommes-d-aujourdhui.html\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/statistiques\\\/etude-statistiques-celibataires\\\/qui-sont-les-hommes-d-aujourdhui.html\",\"name\":\"M\u00e9trosexuels, \u00fcbersexuels : Qui sont les hommes d'aujourd'hui ? - Les Bridgets\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/statistiques\\\/etude-statistiques-celibataires\\\/qui-sont-les-hommes-d-aujourdhui.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/statistiques\\\/etude-statistiques-celibataires\\\/qui-sont-les-hommes-d-aujourdhui.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2007\\\/11\\\/GEORGE-CLOONEY-metrosexuel.jpg\",\"datePublished\":\"2007-11-24T10:31:46+00:00\",\"dateModified\":\"2019-07-18T09:49:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/statistiques\\\/etude-statistiques-celibataires\\\/qui-sont-les-hommes-d-aujourdhui.html#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/statistiques\\\/etude-statistiques-celibataires\\\/qui-sont-les-hommes-d-aujourdhui.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/statistiques\\\/etude-statistiques-celibataires\\\/qui-sont-les-hommes-d-aujourdhui.html#primaryimage\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2007\\\/11\\\/GEORGE-CLOONEY-metrosexuel.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2007\\\/11\\\/GEORGE-CLOONEY-metrosexuel.jpg\",\"width\":800,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/statistiques\\\/etude-statistiques-celibataires\\\/qui-sont-les-hommes-d-aujourdhui.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Les Bridgets\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Statistiques sur le couple &amp; celibat\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/category\\\/statistiques\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Statistiques sur les c\u00e9libataires\",\"item\":\"https:\\\/\\\/www.lesbridgets.com\\\/index.php\\\/category\\\/statistiques\\\/etude-statistiques-celibataires\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"M\u00e9trosexuels, \u00fcbersexuels : Qui sont les hommes d&rsquo;aujourd&rsquo;hui ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#website\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/\",\"name\":\"Les Bridgets\",\"description\":\"R\u00e9f\u00e9rences et r\u00e9flexions sur nos relations\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lesbridgets.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#organization\",\"name\":\"Les Bridgets\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo-3-lesbridgets.png\",\"contentUrl\":\"https:\\\/\\\/www.lesbridgets.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-logo-3-lesbridgets.png\",\"width\":251,\"height\":59,\"caption\":\"Les Bridgets\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Les.Bridgets\",\"https:\\\/\\\/x.com\\\/les_bridgets\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lesbridgets.com\\\/#\\\/schema\\\/person\\\/82a31c27ae0ddd23ee59e1e2ac5713ba\",\"name\":\"Bridget\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g\",\"caption\":\"Bridget\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e9trosexuels, \u00fcbersexuels : Qui sont les hommes d'aujourd'hui ? - Les Bridgets","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-celibataires\/qui-sont-les-hommes-d-aujourdhui.html","og_locale":"fr_FR","og_type":"article","og_title":"M\u00e9trosexuels, \u00fcbersexuels : Qui sont les hommes d'aujourd'hui ? - Les Bridgets","og_description":"La liste des diff\u00e9rentes cat\u00e9gories dans lesquelles les agences de publicit\u00e9s vous casent \"Messieurs les hommes\" en 2007 :","og_url":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-celibataires\/qui-sont-les-hommes-d-aujourdhui.html","og_site_name":"Les Bridgets","article_publisher":"https:\/\/www.facebook.com\/Les.Bridgets","article_published_time":"2007-11-24T10:31:46+00:00","article_modified_time":"2019-07-18T09:49:17+00:00","og_image":[{"width":800,"height":500,"url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2007\/11\/GEORGE-CLOONEY-metrosexuel.jpg","type":"image\/jpeg"}],"author":"Bridget","twitter_card":"summary_large_image","twitter_creator":"@les_bridgets","twitter_site":"@les_bridgets","twitter_misc":{"\u00c9crit par":"Bridget","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-celibataires\/qui-sont-les-hommes-d-aujourdhui.html#article","isPartOf":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-celibataires\/qui-sont-les-hommes-d-aujourdhui.html"},"author":{"name":"Bridget","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/person\/82a31c27ae0ddd23ee59e1e2ac5713ba"},"headline":"M\u00e9trosexuels, \u00fcbersexuels : Qui sont les hommes d&rsquo;aujourd&rsquo;hui ?","datePublished":"2007-11-24T10:31:46+00:00","dateModified":"2019-07-18T09:49:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-celibataires\/qui-sont-les-hommes-d-aujourdhui.html"},"wordCount":810,"commentCount":2,"publisher":{"@id":"https:\/\/www.lesbridgets.com\/#organization"},"image":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-celibataires\/qui-sont-les-hommes-d-aujourdhui.html#primaryimage"},"thumbnailUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2007\/11\/GEORGE-CLOONEY-metrosexuel.jpg","keywords":["nouvelle expression"],"articleSection":["Statistiques sur les c\u00e9libataires"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-celibataires\/qui-sont-les-hommes-d-aujourdhui.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-celibataires\/qui-sont-les-hommes-d-aujourdhui.html","url":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-celibataires\/qui-sont-les-hommes-d-aujourdhui.html","name":"M\u00e9trosexuels, \u00fcbersexuels : Qui sont les hommes d'aujourd'hui ? - Les Bridgets","isPartOf":{"@id":"https:\/\/www.lesbridgets.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-celibataires\/qui-sont-les-hommes-d-aujourdhui.html#primaryimage"},"image":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-celibataires\/qui-sont-les-hommes-d-aujourdhui.html#primaryimage"},"thumbnailUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2007\/11\/GEORGE-CLOONEY-metrosexuel.jpg","datePublished":"2007-11-24T10:31:46+00:00","dateModified":"2019-07-18T09:49:17+00:00","breadcrumb":{"@id":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-celibataires\/qui-sont-les-hommes-d-aujourdhui.html#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-celibataires\/qui-sont-les-hommes-d-aujourdhui.html"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-celibataires\/qui-sont-les-hommes-d-aujourdhui.html#primaryimage","url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2007\/11\/GEORGE-CLOONEY-metrosexuel.jpg","contentUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2007\/11\/GEORGE-CLOONEY-metrosexuel.jpg","width":800,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/www.lesbridgets.com\/index.php\/statistiques\/etude-statistiques-celibataires\/qui-sont-les-hommes-d-aujourdhui.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Les Bridgets","item":"https:\/\/www.lesbridgets.com\/"},{"@type":"ListItem","position":2,"name":"Statistiques sur le couple &amp; celibat","item":"https:\/\/www.lesbridgets.com\/index.php\/category\/statistiques"},{"@type":"ListItem","position":3,"name":"Statistiques sur les c\u00e9libataires","item":"https:\/\/www.lesbridgets.com\/index.php\/category\/statistiques\/etude-statistiques-celibataires"},{"@type":"ListItem","position":4,"name":"M\u00e9trosexuels, \u00fcbersexuels : Qui sont les hommes d&rsquo;aujourd&rsquo;hui ?"}]},{"@type":"WebSite","@id":"https:\/\/www.lesbridgets.com\/#website","url":"https:\/\/www.lesbridgets.com\/","name":"Les Bridgets","description":"R\u00e9f\u00e9rences et r\u00e9flexions sur nos relations","publisher":{"@id":"https:\/\/www.lesbridgets.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lesbridgets.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lesbridgets.com\/#organization","name":"Les Bridgets","url":"https:\/\/www.lesbridgets.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2022\/07\/cropped-logo-3-lesbridgets.png","contentUrl":"https:\/\/www.lesbridgets.com\/wp-content\/uploads\/2022\/07\/cropped-logo-3-lesbridgets.png","width":251,"height":59,"caption":"Les Bridgets"},"image":{"@id":"https:\/\/www.lesbridgets.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Les.Bridgets","https:\/\/x.com\/les_bridgets"]},{"@type":"Person","@id":"https:\/\/www.lesbridgets.com\/#\/schema\/person\/82a31c27ae0ddd23ee59e1e2ac5713ba","name":"Bridget","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7295cbdcf0cdf58bc2d250d0abac0622f7e9f13e4d6b98e0404f82bf994e0a55?s=96&d=mm&r=g","caption":"Bridget"}}]}},"modified_by":"Bridget","_links":{"self":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/comments?post=110"}],"version-history":[{"count":6,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/110\/revisions"}],"predecessor-version":[{"id":248135,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/posts\/110\/revisions\/248135"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/media\/248129"}],"wp:attachment":[{"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/media?parent=110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/categories?post=110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lesbridgets.com\/index.php\/wp-json\/wp\/v2\/tags?post=110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}